{"id":410344,"date":"2025-11-29T00:30:00","date_gmt":"2025-11-28T23:30:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=410344"},"modified":"2025-11-29T08:40:33","modified_gmt":"2025-11-29T07:40:33","slug":"abdominal-pain-internal-hernias","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/en\/abdominal-pain-internal-hernias\/","title":{"rendered":"Abdominal pain &#8211; internal hernias"},"content":{"rendered":"\n<p><strong>Internal hernias can form, particularly after surgery. This usually involves the small intestine twisting around internal organs. Internal hernias occur, for example, but not exclusively, after weight-reducing operations such as a gastric bypass and can be diagnosed using imaging techniques, with contrast-enhanced CT being the most suitable for this.    <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/en\/my-account\/packages\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/en\/log-in\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fen%2Fabdominal-pain-internal-hernias%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Internal hernias can form, particularly after surgery. This usually involves the small intestine twisting around internal organs. Internal hernias occur, for example, but not exclusively, after weight-reducing operations such as&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/en\/my-account\/packages\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/en\/log-in\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fen%2Fabdominal-pain-internal-hernias%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":410347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"From symptom to diagnosis","footnotes":""},"category":[11520,11508,11391,11297,11471,11548,11380],"tags":[66894,66895,85593],"powerkit_post_featured":[],"class_list":["post-410344","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cases-en","category-education","category-gastroenterology-and-hepatology","category-general-internal-medicine","category-radiology","category-rx-en","category-surgery","tag-abdominal-pain-en-2","tag-from-symptom-to-diagnosis","tag-internal-hernias","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:35:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"en_US","wpml_translations":{"fr_FR":{"locale":"fr_FR","id":410325,"slug":"douleurs-abdominales-hernies-internes","post_title":"Douleurs abdominales - hernies internes","href":"https:\/\/medizinonline.com\/fr\/douleurs-abdominales-hernies-internes\/"},"it_IT":{"locale":"it_IT","id":410360,"slug":"dolore-addominale-ernie-interne","post_title":"Dolore addominale - ernie interne","href":"https:\/\/medizinonline.com\/it\/dolore-addominale-ernie-interne\/"},"pt_PT":{"locale":"pt_PT","id":410471,"slug":"dor-abdominal-hernias-internas","post_title":"Dor abdominal - h\u00e9rnias internas","href":"https:\/\/medizinonline.com\/pt-pt\/dor-abdominal-hernias-internas\/"},"es_ES":{"locale":"es_ES","id":410328,"slug":"dolor-abdominal-hernias-internas","post_title":"Dolor abdominal - hernias internas","href":"https:\/\/medizinonline.com\/es\/dolor-abdominal-hernias-internas\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/410344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/comments?post=410344"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/410344\/revisions"}],"predecessor-version":[{"id":410357,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/410344\/revisions\/410357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/media\/410347"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/media?parent=410344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/category?post=410344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags?post=410344"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/powerkit_post_featured?post=410344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}