{"id":551851,"date":"2026-04-19T22:27:41","date_gmt":"2026-04-19T20:27:41","guid":{"rendered":"https:\/\/medizinonline.com\/?p=551851"},"modified":"2026-03-11T14:02:51","modified_gmt":"2026-03-11T13:02:51","slug":"clinical-care-from-birth-to-adulthood-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/en\/clinical-care-from-birth-to-adulthood-2\/","title":{"rendered":"Clinical care from birth to adulthood"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>The care of patients with adrenogenital syndrome is challenging across the entire lifespan. Especially during adolescence and the transition to adult medicine, disease-specific knowledge, emergency competence and continuity of treatment must be ensured. Typical case studies are used to illustrate how AGS presents itself from neonatal to adulthood, and key practical knowledge for diagnosis, treatment and long-term care is imparted.  <\/strong><\/p>\n\n\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/en\/my-account\/packages\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/en\/log-in\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fen%2Fclinical-care-from-birth-to-adulthood-2%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>The care of patients with adrenogenital syndrome is challenging across the entire lifespan. Especially during adolescence and the transition to adult medicine, disease-specific knowledge, emergency competence and continuity of treatment&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/en\/my-account\/packages\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">Already a member? <a href=\"https:\/\/medizinonline.com\/en\/log-in\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fen%2Fclinical-care-from-birth-to-adulthood-2%2F\">Log in here<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":551863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Adrenogenital syndrome","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11548,22615,11384,11413,11437,11503],"tags":[88593,88593,88589,88591,88460,88592,88590,15809,11795],"powerkit_post_featured":[],"class_list":["post-551851","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-en","category-cme-continuing-education","category-endocrinology-and-diabetology","category-nephrology","category-pediatrics","category-studies","tag-17-hydroxyprogesterone","tag-21-hydroxylase-deficiency","tag-adrenogenital-syndrome","tag-ags","tag-congenital-adrenal-hyperplasia","tag-pediatrics","tag-therapy-en","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 18:37:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"en_US","wpml_translations":{"fr_FR":{"locale":"fr_FR","id":551853,"slug":"suivi-clinique-de-la-naissance-a-lage-adulte-2","post_title":"Suivi clinique de la naissance \u00e0 l'\u00e2ge adulte","href":"https:\/\/medizinonline.com\/fr\/suivi-clinique-de-la-naissance-a-lage-adulte-2\/"},"it_IT":{"locale":"it_IT","id":551854,"slug":"assistenza-clinica-dalla-nascita-alleta-adulta-2","post_title":"Assistenza clinica dalla nascita all'et\u00e0 adulta","href":"https:\/\/medizinonline.com\/it\/assistenza-clinica-dalla-nascita-alleta-adulta-2\/"},"pt_PT":{"locale":"pt_PT","id":551855,"slug":"cuidados-clinicos-desde-o-nascimento-ate-a-idade-adulta-2","post_title":"Cuidados cl\u00ednicos desde o nascimento at\u00e9 \u00e0 idade adulta","href":"https:\/\/medizinonline.com\/pt-pt\/cuidados-clinicos-desde-o-nascimento-ate-a-idade-adulta-2\/"},"es_ES":{"locale":"es_ES","id":551852,"slug":"atencion-clinica-desde-el-nacimiento-hasta-la-edad-adulta-2","post_title":"Atenci\u00f3n cl\u00ednica desde el nacimiento hasta la edad adulta","href":"https:\/\/medizinonline.com\/es\/atencion-clinica-desde-el-nacimiento-hasta-la-edad-adulta-2\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/551851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/comments?post=551851"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/551851\/revisions"}],"predecessor-version":[{"id":551881,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/551851\/revisions\/551881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/media\/551863"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/media?parent=551851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/category?post=551851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags?post=551851"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/powerkit_post_featured?post=551851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}