{"id":68507,"count":1,"description":"","link":"https:\/\/medizinonline.com\/en\/tag\/treatment-sequences\/","name":"Treatment sequences","slug":"treatment-sequences","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags\/68507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts?tags=68507"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/article_rx?tags=68507"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/post_dl?tags=68507"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events?tags=68507"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=68507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}