{"id":95724,"count":1,"description":"","link":"https:\/\/medizinonline.com\/en\/tag\/mrd-basierte-leitlinienentwicklung\/","name":"MRD-basierte Leitlinienentwicklung","slug":"mrd-basierte-leitlinienentwicklung","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags\/95724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts?tags=95724"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/article_rx?tags=95724"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/post_dl?tags=95724"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events?tags=95724"},{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=95724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}