{"id":403193,"date":"2023-10-22T19:36:03","date_gmt":"2023-10-22T17:36:03","guid":{"rendered":"https:\/\/congressagenda.com\/?post_type=tribe_events&amp;p=1774"},"modified":"2023-10-22T19:36:03","modified_gmt":"2023-10-22T17:36:03","slug":"29-st-galler-infekttag-am-puls-der-zeit-2","status":"publish","type":"tribe_events","link":"https:\/\/medizinonline.com\/en\/event\/29-st-galler-infekttag-am-puls-der-zeit-2\/","title":{"rendered":"29. St.Galler Infekttag &#8211; Am Puls der Zeit"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":17389,"featured_media":1709,"template":"","meta":{"_acf_changed":false,"pmpro_default_level":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[77250,116],"tribe_events_cat":[90,104,110,115],"class_list":["post-403193","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","tag-featured","tag-featured-home","tribe_events_cat-general-practice","tribe_events_cat-infectious-diseases","tribe_events_cat-pharmacology","tribe_events_cat-virology","pmpro-has-access","cat_general-practice","cat_infectious-diseases","cat_pharmacology","cat_virology"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"de_DE","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events\/403193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/users\/17389"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events\/403193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/posts\/1709"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/media?parent=403193"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tags?post=403193"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/medizinonline.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=403193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}