{"id":11418,"count":142,"description":"","link":"https:\/\/medizinonline.com\/es\/categoria\/medicina-fisica-y-rehabilitacion\/","name":"Medicina f\u00edsica y rehabilitaci\u00f3n","slug":"medicina-fisica-y-rehabilitacion","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category\/11418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?category=11418"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?category=11418"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/publication?category=11418"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?category=11418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}