{"id":11493,"count":309,"description":"","link":"https:\/\/medizinonline.com\/es\/categoria\/casos\/","name":"Casos","slug":"casos","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category\/11493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?category=11493"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?category=11493"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/publication?category=11493"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?category=11493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}