{"id":324527,"date":"2022-10-13T01:00:00","date_gmt":"2022-10-12T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/centrarse-en-la-regurgitacion-funcional-de-la-valvula-mitral\/"},"modified":"2022-10-13T01:00:00","modified_gmt":"2022-10-12T23:00:00","slug":"centrarse-en-la-regurgitacion-funcional-de-la-valvula-mitral","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/centrarse-en-la-regurgitacion-funcional-de-la-valvula-mitral\/","title":{"rendered":"Centrarse en la regurgitaci\u00f3n funcional de la v\u00e1lvula mitral"},"content":{"rendered":"<p><strong>La regurgitaci\u00f3n mitral funcional (RMF), a diferencia de la regurgitaci\u00f3n mitral primaria, est\u00e1 causada por una disfunci\u00f3n ventricular. Como siempre es consecuencia de una enfermedad ventricular izquierda, el tratamiento farmacol\u00f3gico \u00f3ptimo de la insuficiencia cardiaca es el primer paso en el tratamiento de estos pacientes. Adem\u00e1s, los procedimientos intervencionistas con cat\u00e9ter tambi\u00e9n se han establecido como terapia en los \u00faltimos a\u00f1os, incluida la denominada reparaci\u00f3n de borde a borde mediante el sistema MitraClip.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La regurgitaci\u00f3n de la v\u00e1lvula mitral es el segundo defecto valvular adquirido m\u00e1s frecuente en adultos y la forma m\u00e1s com\u00fan de insuficiencia valvular. Seg\u00fan su etiolog\u00eda, se dividen en insuficiencias primarias (degenerativas) y secundarias (funcionales), por lo que la estrategia de tratamiento respectiva es fundamentalmente diferente. A diferencia de la regurgitaci\u00f3n mitral primaria, en la que la v\u00e1lvula est\u00e1 afectada per se por anomal\u00edas estructurales o procesos degenerativos de la propia v\u00e1lvula, la regurgitaci\u00f3n mitral secundaria o funcional (RMF), que se produce en el contexto de una disfunci\u00f3n ventricular izquierda, no s\u00f3lo es m\u00e1s frecuente y se asocia a un peor pron\u00f3stico en pacientes con insuficiencia cardiaca, sino que el beneficio de la reparaci\u00f3n quir\u00fargica de la v\u00e1lvula es tambi\u00e9n m\u00e1s incierto en comparaci\u00f3n con la regurgitaci\u00f3n mitral primaria. Anteriormente, se consideraba que la FMR se basaba predominantemente en la enfermedad ventricular, ya fuera una miocardiopat\u00eda isqu\u00e9mica (MCI) o una miocardiopat\u00eda dilatada (MCD). Sin embargo, en los \u00faltimos a\u00f1os se ha hecho m\u00e1s frecuente el diagn\u00f3stico de IM auricular funcional (IMF) en presencia de dilataci\u00f3n auricular izquierda, normalmente en el contexto de una fibrilaci\u00f3n auricular cr\u00f3nica <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1)<\/span> [2]. Esto es de crucial importancia, ya que permite la clasificaci\u00f3n fisiopatol\u00f3gica de la IM grave que se encuentra con frecuencia a pesar de una funci\u00f3n y geometr\u00eda ventricular normales, as\u00ed como una movilidad normal de las valvas de la v\u00e1lvula. Los resultados iniciales del estudio tambi\u00e9n sugieren que los pacientes con AFMR pueden beneficiarse de la terapia.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19793\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0.jpg\" style=\"height:728px; width:600px\" width=\"1100\" height=\"1335\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0-800x971.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0-120x146.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0-90x109.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0-320x388.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/abb1_cv3_s24_0-560x680.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"opcion-terapeutica-con-bajo-riesgo-periintervencional\">Opci\u00f3n terap\u00e9utica con bajo riesgo periintervencional<\/h2>\n<p>En el contexto de la necesidad existente de terapia de la v\u00e1lvula mitral en estos pacientes, en los \u00faltimos a\u00f1os se han podido establecer terapias intervencionistas menos invasivas, que siguen el modelo de las t\u00e9cnicas de reconstrucci\u00f3n quir\u00fargica. El m\u00e9todo m\u00e1s utilizado es la reconstrucci\u00f3n percut\u00e1nea de la v\u00e1lvula mitral &#8220;reparaci\u00f3n de borde a borde&#8221; mediante el sistema MitraClip (Abbott Vascular), que es una opci\u00f3n de tratamiento con bajo riesgo periintervencionista. En un ensayo aleatorio controlado (EVEREST II) que incluy\u00f3 a 279 pacientes con regurgitaci\u00f3n mitral predominantemente primaria, se compar\u00f3 el sistema MitraClip con la cirug\u00eda cardiaca en una aleatorizaci\u00f3n 2:1. El tratamiento con MitraClip fue inferior a la cirug\u00eda en cuanto a la reducci\u00f3n de la insuficiencia, pero mostr\u00f3 una seguridad superior y un beneficio cl\u00ednico comparable a la cirug\u00eda incluso despu\u00e9s de cinco a\u00f1os [3]. Sin embargo, al igual que con la terapia quir\u00fargica, no se ha demostrado ning\u00fan beneficio para la supervivencia con el procedimiento MitraClip en ensayos controlados en comparaci\u00f3n con la terapia farmacol\u00f3gica sola. Hasta la fecha, s\u00f3lo exist\u00eda un an\u00e1lisis post hoc del estudio EVEREST II y un estudio monoc\u00e9ntrico, retrospectivo y emparejado por propensi\u00f3n, que suger\u00edan la equivalencia con la terapia quir\u00fargica y la superioridad sobre la terapia farmacol\u00f3gica.<\/p>\n<h2 id=\"revelacion-de-la-controversia-entre-el-coapt-y-el-mitra-fr\">Revelaci\u00f3n de la controversia entre el COAPT y el MITRA-FR<\/h2>\n<p>Los resultados de dos ensayos controlados aleatorios recientes (COAPT y MITRA-FR) que comparan el tratamiento conservador y el MitraClip han sido contrastados. La reparaci\u00f3n percut\u00e1nea de la v\u00e1lvula mitral con el MitraClip redujo la mortalidad por todas las causas y la estancia hospitalaria en pacientes con regurgitaci\u00f3n mitral al menos de moderada a grave en el ensayo COAPT en comparaci\u00f3n con el tratamiento farmacol\u00f3gico basado \u00fanicamente en pautas. Sin embargo, los datos del ensayo MITRA-FR, publicado simult\u00e1neamente, no mostraron ning\u00fan beneficio pron\u00f3stico para los pacientes con insuficiencia cardiaca avanzada y ventr\u00edculo izquierdo gravemente agrandado, por lo que el tratamiento con MitraClip s\u00f3lo debe realizarse tras una cuidadosa selecci\u00f3n de los pacientes y la toma de decisiones del equipo cardiaco [4,5].<\/p>\n<h2 id=\"criterios-de-seleccion-de-pacientes\">Criterios de selecci\u00f3n de pacientes<\/h2>\n<p>Seg\u00fan el Prof. Dr. Dr. Philipp Lurz, m\u00e9dico jefe de la Cl\u00ednica Universitaria de Cardiolog\u00eda del Centro Cardiol\u00f3gico de Leipzig, la selecci\u00f3n de un paciente con FMR para un tratamiento transcat\u00e9ter depende, por tanto, de varios aspectos. Entre ellos se incluyen la gravedad de la regurgitaci\u00f3n mitral y la disfunci\u00f3n ventricular izquierda, as\u00ed como la optimizaci\u00f3n de la terapia m\u00e9dica dirigida por directrices (TMPD) [1]. Por lo tanto, el tratamiento farmacol\u00f3gico \u00f3ptimo de la insuficiencia cardiaca y, si est\u00e1 indicado, la implantaci\u00f3n de un marcapasos de resincronizaci\u00f3n (sistema TRC) siguen siendo las piedras angulares del tratamiento de la regurgitaci\u00f3n funcional de la v\u00e1lvula mitral. Sin embargo, incluso con un tratamiento farmacol\u00f3gico y de TRC \u00f3ptimo, la mayor\u00eda de los pacientes siguen presentando una regurgitaci\u00f3n mitral grave sintom\u00e1tica. Seg\u00fan la directriz, si la revascularizaci\u00f3n no est\u00e1 indicada y el riesgo quir\u00fargico no es bajo, puede realizarse un procedimiento percut\u00e1neo de borde a borde en pacientes con regurgitaci\u00f3n mitral secundaria grave y una FEVI  &gt;El 30% que permanezca sintom\u00e1tico a pesar de un tratamiento m\u00e9dico \u00f3ptimo (incluida la TRC si est\u00e1 indicada) y en el que la ecocardiograf\u00eda muestre una morfolog\u00eda valvular adecuada para evitar la futilidad debe ser considerado. La reparaci\u00f3n transcat\u00e9ter de borde a borde (TEER) debe considerarse en pacientes sintom\u00e1ticos seleccionados que no sean candidatos a la cirug\u00eda y cumplan criterios que sugieran una mayor probabilidad de respuesta a la terapia [6].<\/p>\n<h2 id=\"mensajes-para-llevarse-a-casa\">Mensajes para llevarse a casa<\/h2>\n<ul>\n<li>La regurgitaci\u00f3n mitral funcional est\u00e1 asociada a la insuficiencia cardiaca.<\/li>\n<li>La terapia farmacol\u00f3gica es siempre la primera opci\u00f3n de tratamiento.<\/li>\n<li>Si no hay respuesta a la terapia farmacol\u00f3gica, las opciones de terapia intervencionista son una buena opci\u00f3n.<br \/>\n\t&nbsp;<\/li>\n<\/ul>\n<p><em>Congreso:&nbsp;Simposio cl\u00ednico interdisciplinar de la DGIM<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Prof. Dr. Dr. Philipp Lurz: Terapia intervencionista de la v\u00e1lvula mitral &#8211; en qu\u00e9 punto nos encontramos actualmente y qu\u00e9 ocurre con la regurgitaci\u00f3n tric\u00faspide residual, Simposio cl\u00ednico interdisciplinar de la DGIM, 30.04.2022.<\/li>\n<li>Dferm S, et al: Regurgitaci\u00f3n mitral auricular funcional: Tema de revisi\u00f3n de la semana en el JACC. JACC 2019;&nbsp;https:\/\/doi.org\/10.1016\/j.jacc.2019.02.061.<\/li>\n<li>Mauri L, et al: The EVEREST II Trial: design and rationale for a randomized study of the evalve mitraclip system compared with mitral valve surgery for mitral regurgitation. Am Heart J 2010;&nbsp;doi: 10.1016\/j.ahj.2010.04.009.<\/li>\n<li>Stone GW, et al: Reparaci\u00f3n transcat\u00e9ter de la v\u00e1lvula mitral en pacientes con insuficiencia card\u00edaca. N Engl J Med 2018; doi: 10.1056\/NEJMoa1805374.<\/li>\n<li>Obadia JF, et al: Reparaci\u00f3n percut\u00e1nea o tratamiento m\u00e9dico para la regurgitaci\u00f3n mitral secundaria. N Engl J Med 2018; doi: 10.1056\/NEJMoa1805374.<\/li>\n<li>Vahanian A, et al: 2021 ESC\/EACTS Guidelines for the management of valvular heart disease: Developed by the Task Force for the management of valvular heart disease of the European Society of Cardiology (ESC) and the European Association for Cardio-Thoracic Surgery (EACTS). Revista Europea del Coraz\u00f3n 2022; doi: https:\/\/doi.org\/10.1093\/eurheartj\/ehac051.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2022; 21(3): 24-25<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La regurgitaci\u00f3n mitral funcional (RMF), a diferencia de la regurgitaci\u00f3n mitral primaria, est\u00e1 causada por una disfunci\u00f3n ventricular. Como siempre es consecuencia de una enfermedad ventricular izquierda, el tratamiento farmacol\u00f3gico&hellip;<\/p>\n","protected":false},"author":7,"featured_media":125019,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"M\u00e9todos de terapia intervencionista","footnotes":""},"category":[11324,11346,11483,11475,11552],"tags":[13647],"powerkit_post_featured":[],"class_list":["post-324527","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia","category-cirugia","category-el-congreso-informa","category-estudios","category-rx-es","tag-insuficiencia-de-la-valvula-mitral","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:15:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=324527"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/125019"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=324527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=324527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=324527"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=324527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}