{"id":324721,"date":"2022-09-25T01:00:00","date_gmt":"2022-09-24T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/evolucion-de-la-insulinoterapia-pacientes-y-profesionales-se-benefician\/"},"modified":"2022-09-25T01:00:00","modified_gmt":"2022-09-24T23:00:00","slug":"evolucion-de-la-insulinoterapia-pacientes-y-profesionales-se-benefician","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/evolucion-de-la-insulinoterapia-pacientes-y-profesionales-se-benefician\/","title":{"rendered":"Evoluci\u00f3n de la insulinoterapia: pacientes y profesionales se benefician"},"content":{"rendered":"<p><strong>En Suiza, los primeros an\u00e1logos de insulina de acci\u00f3n r\u00e1pida y prolongada llegaron al mercado hace unos veinte a\u00f1os. \u00c9stos se han ido desarrollando sucesivamente, de modo que hoy en d\u00eda se dispone de una amplia gama de preparados para el tratamiento personalizado de la diabetes. Las innovaciones en la tecnolog\u00eda de la diabetes tambi\u00e9n han mejorado significativamente la terapia con insulina y la calidad de vida de los afectados. Entre ellos se incluyen la monitorizaci\u00f3n continua de la glucosa y el&nbsp;<\/strong><strong>Sistemas &#8220;h\u00edbridos&#8221; \/ &#8220;de bucle cerrado&#8221; con administraci\u00f3n adaptativa de insulina.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Para las personas con diabetes, estos logros se traducen en una mayor autonom\u00eda y empoderamiento en todas las etapas de la vida [1]. A pesar de todos estos avances, las medidas relacionadas con el estilo de vida, como el ejercicio regular y los cambios en la dieta, siguen siendo una parte fundamental de la terapia de la diabetes.<\/p>\n<h2 id=\"analogos-de-insulina-de-accion-ultrarrapida-y-ultralarga\">An\u00e1logos de insulina de acci\u00f3n ultrarr\u00e1pida y ultralarga<\/h2>\n<p>Entre los desarrollos m\u00e1s recientes se encuentran los an\u00e1logos ultrarr\u00e1pidos, que reducen a\u00fan m\u00e1s los picos de glucosa posprandiales y la hipoglucemia inducida por acumulaci\u00f3n mediante un inicio y un retroceso a\u00fan m\u00e1s r\u00e1pidos de la acci\u00f3n de la insulina [1]. Las \u00faltimas insulinas basales de acci\u00f3n ultralarga minimizan la hipoglucemia gracias a una mayor duraci\u00f3n de acci\u00f3n y a perfiles de acci\u00f3n m\u00e1s estables. Sin embargo, hasta la fecha no es posible simular completamente la proporci\u00f3n fisiol\u00f3gica 3:1 de exposici\u00f3n a la insulina del h\u00edgado y los tejidos perif\u00e9ricos con la terapia de insulina subcut\u00e1nea. Actualmente se est\u00e1n investigando alternativas como las insulinas orales o espec\u00edficas para el h\u00edgado. La insulina inhalada no est\u00e1 autorizada en Suiza.<\/p>\n<h2 id=\"control-continuo-de-la-glucosa\">Control continuo de la glucosa<\/h2>\n<p>Adem\u00e1s de los sistemas convencionales de monitorizaci\u00f3n continua de la glucosa (MCG) que env\u00edan continuamente lecturas a un dispositivo receptor, tambi\u00e9n existen los denominados sistemas de &#8220;monitorizaci\u00f3n flash de la glucosa&#8221; que requieren que los valores de glucosa se recuperen activamente con un lector [1]. La glucosa se mide en el tejido adiposo subcut\u00e1neo mediante un sensor recubierto de enzimas. Los sistemas CGM\/&#8221;Flash Glucose Monitoring&#8221; proporcionan una curva de glucosa din\u00e1mica en comparaci\u00f3n con las mediciones convencionales de glucosa en sangre capilar. Los estudios han demostrado una mejora del control gluc\u00e9mico con una reducci\u00f3n de la hipoglucemia, y la pr\u00e1ctica cl\u00ednica demuestra que estos sistemas tienen un efecto positivo en la motivaci\u00f3n del usuario para la terapia y el autocontrol. Los afectados pueden anticiparse a las desviaciones de la glucosa y tomar las medidas oportunas. No s\u00f3lo los propios diab\u00e9ticos se benefician del hecho de que la terapia pueda adaptarse de forma m\u00e1s precisa y situacional, sino tambi\u00e9n todo el equipo de tratamiento.<\/p>\n<h2 id=\"sistemas-de-bucle-cerrado-y-apoyo-a-la-toma-de-decisiones-basado-en-la-ia\">&#8220;Sistemas de bucle cerrado y apoyo a la toma de decisiones basado en la IA<\/h2>\n<p>El acoplamiento de las bombas de insulina con los sistemas de MCG condujo al desarrollo de los llamados sistemas de &#8220;bucle cerrado&#8221; [1]. Estos sistemas de circuito cerrado permiten la administraci\u00f3n automatizada y a demanda de insulina con el objetivo de mejorar el control de la glucosa. Esto reduce el esfuerzo terap\u00e9utico de los afectados y supone un alivio. Mientras que los sistemas de &#8220;bucle totalmente cerrado&#8221; funcionan de forma aut\u00f3noma, los sistemas de &#8220;bucle cerrado h\u00edbrido&#8221; requieren la intervenci\u00f3n del usuario, como los anuncios de comidas. Desde hace algunos a\u00f1os, se comercializan en Suiza varios sistemas &#8220;h\u00edbridos de bucle cerrado&#8221; que se han utilizado con gran \u00e9xito principalmente para la diabetes de tipo 1. Por otro lado, ning\u00fan sistema de &#8220;bucle totalmente cerrado&#8221; est\u00e1 aprobado actualmente en este pa\u00eds. Sin embargo, el hecho de que estos sistemas mejoren significativamente el control de la glucosa en el \u00e1mbito hospitalario, con nutrici\u00f3n (par)enteral o en pacientes en di\u00e1lisis se considera confirmado emp\u00edricamente [2\u20134].<\/p>\n<h2 id=\"que-desarrollos-futuros-estan-surgiendo\">\u00bfQu\u00e9 desarrollos futuros est\u00e1n surgiendo?<\/h2>\n<p>En cuanto a los antidiab\u00e9ticos no insul\u00ednicos, se est\u00e1 estudiando la combinaci\u00f3n de las hormonas intestinales GLP-1 y GIP, con potentes efectos sobre el control de la glucosa y la reducci\u00f3n de peso [5]. En el campo de la insulinoterapia, se est\u00e1 investigando, entre otras cosas, en el desarrollo de an\u00e1logos de insulina de acci\u00f3n a\u00fan m\u00e1s prolongada, por ejemplo en forma de insulina b\u00e1sica aplicada una vez a la semana [6].&nbsp;  Los sistemas de &#8220;bucle cerrado&#8221; se mejoran constantemente equip\u00e1ndolos con sensores CGM m\u00e1s precisos, an\u00e1logos de insulina de acci\u00f3n a\u00fan m\u00e1s r\u00e1pida, la adici\u00f3n de hormonas como el glucag\u00f3n o an\u00e1logos de la amilina (&#8220;p\u00e1ncreas artificial de hormonas m\u00faltiples&#8221;) o la integraci\u00f3n de datos de movimiento y nutrici\u00f3n. Tambi\u00e9n intentan que los sistemas sean cada vez m\u00e1s f\u00e1ciles de usar. El an\u00e1lisis integrador de datos ya puede beneficiarse de los m\u00e9todos de la inteligencia artificial (IA). La aplicaci\u00f3n de nuevas tecnolog\u00edas conduce a la generaci\u00f3n de cantidades cada vez mayores de datos. Mediante el uso de m\u00e9todos apoyados en la IA, se pueden reconocer patrones complejos. Esta es la base de los llamados sistemas de &#8220;apoyo a la toma de decisiones&#8221; para ayudar a los pacientes y a sus equipos de tratamiento. La creciente digitalizaci\u00f3n permite el desarrollo de aplicaciones telem\u00e9dicas que proporcionan recomendaciones terap\u00e9uticas a los pacientes bas\u00e1ndose en los datos recogidos. Aunque todav\u00eda existen ciertos obst\u00e1culos reglamentarios y de protecci\u00f3n de datos en relaci\u00f3n con la IA y la digitalizaci\u00f3n, el potencial futuro de estas tecnolog\u00edas innovadoras es enorme. No s\u00f3lo se est\u00e1n realizando nuevos esfuerzos en el campo de la tecnolog\u00eda y la farmacoterapia de la diabetes, sino que tambi\u00e9n prosigue la investigaci\u00f3n sobre el trasplante de c\u00e9lulas de los islotes, por ejemplo con c\u00e9lulas de islotes encapsuladas [1].<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Lehmann V, et al.: La terapia de la diabetes en transici\u00f3n: evoluci\u00f3n y revoluci\u00f3n centradas en los afectados. Swiss Med Forum 2022; 22(0506): 85-87.<\/li>\n<li>Bally L, et al: Administraci\u00f3n de insulina en circuito cerrado para el control gluc\u00e9mico en cuidados no cr\u00edticos. N Engl J Med 2018; 379(6): 547-56.<\/li>\n<li>Boughton CK, et al: Administraci\u00f3n de insulina en circuito cerrado en pacientes hospitalizados que reciben apoyo nutricional: un ensayo controlado aleatorizado, abierto y en dos centros. Lancet Diabetes Endocrinol 2019;7(5): 368-377.<\/li>\n<li>Boughton CK, et al: Control de glucosa de bucle cerrado totalmente automatizado comparado con la terapia de insulina est\u00e1ndar en adultos con diabetes tipo 2 que requieren di\u00e1lisis: un ensayo cruzado aleatorizado de etiqueta abierta. Nat Med 2021; 27(8): 1471-1476.<\/li>\n<li>Fr\u00edas JP, et al: Tirzepatida frente a semaglutida una vez a la semana en pacientes con diabetes tipo 2. N Engl J Med 2021; 385(6): 503-515.<\/li>\n<li>Rosenstock J, et al: Insulina una vez a la semana para la diabetes tipo 2 sin tratamiento previo con insulina. N Engl J Med 2020; 383(22): 2107-2116.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2022; 17(8): 34<br \/>\nCARDIOVASC 2022; 21(3): 32&nbsp;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Suiza, los primeros an\u00e1logos de insulina de acci\u00f3n r\u00e1pida y prolongada llegaron al mercado hace unos veinte a\u00f1os. \u00c9stos se han ido desarrollando sucesivamente, de modo que hoy en&hellip;<\/p>\n","protected":false},"author":7,"featured_media":124279,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Control de la diabetes","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11352,11475,11478,11288,11552],"tags":[13989,11662,13992],"powerkit_post_featured":[],"class_list":["post-324721","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-y-diabetologia","category-estudios","category-formacion-continua","category-medicina-interna-general","category-rx-es","tag-bucle-cerrado","tag-diabetes-es","tag-terapia-con-insulina","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:59:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=324721"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/124279"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=324721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=324721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=324721"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=324721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}