{"id":324792,"date":"2022-09-14T03:00:00","date_gmt":"2022-09-14T01:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-psiquiatria-forense-en-el-contexto-del-derecho-penal\/"},"modified":"2022-09-14T03:00:00","modified_gmt":"2022-09-14T01:00:00","slug":"la-psiquiatria-forense-en-el-contexto-del-derecho-penal","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/la-psiquiatria-forense-en-el-contexto-del-derecho-penal\/","title":{"rendered":"La psiquiatr\u00eda forense en el contexto del derecho penal"},"content":{"rendered":"<p><strong>Adem\u00e1s de proporcionar dict\u00e1menes periciales en todos los \u00e1mbitos del derecho, a la psiquiatr\u00eda forense se le conf\u00eda el tratamiento de los enfermos mentales infractores de la ley. Esta tarea en la interfaz entre el derecho y la psiquiatr\u00eda requiere conocimientos especiales. Los aspectos del derecho penal tratan de la evaluaci\u00f3n de la culpabilidad y el tratamiento en el sistema penitenciario.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Adem\u00e1s de proporcionar dict\u00e1menes periciales en todos los \u00e1mbitos del derecho, a la psiquiatr\u00eda forense se le conf\u00eda el tratamiento de los enfermos mentales infractores de la ley. Esta tarea en la interfaz entre el derecho y la psiquiatr\u00eda requiere conocimientos especiales, por lo que existe el correspondiente t\u00edtulo especializado con requisitos espec\u00edficos de formaci\u00f3n y perfeccionamiento. Este art\u00edculo trata exclusivamente de aspectos del derecho penal, concretamente de la evaluaci\u00f3n de la culpabilidad y el tratamiento en instituciones penitenciarias.<\/p>\n<h2 id=\"peritaje-sobre-la-culpabilidad\">Peritaje sobre la culpabilidad<\/h2>\n<p>La acusaci\u00f3n de culpabilidad est\u00e1 vinculada a la capacidad de autodeterminaci\u00f3n y a la libertad de voluntad del ser humano [1]. Si existen dudas al respecto, por ejemplo debido a la existencia de un trastorno mental, esto justifica la intervenci\u00f3n de un experto en psiquiatr\u00eda forense a efectos de una evaluaci\u00f3n pericial. La base jur\u00eddica de la culpabilidad se establece en el art. 19 del CCE.<strong> <\/strong><span style=\"font-family:franklin gothic demi\">(Tab. 1).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19744\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9.png\" style=\"height:194px; width:400px\" width=\"1083\" height=\"525\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9.png 1083w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9-800x388.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9-120x58.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9-90x44.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9-320x155.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab1-np4_s9-560x271.png 560w\" sizes=\"(max-width: 1083px) 100vw, 1083px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La existencia de un trastorno mental como requisito previo para la reducci\u00f3n de la culpabilidad no se menciona expl\u00edcitamente en el texto de la ley, pero seg\u00fan la doctrina imperante es impl\u00edcitamente la base de los pasos posteriores del examen [2]. En consecuencia, en la primera fase diagn\u00f3stico-normativa, la evaluaci\u00f3n de la culpabilidad aborda la cuesti\u00f3n de si existe un trastorno mental grave. El factor decisivo aqu\u00ed es el grado de deterioro funcional existente en el momento del delito [3].<\/p>\n<p>En el segundo paso, hay que examinar si el cuadro de alteraciones psiqui\u00e1tricas revela s\u00edntomas cercanos al momento del delito que hayan provocado alteraciones de la capacidad de ver y controlar. El t\u00e9rmino perspicacia se refiere al conocimiento de las normas jur\u00eddicas y su validez. Una capacidad de insight suspendida puede deberse, por ejemplo, a una inteligencia reducida o a trastornos psic\u00f3ticos que suspenden la conexi\u00f3n con la realidad. La capacidad de control se refiere a la habilidad del individuo para dirigir sus acciones de acuerdo con la percepci\u00f3n que ha adquirido de la injusticia. Esto tambi\u00e9n requiere la capacidad de rechazar o inhibir los impulsos de actuar. No siempre es posible trazar una l\u00ednea exacta entre la capacidad de perspicacia y la capacidad de control. Por ejemplo, si Si una persona que padece esquizofrenia comete un delito por motivos delirantes, la experiencia delirante tambi\u00e9n puede haber deformado el sistema de valores de la persona, lo que puede anular la capacidad de entrar en raz\u00f3n [4]. Sin embargo, un delirio tambi\u00e9n pone en peligro la capacidad de controlar la acci\u00f3n, porque un alto nivel de din\u00e1mica delirante puede provocar una p\u00e9rdida de la capacidad de control. Por lo tanto, la suposici\u00f3n de que el control de las acciones preservadas puede derivarse de acciones que tienen un efecto planificador y ordenado no es correcta.<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"5\" cellspacing=\"1\" style=\"width:392px\">\n<tbody>\n<tr>\n<td style=\"width:376px\">\n<p><strong>Estudio de caso<\/strong><\/p>\n<p>Un hombre de 30 a\u00f1os que padece esquizofrenia se procura utensilios para construir una bomba incendiaria (c\u00f3ctel molotov). D\u00edas despu\u00e9s lanza el artefacto incendiario contra una comisar\u00eda cercana. Durante el interrogatorio, declar\u00f3 que los polic\u00edas de la comisar\u00eda llevaban meses vigil\u00e1ndole, escuch\u00e1ndole y acos\u00e1ndole. No pudo soportarlo m\u00e1s y quiso poner fin a &#8220;todo aquello&#8221;. En este caso, debido a los s\u00edntomas psic\u00f3ticos, se puede suponer que la capacidad de control motivacional se ha suspendido.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2 id=\"evaluacion-del-riesgo-de-reincidencia-el-pronostico-criminal\">Evaluaci\u00f3n del riesgo de reincidencia: el pron\u00f3stico criminal<\/h2>\n<p>El registro y la evaluaci\u00f3n cuidadosos y deliberados de la personalidad del delincuente constituyen el centro de la evaluaci\u00f3n pron\u00f3stica criminal [5]. Se formula una hip\u00f3tesis de la delincuencia teniendo especialmente en cuenta la interacci\u00f3n de las conspicuidades psicopatol\u00f3gicas. Teniendo en cuenta los factores de riesgo estad\u00edsticos y din\u00e1micos, se hacen declaraciones con respecto al riesgo futuro de delito de las personas afectadas. La Oficina Federal de Estad\u00edstica proporciona informaci\u00f3n sobre la tasa base de reincidencia en relaci\u00f3n con diferentes categor\u00edas de delitos [6]. Partiendo de esta tasa de referencia, el riesgo de reca\u00edda aumenta en presencia de factores de riesgo adicionales. Entre ellos se encuentran el sexo masculino, el bajo nivel socioecon\u00f3mico, la falta de vivienda y el abuso de sustancias, pero tambi\u00e9n el empleo inestable y factores criminol\u00f3gicos como la violencia o el encarcelamiento previos [7]. Las enfermedades mentales, por ejemplo del grupo de los esquizofr\u00e9nicos, tambi\u00e9n pueden tener un efecto negativo en el pron\u00f3stico de riesgo [8].<\/p>\n<p>La previsi\u00f3n (estad\u00edstica) del riesgo se complementa con los llamados Juicios Profesionales Estructurados (SPJ). A diferencia de los instrumentos de riesgo estad\u00edstico, no se asignan valores de puntos, sino que se determinan las necesidades con respecto a una gesti\u00f3n de riesgos requerida [9]. El HCR-20 es el instrumento de SPJ mejor estudiado, que capta 20 factores de riesgo de futuros comportamientos violentos en relaci\u00f3n con tres dominios [10]: problemas pasados (&#8220;historia&#8221; [H]), variables cl\u00ednicas (&#8220;cl\u00ednica&#8221; [C]) y riesgos futuros (&#8220;riesgo&#8221; [R]). A partir de las \u00e1reas problem\u00e1ticas evaluadas como relevantes, se dise\u00f1an escenarios de riesgo en distintas condiciones marco (despido, excedencia, etc.) para poder pronunciarse sobre la gesti\u00f3n de riesgos requerida. En este contexto, no s\u00f3lo la influenciabilidad cl\u00ednica de una sintomatolog\u00eda correspondiente, sino tambi\u00e9n la voluntad de cooperaci\u00f3n de los afectados y el espacio de acogida social influyen en las perspectivas de \u00e9xito [19].<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<table border=\"1\" cellpadding=\"5\" cellspacing=\"1\" style=\"width:500px\">\n<tbody>\n<tr>\n<td>\n<p>En cuanto al caso presentado, cabe se\u00f1alar que el pron\u00f3stico de riesgo del afectado ya estaba precargado: padec\u00eda y padece esquizofrenia paranoide, es decir, una enfermedad mental subyacente grave. De la sintomatolog\u00eda del delirio existente se deduce una estrecha relaci\u00f3n entre la experiencia relacionada con la enfermedad y el delito. En el momento del delito y meses antes, no recib\u00eda tratamiento psiqui\u00e1trico ni tomaba medicaci\u00f3n alguna. El consumo regular de cannabis supone una carga adicional para su pron\u00f3stico de riesgo. Durante una hospitalizaci\u00f3n psiqui\u00e1trica general meses antes, atac\u00f3 a un compa\u00f1ero por el que supuestamente se hab\u00eda sentido acosado, por lo que ya existe un historial de actos violentos. La persona afectada vive sola, no tiene una estructura diaria y afirma no recibir apoyo social de amigos o familiares &#8211; estos factores tambi\u00e9n tienen un efecto desfavorable en el pron\u00f3stico del riesgo.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 id=\"-2\">&nbsp;<\/h2>\n<h2 id=\"medidas-de-tratamiento\">Medidas de tratamiento<\/h2>\n<p>Se ordenan tratamientos con medidas si el castigo no es suficiente para contrarrestar el riesgo de reincidencia. As\u00ed pues, las medidas de tratamiento psiqui\u00e1trico forense sirven principalmente para mejorar el pron\u00f3stico legal. A diferencia de Alemania, el menoscabo de la culpabilidad no es un requisito previo para ordenar una medida terap\u00e9utica en Suiza [11]. Adem\u00e1s del riesgo de reca\u00edda, son relevantes las perspectivas de tratamiento, la voluntad de tratamiento y la viabilidad. En 2021, se ordenaron 200 medidas para pacientes hospitalizados y 279 para pacientes ambulatorios en Suiza [12]. A diferencia de la pr\u00e1ctica psiqui\u00e1trica general, aqu\u00ed no es el paciente quien formula el deseo de tratamiento, sino que \u00e9ste se decreta legalmente. Es comprensible que esta constelaci\u00f3n influya en la relaci\u00f3n m\u00e9dico-paciente [13].<\/p>\n<p>No siempre es necesario llevar a cabo la medida terap\u00e9utica en un entorno hospitalario; una medida tambi\u00e9n puede llevarse a cabo en un entorno ambulatorio. Si esto ocurre durante la ejecuci\u00f3n de una pena privativa de libertad, la medida ambulatoria puede llevarse a cabo paralelamente a la ejecuci\u00f3n de la pena. Las instalaciones adecuadas para la aplicaci\u00f3n de medidas correccionales en r\u00e9gimen de internamiento son las cl\u00ednicas psiqui\u00e1tricas forenses, los departamentos especializados de las instituciones penitenciarias o los centros correccionales. Para los adultos j\u00f3venes, existen instalaciones que abordan la independencia y la asunci\u00f3n de responsabilidades de los reclusos, donde hay una amplia gama de programas de formaci\u00f3n para promover el desarrollo personal <span style=\"font-family:franklin gothic demi\">(Tabla 2)<\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-19745 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9.png\" style=\"--smush-placeholder-width: 1091px; --smush-placeholder-aspect-ratio: 1091\/436;height:160px; width:400px\" width=\"1091\" height=\"436\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9.png 1091w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9-800x320.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9-120x48.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9-90x36.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9-320x128.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/09\/tab2-np4_s9-560x224.png 560w\" data-sizes=\"(max-width: 1091px) 100vw, 1091px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La custodia conforme a El art. 64 StGB tambi\u00e9n pertenece a las medidas, pero no persigue un mandato terap\u00e9utico. Puede ordenarse, entre otras cosas, si se ha cometido un delito de los denominados de cat\u00e1logo, por ejemplo, lesiones corporales graves o violaci\u00f3n. El objetivo de la custodia no es la resocializaci\u00f3n sino la protecci\u00f3n del p\u00fablico.<\/p>\n<p>El tratamiento en el marco de las medidas terap\u00e9uticas se orienta hacia el riesgo individual de reincidencia para cometer nuevos delitos y aborda los factores de riesgo correspondientes, as\u00ed como la capacidad de respuesta del delincuente (el llamado Modelo Riesgo-Necesidad-Responsabilidad [14]). El objetivo es ayudarles a llevar una vida socialmente aceptable <em>(Good Lives Model<\/em> [15]).<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"5\" cellspacing=\"1\" style=\"width:500px\">\n<tbody>\n<tr>\n<td>\n<p>En el caso descrito, la experiencia delirante y el riesgo asociado de nuevos delitos no pueden reducirse con una pena de prisi\u00f3n. El tratamiento psiqui\u00e1trico es necesario para hacer frente a esta constelaci\u00f3n de riesgos. Tratamientos psiqui\u00e1tricos previos del expl. muestran que sus s\u00edntomas de delirio, que son relevantes para los delitos, remiten bien bajo medicaci\u00f3n antipsic\u00f3tica, pero tambi\u00e9n mostraron que hab\u00eda problemas recurrentes con respecto a la capacidad del explante para cooperar. dio: En repetidas ocasiones dej\u00f3 de tomar su medicaci\u00f3n y no acud\u00eda a las citas. Actualmente tampoco estaba dispuesto a volver a tomar medicaci\u00f3n, por lo que el tratamiento de medidas no parece prometedor en r\u00e9gimen ambulatorio, sino s\u00f3lo en r\u00e9gimen de hospitalizaci\u00f3n.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Los datos procedentes de Alemania demuestran de forma impresionante que el tratamiento en una prisi\u00f3n de medidas o de reglas masivas se asocia a tasas de reincidencia m\u00e1s bajas que tras la puesta en libertad: dentro de un largo periodo de catamnesis (una media de 16,5 a\u00f1os), aproximadamente un tercio de los pacientes forenses puestos en libertad (35,2%) cometieron nuevos delitos, el 12,8% cometieron delitos violentos o sexuales graves y s\u00f3lo uno de cada seis pacientes (15,6%) volvi\u00f3 a ingresar en prisi\u00f3n.  [16]. Por el contrario, las personas tras cumplir una pena de prisi\u00f3n sin libertad condicional mostraron una tasa general de reincidencia del 47% y el 28% respectivamente en relaci\u00f3n con los delitos sexuales en un periodo de observaci\u00f3n significativamente m\u00e1s corto (6&nbsp;a\u00f1os) [17].<\/p>\n<h2 id=\"mensajes-para-llevarse-a-casa\">Mensajes para llevarse a casa<\/h2>\n<ul>\n<li>El trabajo psiqui\u00e1trico forense requiere conocimientos especializados.<\/li>\n<li>Las preguntas de evaluaci\u00f3n abordan los efectos jur\u00eddicamente relevantes de los trastornos mentales.<\/li>\n<li>Los tratamientos de intervenci\u00f3n sirven para reducir el riesgo de reca\u00edda, y este objetivo se consigue para una gran parte de los afectados.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Habermeyer E, Hoff P: Sobre la aplicaci\u00f3n forense del concepto de capacidad de discernimiento. Fortschr Neurol Psychiatr. 2004;72(11): 615-620.<\/li>\n<li>Habermeyer E, Mokros A, Briken P: &#8220;La relevancia de un proceso coherente de evaluaci\u00f3n y tratamiento forense&#8221;: \u00bfgran apuesta o vino viejo en una manguera agujereada? Psiquiatr\u00eda forense, psicolog\u00eda, criminolog\u00eda. 2020;14(2): 212-219.<\/li>\n<li>Rosenau H: Cap\u00edtulo 8 &#8211; Fundamentos jur\u00eddicos de la evaluaci\u00f3n psiqui\u00e1trica. En: Foerster V, Habermeyer D, Dre\u00dfing H, Habermeyer E, Bork S, Briken P, et al., editores. Evaluaci\u00f3n psiqui\u00e1trica (S\u00e9ptima edici\u00f3n). M\u00fanich: Urban &amp; Fischer; 2020: 85-150.<\/li>\n<li>Lau S, Kr\u00f6ber H-L: Das Schuldf\u00e4higkeitsgutachten. En: Kr\u00f6ber H-L, D\u00f6lling D, Leygraf N, Sass H, editores. Manual de psiquiatr\u00eda forense: Fundamentos psicopatol\u00f3gicos y pr\u00e1ctica de la psiquiatr\u00eda forense en el derecho penal. Heidelberg: Steinkopff; 2011: 213-560.<\/li>\n<li>Habermeyer E: Psiquiatr\u00eda forense. El Neur\u00f3logo 2009; 80(1): 79-92.<\/li>\n<li>Estad\u00edsticas de condenas penales 2018 [Internet]. Oficina Federal de Estad\u00edstica. 2020. Disponible en: www.bfs.admin.ch\/bfs\/de\/home\/statistiken\/kriminalitaet-strafrecht\/rueckfall.assetdetail.11527036.html.<\/li>\n<li>Whiting D, Fazel S: Epidemiolog\u00eda y factores de riesgo de la violencia en personas con trastornos mentales. En: Carpiniello B, Vita A, Mencacci C, editores. Violencia y trastornos mentales. Cham: Springer International Publishing; 2020: 49-62.<\/li>\n<li>Whiting D, Lichtenstein P, Fazel S: Violencia y trastornos mentales: una revisi\u00f3n estructurada de las asociaciones por diagn\u00f3sticos individuales, factores de riesgo y evaluaci\u00f3n del riesgo. The Lancet Psychiatry 2021; 8(2): 150-161.<\/li>\n<li>Hart S, Douglas K, Guy L: El enfoque de juicio profesional estructurado para la evaluaci\u00f3n del riesgo de violencia: Or\u00edgenes, naturaleza y avances. 2016: 643-666.<\/li>\n<li>Douglas KS, Hart SD, Webster CD, et al: Historical-Clinical-Risk Management-20, Version 3 (HCR-20V3): Desarrollo y visi\u00f3n general. Revista Internacional de Salud Mental Forense. 2014;13(2): 93-108.<\/li>\n<li>Habermeyer E, Dre\u00dfing H, Seifert D, et al: Praxishandbuch Therapie in der Forensischen Psychiatrie und Psychologie: Elsevier Health Sciences; 2021.<\/li>\n<li>Ejecuci\u00f3n de medidas: Admisiones por tipo de medida [Internet]. 2021. Disponible en: www.bfs.admin.ch\/bfs\/de\/home\/statistiken\/kriminalitaet-strafrecht\/justizvollzug.assetdetail.19744601.html.<\/li>\n<li>Meyer M, Hachtel H, Graf M: Caracter\u00edsticas especiales de la relaci\u00f3n terap\u00e9utica en pacientes psiqui\u00e1tricos forenses. Psiquiatr\u00eda forense, psicolog\u00eda, criminolog\u00eda. 2019;13(4): 362-370.<\/li>\n<li>Bonta J, Andrews DA: Modelo de riesgo-necesidad-respuesta para la evaluaci\u00f3n y rehabilitaci\u00f3n del delincuente. Rehabilitaci\u00f3n. 2007;6(1): 1-22.<\/li>\n<li>Franqu\u00e9 Fv, Briken P: El Modelo de las Buenas Vidas (MLV). Psiquiatr\u00eda forense, psicolog\u00eda, criminolog\u00eda. 2013; 7(1): 22-27.<\/li>\n<li>Seifert D, Klink M, Landwehr S: Datos de reincidencia de pacientes tratados en una instituci\u00f3n penitenciaria seg\u00fan el \u00a7 63 StGB. Psiquiatr\u00eda forense, psicolog\u00eda, criminolog\u00eda. 2018; 12(2): 136-148.<\/li>\n<li>Jehle JM, Albrecht HJ, Hohmann-Fricke S, Tetal C: La libertad condicional legal tras las sanciones penales: un estudio de reincidencia a escala nacional de 2010 a 2013 y de 2004 a 2013. 2016: Forum Verlag Godesberg GmbH.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo NEUROLOG\u00edA Y PSIQUIATR\u00cdA 2022; 20(4): 8-10.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de proporcionar dict\u00e1menes periciales en todos los \u00e1mbitos del derecho, a la psiquiatr\u00eda forense se le conf\u00eda el tratamiento de los enfermos mentales infractores de la ley. Esta tarea&hellip;<\/p>\n","protected":false},"author":7,"featured_media":124819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Guiltiness y Co.","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[22619,11478,11446,11288,11430,11435,11552],"tags":[14076,14077],"powerkit_post_featured":[],"class_list":["post-324792","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-cme","category-formacion-continua","category-medicina-forense","category-medicina-interna-general","category-prevencion-y-asistencia-sanitaria","category-psiquiatria-y-psicoterapia","category-rx-es","tag-forense","tag-psiquiatria-forense-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:55:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=324792"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/324792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/124819"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=324792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=324792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=324792"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=324792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}