{"id":325384,"date":"2022-07-12T01:00:00","date_gmt":"2022-07-11T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/una-relacion-medico-paciente-solida-gracias-a-una-buena-comunicacion\/"},"modified":"2023-01-12T14:08:51","modified_gmt":"2023-01-12T13:08:51","slug":"una-relacion-medico-paciente-solida-gracias-a-una-buena-comunicacion","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/una-relacion-medico-paciente-solida-gracias-a-una-buena-comunicacion\/","title":{"rendered":"Una relaci\u00f3n m\u00e9dico-paciente s\u00f3lida gracias a una buena comunicaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La conversaci\u00f3n personal y la respuesta a las preguntas son de gran importancia, especialmente en el cuidado de los enfermos cr\u00f3nicos. Pero fueron precisamente los cuidados de los que muchas personas afectadas tuvieron que prescindir durante la pandemia a causa del bloqueo. Muchos pacientes tambi\u00e9n evitan ir al m\u00e9dico por miedo a una infecci\u00f3n. Se consulta al m\u00e9dico con menos frecuencia, y a veces demasiado tarde.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">La conversaci\u00f3n personal y la respuesta a las preguntas son de gran importancia, especialmente en el cuidado de los enfermos cr\u00f3nicos. Pero fueron precisamente los cuidados de los que muchas personas afectadas tuvieron que prescindir durante la pandemia a causa del bloqueo. Muchos pacientes tambi\u00e9n evitan ir al m\u00e9dico por miedo a las infecciones. Se consulta al m\u00e9dico con menos frecuencia, y a veces demasiado tarde. Este fen\u00f3meno no ha cambiado ni siquiera en la actual situaci\u00f3n pand\u00e9mica, algo m\u00e1s relajada. Adem\u00e1s, muchas personas afectadas recubren sus inseguridades y miedos con agresividad. No es tarea f\u00e1cil para el m\u00e9dico mantener la calma y reaccionar con comprensi\u00f3n y compasi\u00f3n. Adem\u00e1s, la experiencia cl\u00ednica del m\u00e9dico no siempre es lo que cuenta. Seg\u00fan los estudios, la satisfacci\u00f3n y la adherencia del paciente dependen crucialmente de la conversaci\u00f3n m\u00e9dico-paciente. La capacidad de comunicaci\u00f3n suele ser la clave del \u00e9xito. Unos sencillos trucos pueden optimizar la conversaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Cada uno oye s\u00f3lo lo que entiende. Por disparatada que pueda parecer esta frase a primera vista, hay mucho de verdad en ella. Si el paciente no puede seguir las explicaciones del m\u00e9dico, el riesgo de que la terapia no se aplique como se desea es muy alto. El incumplimiento es un problema generalizado. En realidad, la mitad de los medicamentos no se toman correctamente, sobre todo porque los pacientes tienen reservas sobre la terapia. Pero \u00e9stas rara vez se dirigen al m\u00e9dico. La responsabilidad tambi\u00e9n se traslada a menudo al m\u00e9dico. Entonces, \u00bfqu\u00e9 hay que hacer para que el tratamiento tenga m\u00e1s \u00e9xito? Un estudio revel\u00f3 que las habilidades comunicativas del m\u00e9dico se correlacionan con la satisfacci\u00f3n del paciente en un factor de 0,71 [1]. Un elemento clave aqu\u00ed es la atenci\u00f3n y el aprecio, ya que esto conduce directamente a un aumento de la autoestima del paciente. Adem\u00e1s, el paciente debe participar en el proceso de toma de decisiones sobre la gesti\u00f3n de la terapia de forma bien informada. Esto es tanto m\u00e1s importante cuanto que cada vez son m\u00e1s las enfermedades cr\u00f3nicas degenerativas y psicosom\u00e1ticas que requieren la atenci\u00f3n del m\u00e9dico [2]. En estos casos, es esencial una cooperaci\u00f3n duradera y fiable de la persona afectada.<\/p>\n\n<h2 id=\"el-primer-contacto-es-crucial\" class=\"wp-block-heading\">El primer contacto es crucial<\/h2>\n\n<p class=\"wp-block-paragraph\">Por lo tanto, el paciente debe ser el centro de inter\u00e9s y comunicaci\u00f3n. Tomar decisiones de forma participativa y de mutuo acuerdo [3]. Sin embargo, los cimientos de una conversaci\u00f3n positiva ya est\u00e1n puestos cuando se establece el primer contacto. Por ello, los expertos recomiendan recoger usted mismo al paciente en la sala de espera. El contacto visual y la escucha han resultado ser otros par\u00e1metros importantes. Para muchos pacientes, es importante desahogarse en el primer minuto. Un comienzo abierto de la conversaci\u00f3n, como &#8220;Por favor, d\u00edganos&#8230;.&#8221; abre el espacio de conversaci\u00f3n en el que la persona con la enfermedad puede expresar sus necesidades sin ser dirigida en una direcci\u00f3n concreta. Por t\u00e9rmino medio, los m\u00e9dicos interrumpen a sus pacientes entre 11 y 24 segundos [4]. Esto puede hacer que se pierda informaci\u00f3n importante. A menudo, los afectados no comienzan su conversaci\u00f3n con el s\u00edntoma m\u00e1s angustioso, sino que lo dejan para el final [5]. Y la experiencia demuestra que, de todos modos, los pacientes que no son interrumpidos suelen terminar sus comentarios al cabo de entre 60 y 90 segundos.<\/p>\n\n<h2 id=\"\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"-2\" class=\"wp-block-heading\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19367\" style=\"height: 265px; width: 600px;\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/kasten_oh3_s10.png\" alt=\"\" width=\"1100\" height=\"486\"\/><\/h2>\n\n<h2 id=\"-3\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"no-todos-los-problemas-deben-resolverse-inmediatamente\" class=\"wp-block-heading\">No todos los problemas deben resolverse inmediatamente<\/h2>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es importante darse cuenta de que la comunicaci\u00f3n no consiste en poder resolver todos los problemas inmediatamente. Se trata m\u00e1s bien de crear una base segura y competente para la terapia. Al mismo tiempo, no hay que subestimar la degeneraci\u00f3n de los contenidos. Puede haber grandes diferencias entre lo que el m\u00e9dico quiere decir, lo que dice y lo que el paciente entiende. Parafrasear y resumir puede garantizar que m\u00e9dico y paciente quieren decir lo mismo. Adem\u00e1s, las pausas son importantes para dar a la persona afectada la oportunidad de procesar lo que ha o\u00eddo. Las preguntas de cumplimentaci\u00f3n permiten asignar las quejas a un cuadro cl\u00ednico. Tambi\u00e9n en este caso, la regla de oro es formular preguntas abiertas en lugar de cerradas. Esta \u00faltima s\u00f3lo debe utilizarse deliberadamente al final de la anamnesis, cuando el foco de atenci\u00f3n se estrecha. A continuaci\u00f3n, se pasa de una conversaci\u00f3n centrada en el paciente a otra centrada en el m\u00e9dico, lo que aclara el elemento participativo b\u00e1sico de la relaci\u00f3n.<\/p>\n\n<h2 id=\"menor-receptividad-en-situaciones-de-estres\" class=\"wp-block-heading\">Menor receptividad en situaciones de estr\u00e9s<\/h2>\n\n<p class=\"wp-block-paragraph\">Por t\u00e9rmino medio, las personas pueden recordar siete datos nuevos. Sin embargo, en una situaci\u00f3n emocionalmente estresante, la capacidad de absorci\u00f3n se reduce al m\u00ednimo. Esto podr\u00eda dar lugar a que el 93% de todos los afectados tengan el deseo de educarse, pero s\u00f3lo el 18% se sientan bien informados [6]. Por lo tanto, la informaci\u00f3n relevante para el paciente debe resumirse de nuevo al final de la entrevista. Adem\u00e1s, siempre hay que preguntarse qu\u00e9 se recuerda de esta conversaci\u00f3n. Al hacerlo, deben mitigarse las exageraciones negativas por parte del paciente y se\u00f1alarse las posibilidades de desarrollo positivo<span style=\"font-family: franklin gothic demi;\"> (Fig. 1) <\/span>. Una buena pregunta orientativa es considerar qu\u00e9 d\u00e9ficit de conocimientos podr\u00eda perjudicar al paciente hasta el pr\u00f3ximo contacto.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1273\" height=\"996\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/abb1-oh3_s11.png\" alt=\"\" class=\"wp-image-19368 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1273px; --smush-placeholder-aspect-ratio: 1273\/996;\" \/><\/figure>\n\n<h2 id=\"evite-el-correo-silencioso\" class=\"wp-block-heading\">Evite el correo silencioso<\/h2>\n\n<p class=\"wp-block-paragraph\">Ha dado buenos resultados seguir una estructura clara con la descripci\u00f3n de la situaci\u00f3n, el establecimiento de prioridades, el tratamiento de la enfermedad, la visi\u00f3n de los recursos hasta la clarificaci\u00f3n del mandato de tratamiento para apoyar al paciente de la mejor manera posible. En cualquier comunicaci\u00f3n m\u00e9dico-paciente puede surgir el problema del &#8220;silencio-posterior&#8221;: Puede haber una gran diferencia entre lo que el m\u00e9dico quiere decir y lo que dice, y uno debe ser consciente de ello. Lo que el paciente oye y lo que realmente entiende puede ser muy diferente del mensaje inicial<span style=\"font-family: franklin gothic demi;\"> (fig. 2)<\/span>. Por lo tanto, no s\u00f3lo es sensato sino imperativo limitarse a unos pocos datos relevantes y ser lo m\u00e1s claro posible al transmitir el mensaje.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1269\" height=\"703\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/abb2-oh3_s11.png\" alt=\"\" class=\"wp-image-19369 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1269px; --smush-placeholder-aspect-ratio: 1269\/703;\" \/><\/figure>\n\n<h2 id=\"cuando-de-repente-todo-es-diferente\" class=\"wp-block-heading\">Cuando de repente todo es diferente<\/h2>\n\n<p class=\"wp-block-paragraph\">Una frase&#8230; y el mundo del paciente se desmorona. Un diagn\u00f3stico potencialmente mortal o que pone en peligro la vida coge a la mayor\u00eda de las personas desprevenidas y las deja con un sentimiento de incertidumbre y ansiedad. Para el paciente, toda su vida cambia con la enfermedad. Por lo tanto, es esencial un enfoque prudente adaptado a la persona afectada<span style=\"font-family: franklin gothic demi;\"> (Tabla 1)<\/span>. En esta fase vulnerable, una relaci\u00f3n m\u00e9dico-paciente reforzada es a\u00fan m\u00e1s importante. El diagn\u00f3stico suele ir seguido de una dependencia inmediata de los proveedores de servicios m\u00e9dicos, no pocas veces unida a un accionismo salvaje. Ahora tambi\u00e9n es importante prestar atenci\u00f3n a los tonos tranquilos y leer entre l\u00edneas. Sobre todo, temas como el miedo al dolor, la situaci\u00f3n familiar y la carga que supone para los parientes, las experiencias previas con la enfermedad o, m\u00e1s adelante, el miedo a la recidiva son temas que deben tratarse pero que no siempre son abordados por la persona afectada.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"860\" height=\"819\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab1_oh3_s12.png\" alt=\"\" class=\"wp-image-19370 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 860px; --smush-placeholder-aspect-ratio: 860\/819;\" \/><\/figure>\n\n<h2 id=\"no-hay-que-subestimar-la-propia-sensibilidad\" class=\"wp-block-heading\">No hay que subestimar la propia sensibilidad<\/h2>\n\n<p class=\"wp-block-paragraph\">Ser el portador de malas noticias tambi\u00e9n es estresante para el m\u00e9dico. Por un lado, hay que evaluar la situaci\u00f3n con profesionalidad y actuar en consecuencia. Por otro lado, tambi\u00e9n se es un ser humano con sentimientos y empat\u00eda, que tambi\u00e9n deben ser atendidos. El paciente est\u00e1 en crisis. Se define como &#8220;una sobrecarga aguda de un sistema habitual de comportamiento y de afrontamiento&#8221; [7]. Lo que sigue es un estado de shock que, adem\u00e1s de una intensa sensaci\u00f3n de amenaza, tambi\u00e9n provoca un desequilibrio mental. No obstante, existe presi\u00f3n para actuar. No es una situaci\u00f3n f\u00e1cil. Ahora pueden aparecer rubor, sudoraci\u00f3n, palpitaciones, palidez y n\u00e1useas, as\u00ed como sobreexcitaci\u00f3n, aumento de la irritabilidad y fuertes cambios de humor. Si el paciente descarga sus sentimientos contra usted, es esencial que se d\u00e9 cuenta de que esto no tiene nada que ver con usted como mensajero. No en vano, en el pasado se ejecutaba a los portadores de malas noticias. Alguien que muestra comprensi\u00f3n suele llegar mejor al paciente que alguien que desv\u00eda la reacci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, a\u00fan m\u00e1s dif\u00edcil de soportar que el comportamiento agresivo es el horror sin palabras o el llanto. Aunque el sentimiento de querer ayudar es comprensible, no es posible. Las perogrulladas ya est\u00e1n fuera de lugar. A menudo puede mostrar su simpat\u00eda simplemente entregando a la persona un pa\u00f1uelo. Ofrezca tambi\u00e9n que est\u00e1 disponible para una conversaci\u00f3n en cualquier momento si es necesario. Por lo general, una situaci\u00f3n de estr\u00e9s agudo de este tipo dura desde varias horas hasta un m\u00e1ximo de tres d\u00edas. Si los s\u00edntomas persisten durante m\u00e1s tiempo, el paciente no dispone de recursos suficientes para hacer frente a la situaci\u00f3n. El sentimiento de impotencia y la p\u00e9rdida de control se apoderan de usted. En este caso, deben ofrecerse estrategias de afrontamiento para poder superar la crisis.<\/p>\n\n<h2 id=\"la-guia-para-la-entrevista-proporciona-ayuda\" class=\"wp-block-heading\">La gu\u00eda para la entrevista proporciona ayuda<\/h2>\n\n<p class=\"wp-block-paragraph\">Una de las gu\u00edas de entrevista m\u00e1s populares desarrollada espec\u00edficamente para la oncolog\u00eda es el protocolo SPIKES<span style=\"font-family: franklin gothic demi;\"> (Tab. 2)<\/span> [8]. Pretende que el m\u00e9dico pueda cumplir los cuatro objetivos principales de la entrevista de revelaci\u00f3n de malas noticias: Recoger informaci\u00f3n del paciente, comunicar la informaci\u00f3n m\u00e9dica, apoyar al paciente y obtener su cooperaci\u00f3n para desarrollar una estrategia o plan de tratamiento para el futuro. Incluso con las peores noticias, una buena comunicaci\u00f3n influye positivamente en la receptividad, la satisfacci\u00f3n del paciente, la adherencia y, por tanto, tambi\u00e9n en el \u00e9xito de la terapia. La amabilidad, el inter\u00e9s y un moderado dominio del m\u00e9dico han resultado ser especialmente positivos [9].<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"736\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0.png\" alt=\"\" class=\"wp-image-19371 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0-800x535.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0-120x80.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0-90x60.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0-320x214.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab2_oh3_s12_0-560x375.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/736;\" \/><\/figure>\n\n<h2 id=\"el-paciente-dificil\" class=\"wp-block-heading\">El paciente dif\u00edcil<\/h2>\n\n<p class=\"wp-block-paragraph\">El paciente no siempre reacciona como espera el m\u00e9dico. Entonces todo el proceso puede tambalearse porque se necesita m\u00e1s tiempo, energ\u00eda y atenci\u00f3n. Los cient\u00edficos han comprobado diferentes tipos de pacientes que han desarrollado estrategias individuales para ser percibidos como un individuo y experimentar apoyo emocional <span style=\"font-family: franklin gothic demi;\">(Tab. 3) <\/span>. B\u00e1sicamente, cuanto m\u00e1s baja es la autoestima, mayor es la vulnerabilidad. Por lo tanto, una reacci\u00f3n sensata y h\u00e1bil del m\u00e9dico es esencial, especialmente en este caso.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"557\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0.png\" alt=\"\" class=\"wp-image-19372 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0-800x405.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0-120x61.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0-90x46.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0-320x162.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/tab3_oh3_s13_0-560x284.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/557;\" \/><\/figure>\n\n<h2 id=\"preste-tambien-atencion-al-lenguaje-no-verbal\" class=\"wp-block-heading\">Preste tambi\u00e9n atenci\u00f3n al lenguaje no verbal<\/h2>\n\n<p class=\"wp-block-paragraph\">M\u00e1s del 90% de nuestro impacto comunicativo no procede de nuestras palabras. M\u00e1s bien se crea a trav\u00e9s del lenguaje corporal, los gestos, las expresiones faciales, el tempo del habla y el tono [10]. Con la pr\u00e1ctica, puede conseguir parecer exteriormente abierto, tranquilo y accesible, mientras que por dentro est\u00e1 hirviendo. Sin embargo, las se\u00f1ales no verbales s\u00f3lo resultan convincentes si realmente pensamos con aprecio. Un estado de curiosidad receptiva puede ser \u00fatil en este caso. En lugar de enfadarse por una reacci\u00f3n, uno puede preguntarse c\u00f3mo y en qu\u00e9 se ha podido producir. Al adoptar una postura de observaci\u00f3n, uno no se siente atacado personalmente con tanta rapidez. En \u00faltima instancia, el comportamiento depende menos de la situaci\u00f3n objetiva que de su interpretaci\u00f3n. Bas\u00e1ndose en las propias experiencias, se formulan hip\u00f3tesis sobre c\u00f3mo resultar\u00e1 una situaci\u00f3n. Por lo tanto, dos personas en la misma situaci\u00f3n tambi\u00e9n pueden reaccionar de forma diferente.<\/p>\n\n<h2 id=\"mensajes-para-llevarse-a-casa\" class=\"wp-block-heading\">Mensajes para llevarse a casa<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>La competencia comunicativa es la clave del \u00e9xito.<\/li>\n\n\n\n<li>Seg\u00fan los estudios, la satisfacci\u00f3n y el cumplimiento del paciente dependen crucialmente de la conversaci\u00f3n m\u00e9dico-paciente.<\/li>\n\n\n\n<li>Las habilidades comunicativas suelen desempe\u00f1ar un papel m\u00e1s importante que la experiencia cl\u00ednica del m\u00e9dico.<\/li>\n\n\n\n<li>La atenci\u00f3n y el aprecio generan confianza.<\/li>\n\n\n\n<li>Las pausas permiten al paciente ponerse al d\u00eda mentalmente.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Langewitz W, Denz M, Keller A, et al: Tiempo de conversaci\u00f3n espont\u00e1nea al inicio de la consulta en el ambulatorio: estudio de cohortes. BMJ 2002; 325(7366): 682-683.<\/li>\n\n\n\n<li>Bensing J, Langewitz W: Psychosomatische Medizin: Modelle \u00e4rztlichen Denkens und Handelns. Medicina psicosom\u00e1tica 2003; 415-424.<\/li>\n\n\n\n<li>Stewart MA, Brown JB, Weston WW, et al: Medicina centrada en el paciente: Transformaci\u00f3n del m\u00e9todo cl\u00ednico. Segunda edici\u00f3n. Int J Integr Care. 2005; 5: e20.<\/li>\n\n\n\n<li>Wilm S, Knauf A, Peters T, Bahrs O: \u00bfCu\u00e1ndo interrumpe el m\u00e9dico de cabecera a sus pacientes al principio de la consulta? Z Allg Med 2004; 80: 53-57.<\/li>\n\n\n\n<li>Burack RC, Carpenter RR: El valor predictivo de la queja de presentaci\u00f3n. The Journal of Family Practice 1983; 16(4):749-754.<\/li>\n\n\n\n<li>Ochsner KN, Gross JJ, et al: Cognitive Emotion Regulation: Insights from Social Cognitive and Affective Neuroscience. Curr Dir Psychol Sci. 2008; 17(2): 153-158.<\/li>\n\n\n\n<li>Simmich T, Reimer C: Aspectos psicoterap\u00e9uticos de la intervenci\u00f3n en crisis. Una revisi\u00f3n bibliogr\u00e1fica con especial referencia a los \u00faltimos 10 a\u00f1os. Psicoterapeuta 1998, 43: 143-156.<\/li>\n\n\n\n<li>Baile WF, Buckman, Lenzi R, et al: SPIKES-Un protocolo de seis pasos para dar malas noticias: aplicaci\u00f3n al paciente con c\u00e1ncer. Oncologist 2000; 5: 302-311.<\/li>\n\n\n\n<li>Swedlund MP, et al.: Efecto del estilo de comunicaci\u00f3n y las relaciones m\u00e9dico-familia en la satisfacci\u00f3n con la atenci\u00f3n a las enfermedades cr\u00f3nicas pedi\u00e1tricas. Salud Comun. 2012; 27: 498-505.<\/li>\n\n\n\n<li>Ehlich K, Rehbein J: Muster und Institution: Untersuchungen zur schulischen Kommunikation. 1986.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><em>InFo ONCOLOG\u00cdA Y HEMATOLOG\u00cdA 2022; 10(3): 10-13<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conversaci\u00f3n personal y la respuesta a las preguntas son de gran importancia, especialmente en el cuidado de los enfermos cr\u00f3nicos. Pero fueron precisamente los cuidados de los que muchas&hellip;<\/p>\n","protected":false},"author":7,"featured_media":123147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Psicooncolog\u00eda","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11475,22619,11478,11288,11336,11430,11435,11552],"tags":[11881,15271,13373,15267,15269,11758,15270,15272],"powerkit_post_featured":[],"class_list":["post-325384","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudios","category-formacion-cme","category-formacion-continua","category-medicina-interna-general","category-oncologia","category-prevencion-y-asistencia-sanitaria","category-psiquiatria-y-psicoterapia","category-rx-es","tag-adherencia","tag-competencia-es","tag-comunicacion","tag-cumplimiento","tag-entrevista-medico-paciente-es","tag-formacion-cme","tag-incumplimiento","tag-relacion-con-el-paciente","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:53:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/325384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=325384"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/325384\/revisions"}],"predecessor-version":[{"id":325387,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/325384\/revisions\/325387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/123147"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=325384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=325384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=325384"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=325384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}