{"id":325661,"date":"2022-06-09T01:00:00","date_gmt":"2022-06-08T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/trabajar-como-medico-independiente-en-suiza\/"},"modified":"2022-06-09T01:00:00","modified_gmt":"2022-06-08T23:00:00","slug":"trabajar-como-medico-independiente-en-suiza","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/trabajar-como-medico-independiente-en-suiza\/","title":{"rendered":"Trabajar como m\u00e9dico independiente en Suiza"},"content":{"rendered":"<p><strong>Un an\u00e1lisis de la Oficina Federal de Estad\u00edstica concluye que los ingresos netos anuales de los m\u00e9dicos aut\u00f3nomos en Suiza ascienden a 162.455 francos suizos. Todos aquellos que adem\u00e1s trabajen como m\u00e9dicos afiliados o dirijan su propia farmacia de consulta pueden estar satisfechos. Adem\u00e1s, los hombres ganan bastante m\u00e1s que las mujeres, lo que no es ninguna sorpresa.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><em>(rojo)<\/em>  Por cuarta vez, la Oficina Federal de Estad\u00edstica (OFE) realiz\u00f3 la encuesta sobre los datos estructurales de los consultorios m\u00e9dicos y centros ambulatorios MAS. Uno de ellos se dedica por primera vez por separado a los ingresos de los m\u00e9dicos aut\u00f3nomos que ejercen en el sector privado en Suiza. Se basa en los datos de 6472 m\u00e9dicos aut\u00f3nomos que poseen una empresa unipersonal. En 2019, seg\u00fan el an\u00e1lisis, el ingreso medio anual era de 204.985 francos suizos, lo que correspond\u00eda a un salario medio por hora de 115 francos suizos. Mientras que los salarios eran m\u00e1s bajos en psiquiatr\u00eda, con un salario medio por hora de 93 francos suizos, eran m\u00e1s elevados en las especialidades con actividades quir\u00fargicas. Trabajar como m\u00e9dico afiliado, algo especialmente habitual en los campos quir\u00fargicos y en obstetricia, as\u00ed como tener una farmacia de consulta propia tambi\u00e9n tienen un efecto positivo en los ingresos. Sin embargo, esta \u00faltima s\u00f3lo est\u00e1 permitida en algunos cantones german\u00f3fonos de Suiza. La dispensaci\u00f3n de medicamentos por parte de la consulta se asoci\u00f3 a un aumento de los ingresos de alrededor del 18%, y un puesto de m\u00e9dico adjunto se asoci\u00f3 a un aumento de los ingresos de alrededor del 11%. Las prestaciones cubiertas por un seguro complementario o de accidentes tambi\u00e9n son rentables. Por ello, no es de extra\u00f1ar que el salario medio por hora de los m\u00e9dicos en cuya consulta menos del 60% de los pacientes eran atendidos por el seguro obligatorio de enfermedad fuera especialmente elevado, de 132 francos suizos. Sin embargo, los contactos con pacientes de KVG representaron al menos el 90% de los casos en la mayor\u00eda de los consultorios. Por t\u00e9rmino medio, los ingresos generados por las prestaciones de la KVG ascendieron al 88% de los ingresos totales. Al igual que en otros sectores, la brecha de g\u00e9nero no puede pasarse por alto en el an\u00e1lisis de los salarios de los m\u00e9dicos aut\u00f3nomos. En igualdad de condiciones, los m\u00e9dicos ganaron de media un 25% m\u00e1s que sus colegas femeninas en 2019. La mayor tasa de empleo entre los hombres s\u00f3lo explica en parte esta sorprendente diferencia, que puede expresarse en el salario medio por hora. Esto ascendi\u00f3 a 122 francos suizos para los m\u00e9dicos y a 103 francos suizos para las m\u00e9dicas. Sin embargo, la proporci\u00f3n de mujeres est\u00e1 aumentando. Mientras que las mujeres s\u00f3lo representaban el 35% de las personas de entre 55 y 64 a\u00f1os en 2019, en el caso de los menores de 45 a\u00f1os eran el 58%.<\/p>\n<p>&nbsp;<\/p>\n<p>Para saber m\u00e1s:<\/p>\n<ul>\n<li>Consultorios m\u00e9dicos en 2019 &#8211; Estad\u00edsticas de consultorios m\u00e9dicos y centros ambulatorios (MAS). Oficina Federal de Estad\u00edstica (OFE). Neuch\u00e2tel, 2021. www.statistik.ch<\/li>\n<\/ul>\n<p>\n<em>InFo NEUROLOG\u00edA Y PSIQUIATR\u00cdA 2022; 20(2): 40<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un an\u00e1lisis de la Oficina Federal de Estad\u00edstica concluye que los ingresos netos anuales de los m\u00e9dicos aut\u00f3nomos en Suiza ascienden a 162.455 francos suizos. Todos aquellos que adem\u00e1s trabajen&hellip;<\/p>\n","protected":false},"author":7,"featured_media":119664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Potencial de ingresos","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11288,11470,11430,11552],"tags":[15706,15703,14546,15700,13369,15695,15705,15701,15698,15693],"powerkit_post_featured":[],"class_list":["post-325661","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-medicina-interna-general","category-noticias","category-prevencion-y-asistencia-sanitaria","category-rx-es","tag-bfs-es","tag-doctor-es","tag-estadisticas","tag-ganancias","tag-gestion-de-la-practica","tag-ingresos","tag-oficina-federal","tag-salario-es","tag-salarios-es","tag-suiza","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 10:56:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/325661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=325661"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/325661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/119664"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=325661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=325661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=325661"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=325661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}