{"id":326018,"date":"2022-04-18T01:00:00","date_gmt":"2022-04-17T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/estrategias-topicas-antienvejecimiento\/"},"modified":"2022-04-18T01:00:00","modified_gmt":"2022-04-17T23:00:00","slug":"estrategias-topicas-antienvejecimiento","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/estrategias-topicas-antienvejecimiento\/","title":{"rendered":"Estrategias t\u00f3picas antienvejecimiento"},"content":{"rendered":"<p><strong>El primer pilar del antienvejecimiento en dermatolog\u00eda es la prevenci\u00f3n. La protecci\u00f3n frente a la radiaci\u00f3n UV y el uso de antioxidantes son medidas importantes para ello. En segundo lugar est\u00e1n la correcci\u00f3n y la ralentizaci\u00f3n de los signos de envejecimiento de la piel. Los preparados t\u00f3picos pueden ralentizar el envejecimiento de la piel, favorecer la reparaci\u00f3n del da\u00f1o celular y promover la regeneraci\u00f3n del col\u00e1geno.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Los procesos de envejecimiento son consecuencia de cambios en los procesos fisiol\u00f3gicos y de una ralentizaci\u00f3n de la capacidad regenerativa <span style=\"font-family:franklin gothic demi\">(recuadro) <\/span>. Los dermocosm\u00e9ticos adecuados contra el envejecimiento cut\u00e1neo tienen propiedades de cuidado y protecci\u00f3n&nbsp; y contrarrestan los cambios degenerativos de la piel [1]. A continuaci\u00f3n se ofrece una visi\u00f3n general de las f\u00f3rmulas e ingredientes que han sido probados cient\u00edficamente [1].<\/p>\n<h2 id=\"sustancias-activas-con-evidencia-de-estudios-controlados-con-placebo\">Sustancias activas con evidencia de estudios controlados con placebo<\/h2>\n<p><span style=\"font-family:franklin gothic demi\">El retinol (vitamina A) <\/span>es uno de los reguladores celulares. La forma biol\u00f3gicamente activa es el \u00e1cido retinoico todo trans (tretino\u00edna, retin A, \u00e1cido vitam\u00ednico A).<\/p>\n<ul>\n<li>En un estudio aleatorizado doble ciego controlado con placebo en 36 sujetos con claros signos cl\u00ednicos de envejecimiento cut\u00e1neo (incluso en el cuerpo), una loci\u00f3n que conten\u00eda retinol al 0,4% demostr\u00f3 su eficacia tras 24 horas de aplicaci\u00f3n, incluso cuando se aplicaba tres veces por semana.&nbsp;semanas condujo cl\u00ednicamente a una reducci\u00f3n significativa de las arrugas finas y bioqu\u00edmicamente a un aumento significativo de la s\u00edntesis de glicosaminoglicanos y procol\u00e1geno I [3].<\/li>\n<li>En un ensayo controlado de tres brazos en el que participaron un total de 125 sujetos, se compar\u00f3 una crema de retinaldeh\u00eddo al 0,5% con placebo y con una crema de \u00e1cido transretinoico total al 0,05% en cuanto a su eficacia y tolerabilidad en la zona de las arrugas laterales del ojo [4]. Se utiliz\u00f3 la perfilometr\u00eda \u00f3ptica para determinar una evaluaci\u00f3n cuantitativa de la textura de la piel, la profundidad de las arrugas, la rugosidad de la piel y otros par\u00e1metros. Tras un periodo de aplicaci\u00f3n de 18 semanas, se observ\u00f3 una reducci\u00f3n significativa de la profundidad de las arrugas y de la rugosidad de la piel bajo tratamiento con crema de retinaldeh\u00eddo. El examen histol\u00f3gico de muestras de piel de 53 voluntarios mayores de 80 a\u00f1os demostr\u00f3 que la aplicaci\u00f3n durante siete d\u00edas de un preparado de retinol al uno por ciento puede mejorar significativamente la composici\u00f3n de la matriz extracelular y provocar un aumento de los fibroblastos y de la s\u00edntesis de col\u00e1geno con una disminuci\u00f3n simult\u00e1nea de la metaloproteinasa MMP-1 que degrada la matriz [5].<\/li>\n<li>En estudios posteriores, estos efectos se confirmaron para el retinol y tambi\u00e9n para el retinaldeh\u00eddo. Se han demostrado efectos similares para el \u00e1cido retinoico todo trans [6,7].<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18470\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/04\/kasten1_dp1_s40.png\" style=\"height:183px; width:600px\" width=\"1100\" height=\"336\"><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family:franklin gothic demi\">Niacinamida (vitamina B3): <\/span>La niacinamida bloquea el efecto inhibidor de la radiaci\u00f3n UV sobre la producci\u00f3n de ATP, favorece la reparaci\u00f3n del ADN, reduce la queratosis act\u00ednica y la hiperpigmentaci\u00f3n y tambi\u00e9n minimiza de forma t\u00f3pica la inmunosupresi\u00f3n inducida por los rayos UV [8].<\/p>\n<ul>\n<li>Una formulaci\u00f3n que conten\u00eda un cinco por ciento de niacinamida redujo significativamente las l\u00edneas finas y las arrugas y disminuy\u00f3 la hiperpigmentaci\u00f3n, el enrojecimiento y la decoloraci\u00f3n amarilla en el rostro de 50 mujeres con piel facial fotoda\u00f1ada tras su uso dos veces al d\u00eda durante 12&nbsp;semanas. Adem\u00e1s, se observ\u00f3 un aumento de la elasticidad de la piel [9].<\/li>\n<li>En un estudio aleatorizado doble ciego controlado con placebo en 30 mujeres asi\u00e1ticas&nbsp;publicado posteriormente, un preparado que conten\u00eda un cuatro por ciento de niacinamida demostr\u00f3 ser significativamente m\u00e1s eficaz contra las arrugas de la regi\u00f3n ocular tras ocho semanas de aplicaci\u00f3n en el rostro en comparaci\u00f3n con el control [10]. Interesante en relaci\u00f3n con la eficacia de la niacinamida contra el envejecimiento cut\u00e1neo es tambi\u00e9n el resultado de un estudio in vitro, seg\u00fan el cual la niacinamida estimula la s\u00edntesis de ceramidas, que disminuye con el avance de la edad [11].<\/li>\n<\/ul>\n<p><span style=\"font-family:franklin gothic demi\">Vitamina C (\u00e1cido L-asc\u00f3rbico): <\/span>La vitamina C (forma biol\u00f3gicamente activa: \u00e1cido L-asc\u00f3rbico) act\u00faa como cofactor en la s\u00edntesis de col\u00e1geno y es uno de los principios activos antienvejecimiento mejor estudiados [12\u201314]<span style=\"color:rgb(61, 113, 176)\">. <\/span>Como la sustancia es muy hidr\u00f3fila, la formulaci\u00f3n es muy importante para que penetre en la piel.<\/p>\n<ul>\n<li>Existen pruebas de la eficacia de estudios doble ciego controlados con placebo para algunas f\u00f3rmulas que contienen vitamina C [15,16]. En uno de estos estudios, se aplic\u00f3 un preparado de vitamina C al cinco por ciento en un antebrazo y placebo en el otro durante seis meses en sujetos femeninos con piel fotoda\u00f1ada [16]. Despu\u00e9s de este periodo, se encontr\u00f3 una mayor expresi\u00f3n de col\u00e1geno tipo I y tipo III, as\u00ed como del inhibidor tisular de MMP-1, para el preparado de vitamina C en las biopsias. Adem\u00e1s, se observ\u00f3 un aumento de las fibras el\u00e1sticas y una reorganizaci\u00f3n de los haces de col\u00e1geno de tipo I.<\/li>\n<li>Algunos grupos de investigaci\u00f3n utilizaron la perfilometr\u00eda \u00f3ptica para documentar la mejora significativa de la textura de la piel, el alivio de las arrugas y la rugosidad cut\u00e1nea tras la aplicaci\u00f3n de preparados que contienen vitamina C [17,18]. En un estudio aleatorizado doble ciego controlado con placebo en el que participaron 19 sujetos (rango de edad: 36 a 72 a\u00f1os) con piel facial moderadamente fotoda\u00f1ada (&nbsp;), se observ\u00f3 una mejora significativa de la textura superficial, las l\u00edneas finas y la elasticidad de la piel tras tres meses de aplicaci\u00f3n de un preparado de vitamina C al 10% en comparaci\u00f3n con el control no tratado [17]. Estos hallazgos fueron confirmados por investigaciones cient\u00edficas posteriores. Los preparados t\u00f3picos de vitamina C deben protegerse de la exposici\u00f3n a la luz y al aire, debido a su considerable inestabilidad y sensibilidad a influencias oxidantes como el aire y la luz ultravioleta.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-18471 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/04\/kasten2_dp1_s41.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/531;height:290px; width:600px\" width=\"1100\" height=\"531\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family:franklin gothic demi\">\u00c1cido hialur\u00f3nico de bajo peso molecular: <\/span>El \u00e1cido hialur\u00f3nico es un componente importante del tejido conjuntivo que interviene en la proliferaci\u00f3n celular. En los seres humanos, el \u00e1cido hialur\u00f3nico se encuentra, entre otros lugares, en la dermis, donde su capacidad para ligar grandes cantidades de agua confiere al tejido fuerza y elasticidad. Utilizado originalmente en medicina para favorecer la cicatrizaci\u00f3n de heridas, el \u00e1cido hialur\u00f3nico es ahora uno de los principios activos m\u00e1s utilizados contra el envejecimiento cut\u00e1neo. El compuesto se utiliza para inyectar arrugas y tambi\u00e9n est\u00e1 contenido en numerosos dermocosm\u00e9ticos. Su uso en cosm\u00e9ticos antienvejecimiento se basa en la observaci\u00f3n de que la producci\u00f3n corporal de \u00e1cido hialur\u00f3nico disminuye con la edad [19].<\/p>\n<ul>\n<li>Como demuestran los estudios experimentales, as\u00ed como una investigaci\u00f3n cl\u00ednica, los fragmentos de \u00e1cido hialur\u00f3nico de cierta longitud contrarrestan la atrofia cut\u00e1nea cuando se aplican t\u00f3picamente. Con fragmentos de longitud media, se pudo estimular la proliferaci\u00f3n de queratinocitos in vitro. En un ensayo cl\u00ednico m\u00e1s peque\u00f1o realizado en 7 sujetos con atrofia cut\u00e1nea relacionada con los corticosteroides o la edad y 17 controles, el uso durante un mes de un preparado que conten\u00eda un 1% de \u00e1cido hialur\u00f3nico produjo un aumento significativo del grosor de la piel en comparaci\u00f3n con el control. Esto se considera una prueba de que los fragmentos de \u00e1cido hialur\u00f3nico utilizados pueden penetrar en la epidermis [20].<\/li>\n<li>Independientemente de esta cuesti\u00f3n, el efecto de los fragmentos de \u00e1cido hialur\u00f3nico correspondientes sobre la profundidad de las arrugas se investig\u00f3 en un estudio doble ciego controlado con placebo [21]. En este estudio, 76 voluntarias de&nbsp;de entre 30 y 60 a\u00f1os con arrugas oculares macrosc\u00f3picamente visibles (&#8220;patas de gallo&#8221;) se aplicaron una crema al 0,1 por ciento con fragmentos de \u00e1cido hialur\u00f3nico de diferentes pesos moleculares (50, 130, 300, 800 y 2000&nbsp;kDa) en una cara dos veces al d\u00eda durante ocho semanas. En el lado contralateral, se aplic\u00f3 la base de crema sin \u00e1cido hialur\u00f3nico. Se realiz\u00f3 una evaluaci\u00f3n biof\u00edsica despu\u00e9s de 30 y despu\u00e9s de 60 d\u00edas&nbsp;. Para ello fue necesario medir la hidrataci\u00f3n de la capa c\u00f3rnea y la elasticidad de la piel, as\u00ed como evaluar el perfil de la superficie cut\u00e1nea mediante impresiones de silicona. Todas las zonas de la piel en las que se aplic\u00f3 uno de los productos de prueba mostraron un aumento significativo de la hidrataci\u00f3n de la capa c\u00f3rnea y de la elasticidad cut\u00e1nea en comparaci\u00f3n con la parte placebo. Adem\u00e1s, los fragmentos m\u00e1s peque\u00f1os (50 y 130&nbsp;kDa) provocaron una reducci\u00f3n significativa de la rugosidad cut\u00e1nea, as\u00ed como un alisamiento duradero del relieve de la superficie de la piel [21].<\/li>\n<\/ul>\n<h2 id=\"considere-la-galenica\">Considere la gal\u00e9nica<\/h2>\n<p>Adem\u00e1s de las pruebas mencionadas, existen resultados de estudios in vitro e in vivo sobre otros numerosos ingredientes activos como componentes de dermocosm\u00e9ticos t\u00f3picos que demuestran un beneficio contra el envejecimiento prematuro de la piel&nbsp;[1]. Las propiedades antienvejecimiento de los dermocosm\u00e9ticos est\u00e1n ligadas a la formulaci\u00f3n global y no exclusivamente a los ingredientes individuales. Las cremas y lociones m\u00e1s utilizadas son las emulsiones W\/O*, las emulsiones O\/W#, las emulsiones m\u00faltiples o los sistemas lamelares. Pero tambi\u00e9n se utilizan hidrogeles sin l\u00edpidos como base. Otros enfoques gal\u00e9nicos, como las formulaciones liposomales, las part\u00edculas ultrapeque\u00f1as de principios activos (nanocristales), las emulsiones a nanoescala y las nanopart\u00edculas lip\u00eddicas, pretenden mejorar el transporte de los principios activos a la piel [22\u201324].<\/p>\n<p><span style=\"font-size:12px\">*&nbsp;W\/O=Agua en aceite<br \/>\n<sup>#<\/sup>&nbsp;O\/W=aceite en agua<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>&#8220;Dermocosm\u00e9ticos contra el envejecimiento cut\u00e1neo&#8221;, directriz de la GD Gesellschaft f\u00fcr Dermopharmazie e. V., www.gd-online.de\/german\/veranstalt\/images2017\/GD_LL_Dermokosmetika_gegen_Hautalterung_13.03.2017.pdf (\u00faltima recuperaci\u00f3n 28.01.2022).<\/li>\n<li>Bayerl C: Hautarzt 2016; 67: 140-147.<\/li>\n<li>Kafi R, et al: Arch Dermatol 2007: 143: 606-612.<\/li>\n<li>Creidi P, et al: J Am Acad Dermatol 1998; 39: 960-965.<\/li>\n<li>Varani J, et al: J Invest Dermatol 2000; 114: 480-486.<\/li>\n<li>Bhawan J: Int J Dermatol 1998; 37: 286-292.<\/li>\n<li>Boisnic S, et al: Dermatolog\u00eda 1999; 199; Suppl. 1: 43-48.<\/li>\n<li>Bayerl C: Akt Dermatol 2017; 43: 431-433.<\/li>\n<li>Bisset DL, Oblong JE, Berge C: Dermatol Surg 2005; 31: 860-865.<\/li>\n<li>Kawada A, et al: J Dermatol 2008; 35: 637-642.<\/li>\n<li>Tanno O, et al: Br J Dermatol 2000; 143: 524-531.<\/li>\n<li>Pinnell SR: J Am Acad Dermatol 2003; 48: 1-19.<\/li>\n<li>Van Scott E, Ditre CM, Yu RJ: Clin Dermatol 1996; 14: 217-226.<\/li>\n<li>Phillips CL, Combs SB, Pinnell SR: J Invest Dermatol 1994; 103: 228-231.<\/li>\n<li>Haftek M, et al: Exp Dermatol 2008; 17: 946-952.<\/li>\n<li>Humbert PG, et al: Exp Dermatol 2003; 12: 237-244.<\/li>\n<li>Traikovich SS: Arch Otolaryngol Head Neck Surg 1999; 125: 1091-1098.<\/li>\n<li>Rubino C, et al: Plast Reconstr Surg 2005; 115: 1156-1162.<\/li>\n<li>Ghersetich I, et al: Int J Dermatol 1994; 33: 119-122.<\/li>\n<li>Kaya G, et al: PLoS 2006; Med 3 : e493<\/li>\n<li>Pavicic T, et al: J Drugs Dermatol 2011; 10: 990-1000.<\/li>\n<li>Ashtikar M, Nagarsekar K, Fahr A: J Control Release 2016; 242: 126-140.<\/li>\n<li>Zhai X, et al: Int J Pharm 2014; 470: 141-150.<\/li>\n<li>M\u00fcller RH, Shegokar R, Keck CM: Curr Drug Discov Technol 2011; 8: 207-227.<\/li>\n<li>Kerscher M, Buntrock H: Hautarzt 2011; 62: 607-613<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA DERMATOL\u00d3GICA 2022; 32(1): 40-41<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer pilar del antienvejecimiento en dermatolog\u00eda es la prevenci\u00f3n. La protecci\u00f3n frente a la radiaci\u00f3n UV y el uso de antioxidantes son medidas importantes para ello. En segundo lugar&hellip;<\/p>\n","protected":false},"author":7,"featured_media":116769,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Dermatolog\u00eda cosm\u00e9tica","footnotes":""},"category":[11310,11475,11478,11430,11552],"tags":[16132,14397],"powerkit_post_featured":[],"class_list":["post-326018","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-y-venereologia","category-estudios","category-formacion-continua","category-prevencion-y-asistencia-sanitaria","category-rx-es","tag-cosmeticos-es","tag-topico-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:30:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=326018"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/116769"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=326018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=326018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=326018"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=326018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}