{"id":326341,"date":"2022-03-18T01:00:00","date_gmt":"2022-03-18T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/fisiopatologia-y-clinica\/"},"modified":"2023-01-12T14:09:01","modified_gmt":"2023-01-12T13:09:01","slug":"fisiopatologia-y-clinica","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/fisiopatologia-y-clinica\/","title":{"rendered":"Fisiopatolog\u00eda y cl\u00ednica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La sobrecarga de hierro es una consecuencia inevitable y potencialmente mortal de las transfusiones m\u00faltiples de concentrados de hemat\u00edes. Como las manifestaciones cl\u00ednicas son inespec\u00edficas y suelen desarrollarse lentamente, esta complicaci\u00f3n suele pasarse por alto.<\/strong><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">La sobrecarga de hierro es una consecuencia inevitable y potencialmente mortal de las transfusiones m\u00faltiples de concentrados de hemat\u00edes. Como las manifestaciones cl\u00ednicas son inespec\u00edficas y suelen desarrollarse lentamente, esta complicaci\u00f3n suele pasarse por alto.<\/p>\n\n<p class=\"wp-block-paragraph\">En general, hoy en d\u00eda ya no se distingue entre sobrecarga de hierro primaria y secundaria porque tal definici\u00f3n depende, entre otras cosas, de la sensibilidad de los m\u00e9todos de examen. El t\u00e9rmino &#8220;siderosis&#8221; suele utilizarse para describir la deposici\u00f3n de hierro sin da\u00f1o tisular, como ocurre en la deposici\u00f3n de hierro localizada y relacionada con hemorragias (por ejemplo, la siderosis pulmonar).<\/p>\n\n<h2 id=\"aparicion-de-sobrecarga-de-hierro\" class=\"wp-block-heading\">Aparici\u00f3n de sobrecarga de hierro<\/h2>\n\n<p class=\"wp-block-paragraph\">Una dieta occidental t\u00edpica contiene unos 6 mg de hierro\/1.000 kcal, de los cuales s\u00f3lo se absorben normalmente 1-2 mg\/d\u00eda (alrededor del 10%) y un m\u00e1ximo de 3-5 mg\/d\u00eda cuando la absorci\u00f3n intestinal de hierro est\u00e1 aumentada. El almacenamiento normal de hierro es de 500-1000 mg en los hombres y de 300-400 mg en las mujeres premenop\u00e1usicas y se encuentra sobre todo en el h\u00edgado. El organismo no dispone de mecanismos fisiol\u00f3gicos activos para excretar el exceso de hierro. Los adultos sanos excretan alrededor de 1 mg de hierro\/d\u00eda a trav\u00e9s de la piel y las c\u00e9lulas gastrointestinales, las mujeres premenop\u00e1usicas pierden una media adicional de 0,5-1 mg\/d\u00eda a trav\u00e9s de la menstruaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Los niveles plasm\u00e1ticos de hierro est\u00e1n regulados por el sistema hepcidina\/ferroportina <span style=\"font-family: franklin gothic demi;\">(Fig. 1)<\/span>. La hormona pept\u00eddica hepcidina induce la degradaci\u00f3n de la prote\u00edna exportadora de hierro ferroportina. La ferroportina se expresa principalmente en las c\u00e9lulas de la mucosa duodenal, las c\u00e9lulas hep\u00e1ticas y los macr\u00f3fagos y media en la regulaci\u00f3n de la absorci\u00f3n de hierro de los alimentos, la liberaci\u00f3n de hierro del h\u00edgado seg\u00fan sea necesario y el reciclaje de hierro en los macr\u00f3fagos. Con una disponibilidad suficiente de hierro, la s\u00edntesis hep\u00e1tica de hepcidina aumenta, bloqueando una mayor absorci\u00f3n gastrointestinal de hierro. Por otro lado, la anemia cr\u00f3nica y la eritropoyesis ineficaz provocan la inhibici\u00f3n de la s\u00edntesis de hepcidina en el h\u00edgado y, por tanto, un aumento de la absorci\u00f3n de hierro en el duodeno. La hormona eritroferr\u00f3n, que se produce bajo la influencia de la eritropoyetina en los eritroblastos, tambi\u00e9n suprime la producci\u00f3n de hepcidina y estimula as\u00ed la absorci\u00f3n de hierro y la movilizaci\u00f3n a partir de las reservas en situaciones de estr\u00e9s eritropoy\u00e9tico.<\/p>\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"453\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0.png\" alt=\"\" class=\"wp-image-18607\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0-800x329.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0-120x49.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0-90x37.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0-320x132.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_oh1_s12_0-560x231.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">El almacenamiento excesivo de hierro se debe a dos mecanismos principales: El aporte iatrog\u00e9nico de hierro a trav\u00e9s de transfusiones de concentrados de gl\u00f3bulos rojos y el aumento de la ingesta de hierro a trav\u00e9s de los alimentos. Cada concentrado de hemat\u00edes contiene 220-250 mg de hierro. En pacientes adultos, la deposici\u00f3n relevante de hierro se produce despu\u00e9s de 15-20 transfusiones, en ni\u00f1os peque\u00f1os ya despu\u00e9s de m\u00e1s de 10 administraciones de concentrados de gl\u00f3bulos rojos. El aumento de la absorci\u00f3n gastrointestinal desempe\u00f1a un papel central en todas las situaciones de eritropoyesis aumentada o ineficaz. En este caso, los eritroblastos perecen por muerte celular en la m\u00e9dula \u00f3sea antes de que puedan madurar y convertirse en eritrocitos. Esto conduce a una sobreestimulaci\u00f3n e hiperplasia de la eritropoyesis, que var\u00eda en funci\u00f3n de la enfermedad subyacente. Cuanto m\u00e1s pronunciada es la alteraci\u00f3n de la eritropoyesis, m\u00e1s se incrementa la absorci\u00f3n de hierro de los alimentos <span style=\"font-family: franklin gothic demi;\">(Tab. 1)<\/span>.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"555\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0.png\" alt=\"\" class=\"wp-image-18608 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0-800x404.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0-120x61.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0-90x45.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0-320x161.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_oh1_s13_0-560x283.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/555;\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">En la hemocromatosis hereditaria, un trastorno gen\u00e9tico del metabolismo del hierro sin anemia, la deposici\u00f3n de hierro es el resultado de la desregulaci\u00f3n del eje hepcidina-ferroportina, m\u00e1s com\u00fanmente por la disminuci\u00f3n de la producci\u00f3n de hepcidina (como en la hemocromatosis hereditaria de tipo 1). M\u00e1s raramente, existe una disfunci\u00f3n de otras mol\u00e9culas reguladoras del hierro.<\/p>\n\n<p class=\"wp-block-paragraph\">Dependiendo de la enfermedad, el curso temporal y el alcance de la acumulaci\u00f3n de hierro, as\u00ed como su distribuci\u00f3n en los \u00f3rganos, difieren. Tambi\u00e9n influyen otros factores como las infecciones cr\u00f3nicas (por ejemplo, la hepatitis cr\u00f3nica) y las enfermedades metab\u00f3licas (por ejemplo, la esteatohepatitis).<\/p>\n\n<h2 id=\"efectos-del-exceso-de-hierro-en-las-celulas\" class=\"wp-block-heading\">Efectos del exceso de hierro en las c\u00e9lulas<\/h2>\n\n<p class=\"wp-block-paragraph\">La toxicidad asociada al hierro se observa principalmente en los tejidos que almacenan hierro en altas concentraciones. Se trata, en particular, del h\u00edgado, el sistema endocrino y el miocardio. El hierro de las transfusiones se deposita primero en los macr\u00f3fagos del h\u00edgado, el bazo y la m\u00e9dula \u00f3sea, despu\u00e9s en los hepatocitos y s\u00f3lo m\u00e1s tarde en los \u00f3rganos endocrinos (sobre todo en el p\u00e1ncreas) y en el m\u00fasculo cardiaco.<\/p>\n\n<p class=\"wp-block-paragraph\">El hierro circulante est\u00e1 ligado a la prote\u00edna transferrina y luego es entregado a las c\u00e9lulas por la uni\u00f3n de la transferrina a los receptores apropiados (TfR1, expresado en todas las c\u00e9lulas, y TfR2, presente en los hepatocitos). La proporci\u00f3n normal de transferrina unida al hierro es del 16-45% y se mide como saturaci\u00f3n de transferrina. En presencia de un exceso de hierro, se supera la capacidad de uni\u00f3n de la transferrina y, a niveles superiores al 70-75%, aparecen mol\u00e9culas circulantes de <em> hierro <\/em>no unido <em>(hierro no unido a la transferrina <\/em>, NTBI) que se absorben r\u00e1pidamente en las c\u00e9lulas a trav\u00e9s de v\u00edas no reguladas (por ejemplo, a trav\u00e9s de los canales de calcio en las c\u00e9lulas del miocardio). La ingesta continuada de NTBI aumenta tanto las reservas fisiol\u00f3gicas de hierro intracelular (ferritina) como la aparici\u00f3n de formas l\u00e1biles de hierro. Estos \u00faltimos catalizan reacciones bioqu\u00edmicas como la reacci\u00f3n de Fenton, produciendo radicales de ox\u00edgeno reactivos (ROS). Las consecuencias son la peroxidaci\u00f3n de las mol\u00e9culas intracelulares, especialmente los l\u00edpidos, con da\u00f1os en los org\u00e1nulos, la muerte celular, la estimulaci\u00f3n de la fibrog\u00e9nesis y, finalmente, la disfunci\u00f3n de los \u00f3rganos. Adem\u00e1s, el ADN resulta da\u00f1ado, lo que puede provocar la inestabilidad del genoma y una tendencia a la mutag\u00e9nesis <span style=\"font-family: franklin gothic demi;\">(Fig. 2) <\/span>.  <\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"693\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14.png\" alt=\"\" class=\"wp-image-18609 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14-800x504.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14-120x76.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14-90x57.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14-320x202.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_oh1_s14-560x353.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/693;\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">La deposici\u00f3n de hierro es tolerada de forma diferente por los distintos tejidos. Por ejemplo, el h\u00edgado puede almacenar mucho m\u00e1s hierro que el miocardio sin consecuencias perjudiciales. Otro factor decisivo para el desarrollo de da\u00f1os en los \u00f3rganos es la duraci\u00f3n de la exposici\u00f3n de las c\u00e9lulas al NTBI. Actualmente puede persistir durante varias d\u00e9cadas en las enfermedades cong\u00e9nitas dependientes de la transfusi\u00f3n, como la talasemia mayor, y se asocia a un mayor riesgo de neoplasias malignas.<\/p>\n\n<p class=\"wp-block-paragraph\">Un efecto subestimado de la sobrecarga de hierro es el favorecimiento del crecimiento bacteriano y el correspondiente riesgo de infecciones. La r\u00e1pida disponibilidad de hierro libre para los microorganismos, por un lado, y los efectos sobre la funci\u00f3n de los macr\u00f3fagos y los leucocitos, por otro, explican la mayor susceptibilidad a las infecciones de los pacientes con talasemia dependiente de transfusiones. Las nuevas observaciones tambi\u00e9n muestran que el exceso de hierro provoca un estr\u00e9s oxidativo en el endotelio de todos los vasos y una reducci\u00f3n de la exportaci\u00f3n de colesterol por parte de los macr\u00f3fagos de la pared vascular, lo que puede conducir a un aumento de la formaci\u00f3n de placas.<\/p>\n\n<h2 id=\"pacientes-con-riesgo-de-sobrecarga-de-hierro\" class=\"wp-block-heading\">Pacientes con riesgo de sobrecarga de hierro<\/h2>\n\n<p class=\"wp-block-paragraph\">Las situaciones cl\u00ednicas asociadas a la sobrecarga de hierro incluyen enfermedades cong\u00e9nitas y adquiridas con eritropoyesis ineficaz (por ejemplo, talasemia y s\u00edndrome mielodispl\u00e1sico), enfermedades hemol\u00edticas cr\u00f3nicas, anemia falciforme (ECF) que requiere transfusi\u00f3n y trastornos gen\u00e9ticos del metabolismo del hierro sin anemia (hemocromatosis hereditaria).<span style=\"font-family: franklin gothic demi;\">  (Tab. 2).<\/span>  Adem\u00e1s, el exceso de hierro tiene importancia pron\u00f3stica en pacientes tras un trasplante alog\u00e9nico de c\u00e9lulas madre.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"869\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15.png\" alt=\"\" class=\"wp-image-18610 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15-800x632.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15-120x95.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15-90x71.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15-320x253.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab2_oh1_s15-560x442.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/869;\" \/><\/figure>\n\n<h3 id=\"talasemia-dependiente-de-transfusion-tdt-y-no-dependiente-de-transfusion-ntdt\" class=\"wp-block-heading\">Talasemia dependiente de transfusi\u00f3n (TDT) y no dependiente de transfusi\u00f3n (NTDT)<\/h3>\n\n<p class=\"wp-block-paragraph\">Los s\u00edndromes talas\u00e9micos se encuentran entre las enfermedades gen\u00e9ticas m\u00e1s comunes en todo el mundo y est\u00e1n causados por defectos gen\u00e9ticos en el cromosoma 11<span style=\"font-family: times new roman;\">(\u03b2-talasemia<\/span>) o 16<span style=\"font-family: times new roman;\">(\u03b1-talasemia<\/span>), que conducen a una s\u00edntesis reducida o ausente de las cadenas de globina correspondientes. El enorme n\u00famero de variantes gen\u00e9ticas y sus combinaciones descritas hasta ahora, as\u00ed como el tipo de herencia, explican la gran variabilidad cl\u00ednica. Desde un punto de vista cl\u00ednico, se distingue entre talasemias dependientes de transfusi\u00f3n (TDT) y no dependientes de transfusi\u00f3n (NTDT). Esta subdivisi\u00f3n corresponde aproximadamente a la de Thalass\u00e4mia major e intermedia.<\/p>\n\n<p class=\"wp-block-paragraph\">La <span style=\"font-family: times new roman;\">\u03b2-talasemia<\/span> mayor se considera el paradigma de la TDT y de las enfermedades por sobrecarga de hierro. La caracter\u00edstica principal de la TDT es una eritropoyesis gravemente alterada o ausente, que resulta de una s\u00edntesis reducida de hemoglobina y de la precipitaci\u00f3n de un exceso de cadenas de globina<span style=\"font-family: times new roman;\">(\u03b1<\/span> o <span style=\"font-family: times new roman;\">\u03b2<\/span>). Existe una anemia grave con, por un lado, una necesidad de transfusiones de por vida desde el primer a\u00f1o de vida y, por otro, una absorci\u00f3n intestinal de hierro estimulada al m\u00e1ximo. As\u00ed pues, la ingesta masiva diaria de hierro procedente de los alimentos y la iatrog\u00e9nica, que por s\u00ed sola asciende a unos 0,4 mg\/kg de peso corporal al d\u00eda, se suman. Los s\u00edntomas cl\u00e1sicos de la sobrecarga de hierro en la TDT son la hepatopat\u00eda (fibrosis, cirrosis, carcinoma hepatocelular), la cardiopat\u00eda (especialmente la cardiopat\u00eda ritmog\u00e9nica y dilatada), las endocrinopat\u00edas (diabetes mellitus, hipotiroidismo, hipogonadismo) y la osteoporosis <span style=\"font-family: franklin gothic demi;\">(Fig. 3) <\/span>.  <\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"1048\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16.png\" alt=\"\" class=\"wp-image-18611 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16-800x762.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16-120x114.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16-90x86.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16-320x305.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb3_oh1_s16-560x534.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1048;\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Con la introducci\u00f3n de la terapia transfusional en los a\u00f1os 70, la esperanza de vida de los pacientes con TDT se alarg\u00f3 hasta la pubertad, siendo el fallo cardiaco y endocrino las causas m\u00e1s comunes de muerte. Gracias a la posibilidad de la quelaci\u00f3n del hierro, los pacientes con TDT tienen ahora una esperanza de vida de 40-50 a\u00f1os o m\u00e1s y presentan formas menos graves de cardiopat\u00edas y endocrinopat\u00edas. Sin embargo, existe un mayor riesgo de neoplasias malignas, especialmente carcinomas gastrointestinales, y un riesgo m\u00e1s de 5 veces mayor de neoplasias hematol\u00f3gicas como consecuencia a largo plazo de la toxicidad del hierro.<\/p>\n\n<p class=\"wp-block-paragraph\">En la NTDT, el aumento de la absorci\u00f3n de hierro (aprox. 0,01 mg\/kg de peso corporal al d\u00eda) es consecuencia de un gran aumento de la eritropoyesis y representa el principal mecanismo de deposici\u00f3n de hierro. Dado que la acumulaci\u00f3n de hierro en el NTDT se desarrolla lentamente, las manifestaciones cl\u00ednicas no se producen hasta la infancia tard\u00eda o incluso hasta la edad adulta temprana. Los s\u00edntomas de sobrecarga de hierro suelen ser menos pronunciados, la afectaci\u00f3n cardiaca menos frecuente y el riesgo de neoplasia menor que con la TDT. Sin embargo, los pacientes con NTDT tienen tendencia a acumular hierro en los ri\u00f1ones, lo que puede provocar una disfunci\u00f3n intersticial y glomerular. Es importante se\u00f1alar que la NTDT puede convertirse en TDT a lo largo de la vida.<\/p>\n\n<h3 id=\"anemias-congenitas-raras-con-eritropoyesis-ineficaz-y-anemias-hemoliticas-cronicas-congenitas\" class=\"wp-block-heading\">Anemias cong\u00e9nitas raras con eritropoyesis ineficaz y anemias hemol\u00edticas cr\u00f3nicas cong\u00e9nitas<\/h3>\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n en las anemias cong\u00e9nitas, como el s\u00edndrome de Diamond-Blackfan, la gravedad de la eritropoyesis ineficaz y la anemia, as\u00ed como la necesidad de transfusi\u00f3n, determinan el grado de sobrecarga de hierro. Los datos espec\u00edficos sobre estas enfermedades raras son escasos. En funci\u00f3n de la necesidad de transfusi\u00f3n, que puede ser relevante incluso en ni\u00f1os peque\u00f1os, los riesgos y las manifestaciones cl\u00ednicas de la sobrecarga de hierro son similares a los de la TDT y la NTDT.<\/p>\n\n<p class=\"wp-block-paragraph\">Las enzimopat\u00edas eritroc\u00edticas cong\u00e9nitas como la deficiencia de piruvato quinasa, las membranopat\u00edas (por ejemplo, la esferocitosis hereditaria) y los trastornos de la s\u00edntesis del hemo (por ejemplo, las porfirias) conducen a una hem\u00f3lisis cr\u00f3nica m\u00e1s o menos pronunciada y, por tanto, a una hiperplasia de la eritropoyesis. La sobrecarga de hierro puede producirse en los individuos afectados incluso sin transfusiones (hasta en el 47% de los pacientes con deficiencia de piruvato cinasa), y los s\u00edntomas correspondientes suelen aparecer en la edad adulta y s\u00f3lo en raras ocasiones en la infancia. En la esferocitosis hereditaria, que es la causa m\u00e1s com\u00fan de hem\u00f3lisis cr\u00f3nica con una prevalencia estimada de 1:2000 a 1:2500, s\u00f3lo una proporci\u00f3n de pacientes requiere transfusiones espor\u00e1dicas o regulares.<\/p>\n\n<h3 id=\"enfermedad-de-celulas-falciformes-ecf-con-necesidad-de-transfusion\" class=\"wp-block-heading\">Enfermedad de c\u00e9lulas falciformes (ECF) con necesidad de transfusi\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Las transfusiones regulares est\u00e1n indicadas en los pacientes con ECF s\u00f3lo en situaciones espec\u00edficas, como la prevenci\u00f3n de insultos cerebrovasculares en ni\u00f1os y el s\u00edndrome tor\u00e1cico agudo recurrente o las crisis vaso-oclusivas graves. En estos casos, suelen realizarse exanguinotransfusiones manuales o autom\u00e1ticas, que no se asocian a un mayor aporte de hierro relacionado con la transfusi\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Los pacientes con ECF suelen perder hierro a trav\u00e9s de la hemoglobinuria (en cantidades equivalentes a hasta 10 concentrados de hemat\u00edes al a\u00f1o) y presentan niveles plasm\u00e1ticos bajos de NTBI. Por lo tanto, la sobrecarga de hierro s\u00f3lo se desarrolla en una proporci\u00f3n relativamente peque\u00f1a de los afectados y los s\u00edntomas -especialmente la hepatopat\u00eda y la fibrosis hep\u00e1tica- aparecen cl\u00e1sicamente m\u00e1s tarde en la vida. Aunque el da\u00f1o endocrino o cardiaco es poco frecuente en pacientes con MSC, las manifestaciones cl\u00ednicas de la sobrecarga de hierro y la propia MSC son a menudo dif\u00edciles de distinguir, y el da\u00f1o org\u00e1nico relacionado con el hierro se subestima en ocasiones. Los estudios demuestran que hasta un 11% de los pacientes con ECF mueren como consecuencia de una sobrecarga de hierro. Debido a la esperanza de vida cada vez m\u00e1s larga, es de esperar que las complicaciones a largo plazo asociadas al hierro tambi\u00e9n aumenten en la ECF, al igual que en la TDT y la NTDT.<\/p>\n\n<h3 id=\"anemia-cronica-adquirida-por-insuficiencia-de-la-medula-osea\" class=\"wp-block-heading\">Anemia cr\u00f3nica adquirida por insuficiencia de la m\u00e9dula \u00f3sea<\/h3>\n\n<p class=\"wp-block-paragraph\">El s\u00edndrome mielodispl\u00e1sico (SMD) comprende un grupo de enfermedades adquiridas caracterizadas por un fallo de la m\u00e9dula \u00f3sea de diversos grados y la posibilidad de desarrollar una leucemia mieloide aguda. El SMD es una de las neoplasias hematol\u00f3gicas m\u00e1s frecuentes (incidencia de aproximadamente 4\/100.000 en Europa) y afecta sobre todo a pacientes de edad avanzada (edad media en el momento del diagn\u00f3stico: 71 a\u00f1os).<\/p>\n\n<p class=\"wp-block-paragraph\">En los SMD de bajo riesgo (IPSS bajo e intermedio-1), predominan las citopenias, con anemia debida a una eritropoyesis ineficaz en cerca del 80% de los casos. Como la mayor\u00eda de los pacientes con SMD se vuelven dependientes de las transfusiones, a menudo desarrollan una sobrecarga de hierro. Las diferencias m\u00e1s importantes con la TDT y la NTDT son la edad mucho mayor de los pacientes en el momento del diagn\u00f3stico y la elevada estabilidad gen\u00f3mica de los clones displ\u00e1sicos en la m\u00e9dula \u00f3sea. Al igual que en la TDT, las complicaciones cardiacas son frecuentes en los pacientes con SMD transfundidos regularmente (82,4% frente al 67,1% en los pacientes no transfundidos). Una importancia particular de la toxicidad del hierro en los SMD radica en el fomento de la progresi\u00f3n a leucemia aguda y en la influencia negativa sobre la supervivencia tras el trasplante alog\u00e9nico de c\u00e9lulas madre.<\/p>\n\n<h3 id=\"trasplante-alogenico-de-celulas-madre\" class=\"wp-block-heading\">Trasplante alog\u00e9nico de c\u00e9lulas madre<\/h3>\n\n<p class=\"wp-block-paragraph\">El trasplante alog\u00e9nico de c\u00e9lulas madre es un tratamiento potencialmente curativo para los pacientes con TDT, SCD y MDS y otras enfermedades con dep\u00f3sito de hierro. La influencia de la sobrecarga de hierro en el \u00e9xito del trasplante alog\u00e9nico de c\u00e9lulas madre, especialmente en la mortalidad asociada a la terapia, se describi\u00f3 por primera vez en las talasemias y ahora se reconoce cada vez m\u00e1s en otros cuadros cl\u00ednicos.<\/p>\n\n<p class=\"wp-block-paragraph\">Incluso la toxicidad de la quimioterapia puede atribuirse en parte a los efectos negativos de la sobrecarga de hierro, ya que durante el acondicionamiento se produce una movilizaci\u00f3n masiva de las reservas de hierro de la m\u00e9dula \u00f3sea con liberaci\u00f3n de NTBI. Las necesidades de transfusi\u00f3n antes y despu\u00e9s del trasplante influyen en la evoluci\u00f3n peritrasplante. Los datos muestran que el 88% de los pacientes con SMD y el 97% de los pacientes con leucemia mieloide aguda presentan niveles elevados de ferritina antes del trasplante y que el exceso de hierro se asocia a mucositis, obstrucci\u00f3n de los vasos sinusoidales hep\u00e1ticos, sepsis y, en general, a una menor supervivencia global.<\/p>\n\n<h3 id=\"trastornos-geneticos-del-metabolismo-del-hierro-sin-anemia\" class=\"wp-block-heading\">Trastornos gen\u00e9ticos del metabolismo del hierro sin anemia<\/h3>\n\n<p class=\"wp-block-paragraph\">El aumento de la absorci\u00f3n intestinal de hierro es el correlato fisiopatol\u00f3gico de las diversas formas de hemocromatosis hereditaria. La ingesta de hierro puede aumentarse hasta 4 mg diarios, es decir, de 2 a 4 veces m\u00e1s que en los individuos sin hemocromatosis hereditaria<span style=\"font-family: franklin gothic demi;\"> (Tabla 1) <\/span>.  <\/p>\n\n<p class=\"wp-block-paragraph\">En la hemocromatosis hereditaria asociada al HFE (tipo 1), una de las enfermedades gen\u00e9ticas m\u00e1s comunes en la poblaci\u00f3n europea, el hierro se deposita muy lentamente (alrededor de 1 g\/a\u00f1o) y los s\u00edntomas suelen aparecer en la edad adulta (entre los 40 y los 50 a\u00f1os en los hombres, a menudo despu\u00e9s de la menopausia en las mujeres). Las manifestaciones cl\u00ednicas m\u00e1s comunes son la hepatopat\u00eda, las artropat\u00edas y la diabetes mellitus. El momento y la gravedad de la acumulaci\u00f3n de hierro difieren en funci\u00f3n de la mutaci\u00f3n subyacente. Algunas formas raras como la hemocromatosis juvenil (tipo 2) son m\u00e1s agresivas y conducen a un almacenamiento relevante de hierro ya en la pubertad.<\/p>\n\n<p class=\"wp-block-paragraph\">Debido a su frecuencia, la hemocromatosis hereditaria, especialmente la de tipo 1, se detecta con no poca frecuencia en pacientes con talasemia, SMD o riesgos de acumulaci\u00f3n patol\u00f3gica de hierro, por lo que representa un factor adicional en el desarrollo de una sobrecarga de hierro potencialmente grave.<\/p>\n\n<h2 id=\"mensajes-para-llevarse-a-casa\" class=\"wp-block-heading\">Mensajes para llevarse a casa<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>El aumento de la absorci\u00f3n intestinal de hierro y el aporte iatrog\u00e9nico de hierro a trav\u00e9s de transfusiones de concentrados de gl\u00f3bulos rojos son los principales mecanismos de desarrollo de la sobrecarga de hierro.<\/li>\n\n\n\n<li>La acumulaci\u00f3n patol\u00f3gica de hierro se produce en enfermedades hematol\u00f3gicas cong\u00e9nitas y adquiridas con eritropoyesis ineficaz, incluso en ausencia de transfusiones regulares.<\/li>\n\n\n\n<li>La sobrecarga de hierro se desarrolla m\u00e1s r\u00e1pidamente y en mayor medida en los pacientes transfundidos regularmente que en las enfermedades no dependientes de la transfusi\u00f3n; en los trastornos gen\u00e9ticos del metabolismo del hierro (hemocromatosis hereditaria), el hierro se deposita mucho m\u00e1s lentamente en comparaci\u00f3n.<\/li>\n\n\n\n<li>En los SMD, el exceso de hierro celular puede aumentar la inestabilidad del genoma en los clones celulares preleuc\u00e9micos, favoreciendo la transformaci\u00f3n en leucemia aguda.<\/li>\n\n\n\n<li>La sobrecarga de hierro se asocia a complicaciones cl\u00ednicas y a una mayor mortalidad tras el trasplante alog\u00e9nico de c\u00e9lulas madre.<\/li>\n\n\n\n<li>La hemocromatosis hereditaria, debido a su frecuencia, puede estar presente en pacientes con otros riesgos de sobrecarga de hierro cl\u00ednicamente relevantes y puede influir en la evoluci\u00f3n cl\u00ednica.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Porter JB, et al: Nuevos conocimientos sobre la toxicidad del hierro relacionada con las transfusiones: implicaciones para el onc\u00f3logo. Crit Rev Oncolog\u00eda\/Hematolog\u00eda 2016; 99: 261-271<\/li>\n\n\n\n<li>Camaschella C, Nai A, Silvestri L: Metabolismo del hierro y trastornos del hierro revisitados en la era de la hepcidina. Haematologica 2020; 105: 260-72<\/li>\n\n\n\n<li>Porter JB, Garbowski M: La fisiopatolog\u00eda de la sobrecarga transfusional de hierro. Hematol. Oncol Clin N Am 2014; 28: 683-701.<\/li>\n\n\n\n<li>Hahalis G, et al.: Disfunci\u00f3n vasomotora global y envejecimiento vascular acelerado en la beta-talasemia mayor. Aterosclerosis 2008; 198 (2): 448-457.<\/li>\n\n\n\n<li>Gardenghi S, et al.: La eritropoyesis ineficaz en la beta-talasemia se caracteriza por una mayor absorci\u00f3n de hierro mediada por la regulaci\u00f3n a la baja de la hepcidina y la regulaci\u00f3n al alza de la ferroportina. Sangre 2007; 109(11): 5027-5035.<\/li>\n\n\n\n<li>Vento S, Cainelli F, Cesario F: Infecciones y talasemia. Lancet Infect Dis 2006; 6(4): 226-233.<\/li>\n\n\n\n<li>Porter J, Garbowski M: Consecuencias y gesti\u00f3n de la sobrecarga de hierro en la anemia falciforme. Hematolog\u00eda Am Soc Hematol Educ Program. 2013; 2013: 447-456.<\/li>\n\n\n\n<li>Roggero S, et al: Sobrecarga grave de hierro en la anemia de Blackfan-Diamond: un estudio de casos y controles. Am J Hematol. 2009; 84: 729-32.<\/li>\n\n\n\n<li>Zanella S, Garani MC, Borgna-Pignatti C: Malignidades y talasemia: una revisi\u00f3n de la literatura. Ann N Y Acad Sci 2016; 1368(1): 140-148.<\/li>\n\n\n\n<li>Gattermann N: Sobrecarga de hierro en los s\u00edndromes mielodispl\u00e1sicos (SMD). Int J Hematol 2018; 107: 55-63.<\/li>\n\n\n\n<li>Koreth J, Antin JH: Sobrecarga de hierro en neoplasias hematol\u00f3gicas y resultado del trasplante alog\u00e9nico de c\u00e9lulas madre hematopoy\u00e9ticas. Haematologica 2010; 95: 364-366.<\/li>\n\n\n\n<li>Pilling LC, et al: Afecciones comunes asociadas a las variantes gen\u00e9ticas de la hemocromatosis hereditaria: estudio de cohortes en el Biobanco del Reino Unido. BMJ 2019; 364: k5222.<\/li>\n\n\n\n<li>Leuenberger N, et al.: La hepcidina como biomarcador potencial del dopaje sangu\u00edneo. Prueba de drogas Anal 2017; 9(7): 1093-1097.<\/li>\n\n\n\n<li>Novartis: Vivir con transfusiones. www.leben-mit-transfusionen.de\/eisenueberladung\/krankheitsbild (fecha de acceso: 10.02.2022)<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\"><em>InFo ONCOLOG\u00cdA Y HEMATOLOG\u00cdA 2022; 10(1): 12-17<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sobrecarga de hierro es una consecuencia inevitable y potencialmente mortal de las transfusiones m\u00faltiples de concentrados de hemat\u00edes. Como las manifestaciones cl\u00ednicas son inespec\u00edficas y suelen desarrollarse lentamente, esta&hellip;<\/p>\n","protected":false},"author":7,"featured_media":117784,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Sobrecarga de hierro","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11352,11475,22619,11478,11358,11321,11336,11552],"tags":[11758,16729,16721,16725],"powerkit_post_featured":[],"class_list":["post-326341","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-y-diabetologia","category-estudios","category-formacion-cme","category-formacion-continua","category-gastroenterologia-y-hepatologia","category-hematologia","category-oncologia","category-rx-es","tag-formacion-cme","tag-hemocromatosis","tag-sobrecarga-de-hierro","tag-talasemia","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 17:28:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=326341"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326341\/revisions"}],"predecessor-version":[{"id":326344,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326341\/revisions\/326344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/117784"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=326341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=326341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=326341"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=326341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}