{"id":326416,"date":"2022-03-08T01:00:00","date_gmt":"2022-03-08T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/terapia-multidisciplinar-de-una-enfermedad-compleja\/"},"modified":"2022-03-08T01:00:00","modified_gmt":"2022-03-08T00:00:00","slug":"terapia-multidisciplinar-de-una-enfermedad-compleja","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/terapia-multidisciplinar-de-una-enfermedad-compleja\/","title":{"rendered":"Terapia multidisciplinar de una enfermedad compleja"},"content":{"rendered":"<p><strong>En las polineuropat\u00edas, se ven afectadas todas las partes del sistema nervioso que est\u00e1n fuera del sistema nervioso central. En la mayor\u00eda de los casos, estas deficiencias pueden atribuirse al abuso cr\u00f3nico de alcohol, a la diabetes o a enfermedades malignas. Por lo tanto, la terapia de estas causas tambi\u00e9n est\u00e1 en el centro de la gesti\u00f3n. Tambi\u00e9n pueden utilizarse analg\u00e9sicos, antidepresivos o anticonvulsivos para aliviar los s\u00edntomas.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Las polineuropat\u00edas (PNP) son enfermedades generalizadas del sistema nervioso perif\u00e9rico y, con una prevalencia del 5-8%, se dan principalmente en pacientes con abuso cr\u00f3nico de alcohol, diabetes o enfermedades malignas. Adem\u00e1s de las PNP sim\u00e9tricas distales que comienzan en las piernas y est\u00e1n causadas por un proceso de la enfermedad dependiente de la longitud axonal neuronal, pueden darse polirradiculoneuropat\u00edas con afectaci\u00f3n proximal y distal o mononeuropat\u00edas m\u00faltiples con un cuadro cl\u00ednico asim\u00e9trico. Debido al deterioro de la transmisi\u00f3n de est\u00edmulos en las fibras nerviosas da\u00f1adas o destruidas, los est\u00edmulos sensoriales no se transmiten al cerebro en absoluto, o se transmiten de forma reducida o intensificada. El resultado pueden ser molestias como hormigueo, ardor y dolor. Debido a la longitud de los nervios de las piernas y los brazos, los s\u00edntomas son especialmente notables aqu\u00ed.<\/p>\n<p>B\u00e1sicamente, se conocen m\u00e1s de 200 causas diferentes de polineuropat\u00eda. Sin embargo, la mayor\u00eda de las veces puede atribuirse a la diabetes mellitus o al alcoholismo. Sin embargo, las enfermedades infecciosas o metab\u00f3licas, la malnutrici\u00f3n (por ejemplo, la carencia de vitaminas), los efectos t\u00f3xicos o farmacol\u00f3gicos y las enfermedades hereditarias tambi\u00e9n pueden favorecer el desarrollo de lesiones nerviosas. Las neuropat\u00edas inducidas por la quimioterapia son el efecto secundario neurol\u00f3gico m\u00e1s com\u00fan de la terapia tumoral. Como las enfermedades malignas han aumentado, la incidencia tambi\u00e9n est\u00e1 aumentando aqu\u00ed. La neurotoxicidad depende de la cantidad de la dosis \u00fanica, de la dosis total acumulada y de la duraci\u00f3n de la quimioterapia.<\/p>\n<h2 id=\"las-recomendaciones-de-las-directrices-facilitan-el-diagnostico\">Las recomendaciones de las directrices facilitan el diagn\u00f3stico<\/h2>\n<p>La directriz S1 &#8220;Diagn\u00f3stico en polineuropat\u00edas&#8221; apoya la planificaci\u00f3n del diagn\u00f3stico. Adem\u00e1s de los desencadenantes conocidos, destacan aspectos como los trasplantes de \u00f3rganos, los virus de la hepatitis E y Zika, el anticuerpo anti-FGF3 y las mutaciones de los genes SCN9A, SCN10A, SCN11A (neuropat\u00edas de fibras peque\u00f1as), as\u00ed como del gen GLA (M.&nbsp;Fabry con neuropat\u00eda dolorosa). Los inhibidores de los puntos de control inmunitarios tambi\u00e9n pueden causar efectos secundarios neurol\u00f3gicos. Para el diagn\u00f3stico son obligatorios la historia cl\u00ednica, el examen cl\u00ednico, la electrofisiolog\u00eda y el laboratorio est\u00e1ndar. Adem\u00e1s, se recomienda un laboratorio ampliado, diagn\u00f3sticos de LCR, biopsias de m\u00fasculo\/nervio\/piel, gen\u00e9tica y diagn\u00f3sticos por imagen.<\/p>\n<h2 id=\"gestion-integral-del-tratamiento\">Gesti\u00f3n integral del tratamiento<\/h2>\n<p>La terapia coherente de la enfermedad subyacente debe ser la base de la gesti\u00f3n del tratamiento multimodal. Un buen control del az\u00facar en sangre o la abstinencia de alcohol pueden prevenir una mayor progresi\u00f3n del da\u00f1o nervioso. Adem\u00e1s, hay que contener los s\u00edntomas, en primer lugar el dolor. Pero los mecanismos del dolor neurop\u00e1tico son fundamentalmente diferentes de los del dolor nociceptivo. Por lo tanto, est\u00e1 indicado un concepto de terapia especial.<\/p>\n<p>El dolor polineurop\u00e1tico suele ser dif\u00edcil de controlar con analg\u00e9sicos. Las molestias ocasionales suelen responder a la terapia con \u00e1cido acetilsalic\u00edlico (AAS) o medicamentos relacionados. Si no puede conseguirse un alivio adecuado de los s\u00edntomas de esta forma, existen otros analg\u00e9sicos cuya eficacia debe probarse sistem\u00e1ticamente. En ese caso, deben utilizarse en primer lugar antidepresivos tric\u00edclicos, inhibidores de la recaptaci\u00f3n de serotonina\/norepinefrina y anticonvulsivos <span style=\"font-family:franklin gothic demi\">(tab.&nbsp;1) <\/span>.  <\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18382\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/tab1_np1_s36.png\" style=\"height:376px; width:600px\" width=\"1100\" height=\"689\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"intervenciones-sin-medicacion\">Intervenciones sin medicaci\u00f3n<\/h2>\n<p>La fisioterapia tambi\u00e9n puede ayudar a aliviar el dolor. Las diferentes aplicaciones tienen como objetivo mejorar la circulaci\u00f3n, fortalecer los m\u00fasculos debilitados y mantener la movilidad el mayor tiempo posible. Para ello se utilizan la fisioterapia, los ba\u00f1os de alternancia y movimiento, el tratamiento el\u00e9ctrico de los m\u00fasculos paralizados y las compresas calientes y fr\u00edas.<\/p>\n<p>&nbsp;<\/p>\n<p>Para saber m\u00e1s:<\/p>\n<ul>\n<li>www.neurologen-und-psychiater-im-netz.org\/neurologie\/erkrankungen\/polyneuropathie\/therapie (\u00faltima consulta: 31.01.2022)<\/li>\n<li>https:\/\/dgn.org\/wp-content\/uploads\/2012\/12\/030067_LL_Polyneuropathien_2019.pdf (\u00faltima consulta: 31.01.2022)<\/li>\n<li>Sommer C, Geber C, Young P, et al: Polineuropat\u00edas: etiolog\u00eda, diagn\u00f3stico y opciones de tratamiento. Dtsch Arztebl Int 2018; 115: 83-90. DOI: 10.3238\/arztebl.2018.008<\/li>\n<\/ul>\n<p>\n<em>InFo NEUROLOG\u00edA Y PSIQUIATR\u00cdA 2022; 20(1): 36<br \/>\nInFo PAIN &amp; GERIATry 2022; 4(1-2): 29<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las polineuropat\u00edas, se ven afectadas todas las partes del sistema nervioso que est\u00e1n fuera del sistema nervioso central. En la mayor\u00eda de los casos, estas deficiencias pueden atribuirse al&hellip;<\/p>\n","protected":false},"author":7,"featured_media":116072,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Polineuropat\u00eda","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11418,11288,11328,11398,11552],"tags":[11592,14965,16889],"powerkit_post_featured":[],"class_list":["post-326416","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-medicina-fisica-y-rehabilitacion","category-medicina-interna-general","category-neurologia","category-ortopedia","category-rx-es","tag-analgesicos","tag-dolor","tag-polineuropatia-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:20:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=326416"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/116072"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=326416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=326416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=326416"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=326416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}