{"id":326613,"date":"2022-02-15T20:00:00","date_gmt":"2022-02-15T19:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/directriz-actualizada-de-la-esc-que-permanece-igual-y-que-es-nuevo\/"},"modified":"2022-02-15T20:00:00","modified_gmt":"2022-02-15T19:00:00","slug":"directriz-actualizada-de-la-esc-que-permanece-igual-y-que-es-nuevo","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/directriz-actualizada-de-la-esc-que-permanece-igual-y-que-es-nuevo\/","title":{"rendered":"Directriz actualizada de la ESC: \u00bfQu\u00e9 permanece igual y qu\u00e9 es nuevo?"},"content":{"rendered":"<p><strong>Los s\u00edntomas de insuficiencia cardiaca son una consecuencia com\u00fan de diversos factores de riesgo cardiovascular. Por regla general, el m\u00e9dico de cabecera es la primera persona de contacto y un importante asesor terap\u00e9utico en el tratamiento posterior de la enfermedad. La directriz de la Sociedad Europea de Cardiolog\u00eda (ESC), recientemente actualizada, proporciona una base basada en la evidencia para ayudar a los pacientes con insuficiencia card\u00edaca&nbsp;<\/strong><strong>individualmente seg\u00fan el \u00faltimo estado de los conocimientos. Se han revisado varios principios terap\u00e9uticos y tambi\u00e9n hay nuevos conceptos para el tratamiento de las enfermedades concomitantes.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Las causas m\u00e1s comunes de la insuficiencia cardiaca cr\u00f3nica son la enfermedad coronaria (EC) y\/o la hipertensi\u00f3n arterial. La prevalencia aumenta con la edad y, si no se trata, los pacientes con insuficiencia cardiaca tienen un alto riesgo de mortalidad. El diagn\u00f3stico y la diferenciaci\u00f3n de otras enfermedades es un reto porque los s\u00edntomas suelen ser inespec\u00edficos. Los pacientes con disnea, tolerancia reducida al ejercicio y retenci\u00f3n de l\u00edquidos deben ser evaluados para detectar una posible insuficiencia cardiaca. Para la clasificaci\u00f3n se dispone de los criterios de la NYHA* y de la clasificaci\u00f3n seg\u00fan el Colegio Americano de Cardiolog\u00eda y la Asociaci\u00f3n Americana del Coraz\u00f3n (AHA), entre otros [1]. La categorizaci\u00f3n de la insuficiencia card\u00edaca seg\u00fan la fisiopatolog\u00eda funcional no ha cambiado significativamente en la directriz&nbsp;recientemente actualizada&nbsp;de la Sociedad Europea de Cardiolog\u00eda (ESC), que sigue bas\u00e1ndose en la fracci\u00f3n de eyecci\u00f3n del ventr\u00edculo izquierdo (FEVI) [2,3]: La HFrEF est\u00e1 presente en \u226440%, la HFmrEF en 41-49% y la HFpEF en \u226550%. Tampoco ha cambiado mucho el objetivo general del tratamiento: mejorar el estado cl\u00ednico de los pacientes, contribuyendo as\u00ed a reducir el riesgo de hospitalizaci\u00f3n y mortalidad, y mejorar la calidad de vida de los afectados.<\/p>\n<p><span style=\"font-size:12px\"><em>* NYHA = Asociaci\u00f3n Cardiaca de Nueva York<\/em><\/span><\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18318\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/02\/tab1_hp1_s26.png\" style=\"height:397px; width:600px\" width=\"1100\" height=\"728\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"hfref-algoritmo-terapeutico-simplificado-e-inclusion-de-fenotipos\">HFrEF: algoritmo terap\u00e9utico simplificado e inclusi\u00f3n de fenotipos<\/h2>\n<p>Para la insuficiencia cardiaca con fracci\u00f3n de eyecci\u00f3n reducida (IC-FEr), el r\u00e9gimen de tratamiento se ha modificado significativamente. Los autores de las directrices se han alejado del esquema de estadificaci\u00f3n convencional y han optado por una simplificaci\u00f3n del algoritmo. Los puntos clave m\u00e1s importantes de un vistazo [2,3]:<\/p>\n<p><span style=\"font-family:franklin gothic demi\">Estos cuatro f\u00e1rmacos clave son esenciales: <\/span>todo paciente con IC-FEr debe recibir un inhibidor de la ECA (IECA) o un inhibidor de la neprilisina de los receptores de angiotensina (IRA), un betabloqueante, un antagonista de los receptores de corticoides minerales&nbsp; y un inhibidor de SGLT-2 (dapagliflozina o empagliflozina). Las cuatro sustancias tienen una recomendaci\u00f3n de clase IA.<\/p>\n<p><span style=\"font-family:franklin gothic demi\">No se especifica la secuencia terap\u00e9utica: <\/span>La decisi\u00f3n sobre cu\u00e1l de las cuatro sustancias activas enumeradas debe prescribirse en primer lugar se deja en manos del m\u00e9dico. Por lo tanto, las directrices actualizadas en 2021 ya no especifican una secuencia terap\u00e9utica. Aqu\u00ed se dej\u00f3 la puerta abierta, dijo la presidenta de las directrices, la Dra. Theresa McDonagh, del King&#8217;s College Hospital de Londres (GB).<\/p>\n<p><span style=\"font-family:franklin gothic demi\">Considere el fenotipo de insuficiencia cardiaca: <\/span>El tratamiento m\u00e1s all\u00e1 de esta terapia est\u00e1ndar debe adaptarse al fenotipo particular de insuficiencia cardiaca, en funci\u00f3n de la gravedad del bloqueo de rama izquierda del haz de His (BRIHH), la etiolog\u00eda (isqu\u00e9mica o no isqu\u00e9mica), la frecuencia cardiaca y las enfermedades concomitantes.<\/p>\n<p>Otros aspectos importantes relativos al tratamiento de los pacientes con IC-FEr pueden verse en<span style=\"font-family:franklin gothic demi\">las tablas&nbsp;1 y 2 <\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-18319 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/02\/tab2_hp1_s27.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/759;height:414px; width:600px\" width=\"1100\" height=\"759\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"hfpef-algoritmo-de-diagnostico-adaptado\">HFpEF: algoritmo de diagn\u00f3stico adaptado<\/h2>\n<p>Los tres criterios esenciales del algoritmo de diagn\u00f3stico simplificado y m\u00e1s pragm\u00e1tico para los pacientes con fracci\u00f3n de eyecci\u00f3n preservada (FEFC) son los siguientes [2,3]:<\/p>\n<ol>\n<li>S\u00edntomas y signos de insuficiencia card\u00edaca<\/li>\n<li>FEVI \u226550%.<\/li>\n<li>Evidencia objetiva de anomal\u00edas cardiacas estructurales y\/o funcionales consistentes con disfunci\u00f3n diast\u00f3lica del ventr\u00edculo izquierdo y aumento de las presiones de llenado del VI, incluyendo p\u00e9ptidos natriur\u00e9ticos elevados.<\/li>\n<\/ol>\n<p>En cuanto al tratamiento de la IC-FEM, la directriz actualizada sigue al mismo nivel que hace cinco a\u00f1os: Debido a la falta de pruebas, actualmente no se recomienda ning\u00fan f\u00e1rmaco para mejorar el pron\u00f3stico. Sin embargo, las cosas se est\u00e1n moviendo y tenemos que esperar a los resultados de los estudios en curso sobre la HFpEF. En este sentido, resulta especialmente interesante el estudio EMPEROR-Preserved, que se present\u00f3 en el congreso de la ESC poco despu\u00e9s de que se publicara la directriz. Esto demuestra que la empagliflozina puede reducir eficazmente el riesgo de hospitalizaci\u00f3n relacionada con la insuficiencia cardiaca en pacientes con IC-FEM.<\/p>\n<h2 id=\"hfmref-innovacion-en-materia-de-terminologia\">HFmrEF: Innovaci\u00f3n en materia de terminolog\u00eda<\/h2>\n<p>Seg\u00fan la nueva versi\u00f3n de las directrices, la abreviatura HFmrEF ya no significa &#8220;insuficiencia cardiaca con fracci\u00f3n de eyecci\u00f3n media&#8221;, sino &#8220;insuficiencia cardiaca con fracci\u00f3n de eyecci\u00f3n ligeramente reducida&#8221; [2,3]. La raz\u00f3n aducida para este cambio fue la creciente evidencia de que los pacientes con&nbsp; HFmrEF parecen beneficiarse de los tratamientos de la HFrEF en una medida similar a la de los propios pacientes con HFrEF. Esto tambi\u00e9n se refleja en las recomendaciones terap\u00e9uticas para estos pacientes. \u00c9stas difieren poco de las de la IC-FEr, salvo que los inhibidores de SGLT-2 no figuran en absoluto y todos los dem\u00e1s agentes, aparte de los diur\u00e9ticos, s\u00f3lo figuran con una recomendaci\u00f3n de clase IIb C.<\/p>\n<h2 id=\"-4\">&nbsp;<\/h2>\n<h2 id=\"-5\"><img decoding=\"async\" class=\"size-full wp-image-18320 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/02\/tab3_hp1_s27.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/595;height:325px; width:600px\" width=\"1100\" height=\"595\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-6\">&nbsp;<\/h2>\n<h2 id=\"ademas-nuevas-recomendaciones-para-las-enfermedades-concomitantes\">Adem\u00e1s: nuevas recomendaciones para las enfermedades concomitantes<\/h2>\n<p>Existen recomendaciones de tratamiento separadas para los pacientes con IC-FEr que sufren las siguientes comorbilidades [2,3]: fibrilaci\u00f3n auricular, inestabilidad hemodin\u00e1mica, s\u00edndrome coronario cr\u00f3nico, valvulopat\u00eda. Tambi\u00e9n se han desarrollado algoritmos de tratamiento espec\u00edficos para pacientes con insuficiencia cardiaca y c\u00e1ncer, embarazo, miocarditis aguda o amiloidosis cardiaca. Una innovaci\u00f3n importante se refiere tambi\u00e9n a la recomendaci\u00f3n de un seguimiento regular para detectar una posible carencia de hierro o anemia y sus consecuencias terap\u00e9uticas**: a partir de ahora, para los pacientes sintom\u00e1ticos (FEVI  &lt;50%) con deficiencia de hierro y hospitalizaci\u00f3n reciente por insuficiencia cardiaca, se recomienda la carboximaltosa de hierro i.v. para reducir el riesgo de nuevas hospitalizaciones m\u00e1s que para mejorar la capacidad de ejercicio y la calidad de vida por s\u00ed sola.<\/p>\n<p><span style=\"font-size:12px\"><em>** Ferritina s\u00e9rica &lt;100 ng\/ml, o ferritina s\u00e9rica 100-299 ng\/ml con saturaci\u00f3n de transferrina &lt;20%.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>&#8220;Insuficiencia cardiaca cr\u00f3nica: la gu\u00eda recomienda los inhibidores de SGLT-2&#8221;, www.pharmazeutische-zeitung.de\/leitlinie-empfiehlt-sglt-2-hemmer-127991, \u00faltimo acceso 03.01.2022<\/li>\n<li>&#8220;Heart failure guideline 2021 &#8211; what&#8217;s new, what&#8217;s changed&#8221;, 29.08.2021, www.kardiologie.org\/esc-kongress-2021\/akute-herzinsuffizienz-und-lungenoedem\/neue-herzinsuffizienz-leitlinie&#8212;das-ist-neu&#8211;das-hat-sich-geae\/19609474, \u00faltimo acceso 03.01.2022.<\/li>\n<li>McDonagh TA, et al: Grupo de documentos cient\u00edficos de la ESC: Directrices de la ESC 2021 para el diagn\u00f3stico y tratamiento de la insuficiencia cardiaca aguda y cr\u00f3nica. Eur Heart J. 2021 Sep 21;42(36): 3599-3726.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2022; 17(1): 26-27<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los s\u00edntomas de insuficiencia cardiaca son una consecuencia com\u00fan de diversos factores de riesgo cardiovascular. Por regla general, el m\u00e9dico de cabecera es la primera persona de contacto y un&hellip;<\/p>\n","protected":false},"author":7,"featured_media":115660,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Insuficiencia card\u00edaca","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11324,11478,11288,11552],"tags":[17257,12198],"powerkit_post_featured":[],"class_list":["post-326613","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia","category-formacion-continua","category-medicina-interna-general","category-rx-es","tag-esc-es","tag-insuficiencia-cardiaca-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:54:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=326613"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/326613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/115660"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=326613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=326613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=326613"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=326613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}