{"id":327241,"date":"2021-12-06T01:00:00","date_gmt":"2021-12-06T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/analisis-conjunto-sobre-la-eficacia-de-secukinumab-de-cuatro-estudios-de-fase-iii\/"},"modified":"2021-12-06T01:00:00","modified_gmt":"2021-12-06T00:00:00","slug":"analisis-conjunto-sobre-la-eficacia-de-secukinumab-de-cuatro-estudios-de-fase-iii","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/analisis-conjunto-sobre-la-eficacia-de-secukinumab-de-cuatro-estudios-de-fase-iii\/","title":{"rendered":"An\u00e1lisis conjunto sobre la eficacia de secukinumab de cuatro estudios de fase III"},"content":{"rendered":"<p><strong>Se observ\u00f3 una mejora en los criterios de valoraci\u00f3n cl\u00ednicos con el tratamiento con secukinumab independientemente de la latencia desde el diagn\u00f3stico inicial de artritis psori\u00e1sica, y los pacientes diagnosticados hace menos de un a\u00f1o mostraron una respuesta ligeramente mejor que los diagnosticados hace m\u00e1s de dos a\u00f1os. En otro an\u00e1lisis post-hoc de un conjunto de datos de los mismos cuatro estudios, se demostr\u00f3 que la eficacia de secukinumab como terapia de primera l\u00ednea era superior en comparaci\u00f3n con los pacientes pretratados con anti-TNF\u03b1.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La artritis psori\u00e1sica (APs) puede progresar r\u00e1pidamente si no se trata, provocando da\u00f1os irreversibles a los dos a\u00f1os del diagn\u00f3stico inicial [1]. El inhibidor selectivo de la interleucina (IL)-17 secukinumab mostr\u00f3 una mejor\u00eda r\u00e1pida y sostenida de los s\u00edntomas en los ensayos de fase III FUTURE 1-5. La duraci\u00f3n media desde el diagn\u00f3stico de PsoA en estos estudios fue de 6-7 a\u00f1os [2\u20136]. Para comprender mejor los efectos de la intervenci\u00f3n terap\u00e9utica previa en pacientes con PsoA, se llev\u00f3 a cabo una evaluaci\u00f3n del tratamiento con secukinumab en funci\u00f3n de la duraci\u00f3n desde el diagn\u00f3stico inicial de PsoA [7]. Se analizaron los datos agrupados (n=1803) de los ensayos controlados aleatorizados FUTURE 2-5*. Los pacientes incluidos recibieron secukinumab (s.c.) 300&nbsp;mg o 150&nbsp;mg como dosis de carga, secukinumab 150&nbsp;mg sin dosis de carga o placebo. Los pacientes se dividieron en dos grupos: el grupo 1 estaba formado por pacientes a los que se hab\u00eda diagnosticado PsoA \u22641 a\u00f1o antes, y el grupo&nbsp;2 estaba formado por pacientes a los que se hab\u00eda diagnosticado PsoA &gt;2 a\u00f1os antes. La respuesta al tratamiento se evalu\u00f3 mediante los cambios en ACR20\/50\/70 y PASI75\/90\/100 despu\u00e9s de 16 semanas**. Tambi\u00e9n se registraron la calidad de vida y los par\u00e1metros de resultado de la actividad de la enfermedad.<\/p>\n<p><span style=\"font-size:11px\"><em>* FUTURE 2 (NCT01752634), FUTURE 3 (NCT01989468), FUTURE 4 (NCT02294227) y 5 (NCT02404350)<\/em><\/span><br \/>\n<em style=\"font-size:11px\">**&nbsp;Imputaci\u00f3n sin respuesta; sin correcci\u00f3n para comparaciones m\u00faltiples<\/em><\/p>\n<h2 id=\"mayor-mejoria-de-los-sintomas-con-menor-latencia-del-tratamiento\">\nMayor mejor\u00eda de los s\u00edntomas con menor latencia del tratamiento<\/h2>\n<p>En total, 419 pacientes (23,2%) ten\u00edan un primer diagn\u00f3stico de PsoA \u22641 a\u00f1o atr\u00e1s cuando iniciaron el tratamiento con secukinumab, y 1384 (76,8%) ten\u00edan una latencia de tratamiento de &gt;2 a\u00f1os [7]. Al inicio del estudio, las caracter\u00edsticas m\u00e1s relevantes de los pacientes de estos dos grupos eran comparables. En la semana 16, se observ\u00f3 que las tasas de respuesta ACR20\/50\/70 eran superiores con el tratamiento con secukinumab en comparaci\u00f3n con el placebo, independientemente de la latencia desde el diagn\u00f3stico de PsoA <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1)<\/span>, asoci\u00e1ndose el secukinumab 300&nbsp;mg con tasas de respuesta ACR superiores que el secukinumab 150&nbsp;mg. En general, las tasas de respuesta ACR fueron ligeramente superiores en los pacientes con una latencia del tratamiento \u22641 a\u00f1o, especialmente en los que recibieron secukinumab 300&nbsp;mg. El secukinumab tambi\u00e9n demostr\u00f3 ser superior al placebo en cuanto a otros par\u00e1metros de resultado como la entesitis, la dactilitis, la psoriasis cut\u00e1nea y la psoriasis ungueal. Una mayor proporci\u00f3n de pacientes con una latencia del tratamiento con secukinumab \u22641 a\u00f1o en comparaci\u00f3n con el grupo con un diagn\u00f3stico inicial de PsoA &gt;hace 2 a\u00f1os no ten\u00edan articulaciones inflamadas ni sensibles (&#8220;recuento de articulaciones inflamadas&#8221; = 0, &#8220;recuento medio de articulaciones sensibles&#8221; = 0) y una PCR \u226410&nbsp;mg\/L. Los pacientes con menor latencia de tratamiento tambi\u00e9n obtuvieron mejores resultados en cuanto a las puntuaciones parciales sobre bienestar mental en el SF-36 (&#8220;Short Form-36 of the Health Survey&#8221;). Los efectos secundarios m\u00e1s frecuentes en los pacientes tratados con secukinumab (tiempo transcurrido desde el diagn\u00f3stico \u22641 a\u00f1o o&nbsp; &gt;2 a\u00f1os) fueron nasofaringitis (8,3% y 6,1%, respectivamente), cefalea (6,2% y 3,6%, respectivamente) e infecciones de las v\u00edas respiratorias superiores (5,1% y 4,7%, respectivamente).<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-17517\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/12\/abb1_dp5_s57.png\" style=\"height:284px; width:600px\" width=\"1100\" height=\"520\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"datos-sobre-secukinumab-como-tratamiento-de-primera-linea\">Datos sobre secukinumab como tratamiento de primera l\u00ednea<\/h2>\n<p>Otro an\u00e1lisis post hoc de los datos agrupados (n=2049) de los estudios FUTURE 2-5 demostr\u00f3, en primer lugar, que la eficacia del secukinumab era superior a la del placebo en todos los dominios de manifestaci\u00f3n cl\u00ednica de la PsoA definidos por el Grupo de Investigaci\u00f3n y Evaluaci\u00f3n de la Psoriasis y la Artritis Psori\u00e1sica (GRAPPA) (artritis perif\u00e9rica, afectaci\u00f3n axial, entesitis, dactilitis, psoriasis cut\u00e1nea, afectaci\u00f3n ungueal) [8]. Por otro lado, la respuesta cl\u00ednica fue mayor en los pacientes sin tratamiento anti-TNF\u03b1 en comparaci\u00f3n con los que hab\u00edan sido tratados previamente con inhibidores del TNF\u03b1. Estos resultados son un argumento a favor del uso de secukinumab como opci\u00f3n de tratamiento de primera l\u00ednea.<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Kane D, et al: Reumatolog\u00eda (Oxford) 2003; 42: 1460-1468.<\/li>\n<li>Mease PJ, et al. RMD Open 2018; 4: e000723.<\/li>\n<li>McInnes IB, et al. Lancet 2015; 386: 1137-1146.<\/li>\n<li>Nash P, et al. Arthritis Res Ther 2018; 20: 47.<\/li>\n<li>Kivitz A, et al. Reumatol Ther 2019; 6(3): 393-407.<\/li>\n<li>Mease PJ, et al. Ann Rheum Dis 2018; 77: 890-897.<\/li>\n<li>Ritchlin C, et al: Arthritis Rheumatol 2020; 72 (suppl 10). https:\/\/acrabstracts.org\/abstract\/efficacy-of-secukinumab-treatment-in-patients-with-early-psoriatic-arthritis-a-pooled-analysis-of-4-phase-3-studies (\u00faltima consulta: 20\/09\/2021).<\/li>\n<li>Orbai AM, et al: Rheumatol Ther 2021: 1223-1240.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA DERMATOL\u00d3GICA 2021; 31(5): 57-58<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se observ\u00f3 una mejora en los criterios de valoraci\u00f3n cl\u00ednicos con el tratamiento con secukinumab independientemente de la latencia desde el diagn\u00f3stico inicial de artritis psori\u00e1sica, y los pacientes diagnosticados&hellip;<\/p>\n","protected":false},"author":7,"featured_media":112440,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Artritis psori\u00e1sica (PsoA)  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11310,11475,11478,11288,11451,11552],"tags":[13364,18293],"powerkit_post_featured":[],"class_list":["post-327241","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-y-venereologia","category-estudios","category-formacion-continua","category-medicina-interna-general","category-reumatologia","category-rx-es","tag-artritis-psoriasica","tag-psoa-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:29:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/327241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=327241"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/327241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/112440"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=327241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=327241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=327241"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=327241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}