{"id":328937,"date":"2021-05-29T01:00:00","date_gmt":"2021-05-28T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-eleccion-de-la-quimioterapia-es-crucial\/"},"modified":"2021-05-29T01:00:00","modified_gmt":"2021-05-28T23:00:00","slug":"la-eleccion-de-la-quimioterapia-es-crucial","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/la-eleccion-de-la-quimioterapia-es-crucial\/","title":{"rendered":"La elecci\u00f3n de la quimioterapia es crucial"},"content":{"rendered":"<p><strong>Los cambios inducidos por la quimioterapia en el sistema inmunitario pueden utilizarse terap\u00e9uticamente en la era de la inmuno-oncolog\u00eda. La caracterizaci\u00f3n precisa de los efectos inmunol\u00f3gicos de las distintas sustancias permite no s\u00f3lo una mejor gesti\u00f3n de los riesgos, sino tambi\u00e9n el desarrollo de nuevos enfoques terap\u00e9uticos que combinen la quimioterapia y la inmunoterapia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Hist\u00f3ricamente, los efectos inmunol\u00f3gicos de la quimioterapia han sido principalmente un riesgo del tratamiento. Dependiendo de la sustancia utilizada, se producen diversas lagunas en las defensas, lo que puede dar lugar a infecciones oportunistas con cursos graves. Sin embargo, hasta ahora no se han estudiado en detalle los efectos de muchos agentes quimioterap\u00e9uticos sobre el sistema inmunitario. En el futuro podr\u00eda merecer la pena examinarlos m\u00e1s de cerca, no s\u00f3lo para evaluar mejor los riesgos, sino tambi\u00e9n para el desarrollo selectivo de nuevos enfoques terap\u00e9uticos. Pues con la creciente prevalencia de la inmunoterapia, las consecuencias inmunol\u00f3gicas de la quimioterapia tambi\u00e9n representan potencialmente una oportunidad. Investigadores belgas han analizado ahora seis reg\u00edmenes de quimioterapia habituales para el c\u00e1ncer de ovario en relaci\u00f3n con sus efectos sobre el sistema inmunitario y han hallado diferencias sorprendentes.<\/p>\n<h2 id=\"carboplatino-paclitaxel-como-ganador-inmunologico\">Carboplatino-paclitaxel como ganador inmunol\u00f3gico<\/h2>\n<p>En el trabajo publicado recientemente, los autores compararon los efectos inmunol\u00f3gicos del carboplatino, el paclitaxel, la doxorrubicina liposomal pegilada, la gemcitabina, el carboplatino-paclitaxel y el carboplatino-gemcitabina en un modelo de rat\u00f3n. Mientras que el carboplatino-paclitaxel presentaba el perfil m\u00e1s favorable, el carboplatino-gemcitabina parec\u00eda inducir una constelaci\u00f3n inmunol\u00f3gica delet\u00e9rea. Para su evaluaci\u00f3n, los investigadores analizaron muestras de sangre, l\u00edquido peritoneal y tejido tumoral una semana despu\u00e9s de la quimioterapia. La inmunosupresi\u00f3n en el l\u00edquido peritoneal fue menor con gemcitabina, paclitaxel y carboplatino-paclitaxel, siendo la respuesta inmunitaria menos suprimida por el carboplatino-paclitaxel e incluso pudo detectarse una disminuci\u00f3n del n\u00famero de c\u00e9lulas inmunosupresoras.<\/p>\n<p>En el propio tejido tumoral, no se pudo detectar ning\u00fan cambio estad\u00edsticamente significativo en los par\u00e1metros inmunol\u00f3gicos para ninguna sustancia activa, excepto para el carboplatino-gemcitabina. Esta \u00faltima terapia provoc\u00f3 un aumento del n\u00famero de c\u00e9lulas T reguladoras con la consiguiente supresi\u00f3n de la respuesta inmunitaria. El tratamiento con carboplatino-gemcitabina tambi\u00e9n mostr\u00f3 un aumento significativo de la citocina MIP-1\u03b2, que los autores califican de desfavorable. Por otro lado, el carboplatino-paclitaxel provoc\u00f3 concentraciones s\u00e9ricas m\u00e1s elevadas de IFN\u03b3, un factor protector. Todas las monoterapias tuvieron efectos menores sobre el sistema inmunitario que el carboplatino-paclitaxel y el carboplatino-gemcitabina en el estudio <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1<\/span>).<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16181\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_oh2_s32.png\" style=\"height:391px; width:600px\" width=\"1100\" height=\"716\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"importancia-para-futuras-terapias\">Importancia para futuras terapias<\/h2>\n<p>Los autores concluyen que es poco probable que el carboplatino-gemcitabina sea adecuado para las estrategias de combinaci\u00f3n debido a la mayor supresi\u00f3n del sistema inmunitario. Atribuyen la falta de \u00e9xito hasta ahora de la inmunoterapia en el c\u00e1ncer de ovario, que se ha probado principalmente como monoterapia, entre otras cosas a la pronunciada inmunosupresi\u00f3n que conlleva esta entidad. Sin embargo, seg\u00fan los cient\u00edficos, en el futuro podr\u00eda lograrse el \u00e9xito mediante terapias combinadas adecuadas. Especialmente si fuera posible superar la inmunosupresi\u00f3n inducida por el tumor. Sin embargo, para ello es indispensable conocer bien los efectos de todas las sustancias implicadas sobre el sistema inmunitario.<\/p>\n<h2 id=\"la-perspectiva-mas-amplia\">La perspectiva m\u00e1s amplia<\/h2>\n<p>Tambi\u00e9n en otras entidades, el perfil inmunol\u00f3gico detallado de los agentes conocidos podr\u00eda contribuir de forma importante al \u00e9xito de las nuevas terapias, especialmente las combinadas. Con una comprensi\u00f3n m\u00e1s precisa de los efectos relacionados con los f\u00e1rmacos y tambi\u00e9n con las enfermedades sobre el sistema inmunitario, la importancia de los enfoques inmunoterap\u00e9uticos podr\u00eda crecer a\u00fan m\u00e1s en el futuro. Esto se debe a que los agentes quimioterap\u00e9uticos no s\u00f3lo provocan una p\u00e9rdida de c\u00e9lulas inmunitarias y, por tanto, abren brechas en el sistema de defensa del propio organismo, sino que tambi\u00e9n son capaces de reforzar la defensa del tumor mediante efectos inmunol\u00f3gicos. Por ejemplo, la presentaci\u00f3n de ant\u00edgenos suele aumentar con la quimioterapia. Otros efectos var\u00edan en funci\u00f3n de la sustancia y a menudo a\u00fan no se han aclarado de forma concluyente. As\u00ed que a\u00fan queda mucho margen para la investigaci\u00f3n precl\u00ednica, y esperemos que su traslaci\u00f3n a la pr\u00e1ctica cl\u00ednica.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente:<\/p>\n<ol>\n<li>Vankerckhoven A, et al: El tipo de quimioterapia tiene efectos sustanciales sobre el sistema inmunitario en el c\u00e1ncer de ovario. Transl Oncol. 2021; 14(6): 101076 (publicado en l\u00ednea antes de impresi\u00f3n).<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOG\u00cdA Y HEMATOLOG\u00cdA 2021; 9(2): 32<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cambios inducidos por la quimioterapia en el sistema inmunitario pueden utilizarse terap\u00e9uticamente en la era de la inmuno-oncolog\u00eda. La caracterizaci\u00f3n precisa de los efectos inmunol\u00f3gicos de las distintas sustancias&hellip;<\/p>\n","protected":false},"author":7,"featured_media":106473,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"El c\u00e1ncer de ovario y el sistema inmunitario","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11369,11336,11552],"tags":[20362,18046,12938,19293],"powerkit_post_featured":[],"class_list":["post-328937","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-ginecologia","category-oncologia","category-rx-es","tag-cancer-de-ovario","tag-carcinoma-ovarico-es","tag-quimioterapia-es","tag-sistema-inmunologico","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 20:53:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/328937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=328937"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/328937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/106473"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=328937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=328937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=328937"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=328937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}