{"id":329053,"date":"2021-05-16T14:00:00","date_gmt":"2021-05-16T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/como-se-puede-retrasar-la-progresion\/"},"modified":"2021-05-16T14:00:00","modified_gmt":"2021-05-16T12:00:00","slug":"como-se-puede-retrasar-la-progresion","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/como-se-puede-retrasar-la-progresion\/","title":{"rendered":"\u00bfC\u00f3mo se puede retrasar la progresi\u00f3n?"},"content":{"rendered":"<p><strong>Los pacientes con &#8220;deterioro cognitivo leve&#8221; (DCL) tienen un mayor riesgo de desarrollar demencia manifiesta. Las pruebas&nbsp;sobre los tratamientos farmacol\u00f3gicos que ralentizan la progresi\u00f3n del deterioro neurocognitivo son contradictorias. En t\u00e9rminos de calidad de vida y adherencia, las opciones terap\u00e9uticas con pocos efectos secundarios son ventajosas. Un enfoque de tratamiento multimodal es el m\u00e1s prometedor.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La demencia suele comenzar de forma insidiosa y a menudo es dif\u00edcil distinguirla de los trastornos neurocognitivos relacionados con la edad en las primeras fases. El s\u00edndrome de deterioro cognitivo leve (DCL) se ha conceptualizado como un s\u00edndrome prodr\u00f3mico o de riesgo de demencia [1]. Los afectados sufren trastornos de la memoria, pero las funciones cotidianas no se ven afectadas o s\u00f3lo ligeramente [2]. La clasificaci\u00f3n del DCL como s\u00edndrome cl\u00ednico ha cambiado a lo largo de los a\u00f1os<span style=\"font-family:franklin gothic demi\">(recuadro)<\/span> [1]. En aproximadamente un 5-10%, el DCL evoluciona a la enfermedad de Alzheimer u otra forma de demencia; en otros, las capacidades cognitivas permanecen estables durante mucho tiempo o mejoran de nuevo [3]. Entre el 8 y el 14% de los pacientes con DCL desarrollan demencia en el plazo de un a\u00f1o [4]. El deterioro aislado de la memoria epis\u00f3dica como s\u00edntoma principal (&#8220;DCL amn\u00e9sico&#8221;) es de pron\u00f3stico desfavorable [1].<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"4\" cellspacing=\"1\" style=\"width:500px\">\n<tbody>\n<tr>\n<td>\n<p><strong>&#8220;Deterioro cognitivo leve (DCL)<\/strong><\/p>\n<p>En el sistema de clasificaci\u00f3n CIE-11 existe la clasificaci\u00f3n diagn\u00f3stica &#8220;trastornos neurocognitivos leves&#8221; [5,11]. Seg\u00fan la directriz S3, un s\u00edndrome DCL puede diagnosticarse sobre la base del cuadro cl\u00ednico y con la inclusi\u00f3n de procedimientos de pruebas neuropsicol\u00f3gicas [1]. Los diagn\u00f3sticos neuropsicol\u00f3gicos deben incluir pruebas de rendimiento atencional y funciones ejecutivas, incluido el dominio del recuerdo retardado, ya que este \u00faltimo se considera un indicador precoz de demencia de Alzheimer incipiente [1,12]. Las pruebas cortas como el MMST, el DemTect y el TFDD no tienen suficiente sensibilidad para detectar el DCL porque pueden provocar efectos techo. Al igual que en el diagn\u00f3stico de la demencia, tambi\u00e9n son relevantes la informaci\u00f3n anamn\u00e9sica y la consideraci\u00f3n del estado general de salud del paciente, as\u00ed como su historia vital y su contexto sociocultural actual. Diferencialmente, es importante distinguir el DCL como expresi\u00f3n de una demencia neurodegenerativa incipiente de otras posibles causas como las lesiones vasculares, los episodios depresivos, los efectos secundarios de la medicaci\u00f3n y el abuso del alcohol [1].<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h2 id=\"terapia-farmacologica-para-el-dcl-se-necesitan-mas-estudios\">Terapia farmacol\u00f3gica para el DCL: se necesitan m\u00e1s estudios<\/h2>\n<p>Reducir los factores de riesgo vasculares, metab\u00f3licos, t\u00f3xicos y psicol\u00f3gicos es un objetivo terap\u00e9utico importante en el DCL, pero las pruebas son inconsistentes en cuanto a las opciones de tratamiento farmacol\u00f3gico. Seg\u00fan los estudios realizados hasta la fecha, no existe ning\u00fan tratamiento farmacol\u00f3gico que haya demostrado claramente ser una intervenci\u00f3n modificadora de la enfermedad en el DCL [5]. Una revisi\u00f3n publicada en 2020 por Kasper et al. concluye que faltan recomendaciones para el tratamiento del DCL y que las directrices internacionales deber\u00edan hacer m\u00e1s hincapi\u00e9 en el tratamiento del DCL basado en pruebas [5]. Teniendo en cuenta la naturaleza multifactorial de la enfermedad, una intervenci\u00f3n &#8220;multiobjetivo&#8221; parece ser m\u00e1s eficaz que centrarse en un \u00fanico objetivo. Un enfoque de tratamiento multimodal, que incluya intervenciones en el estilo de vida -incluyendo dieta, ejercicio, actividades sociales y entrenamiento mental- adem\u00e1s de la terapia farmacol\u00f3gica sintom\u00e1tica, parece ser el m\u00e1s prometedor. En una actualizaci\u00f3n sobre el tratamiento del DCL, la Academia Americana de Neurolog\u00eda ha incluido la recomendaci\u00f3n de hacer ejercicio regularmente (al menos dos veces por semana) en sus directrices [14]. Los estudios han demostrado que los pacientes con DCL tambi\u00e9n pueden beneficiarse de las intervenciones psicoterap\u00e9uticas, incluidos los enfoques de terapia cognitivo-conductual para aliviar el deterioro cognitivo leve y los s\u00edntomas depresivos [6]. En cuanto a las opciones de tratamiento farmacol\u00f3gico sintom\u00e1tico, es importante tener en cuenta tambi\u00e9n el factor de la calidad de vida y aconsejar opciones de tratamiento con pocos efectos secundarios.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-16118\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/abb1_hp4-s32.png\" style=\"height:233px; width:600px\" width=\"1100\" height=\"427\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"inhibidores-de-la-acetilcolinesterasa-base-de-pruebas-inconsistente\">Inhibidores de la acetilcolinesterasa: base de pruebas inconsistente<\/h2>\n<p>En un an\u00e1lisis secundario, Matsunaga et al. la eficacia y la tolerabilidad de los inhibidores de la acetilcolinesterasa en pacientes con deterioro cognitivo leve (DCL) [7,8]. El metaan\u00e1lisis incluy\u00f3 14 ensayos controlados aleatorios doble ciego (6 con donepezilo, 4 con galantamina, 4 con rivastigmina) con un total de 5278 pacientes. La edad media era de 70,3 a\u00f1os y la duraci\u00f3n media del estudio de 67,9 semanas. En general, no se pudo demostrar ning\u00fan efecto significativo de los inhibidores de la acetilcolinesterasa sobre el criterio de valoraci\u00f3n primario &#8220;funci\u00f3n cognitiva en pacientes con DCL&#8221;. Sin embargo, en los an\u00e1lisis de subgrupos de los agentes individuales, se pudo demostrar un efecto muy peque\u00f1o del donepezilo sobre la funci\u00f3n cognitiva en pacientes con DCL. En cuanto a los criterios de valoraci\u00f3n secundarios, el tratamiento con inhibidores de la acetilcolinesterasa dio lugar a una conversi\u00f3n menos frecuente a un s\u00edndrome de demencia que el placebo (cociente de riesgos [RR]: 0,76; n\u00famero necesario a tratar [NNT]: 20), pero seg\u00fan los an\u00e1lisis de subgrupos s\u00f3lo la galantamina tuvo este peque\u00f1o efecto (RR: 0,68; NNT: 17). En general, no hubo ning\u00fan efecto de los inhibidores de la acetilcolinesterasa sobre la impresi\u00f3n cl\u00ednica general (puntuaciones CGI). Seg\u00fan los an\u00e1lisis de subgrupos, s\u00f3lo la rivastigmina tuvo un peque\u00f1o efecto al respecto.<\/p>\n<p>En cuanto a la tolerabilidad, los inhibidores de la acetilcolinesterasa dieron lugar a interrupciones del tratamiento m\u00e1s frecuentes en general (RR: 1,25; N\u00famero necesario para da\u00f1ar [NNH]: 11) y a interrupciones del tratamiento debidas a efectos secundarios (RR: 2,14; NND: 11). Adem\u00e1s, los efectos secundarios fueron m\u00e1s frecuentes con los inhibidores de la acetilcolinesterasa (RR: 1,10, NNT: 13). En los an\u00e1lisis de subgrupos, esto fue especialmente cierto en el caso del donezepil y la galantamina.<\/p>\n<p>Un estudio publicado tambi\u00e9n en 2019, que analiz\u00f3 los datos de 2242 pacientes con diagn\u00f3stico de DCL y enfermedad de Alzheimer leve, concluy\u00f3 que el uso de inhibidores de la acetilcolinesterasa (ACh-i) no mejora el curso de estas enfermedades [9]. El 34% de los 944 pacientes de&nbsp;con DCL de tipo Alzheimer y el 72% de los 1298 pacientes con una forma leve de la enfermedad de Alzheimer fueron tratados con ACh-i. Las evaluaciones mostraron que el deterioro cognitivo era m\u00e1s pronunciado tras iniciar la terapia ACh-i. Esto fue as\u00ed tanto para los pacientes tratados con ACh-i con DCL de tipo Alzheimer como para los que padec\u00edan una forma leve de<span style=\"color:rgb(128, 128, 128)\"> la enfermedad<\/span> de Alzheimer, en comparaci\u00f3n con los pacientes que no recibieron ACh-i.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-16119 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2021\/05\/ubersicht1_hp4_s33.png\" style=\"--smush-placeholder-width: 714px; --smush-placeholder-aspect-ratio: 714\/997;height:559px; width:400px\" width=\"714\" height=\"997\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>En general, se espera que en el futuro se desarrollen y eval\u00faen en ensayos m\u00e1s opciones de tratamiento sintom\u00e1tico y causal para el DCL. Las opciones actuales de tratamiento farmacol\u00f3gico para el DCL incluyen el extracto especial de ginkgo EGb 761\u00ae <span style=\"font-family:franklin gothic demi\">(revisi\u00f3n 1)<\/span> para el tratamiento sintom\u00e1tico del deterioro cognitivo y los s\u00edntomas neuropsiqui\u00e1tricos asociados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>DGPPN\/DGN: S3-Leitlinie &#8220;Demenzen&#8221;, 2016, versi\u00f3n larga. www.dgppn.de<\/li>\n<li>McDade EM, Petersen RC: Deterioro cognitivo leve: epidemiolog\u00eda, patolog\u00eda y evaluaci\u00f3n cl\u00ednica. UpToDate 10\/2015.<\/li>\n<li>Huber F, Beise U: Demencia. \u00daltima revisi\u00f3n: 03\/2017. www.medix.ch\/wissen\/guidelines\/psychische-krankheiten\/demenz (\u00faltima llamada 23.03.2021)<\/li>\n<li>Mosimann UP, Annoni J-M: Demencia: diagn\u00f3stico precoz de los trastornos cognitivos. Sociedad Neurol\u00f3gica Suiza (SNS), 01.11.10, www.swissneuro.ch (\u00faltima consulta: 23.03.2021)<\/li>\n<li>Kasper S, et al: Gesti\u00f3n del deterioro cognitivo leve (DCL): Necesidad de directrices nacionales e internacionales. Revista Mundial de Psiquiatr\u00eda Biol\u00f3gica 2020; 21 (8): 579-594.<\/li>\n<li>Simon SS, Cordas TA, Bottino CM: Terapias cognitivas en adultos mayores con depresi\u00f3n y d\u00e9ficits cognitivos: una revisi\u00f3n sistem\u00e1tica. Int J Geriatr Psychiatry 2015; 30(3): 223-233.<\/li>\n<li>Matsunaga S, Fujishiro H, Takechi H: Eficacia y seguridad de los inhibidores de la colinesterasa para el deterioro cognitivo leve:revisi\u00f3n sistem\u00e1tica y metaan\u00e1lisis. J Alzheimers Dis 2019; 71(2): 513-523.<\/li>\n<li>Geschke K: Poco efecto con claros efectos secundarios. Neurolog\u00eda y Psiquiatr\u00eda 2019 (21): 14.<\/li>\n<li>Han J-Y, et al: Los inhibidores de la colinesterasa podr\u00edan no ser beneficiosos para el deterioro cognitivo leve y la demencia leve de la enfermedad de Alzheimer. Alzheimer Dis Assoc Disord 2019; 33(2): 87-94.<\/li>\n<li>IQWiG (ed.): Ginkgohaltige Pr\u00e4parate bei Alzheimer Demenz. Informe final A05-19B (versi\u00f3n 1.0, a 29.9.2008). Colonia, IQWiG 2008.<\/li>\n<li>Organizaci\u00f3n Mundial de la Salud (OMS): CIE-11, Clasificaci\u00f3n Internacional de Enfermedades<sup>11\u00aa<\/sup> Revisi\u00f3n,&nbsp;https:\/\/icd.who.int\/en (\u00faltima consulta 23.03.2021)<\/li>\n<li>Bondi MW, et al: Contribuciones neuropsicol\u00f3gicas a la identificaci\u00f3n precoz de la enfermedad de Alzheimer. Neuropsychol Rev 2008; 18: 73-90.<\/li>\n<li>Cooperaci\u00f3n en Asistencia M\u00e9dica (McCare): Educaci\u00f3n: DCL y demencia, www.mccare.com\/education\/mcidementia.html (\u00faltima consulta: 23.03.2021)<\/li>\n<li>Petersen RC, et al: Resumen de la actualizaci\u00f3n de las directrices pr\u00e1cticas. Academia Americana de Neurolog\u00eda 2018; 90 (3): Art\u00edculo especial, https:\/\/n.neurology.org\/content\/90\/3\/126 (\u00faltima consulta: 24.03.2021).<\/li>\n<\/ol>\n<p>\n<em>PR\u00c1CTICA GP 2021; 16(4): 32-33<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pacientes con &#8220;deterioro cognitivo leve&#8221; (DCL) tienen un mayor riesgo de desarrollar demencia manifiesta. Las pruebas&nbsp;sobre los tratamientos farmacol\u00f3gicos que ralentizan la progresi\u00f3n del deterioro neurocognitivo son contradictorias. En&hellip;<\/p>\n","protected":false},"author":7,"featured_media":106134,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"\"Deterioro cognitivo leve (DCL)","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11475,11478,11316,11288,11328,11435,11552],"tags":[12113,19342],"powerkit_post_featured":[],"class_list":["post-329053","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estudios","category-formacion-continua","category-geriatria","category-medicina-interna-general","category-neurologia","category-psiquiatria-y-psicoterapia","category-rx-es","tag-demencia","tag-mci-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:30:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/329053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=329053"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/329053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/106134"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=329053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=329053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=329053"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=329053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}