{"id":329831,"date":"2021-03-09T01:00:00","date_gmt":"2021-03-09T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/analisis-funcional-exhaustivo-del-sistema-nervioso-somatosensorial\/"},"modified":"2023-01-12T14:10:10","modified_gmt":"2023-01-12T13:10:10","slug":"analisis-funcional-exhaustivo-del-sistema-nervioso-somatosensorial","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/analisis-funcional-exhaustivo-del-sistema-nervioso-somatosensorial\/","title":{"rendered":"An\u00e1lisis funcional exhaustivo del sistema nervioso somatosensorial"},"content":{"rendered":"\n<p><strong>El dolor es uno de los s\u00edntomas m\u00e1s dif\u00edciles de detectar. Muchos otros signos de la enfermedad, como los s\u00edntomas cut\u00e1neos o la par\u00e1lisis, son visibles, palpables y, por tanto, objetivables. Al evaluar el dolor, en cambio, dependemos por completo de la descripci\u00f3n de la persona afectada, el s\u00edntoma siempre sigue siendo subjetivo.<\/strong><\/p>\n\n<!--more-->\n\n<p>El dolor es uno de los s\u00edntomas m\u00e1s dif\u00edciles de detectar. Muchos otros signos de la enfermedad, como los s\u00edntomas cut\u00e1neos o la par\u00e1lisis, son visibles, palpables y, por tanto, objetivables. Al evaluar el dolor, en cambio, dependemos por completo de la descripci\u00f3n de la persona afectada, el s\u00edntoma siempre sigue siendo subjetivo.<\/p>\n\n<h2 id=\"definicion\" class=\"wp-block-heading\">Definici\u00f3n<\/h2>\n\n<p>El dolor neurop\u00e1tico se define como &#8220;el dolor que se produce como resultado directo de un da\u00f1o o lesi\u00f3n en el sistema somatosensorial&#8221; [1,2]. Esta definici\u00f3n presupone la prueba de dicho da\u00f1o como condici\u00f3n ineludible para el diagn\u00f3stico de &#8220;dolor neurop\u00e1tico&#8221;. En otras palabras, la informaci\u00f3n proporcionada por el paciente no es suficiente para establecer el diagn\u00f3stico como confirmado. En funci\u00f3n de la evidencia de dicho da\u00f1o, la clasificaci\u00f3n se realiza en dolor neurop\u00e1tico definitivo, probable, posible e improbable [3]<span style=\"font-family: franklin gothic demi;\"> (Fig. 1)<\/span>. Los da\u00f1os relevantes en el sistema somatosensorial pueden detectarse mediante procedimientos de examen especiales, incluida la prueba sensorial cuantitativa (QST).<\/p>\n\n<h2 id=\"\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"877\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7.png\" alt=\"\" class=\"wp-image-14168\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7-800x638.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7-120x96.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7-90x72.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7-320x255.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s7-560x446.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/figure>\n\n<h2 id=\"antecedentes\" class=\"wp-block-heading\">Antecedentes<\/h2>\n\n<p>El examen QST es una extensi\u00f3n estandarizada de las pruebas de sensibilidad neurol\u00f3gica y permite un an\u00e1lisis exhaustivo de la funci\u00f3n del sistema nervioso somatosensorial [4]. Se lleva a cabo seg\u00fan el protocolo de la Red Alemana de Investigaci\u00f3n del Dolor Neurop\u00e1tico (DFNS). La QST complementa otros m\u00e9todos de medici\u00f3n neurol\u00f3gica y electrofisiol\u00f3gica existentes, como la neurograf\u00eda. Mientras que este \u00faltimo examina la funci\u00f3n de las fibras nerviosas m\u00e1s gruesas, el QST tambi\u00e9n registra la funci\u00f3n de las fibras nerviosas finas, poco o nada mielinizadas. Sabemos por estudios post mortem que la proporci\u00f3n de fibras nerviosas de peque\u00f1o calibre en el sistema nervioso perif\u00e9rico es de aproximadamente el 80% [5,6].<\/p>\n\n<h2 id=\"nervios-finos-gran-efecto\" class=\"wp-block-heading\">Nervios finos &#8211; gran efecto<\/h2>\n\n<p>Las finas fibras nerviosas desempe\u00f1an un papel especialmente importante en las enfermedades que se asocian a una disminuci\u00f3n de la sensaci\u00f3n de calor, fr\u00edo o tacto, as\u00ed como en el dolor. Las terminaciones nerviosas libres est\u00e1n situadas en la zona de la piel, reciben est\u00edmulos y los convierten en potenciales el\u00e9ctricos [7]. Las lesiones en el sistema nervioso perif\u00e9rico o central suelen ir acompa\u00f1adas de un aumento de la sensibilidad cut\u00e1nea al dolor, &#8220;s\u00edntomas positivos&#8221; (signos positivos: hiperalgesia y alodinia), y\/o de una disminuci\u00f3n de la percepci\u00f3n, &#8220;s\u00edntomas negativos&#8221; (signos negativos: hipoestesia, hipalgesia). Las parestesias inespec\u00edficas con\/sin dolor pueden manifestarse como s\u00edntomas iniciales de una enfermedad sist\u00e9mica a\u00fan latente en la qu\u00edmica de laboratorio, como la diabetes mellitus. Estos s\u00edntomas caracterizan los mecanismos neurobiol\u00f3gicos implicados en el desarrollo del dolor neurop\u00e1tico. La QST permite registrar el estado funcional de todos los sistemas de fibras aferentes primarias que forman el sistema somatosensorial [8]. Entre ellas se encuentran las fibras nerviosas A\u03b2, que est\u00e1n espesamente mielinizadas, tienen un gran di\u00e1metro y conducen r\u00e1pidamente los est\u00edmulos (propiocepci\u00f3n, tacto ligero) a trav\u00e9s de los tractos cordales posteriores y el sistema lemniscal hasta el t\u00e1lamo. Las fibras A\u03b4 finamente mielinizadas y las fibras C no mielinizadas conducen lentamente los est\u00edmulos nociceptivos y t\u00e9rmicos al t\u00e1lamo a trav\u00e9s de los cordones anteriores y el tracto espinotal\u00e1mico. Mientras que las fibras A\u03b4 son responsables del primer dolor, que es brillante, agudo y f\u00e1cilmente localizable, las fibras C son responsables del segundo dolor, que es duradero [9].<\/p>\n\n<h2 id=\"un-procedimiento-normalizado\" class=\"wp-block-heading\">Un procedimiento normalizado<\/h2>\n\n<p>Como ya se ha mencionado, el examen QST se realiza seg\u00fan el protocolo estandarizado de la Red Alemana de Investigaci\u00f3n del Dolor Neurop\u00e1tico (DFNS) [4]. La validez, la fiabilidad (test-retest y fiabilidad interobservador) y las posibilidades de aseguramiento de la calidad del m\u00e9todo de medici\u00f3n se evaluaron en el marco de estudios multic\u00e9ntricos tanto en pacientes como en sujetos sanos y se cre\u00f3 una base de datos de valores normativos [10,11]. Existen valores normales relacionados con la edad y el sexo para la mano, el pie, la cara y la espalda [10,12]. Para validar el m\u00e9todo QST, se estableci\u00f3 una estaci\u00f3n de medici\u00f3n en la que se examinan todos los par\u00e1metros QST. Esta estaci\u00f3n de medici\u00f3n se utiliza en los cursos de formaci\u00f3n QST para entrenar la aplicaci\u00f3n exacta de los est\u00edmulos QST y contribuye al aseguramiento de la calidad.<\/p>\n\n<h2 id=\"principio-de-funcionamiento\" class=\"wp-block-heading\">Principio de funcionamiento<\/h2>\n\n<p>La bater\u00eda QST normalizada del DFNS consta de 7 pruebas individuales en las que se registran un total de 13 par\u00e1metros. Las pruebas se realizan exclusivamente sobre la piel y se examinan una zona de prueba y una zona de control con imagen especular, de modo que en una hora se puede establecer un perfil sensorial completo [4]. Se aplican est\u00edmulos calibrados en la piel para determinar los umbrales de percepci\u00f3n, dolor o tolerancia al dolor. Esto permite un registro completo de la funci\u00f3n de todas las submodalidades somatosensoriales nociceptivas y no nociceptivas (signo m\u00e1s &#8211; aumento de la funci\u00f3n [Hyperalgesie] o signo menos &#8211; [p\u00e9rdida de funci\u00f3n, hipoestesia]). Existen instrucciones precisas para el investigador con una redacci\u00f3n estandarizada. Siempre se aplican los mismos est\u00edmulos calibrados de prueba t\u00e9rmica y mec\u00e1nica en la misma secuencia de prueba, empezando por la prueba t\u00e9rmica [4,13,14].<\/p>\n\n<h2 id=\"pruebas-termicas\" class=\"wp-block-heading\">Pruebas t\u00e9rmicas<\/h2>\n\n<p>Las pruebas t\u00e9rmicas examinan la funcionalidad de las delgadas fibras A\u03b4 poco mielinizadas y de las fibras C no mielinizadas, as\u00ed como sus sistemas de v\u00edas. Se lleva a cabo mediante un comprobador t\u00e9rmico asistido por ordenador (como ejemplo Thermal Sensory Analyser II [TSA],  <span style=\"font-family: franklin gothic demi;\">Fig. 2).<\/span>  Con la ayuda de un termodo (elemento Peltier), se aplican est\u00edmulos t\u00e9rmicos controlados por ordenador en la zona correspondiente de la piel y las mucosas, comenzando con una temperatura b\u00e1sica de 32 \u00b0C y aumentando lentamente con intervalos de est\u00edmulo de 1 \u00b0C. Se determinan los umbrales sensoriales para la sensaci\u00f3n de fr\u00edo (CDT), la sensaci\u00f3n de calor (WDT), el dolor inducido por el fr\u00edo (CPT), el dolor inducido por el calor (HPT), as\u00ed como el umbral de diferencia t\u00e9rmica (TSL) y si los est\u00edmulos fr\u00edos se perciben como calientes (sensaci\u00f3n parad\u00f3jica de calor, PHS) [4].<\/p>\n\n<h2 id=\"-2\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"817\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8.jpg\" alt=\"\" class=\"wp-image-14169 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8-800x594.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8-120x90.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8-90x68.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8-320x238.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb1_sg1_s8-560x416.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/817;\" \/><\/figure>\n\n<h2 id=\"-3\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"pruebas-mecanicas\" class=\"wp-block-heading\">Pruebas mec\u00e1nicas<\/h2>\n\n<p>Las pruebas mec\u00e1nicas constan de varias pruebas individuales, que se llevan a cabo de la siguiente manera.<\/p>\n\n<p><strong>Umbral de detecci\u00f3n mec\u00e1nica (MDT, mechanical detection threshold-old): <\/strong>Esto se hace con un conjunto de filamentos de fibra de vidrio normalizados de diferentes di\u00e1metros y longitudes variables (filamentos von Frey) <span style=\"font-family: franklin gothic demi;\">(Fig. 3A<\/span> ). Los filamentos se colocan siempre de la misma manera hasta que el filamento se dobla en forma de s para garantizar una prueba exacta. Esto activa los mecanorreceptores de bajo umbral que median la percepci\u00f3n del tacto a trav\u00e9s de las fibras A\u03b2 [4,14].<\/p>\n\n<p><strong>Umbral de dolor mec\u00e1nico (MPT): <\/strong>Para ello se utilizan estimuladores de aguja (PinPrick)<span style=\"font-family: franklin gothic demi;\"> (Fig. 3B<\/span> ). Se trata de agujas romas con una intensidad de estimulaci\u00f3n fija y una superficie de contacto con la piel circular. Esto activa principalmente los A\u03b4-nociceptores. La piel no se da\u00f1a en el proceso [4].<\/p>\n\n<p><strong>Funciones est\u00edmulo-respuesta: <\/strong>Las funciones est\u00edmulo-respuesta se utilizan para determinar la sensibilidad mec\u00e1nica al dolor (SMP) y detectar cualquier alodinia mec\u00e1nica din\u00e1mica (AMD). Se utiliza un set compuesto por los estimuladores de aguja mencionados anteriormente, un bastoncillo de algod\u00f3n, un cepillo suave y algod\u00f3n <span style=\"font-family: franklin gothic demi;\">(Fig. 3C<\/span> ) [4].<\/p>\n\n<p><strong>Fen\u00f3meno de enrollamiento (WUR, wind up ratio):<\/strong> Para ello se utilizan los estimuladores de aguja. En la zona de prueba, se compara la sensibilidad de la piel a un \u00fanico est\u00edmulo con la sensibilidad a una serie de est\u00edmulos. El cociente wind-up se calcula a partir de la relaci\u00f3n entre la intensidad del dolor (en la escala anal\u00f3gica num\u00e9rica: &#8220;0&#8221; ning\u00fan dolor, &#8220;100&#8221; m\u00e1ximo dolor imaginable) a lo largo de la serie de est\u00edmulos dividida por la intensidad del dolor tras los est\u00edmulos individuales [4]. El wind-up representa un fen\u00f3meno de sumaci\u00f3n temporal en la m\u00e9dula espinal que se produce espec\u00edficamente en las neuronas de amplio rango din\u00e1mico (WDR) cuando sus entradas de fibra C se estimulan m\u00e1s de una vez en 3 segundos [14]. La presencia de un RWU es siempre patol\u00f3gica e indica un aumento persistente del dolor.<\/p>\n\n<p><strong>Umbral de detecci\u00f3n de vibraciones (VDT): <\/strong>Esto se determina mediante un diapas\u00f3n calibrado (Rydel-Seiffer-Vibrationsgabel\u00ae) como en el examen neurol\u00f3gico <span style=\"font-family: franklin gothic demi;\">(Fig. 3C) <\/span>. Esta es la \u00fanica prueba dentro de la bater\u00eda QST en la que se determina un &#8220;umbral de desaparici\u00f3n&#8221; [4,14]. Est\u00e1 mediada a trav\u00e9s de las fibras A\u03b2.<\/p>\n\n<p><strong>Umbral de dolor a la presi\u00f3n (PPT, pressure pain thres-h-old): <\/strong>Aqu\u00ed se determina la transici\u00f3n de la percepci\u00f3n de la calidad de la presi\u00f3n a una impresi\u00f3n sensorial dolorosa [4]. Para ello se utiliza un alg\u00f3metro de presi\u00f3n <span style=\"font-family: franklin gothic demi;\">(Fig. 3D)<\/span>.<\/p>\n\n<h2 id=\"-4\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"-5\" class=\"wp-block-heading\"><img decoding=\"async\" class=\"size-full wp-image-14170 lazyload\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/770;height: 420px; width: 600px;\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0.jpg\" alt=\"\" width=\"1100\" height=\"770\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0-800x560.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0-120x84.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0-90x63.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0-320x224.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb3_sg1_s9_0-560x392.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/h2>\n\n<h2 id=\"-6\" class=\"wp-block-heading\">\u00a0<\/h2>\n\n<h2 id=\"evaluacion-de-datos\" class=\"wp-block-heading\">Evaluaci\u00f3n de datos<\/h2>\n\n<p>Los par\u00e1metros QST recogidos, antes de ser transformados en una distribuci\u00f3n normal, se transforman logar\u00edtmicamente, se tabulan y se representan gr\u00e1ficamente. Los valores se comparan con los de un colectivo normativo espec\u00edfico de edad y sexo para la evaluaci\u00f3n de cambios patol\u00f3gicos. Los valores fuera del intervalo de confianza del 95% (\u00b1 1,96) se consideran patol\u00f3gicos [14]. Los par\u00e1metros no nociceptivos son CDT, WDT, TSL, MDT, VDT [15].<\/p>\n\n<h2 id=\"parametros-qst\" class=\"wp-block-heading\">Par\u00e1metros QST<\/h2>\n\n<p>Rolke et al. pudieron demostrar en un estudio que la comparaci\u00f3n intraindividual de los par\u00e1metros QST del lado derecho e izquierdo del cuerpo muestra una alta correlaci\u00f3n y, por tanto, no hay diferencias entre ambos lados del cuerpo en individuos sanos [16]. La dependencia de la edad y la especificidad de g\u00e9nero de los valores de QST se han demostrado en varios estudios. Entre otras cosas, se produce un aumento de la percepci\u00f3n y de los umbrales del dolor con la edad [16,17].<\/p>\n\n<h2 id=\"qst-fortalezas-y-debilidades\" class=\"wp-block-heading\">QST &#8211; Fortalezas y debilidades<\/h2>\n\n<p>La QST es un procedimiento psicof\u00edsico y, por lo tanto, depende siempre de la cooperaci\u00f3n activa del paciente. La experiencia del examinador y los resultados tambi\u00e9n desempe\u00f1an un papel crucial. La QST no es un sustituto del examen cl\u00ednico y no se puede hacer un diagn\u00f3stico s\u00f3lo con la QST. Uno de los puntos fuertes del QST es que se trata de un examen no invasivo y sin efectos secundarios. En comparaci\u00f3n con otros m\u00e9todos para examinar la funci\u00f3n de las fibras nerviosas de peque\u00f1o calibre, con la QST no s\u00f3lo se pueden registrar los signos negativos, sino tambi\u00e9n los positivos.<\/p>\n\n<p>El QST no permite la localizaci\u00f3n en altitud ni la asignaci\u00f3n etiol\u00f3gica de una lesi\u00f3n [4,18,19]. Un hallazgo de QST puede ser normal a pesar de una reducci\u00f3n demostrada de la densidad de las fibras nerviosas intraepid\u00e9rmicas en la biopsia cut\u00e1nea [18].<\/p>\n\n<p>Los datos sobre la sensibilidad y especificidad diagn\u00f3sticas en el diagn\u00f3stico de la neuropat\u00eda de fibras peque\u00f1as son controvertidos [20]. En este caso, a veces se da preferencia a procedimientos m\u00e1s objetivos como el examen morfom\u00e9trico de la piel (biopsia cut\u00e1nea para determinar la densidad de fibras nerviosas intraepid\u00e9rmicas) y la inervaci\u00f3n corneal (microscop\u00eda confocal corneal, entre otros, para determinar la densidad de fibras nerviosas corneales). Ambos m\u00e9todos se centran en la morfolog\u00eda de las fibras nerviosas de peque\u00f1o calibre, por lo que los m\u00e9todos se complementan. Debe tenerse en cuenta que un hallazgo normal tanto en la QST como en la biopsia cut\u00e1nea no excluye el dolor neurop\u00e1tico ni la afecci\u00f3n de fibras peque\u00f1as, como tampoco prueba ninguno de los dos [19]. Los resultados deben valorarse siempre en el contexto global de la historia cl\u00ednica y el examen cl\u00ednico.<\/p>\n\n<h2 id=\"del-sintoma-al-mecanismo\" class=\"wp-block-heading\">Del s\u00edntoma al mecanismo<\/h2>\n\n<p>Los cambios fisiopatol\u00f3gicos que subyacen al desarrollo del dolor neurop\u00e1tico suelen producirse independientemente de la etiolog\u00eda del da\u00f1o nervioso primario. El patr\u00f3n de los perfiles de QST con p\u00e9rdida de funci\u00f3n y aumento de la misma permite extraer conclusiones sobre los mecanismos subyacentes. Si un est\u00edmulo nocivo persiste, conduce a una excitaci\u00f3n permanente y, por tanto, a la sensibilizaci\u00f3n [21]. Se distinguen diferentes mecanismos.<\/p>\n\n<p><strong>Deafferentaci\u00f3n: <\/strong>La deafferentaci\u00f3n sensorial se produce cuando hay da\u00f1os en diferentes tipos de fibras o en los sistemas de v\u00edas asociados en la m\u00e9dula espinal. Esto aumenta la expresi\u00f3n de los canales de sodio sensibles a la tetrodotoxina (por ejemplo, NaV1.3) [22]. Esto se expresa en el perfil QST mediante la presencia de signos menos.<\/p>\n\n<p><strong>Sensibilizaci\u00f3n perif\u00e9rica:<\/strong> Est\u00e1 causada por la liberaci\u00f3n local de mediadores inflamatorios (incluyendo histamina, bradiquinina, prostaglandina, CGRP, sustancia P). La transducci\u00f3n de se\u00f1ales y la sensibilizaci\u00f3n se producen a trav\u00e9s del glutamato, la sustancia P, la neuroquinina A y el CGRP, entre otros [9]. En el examen QST, la sensibilizaci\u00f3n perif\u00e9rica se sospecha por la presencia, por ejemplo, de hiperalgesia al calor [22].<\/p>\n\n<p><strong>Sensibilizaci\u00f3n central: <\/strong>Es el resultado de un aumento de la respuesta de las neuronas centrales WDR. En el QST, la hiperalgesia mec\u00e1nica a los est\u00edmulos de aguja y la alodinia mec\u00e1nica din\u00e1mica se encuentran [22].<\/p>\n\n<p><strong>Alteraci\u00f3n de la inhibici\u00f3n end\u00f3gena del dolor &#8211; desinhibici\u00f3n central: <\/strong>Existe cuando hay evidencia de hiperalgesia generalizada. Esto habla de un fallo en la inhibici\u00f3n del dolor (alteraci\u00f3n de los moduladores centrales del dolor, sistema gris periacueductal (PAG)-RVM (m\u00e9dula ventromedial dorsal)), mientras que la hiperalgesia localizada habla de una sensibilizaci\u00f3n central [23].<\/p>\n\n<h2 id=\"posibles-aplicaciones-para-el-dolor-neuropatico\" class=\"wp-block-heading\">Posibles aplicaciones para el dolor neurop\u00e1tico<\/h2>\n\n<p>La QST puede utilizarse en el diagn\u00f3stico del dolor neurop\u00e1tico de cualquier causa, especialmente cuando los m\u00e9todos electrofisiol\u00f3gicos convencionales no muestran ninguna anomal\u00eda y\/o existe la sospecha de una afecci\u00f3n de las fibras nerviosas de peque\u00f1o calibre o de las v\u00edas centrales asociadas.<\/p>\n\n<p><strong>Neuropat\u00eda de fibra peque\u00f1a (SFN): <\/strong>A\u00fan no se ha definido un patr\u00f3n oro en el diagn\u00f3stico de la SFN. El diagn\u00f3stico se realiza cuando est\u00e1n presentes al menos dos hallazgos patol\u00f3gicos de los siguientes ex\u00e1menes (examen cl\u00ednico, pruebas funcionales y\/o morfolog\u00eda de las fibras nerviosas de peque\u00f1o calibre) [20,24]. De todas las pruebas funcionales especiales, la QST es el procedimiento mejor establecido en la cl\u00ednica. En<span style=\"font-family: franklin gothic demi;\"> la figura 4 <\/span>se muestra un hallazgo t\u00edpico.<\/p>\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1100\" height=\"634\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10.png\" alt=\"\" class=\"wp-image-14171 lazyload\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10-800x461.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10-120x69.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10-90x52.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10-320x184.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2020\/07\/abb4_sg1_s10-560x323.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/634;\" \/><\/figure>\n\n<p><strong>Neuropat\u00eda diab\u00e9tica (NDP): <\/strong>Una polineuropat\u00eda sensoriomotora cr\u00f3nica sim\u00e9trica dependiente de la longitud es t\u00edpica [19]. Aproximadamente el 25% de todos los pacientes diab\u00e9ticos desarrollan DPN dolorosa, que se asocia m\u00e1s con la alteraci\u00f3n de las fibras nerviosas de peque\u00f1o calibre que con la disfunci\u00f3n de las fibras nerviosas gruesas [25,26].<\/p>\n\n<p>El QST tambi\u00e9n se utiliza para el dolor facial (dolor miofascial DD: neuropat\u00eda\/neuralgia del trig\u00e9mino, s\u00edndrome de boca ardiente) y en la regi\u00f3n bucal [27], para las polineuropat\u00edas inducidas por la quimioterapia [28], la neuralgia posherp\u00e9tica [12], el dolor musculoesquel\u00e9tico [29] y como par\u00e1metro del curso postoperatorio [30]. Los perfiles de los patrones de los s\u00edndromes de dolor neurop\u00e1tico m\u00e1s comunes se establecieron en un estudio multic\u00e9ntrico [15].<\/p>\n\n<p>La QST tambi\u00e9n se utiliza en estudios sobre la fibromialgia y la patolog\u00eda de las fibras peque\u00f1as. Se ha demostrado que los hallazgos del QST y el examen neurol\u00f3gico cl\u00ednico difieren entre los pacientes con s\u00edndrome de fibromialgia (SFM) y los pacientes con SFN idiop\u00e1tico [31]. La cuesti\u00f3n del &#8220;huevo y la gallina&#8221; se plantea con la fibromialgia. No est\u00e1 claro si los mecanismos contribuyen a la fisiopatolog\u00eda del FMS o si son consecuencias del FMS o de sus comorbilidades. Es necesario investigar para identificar los subgrupos y desarrollar terapias espec\u00edficas para cada subgrupo.<\/p>\n\n<h2 id=\"terapia-basada-en-mecanismos\" class=\"wp-block-heading\">Terapia basada en mecanismos<\/h2>\n\n<p>El concepto de terapia basada en mecanismos se basa en el supuesto de que los distintos s\u00edntomas del dolor neurop\u00e1tico pueden remontarse a mecanismos biol\u00f3gicos diferentes y requieren una terapia espec\u00edfica que debe adaptarse con precisi\u00f3n a las necesidades del paciente [8]. El objetivo del examen QST es establecer un patr\u00f3n del perfil del dolor, con cuya ayuda pueden extraerse conclusiones sobre los probables mecanismos fisiopatol\u00f3gicos subyacentes y, por tanto, pueden hacerse afirmaciones sobre el concepto terap\u00e9utico del paciente correspondiente [15]. Este concepto no ha podido aplicarse hasta ahora.<\/p>\n\n<p>Una de las enfermedades m\u00e1s estudiadas para probar la viabilidad del concepto de terapia basada en mecanismos es la neuropat\u00eda diab\u00e9tica. Los resultados plantean m\u00e1s preguntas nuevas de las que aclaran. Raputova et al. han descubierto que tanto el perfil QST como la densidad de fibras nerviosas intraepid\u00e9rmicas no son predictivos de la aparici\u00f3n de dolor en pacientes con polineuropat\u00eda diab\u00e9tica [32]. Mientras tanto, Segerdahl et al. muestran que los par\u00e1metros QST difieren en pacientes con y sin dolor neurop\u00e1tico [33]. Los pacientes con neuropat\u00eda diab\u00e9tica dolorosa y nociceptores irritables confirmados gen\u00e9ticamente debido a una mutaci\u00f3n en el canal de sodio (NaV1.7) muestran perfiles de QST sensoriales menos prominentes que aquellos sin mutaci\u00f3n, lo que plantea interrogantes sobre el significado mecanicista de los perfiles de QST [34]. El perfil QST no puede utilizarse para inferir el \u00e9xito del tratamiento (por ejemplo, la respuesta a la oxcarbazapina para el dolor neurop\u00e1tico en el contexto de la neuropat\u00eda diab\u00e9tica) [35].<\/p>\n\n<p>La esperanza de utilizar los perfiles QST para acercarse al concepto de terapia basada en mecanismos requiere m\u00e1s investigaci\u00f3n cl\u00ednica. Esta es la base de la perspectiva de poder ofrecer en el futuro nuevas opciones de tratamiento a los pacientes que a menudo sufren un deterioro significativo y persistente. No hay que olvidar que el desarrollo del dolor neurop\u00e1tico no s\u00f3lo se basa en cambios biol\u00f3gicos, sino que tambi\u00e9n tiene aspectos psicosociales.<\/p>\n\n<h2 id=\"mensajes-para-llevarse-a-casa\" class=\"wp-block-heading\">Mensajes para llevarse a casa<\/h2>\n\n<ul class=\"wp-block-list\">\n<li>Las pruebas sensoriales cuantitativas son un examen no invasivo normalizado y formalizado de la funci\u00f3n de todo el sistema somatosensorial, incluidas las fibras nerviosas de peque\u00f1o calibre.<\/li>\n\n\n\n<li>Esta prueba permite detectar signos m\u00e1s y menos sensibles, a diferencia de la electrofisiolog\u00eda convencional (por ejemplo, la neurograf\u00eda), que se limita al d\u00e9ficit funcional.<\/li>\n\n\n\n<li>El QST es un procedimiento psicof\u00edsico que requiere la cooperaci\u00f3n del paciente.<\/li>\n<\/ul>\n\n<p>Literatura:<\/p>\n\n<ol class=\"wp-block-list\">\n<li>Finnerup NB, et al: Dolor neurop\u00e1tico: un sistema de clasificaci\u00f3n actualizado para la investigaci\u00f3n y la pr\u00e1ctica cl\u00ednica. Dolor 2016; 157(8): 1599-1606.<\/li>\n\n\n\n<li>Treede RD, et al: Dolor neurop\u00e1tico: redefinici\u00f3n y un sistema de clasificaci\u00f3n para fines cl\u00ednicos y de investigaci\u00f3n. Neurolog\u00eda 2008; 70(18): 1630-1635.<\/li>\n\n\n\n<li>Schlereth T, et al: Diagn\u00f3stico y terapia no intervencionista del dolor neurop\u00e1tico, directriz S2k 2019; en: Sociedad Alemana de Neurolog\u00eda (ed.), Directrices para el diagn\u00f3stico y la terapia en neurolog\u00eda.<\/li>\n\n\n\n<li>Rolke R, et al: Pruebas sensoriales cuantitativas en la Red Alemana de Investigaci\u00f3n sobre el Dolor Neurop\u00e1tico (DFNS): protocolo estandarizado y valores de referencia. Dolor 2006; 123: 231-243.<\/li>\n\n\n\n<li>Ahcan U, et al: Composici\u00f3n de la fibra nerviosa de la rama cut\u00e1nea palmar del nervio mediano e implicaciones cl\u00ednicas. Br J Plast Surg 2003 dic; 56(8): 791-796.<\/li>\n\n\n\n<li>Hines AE, et al: Composici\u00f3n del tipo de fibra de las ramas articulares del nervio tibial en la articulaci\u00f3n de la rodilla en el hombre. Anat Rec 1996 dic; 246(4): 573-578.<\/li>\n\n\n\n<li>Klinke, Pape, Kurtz, Silbernagl: Fisiolog\u00eda, Thieme, 2009.<\/li>\n\n\n\n<li>Baron R, et al: Dolor y QST: &#8220;medir lo que es medible&#8221;. Dolor 2009 feb; 23(1): 5-6; doi: 10.1007\/s00482-009-0775-8.<\/li>\n\n\n\n<li>Julius D, et al.: Mecanismos moleculares de la nocicepci\u00f3n. Naturaleza 2001 Sep 13; 413(6852): 203-210.<\/li>\n\n\n\n<li>Magerl W, et al: Datos de referencia para las pruebas sensoriales cuantitativas (QST): estratificaci\u00f3n refinada para la edad y un m\u00e9todo novedoso para la comparaci\u00f3n estad\u00edstica de datos de grupo. Dolor 2010; 151: 598-605.<\/li>\n\n\n\n<li>Geber C, et al: Fiabilidad test-retest e interobservador de las pruebas sensoriales cuantitativas seg\u00fan el protocolo de la Red Alemana de Investigaci\u00f3n sobre el Dolor Neurop\u00e1tico (DFNS): un estudio multic\u00e9ntrico. Dolor 2011 mar; 152(3): 548-556.<\/li>\n\n\n\n<li>Pfau DB, et al: Pruebas sensoriales cuantitativas en la Red Alemana de Investigaci\u00f3n sobre el Dolor Neurop\u00e1tico (DFNS): datos de referencia para el tronco y aplicaci\u00f3n en pacientes con neuralgia postherp\u00e9tica cr\u00f3nica. Dolor 2014 mayo; 155(5): 1002-1015; doi: 10.1016\/j.pain.2014.02.004. Epub 2014 Feb 10.<\/li>\n\n\n\n<li>Gr\u00f6ne E, et al: El orden de las pruebas sensoriales cuantitativas facilita la hiperalgesia mec\u00e1nica en voluntarios sanos. J Pain 2012 Jan; 13(1): 73-80. doi: 10.1016<\/li>\n\n\n\n<li>M\u00fccke M, et al: Pruebas sensoriales cuantitativas. Dolor 2014 dic; 28(6): 635-646.<\/li>\n\n\n\n<li>Maier C, et al.: Pruebas sensoriales cuantitativas en la Red Alemana de Investigaci\u00f3n sobre el Dolor Neurop\u00e1tico (DFNS): anomal\u00edas somatosensoriales en 1236 pacientes con diferentes s\u00edndromes de dolor neurop\u00e1tico. Dolor 2010 Sep; 150(3): 439-450.<\/li>\n\n\n\n<li>Rolke R: Pruebas sensoriales cuantitativas: diagn\u00f3stico basado en mecanismos de los s\u00edndromes de dolor cr\u00f3nico. Habilitationsschrift, autoeditado en Maguncia 2010.<\/li>\n\n\n\n<li>Dimova V, et al: Uso de una bater\u00eda cl\u00ednica estandarizada de pruebas sensoriales cuantitativas para juzgar la relevancia cl\u00ednica de las diferencias sensoriales entre zonas corporales adyacentes. Clin J Pain 2017 Ene; 33(1): 37-43.<\/li>\n\n\n\n<li>Scherens A, et al: Las disestesias dolorosas o indoloras de las extremidades inferiores son altamente predictivas de neuropat\u00eda perif\u00e9rica: comparaci\u00f3n de diferentes modalidades diagn\u00f3sticas. Eur J Pain 2009 ago; 13(7): 711-718; doi: 10.1016.<\/li>\n\n\n\n<li>Krumova EK, et al: Dolor neurop\u00e1tico: \u00bfson \u00fatiles las pruebas sensoriales cuantitativas? Curr Diab Rep 2012 ago; 12(4): 393-402; doi: 10.1007\/s11892-012-0282-7.<\/li>\n\n\n\n<li>Devigili G, et al: Los criterios diagn\u00f3sticos de la neuropat\u00eda de fibras peque\u00f1as: de los s\u00edntomas a la neuropatolog\u00eda. Cerebro 2008 Jul; 131(Pt 7): 1912-1925; doi: 10.1093.<\/li>\n\n\n\n<li>Mense SS, et al.: Neuroanatom\u00eda funcional de los est\u00edmulos dolorosos. Recepci\u00f3n, transmisi\u00f3n y procesamiento. Dolor 2004 Jun; 18(3): 225-237.<\/li>\n\n\n\n<li>Treede RD et al: Hiperalgesia y alodinia: taxonom\u00eda, evaluaci\u00f3n y mecanismos. En: Brune K, Handwerker HO (eds): Hiperalgesia: mecanismos moleculares e implicaciones cl\u00ednicas. IASP Press, Seattle 2004; 991-1015.<\/li>\n\n\n\n<li>Gracely RH, et al: Medidas de dolor evocado en la fibromialgia. Best Pract Res Clin Rheumatol 2003 Ago; 17(4): 593-609.<\/li>\n\n\n\n<li>Blackmore D, et al: Criterios diagn\u00f3sticos de la neuropat\u00eda de fibra peque\u00f1a. J Clin Neuromuscul Dis 2017 Mar; 18(3): 125-131.<\/li>\n\n\n\n<li>Pfau DB, et al: Rendimiento t\u00e9cnico y cl\u00ednico del dispositivo de pruebas t\u00e9rmicas &#8220;Q-Sense&#8221; para evaluar la funci\u00f3n de las fibras peque\u00f1as: Una comparaci\u00f3n directa con el &#8220;Analizador Sensorial T\u00e9rmico&#8221; TSA en pacientes diab\u00e9ticos y voluntarios sanos. Eur J Pain 2019 Nov; 23(10): 1863-1878.<\/li>\n\n\n\n<li>Ekman L, et al: Evaluaci\u00f3n de la disfunci\u00f3n de las fibras nerviosas peque\u00f1as en la diabetes tipo 2. Acta Neurol Scand 2020 Jan; 141(1): 38-46.<\/li>\n\n\n\n<li>Hartmann A, et al: Perfil de las alteraciones neurop\u00e1ticas intraorales tras una lesi\u00f3n del nervio lingual y en el s\u00edndrome de boca ardiente. BMC Oral Health 2017 Mar 23; 17(1): 68.<\/li>\n\n\n\n<li>Roldan CJ, et al: Los inhibidores de la enzima convertidora de angiotensina y los bloqueantes de los receptores de angiotensina modulan la funci\u00f3n de las fibras mielinizadas tras la quimioterapia: un estudio cuantitativo de pruebas sensoriales. Pain Physician 2017 mayo; 20(4): 281-292.<\/li>\n\n\n\n<li>Georgopoulos V, et al: Pruebas sensoriales cuantitativas y predicci\u00f3n de resultados para el dolor musculoesquel\u00e9tico, la discapacidad y el afecto negativo: una revisi\u00f3n sistem\u00e1tica y metaan\u00e1lisis. Dolor 2019 Sep; 160(9): 1920-1932.<\/li>\n\n\n\n<li>Huber JL, et al: Recuperaci\u00f3n de los umbrales de detecci\u00f3n mec\u00e1nica tras la reparaci\u00f3n directa del nervio digital frente a la implantaci\u00f3n de un conducto. J Hand Surg Eur 2017 Sep; 42(7): 720-730.<\/li>\n\n\n\n<li>\u00dcceyler N, et al: Patolog\u00eda de fibras peque\u00f1as en pacientes con s\u00edndrome de fibromialgia. Cerebro 2013 Jun; 136(Pt 6): 1857-1867.<\/li>\n\n\n\n<li>Raputova J, et al: Fenotipo sensorial y factores de riesgo de la neuropat\u00eda diab\u00e9tica dolorosa: un estudio observacional transversal. Dolor 2017 dic; 158(12): 2340-2353.<\/li>\n\n\n\n<li>Segerdahl AR, et al: Un mecanismo cerebral de facilitaci\u00f3n del dolor contribuye a la polineuropat\u00eda diab\u00e9tica dolorosa. Cerebro 2018 Feb 1; 141(2): 357-364.<\/li>\n\n\n\n<li>Blesneac I, et al: Raras variantes de NaV1.7 asociadas a la neuropat\u00eda diab\u00e9tica perif\u00e9rica dolorosa. Dolor 2018 Mar; 159(3): 469-480.<\/li>\n\n\n\n<li>Gierthm\u00fchlen J, et al.: \u00bfPueden utilizarse las caracter\u00edsticas del dolor autoinformado y la prueba de cabecera para la evaluaci\u00f3n de los mecanismos del dolor? Un an\u00e1lisis de los resultados de los cuestionarios de dolor neurop\u00e1tico y las pruebas sensoriales cuantitativas. Dolor 2019 Sep; 160(9): 2093-2104.<\/li>\n<\/ol>\n\n<p><em>InFo NEUROLOG\u00cdA Y PSIQUIATR\u00cdA 2021, 19(1): 10-15<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dolor es uno de los s\u00edntomas m\u00e1s dif\u00edciles de detectar. Muchos otros signos de la enfermedad, como los s\u00edntomas cut\u00e1neos o la par\u00e1lisis, son visibles, palpables y, por tanto,&hellip;<\/p>\n","protected":false},"author":7,"featured_media":103842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Pruebas sensoriales cuantitativas en el dolor neurop\u00e1tico","footnotes":""},"category":[11352,22619,11478,11316,11328,11451,11552],"tags":[21423,11758,21426,21435,21431,21437],"powerkit_post_featured":[],"class_list":["post-329831","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-y-diabetologia","category-formacion-cme","category-formacion-continua","category-geriatria","category-neurologia","category-reumatologia","category-rx-es","tag-dolor-neuropatico","tag-formacion-cme","tag-investigacion-qst","tag-prueba-de-sensibilidad","tag-sensibilidad-al-dolor","tag-umbral-de-vibracion","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:07:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/329831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=329831"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/329831\/revisions"}],"predecessor-version":[{"id":329853,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/329831\/revisions\/329853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/103842"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=329831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=329831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=329831"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=329831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}