{"id":333712,"date":"2020-07-30T02:00:00","date_gmt":"2020-07-30T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/conceptos-personalizados-innovadores-contra-la-melancolia\/"},"modified":"2020-07-30T02:00:00","modified_gmt":"2020-07-30T00:00:00","slug":"conceptos-personalizados-innovadores-contra-la-melancolia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/conceptos-personalizados-innovadores-contra-la-melancolia\/","title":{"rendered":"Conceptos personalizados innovadores contra la melancol\u00eda"},"content":{"rendered":"<p><strong>La tendencia hacia la medicina personalizada tambi\u00e9n est\u00e1 m\u00e1s de actualidad que nunca en el \u00e1mbito psiqui\u00e1trico. Se espera mejorar la respuesta a las sustancias antidepresivas y reducir los efectos secundarios. Recientemente se ha aprobado en Suiza un aerosol nasal que contiene ketamina como nuevo f\u00e1rmaco contra la resistencia al tratamiento.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Bas\u00e1ndose en pruebas emp\u00edricas, cada vez se reconoce m\u00e1s que las estrategias de tratamiento personalizado son las m\u00e1s prometedoras para el tratamiento de muchas enfermedades. Un proyecto financiado por el Instituto Nacional de Investigaci\u00f3n Sanitaria aborda esta cuesti\u00f3n en relaci\u00f3n con el trastorno depresivo mayor. El protocolo de investigaci\u00f3n correspondiente se public\u00f3 en la revista BMJ Evidence-based Mental Health en 2019 [1]. El objetivo es desarrollar un concepto de tratamiento personalizado para adultos que pueda utilizarse en la pr\u00e1ctica cl\u00ednica diaria.<\/p>\n<h2 id=\"enfoque-biopsicosocial\">Enfoque biopsicosocial<\/h2>\n<p>La inclusi\u00f3n de factores individuales en el diagn\u00f3stico y la terapia no es nueva y tambi\u00e9n se menciona, por ejemplo, en las recomendaciones de tratamiento de la Sociedad Suiza para la Ansiedad y la Depresi\u00f3n (SGAD) [2]. Resume las estrategias terap\u00e9uticas basadas en pruebas para el tratamiento agudo de los episodios depresivos seg\u00fan los criterios de la &#8220;Clasificaci\u00f3n Internacional de Enfermedades&#8221; (CIE-10) y el &#8220;Manual Diagn\u00f3stico y Estad\u00edstico de los Trastornos Mentales&#8221; (DSM). Adem\u00e1s de una evaluaci\u00f3n diagn\u00f3stica exhaustiva por parte de un especialista m\u00e9dico, las recomendaciones de tratamiento presuponen que se descarten otras enfermedades tanto mentales como som\u00e1ticas y que se tengan en cuenta los factores individuales desencadenantes de la depresi\u00f3n (por ejemplo, medicaci\u00f3n, alcohol, drogas, factores de estr\u00e9s psicosocial, etc.). Las recomendaciones generales basadas en la evidencia sobre farmacoterapia se ofrecen en forma de niveles de evidencia (niveles A-D) basados en ensayos cl\u00ednicos aleatorizados. En Suiza, la teor\u00eda y la pr\u00e1ctica psiqui\u00e1tricas se basan en un enfoque biopsicosocial. Los cuatro elementos b\u00e1sicos del tratamiento psiqui\u00e1trico son: la espera activa, el tratamiento farmacol\u00f3gico, la psicoterapia y los procedimientos combinados. Se calcula que la duraci\u00f3n media de los episodios de un trastorno depresivo unipolar tratado es de 16 semanas. El curso de los trastornos depresivos muestra una gran variabilidad interindividual.<\/p>\n<h2 id=\"el-genotipado-abcb1-como-base-para-la-terapia-dirigida\">El genotipado ABCB1 como base para la terapia dirigida<\/h2>\n<p>La inclusi\u00f3n de biomarcadores en la evaluaci\u00f3n de los resultados de la terapia y para la optimizaci\u00f3n de las respuestas terap\u00e9uticas es un tema de actualidad en la investigaci\u00f3n sobre terapias para los trastornos depresivos [3]. La prueba ABCB1, desarrollada en el Instituto Max Planck de Psiquiatr\u00eda de M\u00fanich, es un procedimiento de diagn\u00f3stico gen\u00e9tico molecular destinado a apoyar al m\u00e9dico en el tratamiento de un paciente con antidepresivos [4]. Mediante este m\u00e9todo, se pueden medir las variantes de la secuencia de ADN en el gen ABCB1 que codifica la glicoprote\u00edna P. Esto nos permite identificar a los pacientes en los que, debido a polimorfismos, muchos de los antidepresivos utilizados habitualmente son menos capaces de atravesar la barrera hematoencef\u00e1lica, lo que constituye una posible explicaci\u00f3n de la falta de respuesta a los antidepresivos. Existen hallazgos que apoyan emp\u00edricamente la hip\u00f3tesis de que los polimorfismos influyen en los resultados de la terapia. Uhr y sus colegas pudieron demostrar que las variantes gen\u00e9ticas del gen ABCB1 est\u00e1n relacionadas con la eficacia de los antidepresivos si \u00e9stos son sustratos de la P-gp [5]. Bas\u00e1ndose en los resultados del estudio sobre el genotipado ABCB1, se realizaron an\u00e1lisis en el \u00e1mbito cl\u00ednico. Un estudio piloto investig\u00f3 si la traducci\u00f3n pod\u00eda aplicarse con \u00e9xito [6]. Un aumento de 1,5 veces en la dosis del sustrato tras la genotipificaci\u00f3n se asoci\u00f3 a una menor duraci\u00f3n de la estancia hospitalaria. En un metaan\u00e1lisis de todos los estudios con pacientes hospitalizados publicado en 2015, se demostr\u00f3 una asociaci\u00f3n significativa del SNP rs2032583 con la respuesta al tratamiento [7]. La Sociedad Suiza de Psiquiatr\u00eda y Psicoterapia (SGPP) recomienda el uso de la prueba gen\u00e9tica ABCB1.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<table border=\"1\" cellpadding=\"5\" cellspacing=\"1\" style=\"width:788px\">\n<tbody>\n<tr>\n<td style=\"width:770px\"><strong>Resumen<\/strong><\/p>\n<ul>\n<li>El curso de los trastornos depresivos muestra una gran variabilidad interindividual. En Suiza, la teor\u00eda y la pr\u00e1ctica psiqui\u00e1tricas se basan en un enfoque biopsicosocial. Los cuatro pilares del tratamiento son: la espera activa, el tratamiento farmacol\u00f3gico, la psicoterapia y los m\u00e9todos combinados [2].<\/li>\n<li>Los biomarcadores son una posible base para estrategias terap\u00e9uticas individualizadas. La prueba ABCB1 es un procedimiento de diagn\u00f3stico gen\u00e9tico molecular que ayuda a decidir qu\u00e9 antidepresivos utilizar. As\u00ed se identifican polimorfismos relevantes para la respuesta a la terapia [3\u20137].<\/li>\n<li>En los casos resistentes a la terapia, se ha aprobado recientemente el aerosol nasal que contiene ketamina <sup>Spravato\u00ae<\/sup> (esketamina). Una gran ventaja de esta sustancia activa es el r\u00e1pido inicio de su acci\u00f3n [8,9].<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 id=\"-2\">&nbsp;<\/h2>\n<h2 id=\"aprobado-el-aerosol-nasal-con-ketamina-para-el-tratamiento-de-la-resistencia\">Aprobado el aerosol nasal con ketamina para el tratamiento de la resistencia<\/h2>\n<p>El preparado <sup>Spravato\u00ae<\/sup> est\u00e1 aprobado en EE UU y la UE desde 2019 y en Suiza desde febrero de 2020 en combinaci\u00f3n con un ISRS (inhibidor selectivo de la recaptaci\u00f3n de serotonina) o un IRSN (inhibidor selectivo de la recaptaci\u00f3n de norepinefrina) para adultos con depresi\u00f3n mayor resistente al tratamiento [8\u201310]. La resistencia al tratamiento se define como la falta de respuesta a al menos dos antidepresivos diferentes [9]. La aprobaci\u00f3n se basa en cinco estudios de fase III con un total de m\u00e1s de 1600 pacientes mayores de 18 a\u00f1os con depresi\u00f3n resistente al tratamiento. El aerosol nasal con ketamina provoc\u00f3 una respuesta cl\u00ednicamente significativa en el grupo verum ya a los 28 d\u00edas del inicio. La respuesta al tratamiento se operacionaliz\u00f3 como una reducci\u00f3n de al menos el 50% en la Escala de Calificaci\u00f3n de la Depresi\u00f3n de Montgomery-Asberg en la fase de inducci\u00f3n en comparaci\u00f3n con el valor basal. Combinado con un antidepresivo, <sup>Spravato\u00ae<\/sup> redujo el riesgo de reca\u00edda en un 70% en pacientes con respuesta estable en comparaci\u00f3n con el placebo y en un 51% en pacientes en remisi\u00f3n estable. En general, la tolerabilidad fue buena a lo largo del periodo de 52 semanas, y el control de la tensi\u00f3n arterial result\u00f3 importante, ya que los niveles de tensi\u00f3n arterial pueden elevarse temporalmente.<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Tomlinson A, et al: Personalizar el tratamiento antidepresivo para la depresi\u00f3n unipolar combinando opciones individuales, riesgos y big data (PETRUSHKA): justificaci\u00f3n y protocolo. Evid Based Ment Health. 2019 Oct 23. pii: ebmental-2019-300118  [Epub ahead of print]<\/li>\n<li>Holsboer-Trachsler E, et al: El tratamiento agudo de los episodios depresivos. En: El tratamiento som\u00e1tico de los trastornos depresivos unipolares: Actualizaci\u00f3n 2016, Parte 1. Swiss Medical Forum 2016; 16(35): 716-724.<\/li>\n<li>Breitenstein B, Scheuer S, Holsboer F: \u00bfExisten biomarcadores significativos de la respuesta al tratamiento de la depresi\u00f3n? Drug Discov Today 2014; 19(5): 539-561.<\/li>\n<li>Instituto Max Planck de Psiquiatr\u00eda, www.psych.mpg.de<\/li>\n<li>Uhr M, et al: Los polimorfismos en el gen transportador de f\u00e1rmacos ABCB1 predicen la respuesta al tratamiento antidepresivo en la depresi\u00f3n. Neuron 2008; 57(2): 203-209.<\/li>\n<li>Breitenstein B, et al: La aplicaci\u00f3n cl\u00ednica del genotipado ABCB1 en el tratamiento antidepresivo: un estudio piloto. CNS Spectr 2014; 19(2): 165-175.<\/li>\n<li>Breitenstein B, et al: Variantes del gen ABCB1 y resultado del tratamiento antidepresivo: Un metaan\u00e1lisis. Am J Med Genet B Neuropsychiatr Genet 2015; 168B(4): 274-283.<\/li>\n<li>Mahase E: La esketamina se aprueba en Europa para el tratamiento del trastorno depresivo mayor resistente BMJ 2019; 367: l7069<\/li>\n<li>Agencia Europea de Medicamentos. Esketamina spray nasal Resumen de las caracter\u00edsticas del producto, www.ema.europa.eu\/en\/medicines<\/li>\n<li>Swissmedics: <sup>Spravato\u00ae<\/sup>, spray nasal (esketaminum), www.swissmedic.ch<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2020; 15(5): 26-28<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tendencia hacia la medicina personalizada tambi\u00e9n est\u00e1 m\u00e1s de actualidad que nunca en el \u00e1mbito psiqui\u00e1trico. Se espera mejorar la respuesta a las sustancias antidepresivas y reducir los efectos&hellip;<\/p>\n","protected":false},"author":7,"featured_media":96790,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Depresi\u00f3n unipolar  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11288,11435,11552],"tags":[],"powerkit_post_featured":[],"class_list":["post-333712","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-medicina-interna-general","category-psiquiatria-y-psicoterapia","category-rx-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 22:06:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/333712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=333712"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/333712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/96790"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=333712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=333712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=333712"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=333712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}