{"id":333936,"date":"2020-07-03T02:00:00","date_gmt":"2020-07-03T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-tendencia-es-hacia-la-telemedicina-no-solo-por-covid-19\/"},"modified":"2020-07-03T02:00:00","modified_gmt":"2020-07-03T00:00:00","slug":"la-tendencia-es-hacia-la-telemedicina-no-solo-por-covid-19","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/la-tendencia-es-hacia-la-telemedicina-no-solo-por-covid-19\/","title":{"rendered":"La tendencia es hacia la telemedicina &#8211; no s\u00f3lo por COVID-19"},"content":{"rendered":"<p><strong>La digitalizaci\u00f3n en la asistencia sanitaria ambulatoria gana cada vez m\u00e1s importancia. Desde la pandemia de COVID 19, la demanda de servicios de telemedicina tambi\u00e9n ha aumentado considerablemente. No obstante, sigue habiendo limitaciones que no pueden eliminarse de la noche a la ma\u00f1ana.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La necesidad de seguir el ritmo de la digitalizaci\u00f3n en el sector sanitario es cada vez m\u00e1s evidente. Se tomaron medidas para el uso de las consultas de telemedicina, especialmente en el contexto de la pandemia COVID 19. Sin embargo, Suiza se est\u00e1 quedando un poco atr\u00e1s: actualmente, en el sistema de tarifas ambulatorias TARMED, los servicios de telemedicina s\u00f3lo pueden facturarse a trav\u00e9s de la partida arancelaria &#8220;Consulta telef\u00f3nica del especialista&#8221;, y este uso es limitado. Actualmente se est\u00e1 elaborando una soluci\u00f3n. Este ejemplo muestra que a\u00fan quedan algunos obst\u00e1culos por superar antes de que la digitalizaci\u00f3n pueda arraigar plenamente en los consultorios. B\u00e1sicamente, sin embargo, el ambiente es positivo. El 85% de la profesi\u00f3n m\u00e9dica encuestada por el Estudio de Tendencias Digitales 2019 considera importante el uso de las oportunidades digitales. A veces, sin embargo, las capacidades individuales para manejar las opciones digitales se interponen en el deseo de utilizarlas.$<\/p>\n<p>En principio, sin embargo, las ofertas digitales pueden suponer una ventaja decisiva para la pr\u00e1ctica. Porque no s\u00f3lo los m\u00e9dicos, sino tambi\u00e9n los pacientes tienen un gran inter\u00e9s en la digitalizaci\u00f3n. Se demostr\u00f3 que la elecci\u00f3n de la consulta m\u00e9dica tambi\u00e9n se realiza, por ejemplo, mediante la oferta de una cita en l\u00ednea. En general, se constat\u00f3 que el inter\u00e9s de la poblaci\u00f3n por las ofertas digitales es mayor que el inter\u00e9s de la profesi\u00f3n m\u00e9dica por invertir en dichas ofertas o recibir m\u00e1s informaci\u00f3n sobre ellas. Mientras que la profesi\u00f3n m\u00e9dica se interesa sobre todo por las obras de consulta en l\u00ednea, la poblaci\u00f3n ve un valor a\u00f1adido sobre todo en las notificaciones autom\u00e1ticas de las citas con el m\u00e9dico o los tiempos de espera. Por otro lado, tambi\u00e9n es un hecho que los pacientes aprecian el contacto personal y no preferir\u00edan una soluci\u00f3n digital en todos los asuntos.<\/p>\n<p><em>Fuente: &#8220;Encuesta sobre tendencias digitales 2019&#8221;, 06.05.2020, FMH<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGY &amp; HEMATOLOGY 2020; 8(3): 36 (publicado el 19.6.20, antes de impresi\u00f3n).<br \/>\nCARDIOVASC 2020; 19(3): 40<\/em><br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La digitalizaci\u00f3n en la asistencia sanitaria ambulatoria gana cada vez m\u00e1s importancia. Desde la pandemia de COVID 19, la demanda de servicios de telemedicina tambi\u00e9n ha aumentado considerablemente. No obstante,&hellip;<\/p>\n","protected":false},"author":7,"featured_media":97929,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Digitalizaci\u00f3n","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11372,11288,11470,11430,11552],"tags":[13942,24935,13781],"powerkit_post_featured":[],"class_list":["post-333936","post","type-post","status-publish","format-standard","has-post-thumbnail","category-infectologia","category-medicina-interna-general","category-noticias","category-prevencion-y-asistencia-sanitaria","category-rx-es","tag-digitalizacion","tag-medicina-2-0-es","tag-telemedicina-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:29:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/333936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=333936"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/333936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/97929"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=333936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=333936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=333936"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=333936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}