{"id":335559,"date":"2019-10-11T02:00:00","date_gmt":"2019-10-11T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/el-paciente-como-centro-de-atencion-un-cambio-de-perspectiva\/"},"modified":"2019-10-11T02:00:00","modified_gmt":"2019-10-11T00:00:00","slug":"el-paciente-como-centro-de-atencion-un-cambio-de-perspectiva","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/el-paciente-como-centro-de-atencion-un-cambio-de-perspectiva\/","title":{"rendered":"El paciente como centro de atenci\u00f3n &#8211; un cambio de perspectiva"},"content":{"rendered":"<p><strong>Para el tratamiento de la trombocitopenia inmunitaria (PTI), se est\u00e1 debatiendo actualmente el uso de agonistas del receptor de la trombopoyetina (TPO-RA). Aunque la administraci\u00f3n de esteroides como terapia de choque sigue siendo el centro de la terapia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>El hemograma es el centro de inter\u00e9s de un hemat\u00f3logo. Hasta ahora, todo va bien. Si los pacientes son enviados por el m\u00e9dico de cabecera a una aclaraci\u00f3n oncol\u00f3gica debido a un cambio en los valores, la aclaraci\u00f3n diagn\u00f3stica es la primera prioridad. Sin embargo, no hay que olvidar el miedo con el que la persona afectada se sienta ante el m\u00e9dico tratante. La espada de Damocles &#8220;leucemia&#8221; pesa mucho. Aqu\u00ed es importante percibir al paciente en su situaci\u00f3n, educarle y, sobre todo, mostrarle una perspectiva.<\/p>\n<p>La vista del laboratorio no lo es todo, ni mucho menos. Los deseos del paciente tambi\u00e9n deben tenerse en cuenta a la hora de decidir la medicaci\u00f3n. El uso prolongado de esteroides, por ejemplo, es rechazado por una gran proporci\u00f3n de pacientes con PTI. Adem\u00e1s, la proporci\u00f3n de fracasos terap\u00e9uticos en el tratamiento de primera l\u00ednea es muy elevada. Por ello, los cient\u00edficos debatieron no s\u00f3lo el contenido de las directrices actuales, sino tambi\u00e9n el uso anterior de los agonistas del receptor de la trombopoyetina (TPO-RA). \u00bfPuede lograrse una remisi\u00f3n estable de esta forma? Como terapia de choque, la administraci\u00f3n de esteroides sigue siendo el centro del tratamiento. Sin embargo, esto deber\u00eda reducirse significativamente o interrumpirse a largo plazo. Como agente terap\u00e9utico de segunda l\u00ednea, ahora se puede recurrir a un TPO-RA despu\u00e9s de s\u00f3lo seis meses. Elevar las plaquetas a un rango seguro desde el principio es de suma importancia.<br \/>\n&nbsp;<\/p>\n<p><em>Fuente:<sup>24\u00ba<\/sup> Congreso de la Asociaci\u00f3n Europea de Hematolog\u00eda (EHA) 2019<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGY &amp; HEMATOLOGY 2019; 7(4): 26 (publicado el 20.9.19, antes de impresi\u00f3n).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para el tratamiento de la trombocitopenia inmunitaria (PTI), se est\u00e1 debatiendo actualmente el uso de agonistas del receptor de la trombopoyetina (TPO-RA). Aunque la administraci\u00f3n de esteroides como terapia de&hellip;<\/p>\n","protected":false},"author":7,"featured_media":91306,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Trombocitopenia inmunitaria (PTI)","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11483,11321,11552],"tags":[],"powerkit_post_featured":[],"class_list":["post-335559","post","type-post","status-publish","format-standard","has-post-thumbnail","category-el-congreso-informa","category-hematologia","category-rx-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 21:50:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/335559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=335559"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/335559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/91306"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=335559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=335559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=335559"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=335559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}