{"id":335873,"date":"2019-07-29T02:00:00","date_gmt":"2019-07-29T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/la-infeccion-como-causa-del-cancer\/"},"modified":"2019-07-29T02:00:00","modified_gmt":"2019-07-29T00:00:00","slug":"la-infeccion-como-causa-del-cancer","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/la-infeccion-como-causa-del-cancer\/","title":{"rendered":"\u00bfLa infecci\u00f3n como causa del c\u00e1ncer?"},"content":{"rendered":"<p><strong>Todo el mundo habla del microbioma. Tampoco se detiene en las enfermedades malignas. Esto se debe a que muchos tumores reci\u00e9n diagnosticados pueden tener su origen en una infecci\u00f3n.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Se ha demostrado que algunas formas de c\u00e1ncer de mama o de piel negra est\u00e1n causadas por mutaciones puntuales heredadas o por da\u00f1os en el ADN inducidos por los rayos UV. Durante mucho tiempo se asumi\u00f3 que las enfermedades malignas se originaban exclusivamente por cambios en el material gen\u00e9tico. El hecho de que esto no es as\u00ed s\u00f3lo est\u00e1 penetrando poco a poco en la conciencia. Aproximadamente el 20% de todas las enfermedades tumorales que se diagnostican cada a\u00f1o tienen su origen en una infecci\u00f3n.<\/p>\n<p>S\u00f3lo cuatro pat\u00f3genos son los principales responsables de la aparici\u00f3n de tumores dependientes de infecciones: el virus del papiloma humano, la hepatitis B y C y la bacteria Helicobacter pylori. Mientras que los virus son responsables del c\u00e1ncer de cuello de \u00fatero y de los carcinomas hep\u00e1ticos, las bacterias provocan principalmente c\u00e1ncer de est\u00f3mago. Por lo general, para que las c\u00e9lulas degeneren deben a\u00f1adirse a la infecci\u00f3n otros factores como el alcohol o una dieta rica en sal. Se supone que el riesgo de las personas infectadas aumenta alrededor de un 10%.<\/p>\n<p>Las vacunas, algunas de las cuales ya est\u00e1n disponibles, pretenden reducir la incidencia de las formas de c\u00e1ncer mencionadas. Adem\u00e1s, un microbioma sano es crucial para el \u00e9xito del tratamiento de los tumores, como ahora es bien sabido. Los pasos exactos que deben darse a\u00fan no se conocen y son objeto de investigaci\u00f3n en ensayos cl\u00ednicos.<\/p>\n<p><em>Fuente: Simposio Charles Rodolphe Brupbacher 2019<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>InFo ONCOLOGY &amp; HEMATOLOGY 2019; 7(2-3): 36 (publicado el 21.6.19, antes de impresi\u00f3n).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo el mundo habla del microbioma. Tampoco se detiene en las enfermedades malignas. Esto se debe a que muchos tumores reci\u00e9n diagnosticados pueden tener su origen en una infecci\u00f3n.<\/p>\n","protected":false},"author":7,"featured_media":90295,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Microbioma","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11483,11372,11336,11552],"tags":[22289],"powerkit_post_featured":[],"class_list":["post-335873","post","type-post","status-publish","format-standard","has-post-thumbnail","category-el-congreso-informa","category-infectologia","category-oncologia","category-rx-es","tag-microbioma","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-10 01:10:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/335873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=335873"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/335873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/90295"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=335873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=335873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=335873"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=335873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}