{"id":336282,"date":"2019-05-24T02:00:00","date_gmt":"2019-05-24T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/salud-masculina-existe-la-andropausia\/"},"modified":"2019-05-24T02:00:00","modified_gmt":"2019-05-24T00:00:00","slug":"salud-masculina-existe-la-andropausia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/salud-masculina-existe-la-andropausia\/","title":{"rendered":"Salud masculina: \u00bfExiste la andropausia?"},"content":{"rendered":"<p><strong>Cuanto m\u00e1s envejecen los hombres, m\u00e1s probabilidades tienen de sufrir una deficiencia de testosterona. Pero el hipogonadismo no est\u00e1 presente hasta que se ha confirmado en dos laboratorios.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La hormona sexual testosterona desempe\u00f1a un papel muy importante para el organismo masculino. Por ejemplo, influye en casi todos los sistemas org\u00e1nicos del cuerpo masculino, por lo que una deficiencia permanente de testosterona acaba provocando en muchos casos s\u00edntomas psicol\u00f3gicos (irritabilidad, nerviosismo, depresi\u00f3n, limitaci\u00f3n de las capacidades cognitivas), f\u00edsicos (aumento de la grasa abdominal, disminuci\u00f3n de la masa muscular, sofocos, osteopenia\/osteoporosis, s\u00edndrome metab\u00f3lico) y sexuales (p\u00e9rdida de libido, disfunci\u00f3n er\u00e9ctil) <strong>(Fig.&nbsp;1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-11828\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15.png\" style=\"height:426px; width:600px\" width=\"1100\" height=\"781\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15-800x568.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15-120x85.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15-320x227.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb1_hp5_s15-560x398.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Es importante que los m\u00e9dicos sepan que los s\u00edntomas enumerados anteriormente suelen ser s\u00f3lo un primer indicio de una deficiencia de testosterona (=hipogonadismo sintom\u00e1tico). Precauci\u00f3n: El hipogonadismo no debe diagnosticarse \u00fanicamente en funci\u00f3n de los s\u00edntomas presentes. Esto siempre requiere confirmaci\u00f3n dos veces en el laboratorio. Esto significa que, adem\u00e1s de los s\u00edntomas correspondientes, tambi\u00e9n debe haber niveles repetidamente bajos de testosterona en la sangre.<\/p>\n<p>En la pr\u00e1ctica, sin embargo, suele ocurrir que los s\u00edntomas que sugieren hipogonadismo se pasan por alto, o simplemente los hombres no mencionan ciertos s\u00edntomas. S\u00f3lo alrededor del 50% de los m\u00e9dicos piensan en una posible deficiencia hormonal cuando observan s\u00edntomas como los sofocos en los hombres. El paciente no es diagnosticado y a menudo vive con los s\u00edntomas sin tratar durante varios a\u00f1os. Sin embargo, un fallo de este tipo puede tener consecuencias sanitarias de gran alcance para los pacientes afectados: Por ejemplo, una deficiencia prolongada de testosterona provoca disfunci\u00f3n er\u00e9ctil y de la libido. Tambi\u00e9n pueden producirse problemas de fertilidad. Por lo tanto, en el caso de un deseo prolongado e insatisfecho de tener hijos, tambi\u00e9n deber\u00eda pensar al menos una vez en el hombre y en su equilibrio de testosterona.<\/p>\n<p>Por regla general, los hombres s\u00f3lo acuden al m\u00e9dico cuando los problemas sexuales empiezan a interferir en su vida amorosa a largo plazo. En consonancia con nuestra sociedad de consumo orientada al rendimiento, la mayor\u00eda de los hombres le exigir\u00e1n a usted como m\u00e9dico una &#8220;p\u00edldora azul&#8221; que supuestamente solucionar\u00e1 el problema r\u00e1pidamente y como si se tratara de apretar un bot\u00f3n. Sin embargo, un hecho de la pr\u00e1ctica diaria es que casi uno de cada tres hombres que consulta a un m\u00e9dico por disfunci\u00f3n er\u00e9ctil ya padece una deficiencia manifiesta de testosterona y, por lo tanto, necesita m\u00e1s una terapia causal mediante la sustituci\u00f3n de testosterona.<\/p>\n<h2 id=\"tomese-en-serio-el-hipogonadismo-y-tratelo\">T\u00f3mese en serio el hipogonadismo y tr\u00e1telo<\/h2>\n<p>En los hombres que envejecen, el nivel de testosterona tambi\u00e9n disminuye de forma natural y constante <strong>(Fig.&nbsp;2) <\/strong>. Lo m\u00e1s probable es que esto se explique por el hecho de que, en comparaci\u00f3n con las mujeres, los hombres se acercan biol\u00f3gicamente al final de su edad reproductiva. Adem\u00e1s de este descenso hormonal relacionado con la edad, el nivel de testosterona de los hombres tambi\u00e9n se ve afectado por un estilo de vida desfavorable. Por tanto, estos factores del estilo de vida ya tienen efecto a una edad temprana y pueden repercutir en los niveles hormonales.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-11829 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/760;height:415px; width:600px\" width=\"1100\" height=\"760\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15-800x553.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15-120x83.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15-90x62.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15-320x221.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/abb2_hp5_s15-560x387.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Estos factores negativos que influyen incluyen la obesidad, el estr\u00e9s f\u00edsico y mental, el consumo excesivo de alcohol, la reducci\u00f3n de la actividad sexual, as\u00ed como enfermedades agudas o cr\u00f3nicas (infecciones, infarto de miocardio, infecci\u00f3n por VIH, cirrosis hep\u00e1tica, enfermedades renales, hipotiroidismo, diabetes mellitus o incluso asma).<\/p>\n<p>Por lo tanto, la carencia de testosterona no es en absoluto un &#8220;fen\u00f3meno de estilo de vida&#8221; ni la expresi\u00f3n de una condici\u00f3n temporal del hombre que envejece. Por el contrario, el hipogonadismo confirmado es la base de otros problemas de salud mucho m\u00e1s graves. Los hombres con deficiencia de testosterona tienen incluso un mayor riesgo de mortalidad. Por ejemplo, el riesgo de mortalidad en los hombres hipogonadales con niveles de testosterona &lt;2,5&nbsp;ng\/ml es m\u00e1s del doble en comparaci\u00f3n con los hombres con niveles normales de testosterona (riesgo global; OR=2,24). Al mismo tiempo, los hombres con una testosterona normal sufren con menos frecuencia enfermedades cardiovasculares (OR 0,7). Por el contrario, los hombres con niveles de testosterona bajos o hipogonadales tienen aproximadamente el doble de probabilidades de sufrir un ictus, por ejemplo.<\/p>\n<p>Advertencia: Por lo tanto, las directrices actuales de la EAU recomiendan sustituir con testosterona a los hombres con hipogonadismo confirmado por laboratorio [1].<\/p>\n<h2 id=\"la-sustitucion-con-testosterona-es-segura\">La sustituci\u00f3n con testosterona es segura<\/h2>\n<p>El tratamiento con testosterona para los hombres hipogonadales -y s\u00f3lo en estos casos est\u00e1 realmente indicado el reemplazo de testosterona- siempre se ha enfrentado a un fuerte debate. Pero, \u00bfde d\u00f3nde procede realmente esta imagen negativa de la sustituci\u00f3n con testosterona?<\/p>\n<p>Aunque hace tiempo que los estudios lo desmienten, algunos m\u00e9dicos, pero sobre todo los pacientes, siguen temiendo que la sustituci\u00f3n con testosterona pueda provocar un c\u00e1ncer de pr\u00f3stata o favorecer a\u00fan m\u00e1s un tumor no detectado previamente. Sin embargo, incluso despu\u00e9s de a\u00f1os de tratamiento sustitutivo con testosterona, no hay pruebas de ello, ni en los estudios ni en la pr\u00e1ctica diaria.<\/p>\n<p>Sin embargo, un estudio publicado por Vigen y sus colegas en 2013 [2] concluy\u00f3 inicialmente que los hombres en sustituci\u00f3n podr\u00edan tener un mayor riesgo cardiovascular. Sin embargo, el estudio era defectuoso y tras corregir los c\u00e1lculos, la afirmaci\u00f3n de mayores riesgos cardiovasculares con la sustituci\u00f3n de testosterona ya no era sostenible. Sin embargo, el estudio sigui\u00f3 presente en la mente de la gente hasta hoy e inquiet\u00f3 tanto a los pacientes como a los m\u00e9dicos tratantes.<\/p>\n<p>Vigen y sus colegas afirmaron en la versi\u00f3n original de su art\u00edculo que la administraci\u00f3n de testosterona conlleva mayores riesgos cardiovasculares en pacientes adecuadamente preenfermos. A continuaci\u00f3n, las afirmaciones del art\u00edculo se citaron continuamente como prueba de una relaci\u00f3n entre la administraci\u00f3n de testosterona y las enfermedades cardiovasculares resultantes. Posteriormente, los medios de comunicaci\u00f3n mundiales se hicieron eco de esta historia y la dieron a conocer a un amplio p\u00fablico.<\/p>\n<p>Sin embargo, la correcci\u00f3n de los resultados poco despu\u00e9s recibi\u00f3 poca atenci\u00f3n por parte de los medios de comunicaci\u00f3n, por lo que la desinformaci\u00f3n original dio lugar a una percepci\u00f3n distorsionada de la sustituci\u00f3n con testosterona. La confianza de los pacientes en el sistema sanitario qued\u00f3 as\u00ed da\u00f1ada de forma permanente en lo que respecta a la salud de los hombres.<\/p>\n<p>Sin embargo, el estudio presentaba graves deficiencias. Esto no s\u00f3lo falsific\u00f3 los resultados del estudio, sino que les dio la vuelta.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-11830 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18.png\" style=\"--smush-placeholder-width: 876px; --smush-placeholder-aspect-ratio: 876\/1238;height:565px; width:400px\" width=\"876\" height=\"1238\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18.png 876w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18-800x1131.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18-120x170.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18-90x127.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18-320x452.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2019\/05\/kasten_hp5_s18-560x791.png 560w\" data-sizes=\"(max-width: 876px) 100vw, 876px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"los-errores-del-estudio-jama-en-detalle\">Los errores del estudio JAMA en detalle<\/h2>\n<p>Seis d\u00edas despu\u00e9s de su aparici\u00f3n, el art\u00edculo ya hab\u00eda sido corregido. Pasaron otros tres meses hasta que finalmente se publicaron los principales errores del estudio: Por ejemplo, uno de los grupos de hombres incluidos en el estudio no inclu\u00eda a 1132 como se hab\u00eda afirmado anteriormente, sino que, tras comprobar los datos, s\u00f3lo hab\u00eda 128 hombres (\u00a1!). La tasa de error dentro de este grupo de estudio fue, por tanto, \u00a1un impresionante 89%!<\/p>\n<p>Un segundo grupo estaba supuestamente compuesto por m\u00e1s de 900 hombres. Sorprendentemente, el examen de estos datos tras la publicaci\u00f3n del estudio revel\u00f3 que entre los 900 hombres declarados, tambi\u00e9n hab\u00eda 100 mujeres &#8211; el 10% de este grupo estudiado pertenec\u00eda, por tanto, al sexo &#8220;equivocado&#8221; para el estudio.<br \/>\nTras las correcciones necesarias de los datos, muchas de las afirmaciones del estudio se leen ahora finalmente de forma completamente diferente: el 10,1% de los hombres que recibieron testosterona sufrieron un infarto de miocardio o un derrame cerebral o murieron durante el periodo de estudio. Por otro lado, en el grupo no tratado, el 21,2% de los hombres sufrieron un infarto de miocardio, un derrame cerebral o murieron &#8211; por lo que sin el reemplazo de testosterona, incluso el doble de hombres con una deficiencia hormonal manifiesta se vieron afectados por acontecimientos cardiovasculares.<\/p>\n<h2 id=\"deficiencia-de-testosterona-hipogonadismo-en-la-practica-diaria\">Deficiencia de testosterona\/hipogonadismo en la pr\u00e1ctica diaria<\/h2>\n<p>La deficiencia de testosterona y el hipogonadismo que requieren terapia son tambi\u00e9n muy frecuentes en la pr\u00e1ctica, y no s\u00f3lo en los hombres mayores. En octubre de 2017, la Sociedad Alemana para el Hombre y la Salud (DGMG) public\u00f3 los primeros resultados de su propio estudio transversal a escala nacional denominado &#8220;Estudio de los 20.000 de testosterona&#8221; [3].<\/p>\n<p>En este estudio, se analizaron muestras de sangre de m\u00e1s de 20.000 hombres de entre 18 y 100 a\u00f1os para determinar sus respectivos niveles de testosterona. Como resultado, casi uno de cada siete hombres sufr\u00eda una deficiencia significativa de testosterona &#8211; la mayor\u00eda de los valores estaban por debajo de 8,7&nbsp;nmol\/l (&lt;2,5&nbsp;ng\/ml).<\/p>\n<p>Como ya se ha explicado al principio, una deficiencia de testosterona tan pronunciada muestra m\u00e1s a menudo s\u00edntomas y amenaza con consecuencias para la salud de los hombres afectados. En el &#8220;Estudio 20.000 sobre la testosterona&#8221; [3] del DGMG, los hombres con carencia hormonal ten\u00edan muchas m\u00e1s probabilidades de padecer hipertensi\u00f3n (+41%) y diabetes mellitus de tipo 2 (+68%).<\/p>\n<p>Adem\u00e1s, otros estudios internacionales tambi\u00e9n confirman estas conexiones entre los niveles bajos de testosterona y las enfermedades cada vez m\u00e1s extendidas de la civilizaci\u00f3n actual, hasta un mayor riesgo de enfermedades cardiovasculares.<\/p>\n<p>Importante: Si tiene una sospecha razonable de una deficiencia de testosterona en un paciente bas\u00e1ndose en los s\u00edntomas, el nivel de testosterona debe determinarse como una &#8220;prestaci\u00f3n del seguro m\u00e9dico&#8221;. Si el nivel de testosterona se confirma mediante diagn\u00f3stico de laboratorio tras dos mediciones independientes, existe hipogonadismo que requiere tratamiento y es relevante para la facturaci\u00f3n.<\/p>\n<h2 id=\"la-medicion-en-laboratorio-sigue-siendo-un-requisito-previo-para-el-diagnostico\">\u00a1La medici\u00f3n en laboratorio sigue siendo un requisito previo para el diagn\u00f3stico!<\/h2>\n<p>Si se sospecha de hipogonadismo, el nivel de testosterona puede determinarse del siguiente modo: Seg\u00fan las recomendaciones actuales de la EAU [1], el valor de testosterona en sangre debe determinarse siempre por la ma\u00f1ana, antes de las 11 horas y con el est\u00f3mago vac\u00edo. Es importante que la muestra de sangre se tome en dos fechas independientes y que la testosterona se determine utilizando un m\u00e9todo de prueba validado.<\/p>\n<p>La directriz actual de la EAU da valores orientativos para la concentraci\u00f3n de testosterona en los hombres:<\/p>\n<p><em>Testosterona total<\/em><\/p>\n<ul>\n<li>Rango normal: \u226512,1 nmol\/l (\u22653,5&nbsp;ng\/ml)<\/li>\n<li>Rango l\u00edmite: 8-12&nbsp;nmol\/l (2,3-3,5 ng\/ml)<\/li>\n<li>Deficiencia de testosterona: &lt;8&nbsp;nmol\/l (&lt;2,3 ng\/ml)<\/li>\n<\/ul>\n<p><em>Testosterona libre<\/em><\/p>\n<ul>\n<li>D\u00e9ficit de testosterona: &lt;243&nbsp;pmol\/l (=0,243&nbsp;nmol\/l; &lt;0,07&nbsp;ng\/ml)<\/li>\n<\/ul>\n<p><strong>Importante para la pr\u00e1ctica: <\/strong>Para un diagn\u00f3stico confirmado de hipogonadismo, deben determinarse al menos dos valores independientes de testosterona, ambos de los cuales muestren valores bajos de testosterona total o valores bajos de testosterona libre. Adem\u00e1s, el hombre debe presentar s\u00edntomas, por ejemplo, padecer fatiga, p\u00e9rdida de libido o desgana.<\/p>\n<h2 id=\"no-testosterona-en-ausencia-de-indicacion-medica\">No testosterona en ausencia de indicaci\u00f3n m\u00e9dica<\/h2>\n<p>Ocasionalmente, pueden acudir a la consulta pacientes que no padecen hipogonadismo pero solicitan un reemplazo de testosterona, por ejemplo, contra los cambios de humor o para aumentar la libido en momentos de estr\u00e9s. Debe explicar claramente a estos hombres que la sustituci\u00f3n con testosterona no es posible sin un hipogonadismo confirmado por laboratorio como indicaci\u00f3n relacionada con la terapia. La testosterona no es en absoluto una droga para sentirse bien para los hombres cansados. Tampoco es una bala m\u00e1gica contra la grasa del vientre y la obesidad. La terapia de reemplazo de testosterona sirve m\u00e1s bien para corregir un hipogonadismo sintom\u00e1tico confirmado por laboratorio en los hombres. Por un lado, se pretende devolver la testosterona al rango normal para la edad del paciente y, por otro, reducir el posible riesgo de enfermedades secundarias graves.<\/p>\n<p>En cambio, a los hombres con niveles de testosterona en el rango normal bajo se les debe aconsejar que sean m\u00e1s activos, que controlen su peso y que tengan una alternancia saludable de tensi\u00f3n y relajaci\u00f3n en combinaci\u00f3n con un sue\u00f1o nocturno suficiente. Esto ayudar\u00e1 a la mayor\u00eda a superar por completo el bajo estado de \u00e1nimo o el baj\u00f3n de rendimiento sin necesidad de una terapia de reemplazo de testosterona.<\/p>\n<h2 id=\"conclusion\">Conclusi\u00f3n<\/h2>\n<p>Mientras que las mujeres cambian, los hombres tienden a adelgazar, por lo que no existe una andropausia comparable a la menopausia en el verdadero sentido de la palabra. El cuadro cl\u00ednico correspondiente a la deficiencia de testosterona masculina se denomina hipogonadismo. Se trata de una enfermedad que necesita tratamiento y no de una cuesti\u00f3n de bienestar, como han demostrado ahora numerosos estudios. Si los hombres sufren una deficiencia permanente de testosterona -hasta un hipogonadismo confirmado- corren el riesgo de padecer enfermedades cardiovasculares, obesidad y diabetes mellitus de tipo 2. Las comorbilidades del hipogonadismo manifiesto no tratado cuestan a los hombres su salud y su calidad de vida, y posiblemente incluso su vida.<\/p>\n<h2 id=\"mensajes-para-llevarse-a-casa\">Mensajes para llevarse a casa<\/h2>\n<ul>\n<li>El hipogonadismo es una afecci\u00f3n com\u00fan del var\u00f3n que envejece y que requiere tratamiento. Si no se trata, existe el riesgo de sufrir enfermedades cardiovasculares,<\/li>\n<li>Obesidad y diabetes mellitus de tipo 2.<\/li>\n<li>Para un diagn\u00f3stico confirmado, deben obtenerse dos valores independientes de testosterona, ambos de los cuales muestren niveles bajos de testosterona total o niveles disminuidos de testosterona libre. Adem\u00e1s, deben estar presentes otros s\u00edntomas como la fatiga, la p\u00e9rdida de libido o la desgana.<\/li>\n<li>Por regla general, la sustituci\u00f3n con testosterona es muy eficaz. Sin embargo, s\u00f3lo debe utilizarse en casos de hipogonadismo confirmado por laboratorio.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>\nLiteratura:<\/p>\n<ol>\n<li>Dohle GR, et al: Directrices sobre el hipogonadismo masculino. Asociaci\u00f3n Europea de Urolog\u00eda 2018. https:\/\/uroweb.org\/guideline\/male-hypogonadism\/<\/li>\n<li>Vigen R, et al: Asociaci\u00f3n de la terapia de testosterona con la mortalidad, el infarto de miocardio y el ictus en hombres con niveles bajos de testosterona. JAMA 2013; 310(17): 1829-1836.<\/li>\n<li>Deutsche Gesellschaft f\u00fcr Mann und Gesundheit e.V., noviembre de 2017, &#8220;20.000 Testosterone Study of the DGMG&#8221;, www.mann-und-gesundheit.com\/aktuelles\/105-deutsche-testosteron-studie-auf-weltniveau.<\/li>\n<li>Zitzmann M, Faber S, Nieschlag E: Asociaci\u00f3n de s\u00edntomas espec\u00edficos y riesgos metab\u00f3licos con la testosterona s\u00e9rica en hombres mayores. J Clin Endocrinol Metab 2006; 91(11): 4335-4343.<\/li>\n<li>Leifke E, et al.: Cambios relacionados con la edad en los niveles s\u00e9ricos de hormonas sexuales, factor de crecimiento similar a la insulina-1 y globulina fijadora de hormonas sexuales en hombres: datos transversales de una cohorte de hombres sanos. Clin Endocrinol 2000; 53(6): 689-695.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Para saber m\u00e1s:<\/p>\n<ul>\n<li>Deutsche Gesellschaft f\u00fcr Mann und Gesundheit e. V., diciembre de 2018, &#8220;Vorsorge-Leitfaden M\u00e4nnergesundheit f\u00fcr \u00c4rztinnen und \u00c4rzte&#8221;. https:\/\/www.mann-und-gesundheit.com<\/li>\n<li>Deutsche Gesellschaft f\u00fcr Urologie e.V. Hipogonadismo: Cu\u00e1ndo es \u00fatil la terapia hormonal. Revista de negocios para el ur\u00f3logo 2016; 5.<\/li>\n<li>Hackett G, et al: Testosterona s\u00e9rica, terapia de sustituci\u00f3n de testosterona y mortalidad por cualquier causa en hombres con diabetes tipo 2: consideraci\u00f3n retrospectiva del impacto de los inhibidores de la PDE5 y las estatinas. Int J Clin Pract 2016; 70(3): 244-253.<\/li>\n<li>Haider A, Yassin A, Doros G, Saad F: Efectos de la terapia de testosterona a largo plazo en pacientes con &#8220;diabesidad&#8221;: Resultados de estudios observacionales de an\u00e1lisis agrupados en hombres obesos hipogonadales con diabetes de tipo 2. Int J Endocrinol 2014; 2014: 683515. doi: 10.1155\/2014\/683515. Epub 2014 mar 11.<\/li>\n<li>Kapoor D, Goodwin E, Channer KS, Jones TH: El tratamiento sustitutivo con testosterona mejora la resistencia a la insulina, el control gluc\u00e9mico, la adiposidad visceral y la hipercolesterolemia en hombres hipogonadales con diabetes de tipo 2. Eur J Endocrinol 2006; 154: 899-906.<\/li>\n<li>Muraleedharan V, et al: La deficiencia de testosterona se asocia a un mayor riesgo de mortalidad y el reemplazo de testosterona mejora la supervivencia en hombres con diabetes tipo 2. Eur J Endocrinol 2013; 169: 725-733.<\/li>\n<li>Rao PM, Kelly DM, Jones TH: Testosterona y resistencia a la insulina en el s\u00edndrome metab\u00f3lico y la DMT2 en hombres. Nat Rev Endocrinol 2013; 9: 479-493. doi: 10.1038\/nrendo.2013.122. Epub 2013 jun 25.<\/li>\n<li>Schipf S, et al.: La testosterona total baja se asocia con un mayor riesgo de diabetes mellitus tipo 2 incidente en hombres: resultados del Estudio de Salud en Pomerania (SHIP). Envejecimiento Masculino 2011; 14(3): 168-175. doi: 10.3109\/13685538.2010.524955. epub 2010 Nov 2.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2019; 14(5): 14-18<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuanto m\u00e1s envejecen los hombres, m\u00e1s probabilidades tienen de sufrir una deficiencia de testosterona. Pero el hipogonadismo no est\u00e1 presente hasta que se ha confirmado en dos laboratorios.<\/p>\n","protected":false},"author":7,"featured_media":89070,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Androlog\u00eda","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11352,11475,11478,11288,11552],"tags":[21860,29239,23573],"powerkit_post_featured":[],"class_list":["post-336282","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologia-y-diabetologia","category-estudios","category-formacion-continua","category-medicina-interna-general","category-rx-es","tag-deficiencia-de-testosterona-es","tag-hipogonadismo-es","tag-terapia-hormonal-sustitutiva","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:27:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/336282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=336282"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/336282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/89070"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=336282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=336282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=336282"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=336282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}