{"id":339002,"date":"2017-11-16T01:00:00","date_gmt":"2017-11-16T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/trastornos-del-crecimiento-tras-fracturas-en-la-infancia\/"},"modified":"2017-11-16T01:00:00","modified_gmt":"2017-11-16T00:00:00","slug":"trastornos-del-crecimiento-tras-fracturas-en-la-infancia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/trastornos-del-crecimiento-tras-fracturas-en-la-infancia\/","title":{"rendered":"Trastornos del crecimiento tras fracturas en la infancia"},"content":{"rendered":"<p><strong>Los trastornos estimulantes del crecimiento se producen tras cualquier fractura metadiafisaria en la infancia. Suelen provocar un mayor crecimiento de la longitud y pueden durar hasta dos a\u00f1os. Los trastornos inhibitorios del crecimiento son m\u00e1s frecuentes en las extremidades inferiores.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La mayor\u00eda de las fracturas de los ni\u00f1os no son distintas de las de los adultos, aunque las fracturas \u00f3seas del esqueleto en crecimiento presentan algunas caracter\u00edsticas especiales. El hueso infantil es m\u00e1s blando y se rompe con m\u00e1s facilidad que el hueso cortical adulto. En consecuencia, las fracturas tambi\u00e9n se producen m\u00e1s r\u00e1pidamente en los accidentes de baja energ\u00eda. El periostio es mucho m\u00e1s grueso y fuerte en el ni\u00f1o y normalmente sigue manteniendo unidos los extremos del hueso roto o facilita la reducci\u00f3n. Debido a que el hueso es m\u00e1s blando y el\u00e1stico, la deformidad pl\u00e1stica, la fractura en madera verde y la fractura en bulto tambi\u00e9n se producen como otras caracter\u00edsticas especiales en la infancia.<\/p>\n<p>Sin embargo, la mayor peculiaridad del hueso del ni\u00f1o es sin duda la presencia de placas de crecimiento cartilaginosas. Estos son responsables del crecimiento en longitud del hueso, mientras que el periostio es responsable del crecimiento en anchura aposicional. Las zonas de crecimiento dividen los huesos tubulares largos en las respectivas ep\u00edfisis y la parte \u00f3sea central conectada de las dos met\u00e1fisis y la di\u00e1fisis. Dado que la placa de crecimiento es un lugar de estabilidad mec\u00e1nica reducida, una especie de punto de ruptura predeterminado, la conexi\u00f3n entre ep\u00edfisis y met\u00e1fisis se ve reforzada adicionalmente por el anillo pericondral que rodea la placa. El cart\u00edlago de crecimiento protege el bloque articular epifisario en la medida en que las fracturas metafisarias rara vez tienen un espol\u00f3n en la articulaci\u00f3n, sino que se extienden lateralmente a lo largo del cart\u00edlago de crecimiento. Las formas de fractura en la zona de los cart\u00edlagos de crecimiento se clasifican seg\u00fan Salter-Harris <strong>(Fig. 1)<\/strong> [1]. De acuerdo con lo dicho anteriormente, las fracturas de tipo I y II son significativamente m\u00e1s frecuentes que las de tipo III y IV, en las que la ep\u00edfisis se fractura junto con el cart\u00edlago de crecimiento adherido. La fractura de tipo V es una forma especial en la que se asume retrospectivamente una lesi\u00f3n por compresi\u00f3n de la zona de crecimiento en el curso de una alteraci\u00f3n del crecimiento.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-9271\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/11\/abb1_hp10_s17.png\" style=\"height:262px; width:600px\" width=\"1100\" height=\"480\"><\/p>\n<p>&nbsp;<\/p>\n<p>Despu\u00e9s de las fracturas en edad de crecimiento, puede producirse una correcci\u00f3n espont\u00e1nea si se produce una consolidaci\u00f3n en mala posici\u00f3n durante el crecimiento. Dependiendo de la localizaci\u00f3n de la fractura y del tipo de deformidad, as\u00ed como del crecimiento restante que quepa esperar, las deformidades pueden tolerarse en diversos grados [2,3]. Sin embargo, el crecimiento no siempre muestra s\u00f3lo efectos intencionados tras una fractura que ha tenido lugar. Tambi\u00e9n se producen trastornos del crecimiento.<\/p>\n<h2 id=\"trastornos-estimulantes-del-crecimiento\">Trastornos estimulantes del crecimiento<\/h2>\n<p>Se entiende por trastorno estimulante del crecimiento un crecimiento excesivo del hueso debido a la estimulaci\u00f3n del cart\u00edlago de crecimiento adyacente. Son de esperar en diversos grados despu\u00e9s de todas las fracturas de la edad de crecimiento. Las alteraciones pronunciadas del crecimiento estimulante se producen tras realizar manipulaciones retardadas (maniobras de reducci\u00f3n repetidas) u operaciones m\u00e1s all\u00e1 del quinto d\u00eda, as\u00ed como con una larga duraci\u00f3n de la remodelaci\u00f3n, y pueden durar hasta un m\u00e1ximo de dos a\u00f1os. En consecuencia, para evitar una estimulaci\u00f3n prolongada de la articulaci\u00f3n, no deben dejarse malposiciones relevantes (varo, valgo, anteversi\u00f3n o recurvaci\u00f3n o desplazamiento lateral) a las fuerzas correctoras del crecimiento posterior, si es posible [2].<\/p>\n<p>Hoy en d\u00eda, las fracturas de f\u00e9mur en edad escolar suelen tratarse con clavos intramedulares el\u00e1sticos<strong> (Fig.&nbsp;2)<\/strong> [4]. Se ha demostrado que un di\u00e1metro menor de estos clavos intramedulares el\u00e1sticos es un factor de riesgo para un crecimiento adicional m\u00e1s fuerte. Probablemente, la estimulaci\u00f3n prolongada debida a una oferta menos estable es tambi\u00e9n la raz\u00f3n de que el crecimiento adicional sea m\u00e1s fuerte en este caso [5]. La colocaci\u00f3n de clavos intramedulares el\u00e1sticos permite retirar el material tras s\u00f3lo cuatro meses [4], en un momento en el que a\u00fan no se aprecia una diferencia significativa en la longitud de las piernas. Desgraciadamente, a menudo no se realizan m\u00e1s ex\u00e1menes de seguimiento, y una discrepancia en la longitud de las piernas que se produce en el transcurso del procedimiento suele pasar desapercibida. En consecuencia, es sensato y deseable que el m\u00e9dico de cabecera resp. En tales situaciones, el pediatra presta especial atenci\u00f3n a una posible diferencia de longitud de las piernas con ocasi\u00f3n de los ex\u00e1menes de detecci\u00f3n. Aunque s\u00f3lo debe suponerse una carga desfavorable para la espalda a partir de una diferencia de longitud de las piernas superior a 1,5&nbsp;cm, lo decisivo no es tanto el valor absoluto como el efecto funcional sobre la est\u00e1tica de la columna vertebral. Mediante un examen funcional con una tabla bajo la pierna m\u00e1s corta, se puede observar la influencia en la posici\u00f3n de la pelvis y la simetr\u00eda de los tri\u00e1ngulos de la cintura. Si existen afecciones claramente asim\u00e9tricas que s\u00f3lo mejoran de forma relevante tras una subcaptaci\u00f3n de 1&nbsp;cm o m\u00e1s, es aconsejable una aclaraci\u00f3n ortop\u00e9dica adicional.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9272 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/11\/abb2-hp10_s18.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1670;height:911px; width:600px\" width=\"1100\" height=\"1670\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Ciertas fracturas tambi\u00e9n pueden provocar alteraciones asim\u00e9tricas estimuladoras del crecimiento. Un buen ejemplo de ello es la fractura metafisaria proximal de tibia, que en realidad parece trivial en un primer momento <strong>(Fig.&nbsp;3)<\/strong>. En este caso, la estimulaci\u00f3n del cart\u00edlago de crecimiento cercano de la tibia medial puede provocar el desarrollo de una pierna arqueada en aumento, que en muchos casos requiere una intervenci\u00f3n quir\u00fargica.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9273 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/11\/abb3_hp10_s18.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/823;height:449px; width:600px\" width=\"1100\" height=\"823\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"inhibicion-de-los-trastornos-del-crecimiento\">Inhibici\u00f3n de los trastornos del crecimiento<\/h2>\n<p>Los trastornos inhibitorios del crecimiento pueden producirse tras fracturas que atraviesan directamente el cart\u00edlago de crecimiento. Esto puede provocar un cierre parcial de la articulaci\u00f3n o de la propia articulaci\u00f3n. de un puente \u00f3seo que une la articulaci\u00f3n, lo que da lugar a un defecto axial. El cierre completo de un cart\u00edlago de crecimiento es menos frecuente y es m\u00e1s probable que se produzca con lesiones articulares en ni\u00f1os cerca del final del crecimiento. Por lo tanto, el acortamiento resultante de la secci\u00f3n afectada del esqueleto ya no suele ser cl\u00ednicamente relevante. Estos trastornos inhibitorios del crecimiento se producen con mucha m\u00e1s frecuencia en las extremidades inferiores (30%) que en las superiores (3%) tras fracturas articulares. En consecuencia, es importante informar al paciente resp. informar de ello a su familia en caso de lesiones articulares del miembro inferior.<\/p>\n<p>En las fracturas de Salter-Harris de tipo II, que no atraviesan el cart\u00edlago de crecimiento, se producen alteraciones inhibitorias del crecimiento en el radio distal en un 0-4% de los casos seg\u00fan el estudio [6], pero en el f\u00e9mur distal en m\u00e1s de la mitad de los casos [7]. Una de las razones de esta diferencia podr\u00eda ser que los cart\u00edlagos de crecimiento del miembro inferior deben tener una mayor resistencia a la tensi\u00f3n mec\u00e1nica. Por lo tanto, para una disrupci\u00f3n de esta placa de crecimiento es necesario un traumatismo de mayor energ\u00eda, con el correspondiente mayor riesgo de da\u00f1ar la placa de crecimiento. En estos casos, la aparici\u00f3n de un trastorno del crecimiento debe considerarse &#8220;predestinada&#8221; y directamente causada por el trauma. Si la reducci\u00f3n anat\u00f3mica de estas fracturas que no atraviesan la articulaci\u00f3n puede reducir el riesgo de alteraciones del crecimiento es cuestionable seg\u00fan los datos disponibles. No obstante, el restablecimiento de los ejes anat\u00f3micos correctos y una fijaci\u00f3n estable en yeso o con alambres o tornillos parecen ciertamente aconsejables.<\/p>\n<p>La situaci\u00f3n es diferente para las fracturas Salter-Harris III y IV que atraviesan el cart\u00edlago de crecimiento. En estas fracturas suele estar implicada la articulaci\u00f3n, por lo que una fractura dislocada conduce inevitablemente a un escal\u00f3n en la articulaci\u00f3n (fractura articular). La dehiscencia a nivel del cart\u00edlago de crecimiento puede llenarse de hueso durante la curaci\u00f3n de la fractura y dar lugar a un puente. Los puentes \u00f3seos muy peque\u00f1os no pueden frenar el crecimiento o son reventados por \u00e9ste. En el caso de un desplazamiento vertical de los dos fragmentos, suelen producirse malposiciones dif\u00edciles de tratar tras la cicatrizaci\u00f3n. El mejor ejemplo es la fractura Salter-Harris III\/IV del mal\u00e9olo medial (conocida como &#8220;fractura de tobillo&#8221;). Fractura McFarland, <strong>Fig.&nbsp;4) <\/strong>. El desplazamiento del fragmento del mal\u00e9olo medial hacia el lado craneal crea un puente \u00f3seo en el lado interno. Un mayor crecimiento en el exterior de la tibia y el peron\u00e9 conduce a una mala alineaci\u00f3n en varo de la articulaci\u00f3n superior del tobillo, el trastorno de crecimiento m\u00e1s com\u00fan de la articulaci\u00f3n superior del tobillo [8]. Por consiguiente, en el caso de las fracturas que atraviesan el cart\u00edlago de crecimiento, el riesgo de alteraciones inhibitorias del crecimiento puede minimizarse, aunque no eliminarse por completo, mediante un tratamiento correcto.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-9274 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2017\/11\/abb4_hp10_s19.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/706;height:385px; width:600px\" width=\"1100\" height=\"706\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"cuidados-posteriores-a-la-fractura-y-opciones-de-tratamiento-para-los-trastornos-del-crecimiento\">Cuidados posteriores a la fractura y opciones de tratamiento para los trastornos del crecimiento<\/h2>\n<p>A diferencia de las fracturas de la extremidad superior, el autor considera \u00fatil un seguimiento tras las fracturas metadiafisarias de los huesos largos de la extremidad inferior al cabo de al menos dos a\u00f1os, con el fin de detectar cualquier alteraci\u00f3n estimulada pronunciada del crecimiento con la consiguiente diferencia relevante de la longitud de las piernas. En el caso de las fracturas del cart\u00edlago de crecimiento, los intervalos de control deben ajustarse individualmente en funci\u00f3n de la edad del paciente. Las llamadas &#8220;l\u00edneas Harris de detenci\u00f3n del crecimiento&#8221; han demostrado ser \u00fatiles para la detecci\u00f3n precoz de un trastorno del crecimiento. Se trata de l\u00edneas claramente visibles radiol\u00f3gicamente que corresponden a la multiesclerosis del hueso. Se producen con regularidad tras un traumatismo y deber\u00edan alejarse del cart\u00edlago de crecimiento de forma paralela a lo largo del crecimiento <strong>(Fig.&nbsp;4C); <\/strong>si no es as\u00ed, puede tratarse de un signo precoz de alteraci\u00f3n del crecimiento. Es \u00fatil realizar un TAC para identificar los puentes \u00f3seos. Los peque\u00f1os puentes \u00f3seos pueden perforarse y rellenarse con cemento \u00f3seo o tejido graso para permitir el recrecimiento si es necesario. En el caso de un puente \u00f3seo grande, s\u00f3lo se puede cerrar quir\u00fargicamente todo el cart\u00edlago de crecimiento para evitar una malposici\u00f3n axial m\u00e1s pronunciada. Para corregir las alteraciones estimulantes del crecimiento, se suele recurrir a la gu\u00eda del crecimiento (epifisiodesis), en la que se puentea temporalmente el cart\u00edlago de crecimiento con una plaqueta o una pinza y, de este modo, se frena <strong>(Fig.&nbsp;2 y 3)<\/strong>. En caso de acortamiento pronunciado o de desalineaciones axiales, son necesarias reconstrucciones complejas con alargamiento \u00f3seo mediante un fijador anular externo o un clavo intramedular.<\/p>\n<h2 id=\"mensajes-para-llevarse-a-casa\">Mensajes para llevarse a casa<\/h2>\n<ul>\n<li>Las alteraciones estimulantes del crecimiento se producen tras cualquier fractura metadiafisaria en la infancia y suelen provocar un aumento del crecimiento en longitud. Pueden durar hasta dos a\u00f1os.<\/li>\n<li>Las fracturas que afectan directamente al cart\u00edlago de crecimiento se clasifican seg\u00fan Salter-Harris. Tras una fractura de este tipo, puede producirse un trastorno inhibitorio del crecimiento. \u00c9stas se producen con mucha m\u00e1s frecuencia en las extremidades inferiores.<\/li>\n<li>Los ni\u00f1os deben someterse a un control de la discrepancia en la longitud de las piernas tras una fractura de los huesos largos de la extremidad inferior a los dos a\u00f1os. En el caso de lesiones del cart\u00edlago de crecimiento de las extremidades inferiores, es aconsejable un seguimiento individualizado por parte de un especialista.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Salter RB, Harris WR: Lesiones que afectan a la placa epifisaria. J Bone Joint Surg Am 1963; 45(3): 587-622.<\/li>\n<li>Laer L, Kraus R, Linhart WE: Fracturas y luxaciones en la edad de crecimiento. 6\u00aa edici\u00f3n. Thieme-Verlag 2012.<\/li>\n<li>Flynn J: Rockwood &amp; Wilkins Fracturas en ni\u00f1os. Lippincott Williams y Wilkins 2014.<\/li>\n<li>Lascombes P: Clavado intramedular flexible en ni\u00f1os: El manual de la Universidad de Nancy. Springer 2009.<\/li>\n<li>Park SS, Noh H, Kam M: Factores de riesgo de sobrecrecimiento tras el enclavado intramedular flexible para fracturas de la di\u00e1fisis femoral en ni\u00f1os. Bone Joint J 2013; 95-B(2): 254-258.<\/li>\n<li>Larsen MC, et al: Resultados del tratamiento no quir\u00fargico de las fracturas de radio distal Salter-Harris II: Una revisi\u00f3n sistem\u00e1tica. Mano (N Y) 2016; 11(1): 29-35.<\/li>\n<li>Basener CJ, Mehlman CT, DiPasquale TG: Alteraciones del crecimiento tras fracturas del cart\u00edlago de crecimiento femoral distal en ni\u00f1os: un metaan\u00e1lisis. J Orthop Trauma 2009; 23(9): 663-667.<\/li>\n<li>Schneider FJ, Linhart WE: Complicaciones postraum\u00e1ticas del tobillo pedi\u00e1trico. Ortopedia 2013; 42: 665-678.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2017; 12(10): 16-20<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los trastornos estimulantes del crecimiento se producen tras cualquier fractura metadiafisaria en la infancia. Suelen provocar un mayor crecimiento de la longitud y pueden durar hasta dos a\u00f1os. Los trastornos&hellip;<\/p>\n","protected":false},"author":7,"featured_media":71140,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Traumatolog\u00eda pedi\u00e1trica","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11288,11398,11402,11552,11292],"tags":[35990,26846,35984,12561,35996,25431],"powerkit_post_featured":[],"class_list":["post-339002","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-medicina-interna-general","category-ortopedia","category-pediatria","category-rx-es","category-traumatologia-y-cirugia-traumatologica","tag-crecimiento","tag-cuidado-posterior","tag-fracturas-es","tag-ninos","tag-trastorno-del-crecimiento","tag-traumatologia-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:38:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/339002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=339002"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/339002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/71140"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=339002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=339002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=339002"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=339002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}