{"id":339404,"date":"2017-09-10T02:00:00","date_gmt":"2017-09-10T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/panorama-de-la-terapia-en-2017-y-que-viene-despues\/"},"modified":"2017-09-10T02:00:00","modified_gmt":"2017-09-10T00:00:00","slug":"panorama-de-la-terapia-en-2017-y-que-viene-despues","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/panorama-de-la-terapia-en-2017-y-que-viene-despues\/","title":{"rendered":"Panorama de la terapia en 2017 &#8211; \u00bfy qu\u00e9 viene despu\u00e9s?"},"content":{"rendered":"<p><strong>El Prof. Dr. med. Paul Hasler, Jefe de Reumatolog\u00eda del Hospital Cantonal de Aarau, habl\u00f3 sobre la nueva aprobaci\u00f3n de baricitinib en la indicaci\u00f3n de AR activa de moderada a grave con HAUSARZT PRAXIS. \u00bfD\u00f3nde encaja el nuevo principio activo en el ya amplio espectro de terapias? Adem\u00e1s, se debatieron las novedades del congreso EULAR de este a\u00f1o y las investigaciones que probablemente ocupar\u00e1n al mundo profesional en el futuro.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><strong>Profesor Hasler, \u00bfcu\u00e1l es el tratamiento est\u00e1ndar actual para la artritis reumatoide (AR)? \u00bfC\u00f3mo encaja en el espectro terap\u00e9utico el baricitinib, un inhibidor de la cinasa Janus aprobado recientemente en esta indicaci\u00f3n, y con qu\u00e9 r\u00e9gimen terap\u00e9utico se utiliza?<\/strong><\/p>\n<p><em><br \/>\n  <strong>Prof. Dr. Hasler: <\/strong><br \/>\n<\/em>Para el diagn\u00f3stico y la clasificaci\u00f3n se utilizan los criterios ACR\/EULAR revisados de 2010 [1]. \u00c9stas pretenden ofrecer una sensibilidad y una especificidad relativamente altas incluso en las primeras fases de la artritis; sin embargo, la precisi\u00f3n diagn\u00f3stica disminuye de forma natural en las primeras fases en comparaci\u00f3n con las \u00faltimas. B\u00e1sicamente, cuanto antes empiece el tratamiento, mejor. As\u00ed que el objetivo es detectar, diagnosticar y tratar la enfermedad lo antes posible.<\/p>\n<p>Seg\u00fan el algoritmo EULAR [2], se empieza primero con el preparado est\u00e1ndar metotrexato (MTX) o con terapias b\u00e1sicas comparables como la leflunomida, menos sulfasalazina o hidroxicloroquina. Existen diferentes preferencias entre los reumat\u00f3logos en cuanto a la combinaci\u00f3n de estos agentes; en la AR grave, por ejemplo, es posible una combinaci\u00f3n triple de MTX, sulfasalazina e hidroxicloroquina (si es necesario, combinada con prednisona).<\/p>\n<p>Sin embargo, uno procede: despu\u00e9s de tres meses de terapia inicial, ya deber\u00eda haber una buena respuesta. La consecuci\u00f3n del objetivo terap\u00e9utico real, es decir, la &#8220;ausencia de actividad de la enfermedad&#8221; (es decir, la &#8220;remisi\u00f3n&#8221;) debe comprobarse al cabo de seis meses. Seg\u00fan el caso, el objetivo tambi\u00e9n puede ser la m\u00e1xima mejor\u00eda de acuerdo con el paciente, es decir, la menor actividad posible de la enfermedad con una terapia tolerable (si la remisi\u00f3n parece improbable).<\/p>\n<p>Si no se alcanza el objetivo de la terapia, hay que buscar una alternativa. Si la primera terapia b\u00e1sica no ha funcionado lo suficiente o no se ha tolerado, puede realizarse una combinaci\u00f3n o un cambio. Tambi\u00e9n existe la opci\u00f3n de utilizar un biol\u00f3gico o un inhibidor de JAK [2].<\/p>\n<p>Siempre que sea posible, el MTX sigue utiliz\u00e1ndose de forma concomitante, ya que potencia significativamente el efecto de los inhibidores del TNF, la inhibici\u00f3n de la coestimulaci\u00f3n con abatacept y la terapia contra las c\u00e9lulas B con rituximab en particular. Aunque esto es menos pronunciado con los inhibidores de JAK y con la inhibici\u00f3n de IL con tocilizumab, en este caso tambi\u00e9n se recomienda la combinaci\u00f3n con MTX. Los pacientes que antes toleraban bien el MTX pero para los que \u00e9ste ten\u00eda un efecto insuficiente pueden beneficiarse de dicha combinaci\u00f3n. Si no se tolera el MTX, por ejemplo, puede utilizarse tocilizumab o baricitinib como monoterapia. En este caso, los datos son significativamente mejores que con la monoterapia con los inhibidores del TNF tradicionales (aunque los registros muestran que un porcentaje considerable de pacientes tambi\u00e9n responden bien con la monoterapia con inhibidores del TNF).<\/p>\n<p><strong>\u00bfQu\u00e9 pacientes se beneficiar\u00e1n m\u00e1s de la nueva aprobaci\u00f3n?<\/strong><\/p>\n<p>Por un lado, los pacientes que no desean ninguna inyecci\u00f3n o no desean ninguna inyecci\u00f3n adem\u00e1s del MTX, es decir, prefieren una terapia oral (una vez al d\u00eda en el caso del baricitinib). Por otro lado, aquellos que no mejoraron lo suficiente con MTX o que no respondieron a los biol\u00f3gicos (o al inhibidor de JAK tofacitinib, aprobado desde hace tiempo).<\/p>\n<p>La dosis habitual de baricitinib es de 4&nbsp;mg\/d\u00eda. En caso de insuficiencia renal con un aclaramiento entre 30 y 60&nbsp;ml\/min\/1,73&nbsp;<sup>m2<\/sup> o si el paciente presenta riesgo de infecci\u00f3n (infecciones cr\u00f3nicas o recurrentes), se recomienda la dosis reducida de 2&nbsp;mg\/d\u00eda. Adem\u00e1s, tambi\u00e9n se puede considerar bajar la dosis a 2&nbsp;mg\/d\u00eda a modo de prueba si hay una remisi\u00f3n m\u00e1s prolongada con la dosis m\u00e1s alta (m\u00e1s quiz\u00e1s MTX concomitante). Porque en \u00faltima instancia, como en todas partes en medicina, el cumplimiento del paciente es un factor muy decisivo para el \u00e9xito de la terapia.<\/p>\n<p><strong>\u00bfCu\u00e1l es el principio de acci\u00f3n y la situaci\u00f3n de los estudios cl\u00ednicos en el campo de los inhibidores de la Janus quinasa (o qu\u00e9 otros representantes de esta clase de agentes activos existen)?<\/strong><\/p>\n<p>El efecto sobre la hematopoyesis, la inflamaci\u00f3n y la funci\u00f3n inmunitaria se debe a la inhibici\u00f3n de las Janus quinasas (son cuatro, JAK 1, 2, 3 y TYK 2). Adem\u00e1s de la AR, los inhibidores de JAK tambi\u00e9n se est\u00e1n investigando en otras enfermedades que responden a estos mecanismos de acci\u00f3n, desde la psoriasis y la artritis psori\u00e1sica hasta la espondiloartritis seronegativa y las colagenosis.<\/p>\n<p>Otro inhibidor de la quinasa Janus es el tofacitinib. El baricitinib y el tofacitinib se excretan por v\u00eda renal, el tofacitinib tambi\u00e9n se metaboliza hep\u00e1ticamente. Personalmente, comprobar\u00eda la formaci\u00f3n de sangre y los valores hep\u00e1ticos en ambos representantes (entre otras cosas, para comprobar si los granulocitos neutr\u00f3filos est\u00e1n reducidos). Se ha informado de que los dolores de cabeza son menos frecuentes con baricitinib que con tofacitinib. La situaci\u00f3n del estudio del baricitinib tambi\u00e9n parece muy prometedora en lo que respecta a los efectos secundarios hep\u00e1ticos.<\/p>\n<p>Existen varios ensayos de fase III de baricitinib que abarcan poblaciones clave de AR. Entre ellos se incluyen los pacientes sin MTX o con s\u00f3lo dosis bajas de MTX o terap\u00e9utica b\u00e1sica convencional [3], y los que no respondieron o no toleraron los biol\u00f3gicos adem\u00e1s del MTX [4,5].<\/p>\n<p><strong>\u00bfContra qu\u00e9 agentes se compar\u00f3 el baricitinib y en qu\u00e9 criterios de valoraci\u00f3n cl\u00ednicos demostr\u00f3 su \u00e9xito?<\/strong><\/p>\n<p>El baricitinib se compar\u00f3 con placebo, MTX, el inhibidor del TNF adalimumab y tras el fracaso de varios biol\u00f3gicos de diferentes mecanismos de acci\u00f3n [3\u20135]. El criterio de valoraci\u00f3n primario en cada caso fue la respuesta ACR20. Algunos datos: Por ejemplo, el baricitinib de 4 mg fue superior a la monoterapia con MTX despu\u00e9s de 24 semanas (77 frente a 62%; p\u22640,01) [3]. Con los DMARD convencionales de fondo, funcion\u00f3 mejor que el placebo (en la dosis de 4 mg, 55 frente a 27%, p&lt;0,001 y 70 frente a 40%, p&lt;0,001) [4,5] y el adalimumab (70 frente a 61%, p=0,014) [4] tras 12 semanas. Adem\u00e1s, se encontraron beneficios en varios criterios de valoraci\u00f3n secundarios, por ejemplo, DAS28-CRP.<\/p>\n<p><strong>\u00bfC\u00f3mo eval\u00faa el perfil de seguridad?<\/strong><\/p>\n<p>Considero que el perfil de seguridad es bueno; no hay se\u00f1ales de seguridad decisivas que hagan que la gente se siente y tome nota. Por supuesto, habr\u00e1 que hacer un seguimiento de los datos a largo plazo de los estudios de extensi\u00f3n actualmente en curso. Se aplica a todos los preparados: Especialmente con respecto a las infecciones, que pueden brotar de repente y agravarse, hay que estar muy atento. Pueden producirse diverticulitis y perforaciones, sobre todo en la poblaci\u00f3n anciana con AR. Las vacunas deben mantenerse al d\u00eda, se recomienda la vacunaci\u00f3n anual contra la gripe. En caso de zoster, la terapia antiviral debe iniciarse inmediatamente (es decir, los pacientes deben ser informados convenientemente para poder reaccionar con rapidez incluso en caso de pr\u00f3dromos).<\/p>\n<p>Hasta el momento, no existen pruebas de que los aumentos de los par\u00e1metros lip\u00eddicos observados con otros agentes para la AR, como el tofacitinib y los anti-TNF, cursen con un aumento de los acontecimientos adversos cardiacos mayores (MACE). Los par\u00e1metros lip\u00eddicos deben determinarse en consecuencia y los pacientes deben ser tratados seg\u00fan las directrices para la hiperlipidemia.<\/p>\n<p><strong>\u00bfHubo alg\u00fan otro hallazgo importante en el campo de la artritis reumatoide en el Congreso EULAR 2017, que tuvo lugar en Madrid en junio?<\/strong><\/p>\n<p>Por ejemplo, se debati\u00f3 el estado de la investigaci\u00f3n en el campo de los biosimilares, que, al igual que los biol\u00f3gicos, han experimentado entretanto un gran desarrollo. Sin embargo, su introducci\u00f3n es todav\u00eda bastante t\u00edmida; primero deben demostrar su val\u00eda en la pr\u00e1ctica cl\u00ednica diaria y en estudios posteriores a la comercializaci\u00f3n. Hasta ahora, los datos sobre el cambio de un preparado original a un biosimilar correspondiente son limitados &#8211; el llamado estudio NOR-SWITCH [6] fue el tema de debate en el congreso, y habr\u00e1 m\u00e1s. El margen de no inferioridad se defini\u00f3 como el 15% en NOR-SWITCH. La pregunta ahora es: si la enfermedad apenas se controla con el f\u00e1rmaco originario, \u00bfperderemos el control con el biosimilar a la misma dosis?<\/p>\n<p>Adem\u00e1s, hay otros inhibidores de JAK en desarrollo, espero que en unos a\u00f1os dispongamos de una amplia gama de estos agentes.<\/p>\n<p><strong>\u00bfD\u00f3nde ve los futuros campos de investigaci\u00f3n?<\/strong><\/p>\n<p>Desde el punto de vista epidemiol\u00f3gico, el profesor Axel Finckh de Ginebra, entre otros, est\u00e1 llevando a cabo interesantes enfoques que investigan la influencia del tabaquismo, la contaminaci\u00f3n atmosf\u00e9rica y las infecciones v\u00edricas\/bacterianas en el desarrollo y la evoluci\u00f3n de la enfermedad.<\/p>\n<p>En el futuro, puede que tambi\u00e9n sea posible conseguir buenos resultados en el tratamiento influyendo en los granulocitos neutr\u00f3filos. Un pionero en este campo de investigaci\u00f3n es el profesor Gerd Burmester, de Berl\u00edn. Actualmente se est\u00e1n probando anticuerpos apropiados contra el GM-CSF y el G-CSF (factores estimulantes de colonias de granulocitos [macr\u00f3fagos]). El GM-CSF y el G-CSF desempe\u00f1an un papel clave en la activaci\u00f3n de los neutr\u00f3filos. La cuesti\u00f3n aqu\u00ed ser\u00e1 c\u00f3mo pueden combinarse estos anticuerpos con otros agentes como el MTX o la leflunomida sin poner en riesgo a los pacientes, y c\u00f3mo pueden detectarse con antelaci\u00f3n los cursos graves para justificar dicha terapia.<\/p>\n<p><em>Entrevista: Andreas Grossmann<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Aletaha D, et al: 2010 rheumatoid arthritis classification criteria: an American College of Rheumatology\/European League Against Rheumatism collaborative initiative. Ann Rheum Dis 2010; 69(9): 1580-1588.<\/li>\n<li>Smolen JS, et al: Recomendaciones de la EULAR para el tratamiento de la artritis reumatoide con f\u00e1rmacos antirreum\u00e1ticos modificadores de la enfermedad sint\u00e9ticos y biol\u00f3gicos: actualizaci\u00f3n de 2016. Ann Rheum Dis 2017; 76(6): 960-977.<\/li>\n<li>Fleischmann R, et al: Baricitinib, metotrexato o combinaci\u00f3n en pacientes con artritis reumatoide y tratamiento previo nulo o limitado con f\u00e1rmacos antirreum\u00e1ticos modificadores de la enfermedad. Artritis y Reumatolog\u00eda 2017; 69(3): 506-517.<\/li>\n<li>Taylor PC, et al: Baricitinib frente a placebo o adalimumab en la artritis reumatoide. N Engl J Med 2017; 376: 652-662.<\/li>\n<li>Genovese MC, et al: Baricitinib en pacientes con artritis reumatoide refractaria. N Engl J Med 2016; 374: 1243-1252.<\/li>\n<li>J\u00f8rgensen KK, et al: Cambio del infliximab originario al biosimilar CT-P13 en comparaci\u00f3n con el tratamiento mantenido con infliximab originario (NOR-SWITCH): un ensayo aleatorizado, doble ciego y de no inferioridad de 52 semanas de duraci\u00f3n. Lancet 2017; 389(10086): 2304-2316.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2017; 12(8): 8-9<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Prof. Dr. med. Paul Hasler, Jefe de Reumatolog\u00eda del Hospital Cantonal de Aarau, habl\u00f3 sobre la nueva aprobaci\u00f3n de baricitinib en la indicaci\u00f3n de AR activa de moderada a&hellip;<\/p>\n","protected":false},"author":7,"featured_media":69623,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Artritis reumatoide","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11487,11288,11470,11451,11552],"tags":[14323,17623,19223,19988],"powerkit_post_featured":[],"class_list":["post-339404","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entrevistas","category-medicina-interna-general","category-noticias","category-reumatologia","category-rx-es","tag-artritis-reumatoide","tag-baricitinib-es","tag-eular-es","tag-ra-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:28:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/339404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=339404"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/339404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/69623"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=339404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=339404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=339404"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=339404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}