{"id":340564,"date":"2016-12-05T01:00:00","date_gmt":"2016-12-05T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/tratamiento-y-pronostico-de-los-linfomas-cutaneos\/"},"modified":"2016-12-05T01:00:00","modified_gmt":"2016-12-05T00:00:00","slug":"tratamiento-y-pronostico-de-los-linfomas-cutaneos","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/tratamiento-y-pronostico-de-los-linfomas-cutaneos\/","title":{"rendered":"Tratamiento y pron\u00f3stico de los linfomas cut\u00e1neos"},"content":{"rendered":"<p><strong>Los linfomas cut\u00e1neos son un grupo heterog\u00e9neo de enfermedades neopl\u00e1sicas que surgen de la proliferaci\u00f3n clonal de linfocitos en la piel. En general, los linfomas cut\u00e1neos son formas poco frecuentes de c\u00e1ncer de piel, con una prevalencia de 1:100.000 habitantes. La micosis fungoide (MF) es el linfoma cut\u00e1neo de c\u00e9lulas T (LCCT) m\u00e1s frecuente. Los estadios iniciales de la MF se tratan principalmente de forma t\u00f3pica con corticosteroides, fototerapia o radioterapia local. Desde 2008 existe una clasificaci\u00f3n uniforme de la OMS de los linfomas cut\u00e1neos primarios (basada en la EORTC\/OMS). Se distingue entre linfomas de c\u00e9lulas T y B, lo que tambi\u00e9n es relevante desde el punto de vista cl\u00ednico y terap\u00e9utico. Los linfomas cut\u00e1neos tienen un pron\u00f3stico y una terapia completamente diferentes a los linfomas ganglionares histol\u00f3gicamente comparables.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Los linfomas cut\u00e1neos son enfermedades neopl\u00e1sicas de la piel que se desarrollan cuando los linfocitos degenerados empiezan a crecer sin control. Los linfomas de los ganglios linf\u00e1ticos son especialmente conocidos. Pueden surgir en todos los \u00f3rganos del sistema linf\u00e1tico, incluidos el bazo, el timo y las am\u00edgdalas. Si los linfocitos de la piel degeneran, se forman linfomas cut\u00e1neos. Los linfomas cut\u00e1neos son linfomas no Hodgkin. Seg\u00fan el tipo de linfocito que se convierta en neopl\u00e1sico, se distingue entre linfomas cut\u00e1neos de c\u00e9lulas T y de c\u00e9lulas B <strong>(tab.&nbsp;1)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-8027\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0.png\" style=\"height:651px; width:600px\" width=\"1100\" height=\"1193\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0-800x868.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0-120x130.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0-90x98.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0-320x347.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab1_dp6_s7_0-560x607.png 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Esta clasificaci\u00f3n tambi\u00e9n tiene mucho sentido, ya que los linfomas de c\u00e9lulas T y B difieren significativamente entre s\u00ed tanto en el comportamiento cl\u00ednico como en el pron\u00f3stico. Los linfomas de c\u00e9lulas T suelen ser m\u00e1s agresivos que los de c\u00e9lulas B y, por tanto, tienen peor pron\u00f3stico. Los dos tipos de linfoma cut\u00e1neo tambi\u00e9n difieren en su aspecto: los linfomas de c\u00e9lulas T suelen aparecer generalizados por todo el cuerpo, mientras que los linfomas de c\u00e9lulas B suelen aparecer como tumores solitarios <strong>(Fig.&nbsp;1)<\/strong> [1].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8028 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/abb1-dp6_s7.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/409;height:297px; width:800px\" width=\"1100\" height=\"409\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"linfomas-cutaneos-de-celulas-t-y-subtipos\">Linfomas cut\u00e1neos de c\u00e9lulas T y subtipos<\/h2>\n<p>El linfoma cut\u00e1neo de c\u00e9lulas T m\u00e1s frecuente es la micosis fungoide (MF), hoy en d\u00eda apenas conocida como &#8220;liquen de usura&#8221;. El enga\u00f1oso nombre de micosis fungoide fue introducido en 1832 por Jean-Louis-Marc Alibert bajo el supuesto de que se trataba de una enfermedad f\u00fangica. Sin embargo, la etiolog\u00eda de la micosis fungoide, as\u00ed como de todos los dem\u00e1s linfomas cut\u00e1neos, sigue sin estar clara. Las quemaduras solares, como en el caso del melanoma, no son una posible causa de linfomas cut\u00e1neos. Hasta la fecha, s\u00f3lo se ha confirmado que las altas dosis de radiaci\u00f3n radiactiva constituyen un factor de riesgo. El da\u00f1o al material gen\u00e9tico de los linfocitos causado por la radiaci\u00f3n provoca la degeneraci\u00f3n de la divisi\u00f3n celular y la proliferaci\u00f3n clonal de las c\u00e9lulas. Sin embargo, los linfocitos tambi\u00e9n pueden degenerar sin sufrir da\u00f1os externos porque son c\u00e9lulas que se dividen r\u00e1pidamente. Los errores de lectura espont\u00e1neos en el material gen\u00e9tico pueden dar lugar a linfomas [1].<\/p>\n<p><strong>Micosis fungoide (MF): <\/strong>A menudo muestra un curso cl\u00ednico t\u00edpico en fases. La fase inicial muestra una <em>etapa<\/em> lenta y progresiva en forma <em>de parche<\/em> tipo eczema<strong><em> <\/em>(Fig.&nbsp;2)<\/strong>. Cl\u00ednicamente, las alteraciones aparecen como cambios eccematosos en la piel. Esta fase puede persistir durante a\u00f1os y despu\u00e9s puede pasar a la <em>fase de placa<\/em> <strong>(Fig.&nbsp;4) <\/strong>. En esta fase, las lesiones son palpables y est\u00e1n engrosadas. Adem\u00e1s, el estadio de placa puede transformarse en el <em>estadio tumoral<\/em>, cl\u00ednicamente a menudo muy impresionante. Sin embargo, estas etapas no tienen por qu\u00e9 sucederse una tras otra a la manera cl\u00e1sica. Por ejemplo, puede observarse una transici\u00f3n de la fase de parche directamente a la fase tumoral o a la forma eritrodematosa, el llamado s\u00edndrome de S\u00e9zary (SS) <strong>(Fig.&nbsp;5)<\/strong>. La denominada variante leuc\u00e9mica de la micosis fungoide muestra una leucocitosis de entre 10.000-50.000 (raramente hasta 100.000 leucocitos\/ml). Se trata de un cuadro cl\u00ednico grave.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8029 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/abb4-5_dp6_s8.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/394;height:287px; width:800px\" width=\"1100\" height=\"394\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>S\u00edndrome de S\u00e9zary: <\/strong>Se entiende como la variante leuc\u00e9mica de la micosis fungoide y tambi\u00e9n tiene un pron\u00f3stico significativamente peor que \u00e9sta <strong>(Tab.&nbsp;5)<\/strong>. Las llamadas c\u00e9lulas de S\u00e9zary (linfocitos at\u00edpicos) se encuentran en la sangre perif\u00e9rica. Adem\u00e1s, la inflamaci\u00f3n de los ganglios linf\u00e1ticos es palpable en estos pacientes y la eritrodermia es cl\u00ednicamente aparente. El paciente suele experimentar un prurito intenso y el estado general suele reducirse considerablemente.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8030 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab5_dp6_s12.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/515;height:281px; width:600px\" width=\"1100\" height=\"515\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Linfoma<\/strong> cut\u00e1neo de c\u00e9lulas T CD30+ de c\u00e9lulas grandes: Histol\u00f3gicamente, el linfoma cut\u00e1neo de c\u00e9lulas T CD30+ de c\u00e9lulas grandes corresponde al del linfoma ganglionar del mismo tipo. Sin embargo, el pron\u00f3stico es diametralmente distinto y, por lo tanto, tambi\u00e9n debe tratarse terap\u00e9uticamente de forma diferente. El pron\u00f3stico de los linfomas ganglionares de este tipo es muy desfavorable y requiere una quimioterapia costosa. Sin embargo, en el linfoma cut\u00e1neo de c\u00e9lulas T CD30+ de c\u00e9lulas grandes (pleom\u00f3rfico o anapl\u00e1sico), el pron\u00f3stico es excelente y la quimioterapia est\u00e1 contraindicada.<\/p>\n<h2 id=\"linfomas-cutaneos-de-celulas-b\">Linfomas cut\u00e1neos de c\u00e9lulas B<\/h2>\n<p>El raro linfoma de c\u00e9lulas B (aproximadamente el 20% de todos los linfomas cut\u00e1neos) suele ser un tumor solitario de crecimiento r\u00e1pido. Las manifestaciones extracut\u00e1neas son muy raras, por lo que el pron\u00f3stico suele ser excelente. Se trata en su mayor\u00eda de n\u00f3dulos lisos indolentes, que suelen presentarse solitarios, a veces tambi\u00e9n diseminados. Son de un tono rojizo, en parte parduzco. A menudo hay un infiltrado d\u00e9rmico, a veces subcut\u00e1neo, con la epidermis intacta. El cuadro histol\u00f3gico de los linfomas cut\u00e1neos de c\u00e9lulas B es bastante monom\u00f3rfico en contraste con los linfomas de c\u00e9lulas T, que muestran una gran diversidad histol\u00f3gica <strong>(Fig.&nbsp;3)<\/strong> [1].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8031 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/abb3_dp6_s7.jpg\" style=\"--smush-placeholder-width: 919px; --smush-placeholder-aspect-ratio: 919\/851;height:556px; width:600px\" width=\"919\" height=\"851\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"estadios-del-linfoma-de-celulas-t\">Estadios del linfoma de c\u00e9lulas T<\/h2>\n<p>Para la selecci\u00f3n de una terapia adecuada, es necesario reconocer no s\u00f3lo el tipo sino tambi\u00e9n el estadio en el que se encuentra el linfoma cut\u00e1neo<strong> (Tab.&nbsp;2)<\/strong>. El estadio proporciona informaci\u00f3n sobre cu\u00e1nto ha progresado ya la propagaci\u00f3n de las c\u00e9lulas cancerosas a otras partes del cuerpo. En el <em>estadio I<\/em>, el linfoma s\u00f3lo afecta a partes de la piel. La piel presenta manchas escamosas y enrojecidas, pero sin n\u00f3dulos. En el <em>estadio II<\/em>, tambi\u00e9n son visibles engrosamientos nodulares en la piel o los ganglios linf\u00e1ticos est\u00e1n agrandados. En el <em>estadio III<\/em>, el linfoma cut\u00e1neo cubre casi toda la piel. El criterio para el \u00faltimo <em>estadio IV<\/em> es la infestaci\u00f3n de otros \u00f3rganos con c\u00e9lulas cancerosas. Pueden verse afectados los ganglios linf\u00e1ticos u otros \u00f3rganos.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8032 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab2_dp6_s10.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1910;height:1042px; width:600px\" width=\"1100\" height=\"1910\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Por lo general, los linfomas cut\u00e1neos se dan en pacientes mayores de 20 a\u00f1os. Los linfomas cut\u00e1neos de alta malignidad muestran un pico de edad entre los 5-15 a\u00f1os y los 60-70 a\u00f1os [5].<\/p>\n<h2 id=\"diagnostico\">Diagn\u00f3stico<\/h2>\n<p>Los linfomas cut\u00e1neos son poco frecuentes en general y suelen parecerse cl\u00ednicamente a otras enfermedades dermatol\u00f3gicas. As\u00ed, el estadio primario de la MF suele ser confusamente similar al de la dermatitis de contacto, de modo que el m\u00e9dico a menudo s\u00f3lo es alertado de un linfoma cut\u00e1neo por el curso cl\u00ednicamente persistente. Estas neoplasias cut\u00e1neas deben someterse a una biopsia. Hoy en d\u00eda, la detecci\u00f3n monoclonal de los linfocitos es posible a partir de la preparaci\u00f3n histol\u00f3gica. Esta clonalidad puede detectarse a nivel de ADN, ARNm y prote\u00ednas, por lo que pueden detectarse genes de receptores de c\u00e9lulas T o de inmunoglobulinas [1].<\/p>\n<h2 id=\"examen-clinico\">Examen cl\u00ednico<\/h2>\n<p>El examen cl\u00ednico para la sospecha de linfoma cut\u00e1neo incluye una evaluaci\u00f3n detallada de todas las lesiones cut\u00e1neas, as\u00ed como un estado de todos los ganglios linf\u00e1ticos (palpaci\u00f3n de las estaciones ganglionares, h\u00edgado, bazo). Los procedimientos de diagn\u00f3stico por imagen incluyen la ecograf\u00eda abdominal y de los ganglios linf\u00e1ticos y las radiograf\u00edas de t\u00f3rax. El examen depende del estadio de la enfermedad del linfoma cut\u00e1neo de c\u00e9lulas T. Por ejemplo, <em>el TAC de cuerpo entero <\/em>para el <em>linfoma de c\u00e9lulas T<\/em> s\u00f3lo se realiza a partir del estadio IIB en la micosis fungoide, el s\u00edndrome de S\u00e9zary (SS), la leucemia\/linfoma de c\u00e9lulas T del adulto, los trastornos linfoproliferativos primarios CD30+, el linfoma de c\u00e9lulas T subcut\u00e1neo tipo paniculitis, el linfoma extraganglionar de c\u00e9lulas NK\/T (tipo nasal) y el linfoma cut\u00e1neo primario de c\u00e9lulas T (sin especificar).<\/p>\n<p>En <em>los linfomas de c\u00e9lulas B<\/em>, <em>la TC de cuerpo entero<\/em> est\u00e1 indicada para el linfoma cut\u00e1neo difuso primario de c\u00e9lulas B grandes (tipo pierna) (PCBLT) y (PCBLT de otros tipos), as\u00ed como para el linfoma cut\u00e1neo intravascular primario de c\u00e9lulas B grandes.<\/p>\n<p>El diagn\u00f3stico de los linfomas cut\u00e1neos debe confirmarse siempre histol\u00f3gicamente mediante una biopsia. Los ex\u00e1menes inmunohistoqu\u00edmicos, as\u00ed como la posibilidad de realizar ex\u00e1menes biol\u00f3gicos moleculares, en los que se puede examinar la clonalidad de los linfocitos, suelen ser muy \u00fatiles para la diferenciaci\u00f3n de otras enfermedades inflamatorias de la piel.<\/p>\n<h2 id=\"pruebas-de-laboratorio\">Pruebas de laboratorio<\/h2>\n<p>Si se detecta un linfoma cut\u00e1neo, se recomienda realizar las siguientes pruebas de laboratorio:<\/p>\n<ul>\n<li>VSG y PCR, hemograma, enzimas hep\u00e1ticas, creatinina, LDH, electrolitos.<\/li>\n<li>En caso necesario: inmunoelecroforesis, serolog\u00eda HTLV (sobre todo para pacientes procedentes del extranjero), serolog\u00eda Borrelia, ex\u00e1menes hematol\u00f3gicos especiales, otras pruebas de laboratorio en funci\u00f3n de la terapia prevista.<\/li>\n<li>En los linfomas eritrod\u00e9rmicos de c\u00e9lulas T (sospecha de s\u00edndrome de S\u00e9zary), est\u00e1 indicado realizar un frotis sangu\u00edneo para detectar c\u00e9lulas de S\u00e9zary.<\/li>\n<\/ul>\n<p>Para los linfomas de c\u00e9lulas B, pueden ser necesarias biopsias adicionales de m\u00e9dula \u00f3sea: obligatorias para el PCBCL, opcionales para el PCMZL y el PCFCL.<\/p>\n<h2 id=\"estadios-tnm\">Estadios TNM<\/h2>\n<p>La estadificaci\u00f3n de los linfomas cut\u00e1neos CTCL se realiza seg\u00fan la clasificaci\u00f3n TNM <strong>(Tab.&nbsp;3)<\/strong>. La clasificaci\u00f3n proporciona informaci\u00f3n sobre el pron\u00f3stico y, por tanto, tambi\u00e9n indirectamente sobre la terapia necesaria. Nunca se insistir\u00e1 lo suficiente en que los linfomas cut\u00e1neos y los linfomas ganglionares tienen una cl\u00ednica completamente diferente y, por lo tanto, deben evaluarse de forma totalmente independiente (a pesar de que en ocasiones su histolog\u00eda y clasificaci\u00f3n sean casi id\u00e9nticas). En el pasado, sol\u00eda darse el caso de que los linfomas cut\u00e1neos (CTCL) se trataban en exceso. A menudo se han utilizado reg\u00edmenes terap\u00e9uticos id\u00e9nticos a los de los linfomas ganglionares, que no s\u00f3lo son ineficaces sino perjudiciales para el paciente: Los linfomas cut\u00e1neos tienen un pron\u00f3stico y una terapia completamente diferentes a los linfomas ganglionares histol\u00f3gicamente comparables. As\u00ed pues, la clasificaci\u00f3n TNM tampoco es comparable 1:1 con los linfomas ganglionares.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8033 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab3_dp6_s10.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/534;height:388px; width:600px\" width=\"1100\" height=\"534\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"prevision\">Previsi\u00f3n<\/h2>\n<p>Los estadios iniciales de la MF (IA-IIA) suelen tener muy buen pron\u00f3stico. El tiempo medio de supervivencia es de 10 a 20 a\u00f1os. Los linfomas cut\u00e1neos pueden dividirse en tres clases pron\u00f3sticas:<\/p>\n<p>1. Linfomas cut\u00e1neos con buen pron\u00f3stico:<\/p>\n<ul>\n<li>Micosis fungoide (MF)<\/li>\n<li>Reticulosis pagetoide<\/li>\n<li>Granulomatosis piel floja<\/li>\n<li>Linfoma pleom\u00f3rfico cut\u00e1neo primario de c\u00e9lulas T peque\u00f1o-mediano (provisional)<\/li>\n<li>Linfoma anapl\u00e1sico de c\u00e9lulas grandes cut\u00e1neo primario<\/li>\n<li>Papulosis linfomatoide<\/li>\n<li>Linfoma subcut\u00e1neo de c\u00e9lulas T similar a la paniculitis  &nbsp;<\/li>\n<li>Linfoma cut\u00e1neo primario de c\u00e9lulas B de la zona marginal<\/li>\n<li>Linfoma folicular cut\u00e1neo primario<\/li>\n<\/ul>\n<p>2. Linfomas cut\u00e1neos de pron\u00f3stico moderado:<\/p>\n<ul>\n<li>MF foliculotr\u00f3pico<\/li>\n<li>S\u00edndrome de S\u00e9zary<\/li>\n<li>Leucemia\/linfoma de c\u00e9lulas T en adultos (HTLV+)<\/li>\n<li>Linfoma cut\u00e1neo primario difuso de c\u00e9lulas B grandes, tipo pierna\/otros tipos<\/li>\n<\/ul>\n<p>3. linfomas cut\u00e1neos de mal pron\u00f3stico<\/p>\n<ul>\n<li>Linfoma extraganglionar de c\u00e9lulas NK\/T (tipo nasal)<\/li>\n<li>Linfoma epidermotr\u00f3pico agresivo primario cut\u00e1neo de c\u00e9lulas T CD8+ (provisional)<\/li>\n<li>Linfoma cut\u00e1neo de c\u00e9lulas T (provisional)<\/li>\n<li>Linfoma cut\u00e1neo intravascular primario de c\u00e9lulas B grandes<\/li>\n<li>Linfoma subcut\u00e1neo de c\u00e9lulas T similar a la paniculitis con hemofagocitosis<\/li>\n<li>CD4+,CD56+ neoplasia hematodermia<\/li>\n<\/ul>\n<h2 id=\"terapia\">Terapia<\/h2>\n<p>Terapia de los linfomas cut\u00e1neos de c\u00e9lulas T: Los estadios iniciales de la micosis fungoide, como el estadio eccematoso de esquina y en parte tambi\u00e9n el estadio de parche, a menudo pueden tratarse con \u00e9xito durante a\u00f1os con esteroides locales (a veces combinados con PUVA o luz UVB de banda estrecha). Si no hay respuesta, se utiliza el interfer\u00f3n como primera terapia del sistema. Las terapias para los estadios superiores de los linfomas cut\u00e1neos se resumen en<strong> la tabla&nbsp;4 <\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8034 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab4_dp6_s11.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/932;height:678px; width:800px\" width=\"1100\" height=\"932\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<h2 id=\"-2\">&nbsp;<\/h2>\n<h2 id=\"terapia-de-los-linfomas-cutaneos-de-celulas-b-lccb\">Terapia de los linfomas cut\u00e1neos de c\u00e9lulas B (LCCB)<\/h2>\n<p>Linfomas cut\u00e1neos primarios de c\u00e9lulas B de la zona marginal y linfomas de centro germinal: Los linfomas cut\u00e1neos de c\u00e9lulas B de baja malignidad corresponden a los linfomas MALT ganglionares (tejido linfoide asociado a la mucosa) por su similitud morfol\u00f3gica. Debido a las similitudes, algunos autores denominan linfomas SALT (tejido linfoide asociado a la piel) a los CBCL de baja malignidad. El pron\u00f3stico de este grupo de enfermedades suele ser muy favorable. Dado que en algunos casos pueden detectarse part\u00edculas infecciosas (ADN de Borrelia), se recomienda inicialmente el tratamiento con un antibi\u00f3tico de amplio espectro. Dado que la detecci\u00f3n de Borrelia puede ser falsamente negativa y adem\u00e1s es costosa, se recomienda a los pacientes una terapia de tres semanas con doxicilina en una dosis de 2\u00d7 100&nbsp;mg p.o. al d\u00eda.<\/p>\n<p>La escisi\u00f3n quir\u00fargica se recomienda para las lesiones peque\u00f1as, la radioterapia debe considerarse para las m\u00e1s grandes. Se recomienda una dosis total de 20&nbsp;Gy-35&nbsp;Gy, fraccionada en dosis \u00fanicas, de 1 a 2\u00d7 4&nbsp;Gy, luego 2&nbsp;Gy hasta la dosis total, de 2 a 3\u00d7 por semana. Como alternativa, se recomiendan las inyecciones intralesionales de interfer\u00f3n o el uso de rituximab, un anticuerpo humanizado dirigido contra el ant\u00edgeno CD20 de las c\u00e9lulas B. La terapia intralesional tambi\u00e9n es posible con esta sustancia, por lo que s\u00f3lo hay que utilizar el 20% de la dosis sist\u00e9micamente necesaria.<\/p>\n<p>A diferencia de los linfomas cut\u00e1neos de c\u00e9lulas B con estructura folicular, los linfomas de centro germinal y los linfomas difusos de c\u00e9lulas B grandes muestran un pron\u00f3stico comparativamente malo. En primer lugar se recomienda la radioterapia, con dosis de al menos 30Gy. En caso de recidivas, puede considerarse la poliquimioterapia combinada con rituximab [3].<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-8035 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2016\/12\/tab6_dp6_s12.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/510;height:278px; width:600px\" width=\"1100\" height=\"510\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"aspectos-psico-oncologicos\">Aspectos psico-oncol\u00f3gicos<\/h2>\n<p>Los escasos estudios sobre el bienestar psicol\u00f3gico y social de los pacientes con linfoma cut\u00e1neo muestran una dr\u00e1stica reducci\u00f3n de la calidad de vida. Especialmente el tratamiento con esteroides e interfer\u00f3n parece desencadenar estados de \u00e1nimo depresivos y ansiedad en algunos pacientes. Los pacientes con MF describieron principalmente su fatiga y las alteraciones del sue\u00f1o que se producen como factores limitantes. El deterioro en el trato con otras personas, en el trabajo y en las relaciones personales es tambi\u00e9n muy estresante debido a la &#8220;visibilidad&#8221; del diagn\u00f3stico [1].<\/p>\n<h2 id=\"outlook\">Outlook<\/h2>\n<p>Un nuevo enfoque terap\u00e9utico para los linfomas cut\u00e1neos podr\u00eda ser la terapia fotodin\u00e1mica (TFD). Esta terapia ya se utiliza con \u00e9xito en el tratamiento de las queratosis act\u00ednicas y la enfermedad de Bowen. El grupo del profesor Hunger en Berna ha realizado un ensayo piloto en pacientes con MF en las primeras fases de la enfermedad. Los resultados mostraron que se logr\u00f3 una respuesta en el 73% de las lesiones tratadas. El grupo concluye que los pacientes con estadios iniciales de MF pueden ser tratados con \u00e9xito con TFD con excelentes resultados cosm\u00e9ticos [4].<\/p>\n<p>&nbsp;<\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>www.derma.de\/de\/daten\/leitlinien\/leitlinien\/kutane-lymphome<\/li>\n<li>www.awmf.org\/uploads\/tx_szleitlinien\/032-027l_Kutane_Lymphome_2014-verlaengert.pdf<\/li>\n<li>medicalforum.ch\/docs\/smf\/archiv\/de\/2009\/2009-42\/2009-42-379.pdf<\/li>\n<li>Derm. Hel. 2016;28(7): 28-32<\/li>\n<li>www.dermatologie.usz.ch\/ueber-die-klinik\/Documents\/USZ_Lymphom_A5.pdf<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA DERMATOL\u00d3GICA 2016; 26(6): 6-12<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los linfomas cut\u00e1neos son un grupo heterog\u00e9neo de enfermedades neopl\u00e1sicas que surgen de la proliferaci\u00f3n clonal de linfocitos en la piel. En general, los linfomas cut\u00e1neos son formas poco frecuentes&hellip;<\/p>\n","protected":false},"author":7,"featured_media":61959,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Enfermedades neopl\u00e1sicas","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11310,11478,11336,11552],"tags":[40244,39273,12806,25426,40242,30101,40239,12808,40241],"powerkit_post_featured":[],"class_list":["post-340564","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dermatologia-y-venereologia","category-formacion-continua","category-oncologia","category-rx-es","tag-cd30-es","tag-celulas-b","tag-celulas-t","tag-ct-es","tag-fase-de-placa","tag-linfoma","tag-mf-es","tag-micosis-fungoide","tag-sezary-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 19:28:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/340564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=340564"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/340564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/61959"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=340564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=340564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=340564"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=340564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}