{"id":341334,"date":"2016-06-21T02:00:00","date_gmt":"2016-06-21T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/donde-y-cuando-se-producen-los-derrames-cerebrales-con-especial-frecuencia\/"},"modified":"2016-06-21T02:00:00","modified_gmt":"2016-06-21T00:00:00","slug":"donde-y-cuando-se-producen-los-derrames-cerebrales-con-especial-frecuencia","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/donde-y-cuando-se-producen-los-derrames-cerebrales-con-especial-frecuencia\/","title":{"rendered":"\u00bfD\u00f3nde y cu\u00e1ndo se producen los derrames cerebrales con especial frecuencia?"},"content":{"rendered":"<p><strong>La 25\u00aa edici\u00f3n de la Conferencia Europea sobre el Ictus se celebr\u00f3 en la primaveral Venecia. Se presentaron numerosos proyectos de investigaci\u00f3n de diferentes pa\u00edses europeos. A continuaci\u00f3n se presentan algunos estudios interesantes y enfoques innovadores.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Desde el Reino Unido nos llega un metaan\u00e1lisis que aborda una cuesti\u00f3n apasionante y relevante: \u00bfC\u00f3mo difieren las tasas de prevalencia del ictus en pa\u00edses con distintos niveles de renta? \u00bfY cu\u00e1les son las razones de las posibles diferencias?<\/p>\n<h2 id=\"el-ictus-tambien-es-un-problema-sanitario-relevante-en-los-paises-emergentes\">El ictus tambi\u00e9n es un problema sanitario relevante en los pa\u00edses emergentes<\/h2>\n<p>Son principalmente las enfermedades infecciosas las que determinan las tasas de morbilidad en los pa\u00edses de ingresos bajos y medios, mientras que los pa\u00edses occidentales de ingresos altos tienen que luchar contra la diabetes, la obesidad, la hipertensi\u00f3n, la falta de ejercicio y, como consecuencia, los accidentes cerebrovasculares. No obstante, los derrames cerebrales se est\u00e1n convirtiendo cada vez m\u00e1s en un problema sanitario relevante en los pa\u00edses de renta baja, especialmente a medida que la fortaleza econ\u00f3mica aumenta con los a\u00f1os y la gente envejece y es menos activa. La atenci\u00f3n m\u00e9dica suele ir por detr\u00e1s del desarrollo social: la p\u00e9rdida de a\u00f1os de vida ajustados en funci\u00f3n de la discapacidad (AVAD) por ictus en estos pa\u00edses es a veces siete veces superior a la de los pa\u00edses de renta alta.<\/p>\n<p>Para su an\u00e1lisis, los investigadores utilizaron estudios comunitarios de varias grandes bases de datos como MEDLINE, EMBASE, Web of Sciences, SCOPUS, etc. para obtener un inventario actualizado de las tasas de prevalencia de los supervivientes de ictus. En el metaan\u00e1lisis se incluyeron 101 estudios. En general, la prevalencia del ictus aument\u00f3 de forma constante en los pa\u00edses de ingresos bajos y medios de todas las regiones geogr\u00e1ficas, pero fue mayor en Am\u00e9rica Latina y el Caribe (17% de aumento anual), seguida de Asia Oriental y el Pac\u00edfico (13,3%) y, por \u00faltimo, \u00c1frica Subsahariana (12%). Los pa\u00edses de ingresos m\u00e1s bajos experimentaron el mayor aumento en las tasas de prevalencia anual (14,3%), mientras que la prevalencia en los pa\u00edses de ingresos bajos a medios aument\u00f3 a un ritmo ligeramente m\u00e1s lento (6%).<\/p>\n<p>Los autores se\u00f1alaron que los pa\u00edses de ingresos m\u00e1s elevados siguen siendo responsables de la mayor parte de la prevalencia del ictus. Las regiones de renta baja, sin embargo, son las que han experimentado el mayor aumento en los \u00faltimos 30 a\u00f1os, y probablemente incluso superar\u00e1n a los dem\u00e1s estados en el futuro, con importantes consecuencias socioecon\u00f3micas. Los investigadores ven las razones de esta tendencia principalmente en el peor control de los factores de riesgo (por ejemplo, la hipertensi\u00f3n no detectada o no controlada). Adem\u00e1s, cuando se produce un ictus, la atenci\u00f3n a los pacientes de los pa\u00edses con ingresos m\u00e1s bajos es m\u00e1s deficiente, lo que a su vez conlleva un aumento de la morbilidad.<\/p>\n<h2 id=\"seguimiento-a-largo-plazo-espasticidad-tras-un-ictus\">Seguimiento a largo plazo: espasticidad tras un ictus<\/h2>\n<p>La espasticidad tras un ictus, definida como diversas formas de hiperactividad muscular, es una complicaci\u00f3n que puede resultar muy angustiosa y limitante para el paciente y quienes le rodean. Dos investigadores alemanes de una cl\u00ednica neurol\u00f3gica de Hamburgo presentaron los datos de 149 pacientes con ictus y paresia de &gt;24 horas de duraci\u00f3n, que fueron tratados al cabo de 4-6 meses (punto temporal 1) y de 16 a 26 meses (tiempo 2) Se han evaluado el aumento del tono muscular, los espasmos, la paresia y el dolor. Las escalas utilizadas fueron:<\/p>\n<ul>\n<li>Escala de Ashworth modificada (MAS)<\/li>\n<li>Escala de frecuencia de espasmos (SFS)<\/li>\n<li>Escala del Consejo de Investigaci\u00f3n M\u00e9dica (MRCS)<\/li>\n<li>Escala global del dolor (GPS).<\/li>\n<\/ul>\n<p>Un total de 97 personas pudieron ser objeto de seguimiento durante todo el periodo (26 hab\u00edan fallecido, 26 no pudieron ser recordadas). En el 64%, la paresia hab\u00eda remitido en la primera exploraci\u00f3n, el 36% segu\u00eda paralizado (afectados: brazos en el 2%, piernas en el 1%, ambas extremidades en el 33%). Se encontr\u00f3 hiperactividad muscular en el 29% en general. Se encontr\u00f3 un aumento del tono muscular en el 28% (3% brazo, 4% pierna, 21% ambos), y esto se asoci\u00f3 con dolor en el 13% (el 9% de los pacientes ten\u00edan una puntuaci\u00f3n GPS superior a 50). Se produjeron espasmos en el 16% de los pacientes. La diston\u00eda inducida por la acci\u00f3n s\u00f3lo se encontr\u00f3 en el 2%. El tratamiento m\u00e1s habitual inclu\u00eda rehabilitaci\u00f3n (65%), fisioterapia (32%), psicotr\u00f3picos (26%), terapia ocupacional (21%), analg\u00e9sicos (16%) y espasmol\u00edticos (5%).<\/p>\n<p>En la segunda ocasi\u00f3n del estudio, estas caracter\u00edsticas apenas hab\u00edan cambiado. El 35% segu\u00eda paralizado. El 33% mostr\u00f3 hiperactividad muscular, el 32% aumento del tono muscular (a\u00fan asociado a dolor en el 13%), el 13% espasmos y el 3% diston\u00eda inducida por la acci\u00f3n. El n\u00famero de pacientes con MAS de al menos 2 en brazos o piernas aument\u00f3 en comparaci\u00f3n con el primer punto temporal (del 12% al 14% y del 11% al 21%, respectivamente), pero las diferencias no fueron significativas. Las terapias fueron fisioterapia (25%), terapia ocupacional (17%), psicotr\u00f3picos (13%), analg\u00e9sicos (9%) y espasmol\u00edticos (7%).<\/p>\n<p>Los autores tambi\u00e9n ven los datos como una indicaci\u00f3n de que la terapia espasmol\u00edtica es insuficiente. Los enfoques alternativos, por ejemplo con toxina botul\u00ednica, tambi\u00e9n se utilizar\u00edan en raras ocasiones.<\/p>\n<h2 id=\"cuando-se-producen-las-apoplejias-y-cuales-son-sus-efectos-cognitivos\">\u00bfCu\u00e1ndo se producen las apoplej\u00edas y cu\u00e1les son sus efectos cognitivos?<\/h2>\n<p>La Evaluaci\u00f3n Cognitiva de Montreal (MoCA) y el Mini Examen del Estado Mental (MMSE) son pruebas rutinarias para evaluar la cognici\u00f3n. Ambos se utilizaron en un estudio unic\u00e9ntrico presentado en el congreso para medir el deterioro cognitivo en 100 pacientes hospitalizados entre 24 y 48 horas despu\u00e9s del ictus. En la escala de evaluaci\u00f3n del ictus agudo del NIHS, la puntuaci\u00f3n media fue de 15. La localizaci\u00f3n del ictus fue en la arteria cerebral media en todos los pacientes.<\/p>\n<p>Los afectados obtuvieron una media de 21,6 puntos en el MoCA (normal &gt;26) y 23,75 puntos en el MMSE (normal &gt;27). Las diferencias con respecto a la poblaci\u00f3n normal fueron significativas. As\u00ed, 24-48 horas despu\u00e9s del ictus, ambas pruebas mostraron un deterioro relevante de la funci\u00f3n cognitiva. Los autores tambi\u00e9n consideraron que el MoCA era la prueba m\u00e1s adecuada (las puntuaciones de las dos pruebas difer\u00edan significativamente entre s\u00ed).<\/p>\n<p>Los mismos investigadores presentaron otro estudio que analizaba el momento preferido de inicio de un ictus. Es importante describir las condiciones y circunstancias de un ictus con la mayor precisi\u00f3n posible para comprender mejor su posible dependencia del ritmo circadiano. De hecho, se hallaron diferencias relevantes en la cronolog\u00eda de los acontecimientos en los 301 pacientes con ictus isqu\u00e9mico estudiados. Se hicieron visibles dos picos a lo largo de las 24 horas: un 8% experiment\u00f3 la apoplej\u00eda a las 09:00, otro 8% a las 19:00. En comparaci\u00f3n con la siguiente hora m\u00e1s frecuente (16:00, 6,6%), las diferencias fueron significativas en cada caso.<\/p>\n<p>\n<em>Fuente: 25\u00aa Conferencia Europea sobre el Ictus, 13-15 de abril de 2016, Venecia.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>CARDIOVASC 2016; 15(3): 38-39<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 25\u00aa edici\u00f3n de la Conferencia Europea sobre el Ictus se celebr\u00f3 en la primaveral Venecia. Se presentaron numerosos proyectos de investigaci\u00f3n de diferentes pa\u00edses europeos. A continuaci\u00f3n se presentan&hellip;<\/p>\n","protected":false},"author":7,"featured_media":56967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"XXV. Conferencia Europea sobre el Ictus  ","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11324,11483,11475,11552],"tags":[12829,15773,16264,35262],"powerkit_post_featured":[],"class_list":["post-341334","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia","category-el-congreso-informa","category-estudios","category-rx-es","tag-apoplejia-es","tag-apoplejia-cerebral","tag-mmse-es","tag-moca-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:16:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/341334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=341334"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/341334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/56967"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=341334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=341334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=341334"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=341334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}