{"id":342412,"date":"2015-11-19T01:00:00","date_gmt":"2015-11-19T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/remision-al-laboratorio-funcional-de-gastroenterologia-quien-cuando-por-que-2\/"},"modified":"2015-11-19T01:00:00","modified_gmt":"2015-11-19T00:00:00","slug":"remision-al-laboratorio-funcional-de-gastroenterologia-quien-cuando-por-que-2","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/remision-al-laboratorio-funcional-de-gastroenterologia-quien-cuando-por-que-2\/","title":{"rendered":"Remisi\u00f3n al laboratorio funcional de gastroenterolog\u00eda: \u00bfqui\u00e9n, cu\u00e1ndo, por qu\u00e9?"},"content":{"rendered":"<p><strong>Los cambios en los h\u00e1bitos intestinales, el dolor abdominal, las flatulencias, el ardor de est\u00f3mago y la disfagia son quejas habituales por las que los pacientes consultan a su m\u00e9dico de cabecera y que a menudo conducen a la derivaci\u00f3n a un gastroenter\u00f3logo. Los retos en el tratamiento de los trastornos gastrointestinales funcionales son la naturaleza inespec\u00edfica de los s\u00edntomas, la ausencia de un diagn\u00f3stico definitivo mediante las investigaciones est\u00e1ndar y la falta de opciones de tratamiento espec\u00edficas. Se recomienda un enfoque estructurado y basado en pruebas para el tratamiento de los pacientes con s\u00edntomas gastrointestinales cr\u00f3nicos.  <\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Desde el momento en que se ingiere un bolo alimenticio hasta que se excreta, pueden desarrollarse s\u00edntomas de alteraci\u00f3n de la funci\u00f3n gastrointestinal<strong> (Fig.&nbsp;1) <\/strong>.  <\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-6417\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32.jpg\" style=\"height:614px; width:800px\" width=\"1100\" height=\"844\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32-800x614.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32-120x92.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32-90x68.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32-320x246.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/abb1_hp11_s32-560x430.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<p>Son muy frecuentes la disfagia, el ardor de est\u00f3mago, la hinchaz\u00f3n abdominal, el dolor abdominal y los cambios en la consistencia y frecuencia de las heces. Un estudio publicado recientemente muestra una prevalencia del 5-15% en Europa de la enfermedad por reflujo gastroesof\u00e1gico, la dispepsia y el s\u00edndrome del intestino irritable [1]. Por lo tanto, no es de extra\u00f1ar que los &#8220;s\u00edntomas gastrointestinales funcionales&#8221; den lugar muy a menudo a consultas con el m\u00e9dico de familia y, posteriormente, a derivaciones al gastroenter\u00f3logo. La investigaci\u00f3n y el tratamiento de estas dolencias contribuyen a elevar los costes sanitarios [2]. La reducci\u00f3n del rendimiento laboral y los d\u00edas de enfermedad ocasionan costes para el paciente y la sociedad. Aunque la esperanza de vida de los pacientes afectados es normal [3], su calidad de vida puede verse tan limitada por estas dolencias como en un paciente con insuficiencia cardiaca o enfermedad tumoral [4].<\/p>\n<p>La primera parte de esta revisi\u00f3n muestra un procedimiento estructurado para examinar a pacientes con s\u00edntomas gastrointestinales. En la segunda parte, se presentan las posibilidades de un esclarecimiento especializado de los pacientes en los que no se ha podido encontrar la causa de los s\u00edntomas con los esclarecimientos rutinarios.<\/p>\n<h2 id=\"aclaracion-de-molestias-gastrointestinales-funcionales\">Aclaraci\u00f3n de molestias gastrointestinales funcionales<\/h2>\n<p>Los trastornos gastrointestinales funcionales se definen seg\u00fan los criterios de Roma III por s\u00edntomas gastrointestinales durante al menos tres meses en los \u00faltimos seis meses antes del diagn\u00f3stico y sin una patolog\u00eda org\u00e1nica detectable [5]. En funci\u00f3n de la pregunta, se descartan enfermedades tumorales, c\u00e1lculos biliares, enfermedades p\u00e9pticas, celiaqu\u00eda, colitis, etc. mediante endoscopia, procedimientos de diagn\u00f3stico por imagen y pruebas de laboratorio. Los pacientes con s\u00edntomas leves y resultados negativos en los ex\u00e1menes a menudo pueden tratarse bien con medidas sencillas (por ejemplo, supresi\u00f3n de la acidez, regulaci\u00f3n de las heces con fibras hinchables). En particular, no debe subestimarse la importancia que tiene la certeza de que no existe ninguna enfermedad grave para el desarrollo de los s\u00edntomas. Para los pacientes con s\u00edntomas persistentes a pesar de la terapia, la exclusi\u00f3n de enfermedades graves no es suficiente. En estos casos es necesaria una aclaraci\u00f3n especializada en un laboratorio funcional.<\/p>\n<p>Los objetivos de estos ex\u00e1menes especializados son el esclarecimiento etiol\u00f3gico de los s\u00edntomas y el diagn\u00f3stico inequ\u00edvoco como base para un tratamiento racional y eficaz. En el pasado, las opciones de tecnolog\u00eda m\u00e9dica para evaluar la motilidad y la funci\u00f3n gastrointestinales eran muy limitadas. Por lo tanto, s\u00f3lo los pacientes con sospecha cl\u00ednica de un trastorno grave de la motilidad (acalasia), con enfermedad por reflujo grave o con respecto a la remediaci\u00f3n quir\u00fargica de la incontinencia fecal se aclararon m\u00e1s espec\u00edficamente. Incluso en estos pacientes, los diagn\u00f3sticos eran a menudo m\u00e1s subjetivos, basados en la presentaci\u00f3n cl\u00ednica que en el resultado de ex\u00e1menes objetivos [6].<\/p>\n<p>Nuevas tecnolog\u00edas como la manometr\u00eda de alta resoluci\u00f3n (HRM) mejoran la precisi\u00f3n y la utilidad cl\u00ednica de las mediciones fisiol\u00f3gicas. El uso de estas tecnolog\u00edas en situaciones cercanas a la vida cotidiana (por ejemplo, durante una comida de prueba) muestra al examinador si los acontecimientos gastrointestinales (contracciones, reflujo, producci\u00f3n de gases) est\u00e1n relacionados con las quejas del paciente.<\/p>\n<h2 id=\"evaluacion-inicial\">Evaluaci\u00f3n inicial<\/h2>\n<p>En la evaluaci\u00f3n inicial de un paciente con s\u00edntomas gastrointestinales, es importante buscar signos de alarma como la disfagia o la p\u00e9rdida de peso como posible indicio de neoplasia, ulceraci\u00f3n o enfermedad inflamatoria intestinal <strong>(tab.&nbsp;1)<\/strong>. Si se presentan signos de alarma, lo primero que hay que hacer es realizar una endoscopia o un procedimiento de diagn\u00f3stico por imagen. Los estudios prospectivos y los metaan\u00e1lisis muestran que los signos de alarma se asocian a una enfermedad grave en un 5-10%, frente a un riesgo del 1-2% en pacientes sin estos s\u00edntomas [7,8].<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6418 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32.png\" style=\"--smush-placeholder-width: 868px; --smush-placeholder-aspect-ratio: 868\/646;height:298px; width:400px\" width=\"868\" height=\"646\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32.png 868w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32-800x595.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32-120x90.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32-90x68.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32-320x238.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab1-hp11_s32-560x417.png 560w\" data-sizes=\"(max-width: 868px) 100vw, 868px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>Si no hay signos de una posible enfermedad grave, los ex\u00e1menes invasivos no son absolutamente necesarios [9,10]. En este caso, el diagn\u00f3stico de enfermedad gastrointestinal funcional puede hacerse bas\u00e1ndose en la presentaci\u00f3n cl\u00ednica y los resultados negativos de laboratorio<strong> (tab.&nbsp;2)<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6419 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32.png\" style=\"--smush-placeholder-width: 880px; --smush-placeholder-aspect-ratio: 880\/1140;height:518px; width:400px\" width=\"880\" height=\"1140\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32.png 880w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32-800x1036.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32-120x155.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32-90x117.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32-320x415.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab2_hp11_s32-560x725.png 560w\" data-sizes=\"(max-width: 880px) 100vw, 880px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>Diversos indicios ayudan a distinguir entre enfermedades org\u00e1nicas y funcionales <strong>(tab.&nbsp;3)<\/strong>. En una etiolog\u00eda org\u00e1nica, los s\u00edntomas son estables o progresivos a lo largo del tiempo, mientras que en una etiolog\u00eda funcional, los pacientes suelen quejarse de s\u00edntomas m\u00faltiples y cambiantes. Hasta el 50% de los pacientes con enfermedad intestinal funcional padecen un trastorno psiqui\u00e1trico como ansiedad, depresi\u00f3n o somatizaci\u00f3n. En pacientes con enfermedades org\u00e1nicas (por ejemplo, colitis) es de aproximadamente el 20%, en el conjunto de la poblaci\u00f3n de alrededor del 10% [13,14]. Adem\u00e1s, los estresores psicosociales se asocian a menudo con un patr\u00f3n de quejas pronunciado, incapacidad laboral y falta de respuesta a terapias espec\u00edficas [15]. Los cuestionarios son muy \u00fatiles en este contexto para garantizar que se identifica y se trata precozmente la psicopatolog\u00eda cl\u00ednicamente relevante.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6420 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/777;height:565px; width:800px\" width=\"1100\" height=\"777\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33-800x565.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33-120x85.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33-90x64.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33-320x226.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab3_hp11_s33-560x396.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<h2 id=\"terapia-empirica\">Terapia emp\u00edrica<\/h2>\n<p>Si, tras la evaluaci\u00f3n inicial, se considera que un trastorno funcional es la causa m\u00e1s probable de las dolencias, debe comunic\u00e1rselo al paciente. Si se sospecha un trastorno grave de la motilidad (por ejemplo, acalasia), est\u00e1 indicada la remisi\u00f3n a un laboratorio de funci\u00f3n gastrointestinal. En otros casos, la terapia emp\u00edrica es \u00fatil antes de realizar m\u00e1s investigaciones. En caso de quejas por reflujo y s\u00edntomas p\u00e9pticos, es \u00fatil un ensayo terap\u00e9utico con bloqueantes de la bomba de protones, administrados dos veces al d\u00eda [9,10]. Los metaan\u00e1lisis muestran que la supresi\u00f3n de la acidez puede ser \u00fatil para el reflujo y los s\u00edntomas disp\u00e9pticos (por ejemplo, el omeprazol combinado con alginatos o anti\u00e1cidos para los s\u00edntomas intercurrentes). La terapia de erradicaci\u00f3n del Helicobacter pylori (si est\u00e1 presente) tambi\u00e9n es \u00fatil, pero su eficacia es bastante baja (alrededor de un 10% mejor que el placebo) [18].<\/p>\n<p>En pacientes con dolencias colorrectales, se lleva a cabo una terapia emp\u00edrica con antiespasmol\u00edticos y regulaci\u00f3n de las heces con fibra diet\u00e9tica (por ejemplo, psilio). Los medicamentos que regulan la frecuencia y consistencia de las heces (por ejemplo, loperamida, polietilenglicol) pueden administrarse adicionalmente [19]. Los antidepresivos en dosis bajas (por ejemplo, amitriptilina, mirtazapina, citalopram) suelen ser eficaces para los s\u00edntomas GI funcionales como el dolor abdominal, las n\u00e1useas, la hinchaz\u00f3n y la hipersensibilidad visceral  [20\u201322]. Si se sospecha comorbilidad psiqui\u00e1trica, se recomienda remitir al paciente a un psiquiatra o psic\u00f3logo. Si estas estrategias iniciales fracasan, deben considerarse terapias como el asesoramiento nutricional y la fisioterapia. Si estas medidas no conducen a una mejora de las dolencias, est\u00e1 indicada una remisi\u00f3n al laboratorio funcional para determinar las patolog\u00edas cl\u00ednicamente relevantes y permitir as\u00ed una terapia dirigida.  <strong>(Tab.4).<\/strong><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-6421 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/894;height:650px; width:800px\" width=\"1100\" height=\"894\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33-800x650.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33-120x98.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33-90x73.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33-320x260.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2015\/11\/tab4_hp11_s33-560x455.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p><strong>Parte 2 en el pr\u00f3ximo n\u00famero<\/strong><\/p>\n<p><em>Bibliograf\u00eda del editor<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2015; 10(11): 31-34<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cambios en los h\u00e1bitos intestinales, el dolor abdominal, las flatulencias, el ardor de est\u00f3mago y la disfagia son quejas habituales por las que los pacientes consultan a su m\u00e9dico&hellip;<\/p>\n","protected":false},"author":7,"featured_media":53661,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Parte 1 - Aclaraci\u00f3n de las molestias gastrointestinales","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11358,11288,11552],"tags":[29151,44215,44240,16062,15677,25734,44244,27028,44224,44251,44217,43711,44235],"powerkit_post_featured":[],"class_list":["post-342412","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-gastroenterologia-y-hepatologia","category-medicina-interna-general","category-rx-es","tag-acidez","tag-ardor-de-estomago","tag-calculos-biliares-es","tag-colitis-es","tag-dificultad-para-tragar","tag-helicobacter-es","tag-hrm-es","tag-incontinencia-es","tag-laboratorio-funcional-es","tag-manometria-es","tag-polipo","tag-prueba-de-alcoholemia","tag-roma-iii-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:18:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/342412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=342412"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/342412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/53661"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=342412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=342412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=342412"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=342412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}