{"id":343998,"date":"2014-12-28T01:00:00","date_gmt":"2014-12-28T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/que-papel-desempena-la-nutricion\/"},"modified":"2014-12-28T01:00:00","modified_gmt":"2014-12-28T00:00:00","slug":"que-papel-desempena-la-nutricion","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/que-papel-desempena-la-nutricion\/","title":{"rendered":"\u00bfQu\u00e9 papel desempe\u00f1a la nutrici\u00f3n?"},"content":{"rendered":"<p><strong>La importante funci\u00f3n de la luz solar en la formaci\u00f3n de los huesos se descubri\u00f3 muy pronto, pero los conocimientos sobre la vitamina D no se formaron hasta el siglo pasado. Hoy en d\u00eda, los datos son claros y es seguro que unas concentraciones s\u00e9ricas demasiado bajas pueden tener efectos negativos.&nbsp;<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La vitamina D de nuestro organismo procede de dos fuentes diferentes: Puede acumularse a trav\u00e9s de la piel (end\u00f3gena, vitamina D3) o suministrarse a trav\u00e9s de los alimentos (ex\u00f3gena). Los rayos UV-A y UV-B llegan a la superficie terrestre, pero s\u00f3lo los UV-B desencadenan la formaci\u00f3n de vitamina D en la piel. Este proceso depende del tipo de piel, la edad, la duraci\u00f3n de la exposici\u00f3n al sol y el uso de protecci\u00f3n solar. La s\u00edntesis de vitamina D por el propio organismo suele superar la ingesta de vitamina D a trav\u00e9s de los alimentos. La vitamina D suministrada a trav\u00e9s de los alimentos procede principalmente de los productos animales. Fuentes importantes son el pescado graso (arenque, salm\u00f3n, sardinas), los huevos y los productos l\u00e1cteos<strong> (Tab.&nbsp;1)<\/strong>. La vitamina D favorece la absorci\u00f3n de calcio y fosfato en el intestino y su incorporaci\u00f3n a los huesos, regula el metabolismo del calcio y el fosfato con otras hormonas y es importante para la formaci\u00f3n de huesos y dientes sanos.<br \/>\n&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-5046\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12.png\" style=\"height:572px; width:600px\" width=\"670\" height=\"639\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12.png 670w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12-120x114.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12-90x86.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12-320x305.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab_9_hp12-560x534.png 560w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><br \/>\n&nbsp;<\/p>\n<p>\nLa carencia de vitamina D favorece la osteoporosis, la fatiga general, la debilidad muscular y los dolores \u00f3seos y musculares difusos. Entre los grupos de riesgo se encuentran los beb\u00e9s y los ni\u00f1os, las mujeres embarazadas y lactantes, los ancianos, los enfermos cr\u00f3nicos, los obesos y las personas con tipos de piel oscura. Una carencia masiva de vitamina D puede provocar raquitismo en los ni\u00f1os peque\u00f1os y osteomalacia en los adultos.<\/p>\n<p>La ingesta excesiva de suplementos en dosis elevadas durante un largo periodo de tiempo puede provocar una sobredosis, pero no a trav\u00e9s de la dieta o la exposici\u00f3n al sol. El resultado es la hipercalcemia.<\/p>\n<h2 id=\"situacion-en-suiza\">Situaci\u00f3n en Suiza<\/h2>\n<p>Hay que partir de la base de que aproximadamente el 50% de la poblaci\u00f3n suiza tiene una concentraci\u00f3n de 25(OH)D inferior a 50&nbsp;nmol\/l. Sin embargo, los datos actuales sugieren que se necesita un nivel de 25(OH)D de al menos 50&nbsp;nmol\/l para mantener la salud \u00f3sea en todos los adultos y la salud muscular en las personas mayores. Los beneficios para la salud de concentraciones s\u00e9ricas superiores a 50&nbsp;nmol\/l s\u00f3lo se han confirmado hasta ahora para estos dos rangos. Pruebas de la influencia positiva de otras enfermedades o dolencias en la salud de la poblaci\u00f3n. cuya prevenci\u00f3n por concentraciones s\u00e9ricas superiores a 50&nbsp;nmol\/l no existe.<\/p>\n<p>Para las personas mayores de 60 a\u00f1os, se recomienda encarecidamente un suplemento de vitamina D de 800 UI al d\u00eda. Esta recomendaci\u00f3n se basa en ensayos controlados aleatorios que han demostrado una reducci\u00f3n de ca\u00eddas y fracturas del 20%. <strong>El cuadro&nbsp;2<\/strong> resume las recomendaciones del EEK.<br \/>\nSi desea informaci\u00f3n detallada, consulte el informe del EEK sobre la vitamina D www.blv.admin.ch\/eek.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-5047 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/927;height:506px; width:600px\" width=\"1100\" height=\"927\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12.png 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12-800x674.png 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12-120x101.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12-90x76.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12-320x270.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/tab2_9_hp12-560x472.png 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><em>PR\u00c1CTICA GP 2014; 9(12): 9<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La importante funci\u00f3n de la luz solar en la formaci\u00f3n de los huesos se descubri\u00f3 muy pronto, pero los conocimientos sobre la vitamina D no se formaron hasta el siglo&hellip;<\/p>\n","protected":false},"author":5,"featured_media":48483,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Vitamina D","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11470,11354,11552],"tags":[48902,13060,13104],"powerkit_post_featured":[],"class_list":["post-343998","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-nutricion","category-rx-es","tag-luz-solar-es","tag-nutricion","tag-vitamina-d-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 05:14:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/343998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=343998"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/343998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/48483"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=343998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=343998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=343998"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=343998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}