{"id":344145,"date":"2014-12-08T01:00:00","date_gmt":"2014-12-08T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/erupcion-purpuriforme-aguda-en-un-lactante\/"},"modified":"2014-12-08T01:00:00","modified_gmt":"2014-12-08T00:00:00","slug":"erupcion-purpuriforme-aguda-en-un-lactante","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/erupcion-purpuriforme-aguda-en-un-lactante\/","title":{"rendered":"Erupci\u00f3n purpuriforme aguda en un lactante"},"content":{"rendered":"<p><strong><em>Informe de un caso: <\/em>Un ni\u00f1o de once meses presenta una nueva erupci\u00f3n cut\u00e1nea con manchas que ha estado presente durante dos d\u00edas. Diez d\u00edas antes se hab\u00eda producido una infecci\u00f3n de las v\u00edas respiratorias.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>En la exploraci\u00f3n, la cara, las mejillas y la barbilla, as\u00ed como las extremidades, muestran placas purpuriformes eritematosas de tama\u00f1o variable, que van de entumecidas a blancoides <strong>(Fig.&nbsp;1 y 2)<\/strong>. El dorso de las manos y los pabellones auriculares tambi\u00e9n muestran hinchaz\u00f3n edematosa. El tegumento del tronco y las mucosas no se ven afectados. El ni\u00f1o se encuentra en buen estado general, afebril y no hay organomegalias ni linfadenopat\u00edas. El recuento sangu\u00edneo, la coagulaci\u00f3n, los valores hep\u00e1ticos y renales, as\u00ed como el estado de la orina, son anodinos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-4972\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi.jpg\" style=\"height:416px; width:600px\" width=\"1100\" height=\"763\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi-800x555.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi-120x83.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi-90x62.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi-320x222.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb1_paedi-560x388.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/p>\n<h2 id=\"cuestionario\">Cuestionario<\/h2>\n<p>\u00bfQu\u00e9 har\u00eda a continuaci\u00f3n?<br \/>\nA Administraci\u00f3n de antibi\u00f3ticos iv y monitorizaci\u00f3n de cuidados intensivos<br \/>\nB Administraci\u00f3n de <sup>Aciclovir\u00ae<\/sup> en caso de sospecha de enfermedad desencadenada por herpesvirus<br \/>\nC Documentaci\u00f3n fotogr\u00e1fica y espera<br \/>\nD Documentaci\u00f3n fotogr\u00e1fica y contacto con el grupo de protecci\u00f3n de menores<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-4973 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi.jpg\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1128;height:615px; width:600px\" width=\"1100\" height=\"1128\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi-800x820.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi-120x123.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi-90x92.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi-320x328.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/12\/abb2_paedi-560x574.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/p>\n<p>\n<strong>Respuesta correcta y diagn\u00f3stico:<\/strong> La respuesta correcta es la C (documentaci\u00f3n fotogr\u00e1fica y esperar). Se trata del llamado edema hemorr\u00e1gico infantil agudo (EHAI) (sin. &#8220;edema hemorr\u00e1gico agudo de la infancia&#8221;, p\u00farpura cocarda de Seidlmayer, enfermedad de Finkelstein).<\/p>\n<p><strong>Discusi\u00f3n: <\/strong>El diagn\u00f3stico cl\u00ednico de la AIHE se basa en la aparici\u00f3n s\u00fabita de impresionantes placas purpuriformes blancoideas en las mejillas, la barbilla, las orejas y las extremidades acompa\u00f1adas de edema en un ni\u00f1o con buen estado de salud general y una edad t\u00edpica de entre cuatro meses y dos a\u00f1os. Se encuentran simult\u00e1neamente diferentes estadios de placas con desvanecimiento central lento y borde purpuriforme. El tronco se suele dejar fuera [1,2].<\/p>\n<p>La AIHE es una caracter\u00edstica vasculitis leucocitocl\u00e1stica transitoria de peque\u00f1o vaso descrita por primera vez por Snow [3] en 1913. Cl\u00e1sicamente, la enfermedad aparece tras una infecci\u00f3n v\u00edrica (banal) en lactantes y ni\u00f1os peque\u00f1os (normalmente &lt;2 a\u00f1os) y en dos tercios de los casos afecta a varones [1,2].<br \/>\nEl diagn\u00f3stico puede realizarse cl\u00ednicamente bas\u00e1ndose en las caracter\u00edsticas descritas anteriormente. Debe prestarse especial atenci\u00f3n al pabell\u00f3n auricular durante el examen; su edema y p\u00farpura son patognom\u00f3nicos de la enfermedad. No suelen producirse ampollas ni necrosis. Los ni\u00f1os afectados no suelen tener fiebre o s\u00f3lo una fiebre leve y -a diferencia de la p\u00farpura de Sch\u00f6nlein Henoch- carecen de afectaci\u00f3n de otros \u00f3rganos (como intestinos o ri\u00f1ones). Si la cl\u00ednica es caracter\u00edstica, no est\u00e1n indicados m\u00e1s ex\u00e1menes (como an\u00e1lisis de sangre u orina, biopsia de piel). No se requiere ninguna terapia espec\u00edfica. La cicatrizaci\u00f3n espont\u00e1nea y prolongada se produce en un plazo de una a tres semanas [1,2, 4-8].<\/p>\n<p>En ciertos casos, la prominente afectaci\u00f3n facial y las lesiones similares al hematoma en varias fases pueden hacer sospechar de maltrato infantil, especialmente en este grupo de edad tan joven [6]. En la AIHE, sin embargo, los padres niegan un modo de lesi\u00f3n precedente y las lesiones cut\u00e1neas, a diferencia de los hematomas, muestran un cambio espont\u00e1neo mucho m\u00e1s r\u00e1pido en su evoluci\u00f3n. Otro diagn\u00f3stico diferencial es sin duda la p\u00farpura de Sch\u00f6nlein Henoch. En esta forma de vasculitis leucocitocl\u00e1stica de peque\u00f1o vaso, sin embargo, los ni\u00f1os afectados son algo mayores (&gt;2 a\u00f1os) y predomina una p\u00farpura palpable de manchas m\u00e1s bien peque\u00f1as con \u00e9nfasis en las piernas y las nalgas con exclusi\u00f3n de la cara. A diferencia de la p\u00farpura de Sch\u00f6nlein Henoch, la afectaci\u00f3n renal-glomerular no se produce en la AIHE y no es necesario el seguimiento correspondiente.<\/p>\n<p>Debido a las placas blancoides, la AIHE podr\u00eda confundirse con el eritema exsudativum multiforme (EEM). Sin embargo, las verdaderas cocardas como en el EEM muestran tres anillos conc\u00e9ntricos de intensidad de color variable con a menudo una peque\u00f1a burbuja\/costra central, mientras que el AIHE muestra s\u00f3lo dos anillos conc\u00e9ntricos.<\/p>\n<p>Un diagn\u00f3stico diferencial potencialmente mortal es la p\u00farpura fulminans, por ejemplo en el contexto de una infecci\u00f3n meningoc\u00f3cica o estreptoc\u00f3cica. Sin embargo, en la p\u00farpura fulminans, las primeras necrosis hemorr\u00e1gicas suelen encontrarse bastante distales acralmente y existe una coagulopat\u00eda intravascular diseminada. Adem\u00e1s, la p\u00farpura se delimita r\u00e1pidamente con necrosis profunda de la piel y el subcutis y los ni\u00f1os afectados presentan un mal estado general [8].<\/p>\n<p><em>Literatura:<\/em><\/p>\n<ol>\n<li>Fiore E, et al: Edema hemorr\u00e1gico agudo de ni\u00f1os peque\u00f1os (p\u00farpura y edema en escarapela): serie de casos y revisi\u00f3n sistem\u00e1tica. J Am Acad Dermatol 2008; 59(4): 684-695.<\/li>\n<li>Karremann M, et al: Edema hemorr\u00e1gico agudo de la infancia: informe de 4 casos y revisi\u00f3n de la literatura actual. Clin Pediatr (Phila) 2009; 48(3): 323-326.<\/li>\n<li>Nieve I: P\u00farpura, urticaria y edema agioneur\u00f3tico de manos y pies en un beb\u00e9 lactante. JAMA 1913; 61: 18-19.<\/li>\n<li>Lai-Cheong JE, et al: Edema hemorr\u00e1gico agudo bulloso de la piel en la infancia. Clin Exp Dermatol 2007; 32(4): 467-468.<\/li>\n<li>Legrain V, et al: Edema hemorr\u00e1gico agudo infantil de la piel: estudio de diez casos. J Am Acad Dermatol 1991; 24(1): 17-22.<\/li>\n<li>Kos L, Shwayder T: Manifestaciones cut\u00e1neas del maltrato infantil. Pediatr Dermatol 2006; 23(4): 311-320.<\/li>\n<li>Scheer HS, Weibel L: Erupci\u00f3n purpuriforme repentina en un lactante. JAMA 2013; 209(20): 2159-2160.<\/li>\n<li>Chalmers E, et al: P\u00farpura fulminans: reconocimiento, diagn\u00f3stico y tratamiento. Arch Dis Child 2011; 96(11): 1066-1071.<\/li>\n<\/ol>\n<p><em>PR\u00c1CTICA DERMATOL\u00d3GICA 2014; 24(6): 36-37<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informe de un caso: Un ni\u00f1o de once meses presenta una nueva erupci\u00f3n cut\u00e1nea con manchas que ha estado presente durante dos d\u00edas. Diez d\u00edas antes se hab\u00eda producido una&hellip;<\/p>\n","protected":false},"author":7,"featured_media":48203,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"\u00bfCu\u00e1l es su diagn\u00f3stico?","footnotes":""},"category":[11493,11310,11402,11552],"tags":[49408,29177,49418,34682,49424,35097,49413],"powerkit_post_featured":[],"class_list":["post-344145","post","type-post","status-publish","format-standard","has-post-thumbnail","category-casos","category-dermatologia-y-venereologia","category-pediatria","category-rx-es","tag-aihe-es","tag-edema-es","tag-lesion-cutanea","tag-necrosis-es","tag-placas-targetoides","tag-purpura-es","tag-vasculitis-de-pequenos-vasos","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:29:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/344145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=344145"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/344145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/48203"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=344145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=344145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=344145"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=344145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}