{"id":345532,"date":"2014-04-17T00:00:00","date_gmt":"2014-04-16T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/enfermedades-infecciosas-e-inmunologicas-de-la-piel\/"},"modified":"2014-04-17T00:00:00","modified_gmt":"2014-04-16T22:00:00","slug":"enfermedades-infecciosas-e-inmunologicas-de-la-piel","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/enfermedades-infecciosas-e-inmunologicas-de-la-piel\/","title":{"rendered":"Enfermedades infecciosas e inmunol\u00f3gicas de la piel"},"content":{"rendered":"<p><strong>El D\u00eda Suizo del Derma de este a\u00f1o se centr\u00f3 en el tratamiento de las enfermedades infecciosas e inmunol\u00f3gicas de la piel. Entre otros muchos temas, se debatieron la indicaci\u00f3n y relevancia de las pruebas del parche, as\u00ed como las opciones de tratamiento para las verrugas vulgares.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><em>(ts) <\/em>&#8220;Los \u00faltimos a\u00f1os han demostrado que la prueba epicut\u00e1nea se utiliza cada vez menos&#8221;, el Prof. Dr. med. Andreas J. Bircher, de Basilea, abri\u00f3 su conferencia sobre la indicaci\u00f3n y relevancia de las pruebas epicut\u00e1neas. &#8220;Sin embargo, creo que sigue siendo un m\u00e9todo que pertenece a las manos de los dermat\u00f3logos y que deber\u00edamos utilizar nosotros&#8221;. Tambi\u00e9n subray\u00f3 que, aunque es f\u00e1cil realizar una prueba del parche, se necesita una combinaci\u00f3n de conocimientos y experiencia\/juicio cl\u00ednico para evaluar tambi\u00e9n la relevancia de una prueba positiva.<\/p>\n<p>Seg\u00fan el Prof. Bircher, las pruebas del parche est\u00e1n indicadas en casos de sospecha de alergia de contacto (dermatitis de contacto, dermatitis at\u00f3pica) o exantema medicamentoso. &#8220;La etiolog\u00eda de la dermatitis de contacto y los ant\u00edgenos potencialmente reactivos cruzados s\u00f3lo pueden identificarse con una prueba del parche&#8221;, razon\u00f3.<\/p>\n<h2 id=\"haptenos-prohaptenos-y-prehaptenos\">Haptenos, prohaptenos y prehaptenos<\/h2>\n<p>Los al\u00e9rgenos de contacto cl\u00e1sicos, como los iones de n\u00edquel, pertenecen a la categor\u00eda de los haptenos. Esto significa que tienen que unirse a una prote\u00edna end\u00f3gena para desencadenar una reacci\u00f3n al\u00e9rgica [1]. El n\u00edquel penetra r\u00e1pidamente en la piel, pero requiere una se\u00f1al de Peligro para la sensibilizaci\u00f3n. &#8220;Seg\u00fan las investigaciones actuales en el modelo de rat\u00f3n, el n\u00edquel provoca una activaci\u00f3n a trav\u00e9s del receptor Toll-like, es decir, del sistema inmunitario innato.<\/p>\n<p>El n\u00edquel tiene as\u00ed su propia se\u00f1al de peligro. Esto podr\u00eda explicar por qu\u00e9 es un al\u00e9rgeno de contacto relativamente com\u00fan, pero no explica la diferencia claramente existente en la frecuencia de la alergia al n\u00edquel en hombres y mujeres.&#8221;<\/p>\n<p>Adem\u00e1s de los haptenos, tambi\u00e9n se conocen los prohaptenos. \u00c9stos son a su vez qu\u00edmicamente menos reactivos, pero pueden transformarse metab\u00f3licamente en la piel. Los preaptenos tambi\u00e9n son principalmente qu\u00edmicamente inactivos. Sin embargo, pueden volverse reactivos, por ejemplo, tras una oxidaci\u00f3n espont\u00e1nea. El profesor Bircher puso el ejemplo de las fragancias y las sustancias vegetales como el aceite del \u00e1rbol del t\u00e9, en las que el contacto con el ox\u00edgeno del aire puede provocar una oxidaci\u00f3n espont\u00e1nea, convirtiendo el prehapteno en hapteno.<\/p>\n<h2 id=\"realizacion-y-evaluacion-de-una-prueba-del-parche\">Realizaci\u00f3n y evaluaci\u00f3n de una prueba del parche<\/h2>\n<p>A continuaci\u00f3n, el ponente explic\u00f3 c\u00f3mo debe realizarse y leerse correctamente una prueba del parche. &#8220;Pruebe en la parte superior de la espalda y, si es necesario, en la parte exterior del brazo. El exantema medicamentoso y de flexi\u00f3n debe comprobarse in situ si es posible&#8221;.<\/p>\n<p>El tiempo de aplicaci\u00f3n suele ser de dos d\u00edas, la primera lectura debe realizarse despu\u00e9s de 20-30 minutos. La segunda lectura puede realizarse entonces el d\u00eda 3 (72 h) o el d\u00eda 4 (96 h). &#8220;Especialmente con los metales y sobre todo tambi\u00e9n con los esteroides, debe hacerse una lectura tard\u00eda al cabo de cinco a siete d\u00edas, porque en estos casos a\u00fan podemos ver reacciones tard\u00edas&#8221;, subray\u00f3.<\/p>\n<p>La evaluaci\u00f3n de los resultados de una prueba del parche se basa en un sistema semicuantitativo. &#8220;Que la prueba sea negativa o positiva sigue siendo f\u00e1cil de juzgar&#8221;, afirm\u00f3 el profesor Bircher. &#8220;Sin embargo, la evaluaci\u00f3n de los distintos estadios intermedios, por ejemplo si se trata de un eritema con un infiltrado leve, puede resultar dif\u00edcil. As\u00ed que creo que el dermat\u00f3logo es el \u00fanico especialista predispuesto a la evaluaci\u00f3n precisa de tales lesiones&#8221;. La interpretaci\u00f3n de si se trata de una verdadera reacci\u00f3n al\u00e9rgica o m\u00e1s bien irritante\/t\u00f3xica tambi\u00e9n requiere un conocimiento adecuado. Par\u00e1metros como la frecuencia, la dependencia de la dosis, la dispersi\u00f3n o el curso pueden ayudar en este sentido <strong>(Tab. 1<\/strong>).<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3660\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919.jpg\" width=\"1100\" height=\"717\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919-800x521.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919-120x78.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919-90x59.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919-320x209.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/04\/Tab1_s44_DP2.jpg_1919-560x365.jpg 560w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/><\/strong><\/p>\n<h2 id=\"el-pasaporte-de-la-alergia-un-documento-medico\">El pasaporte de la alergia, un documento m\u00e9dico<\/h2>\n<p>Al final de su intervenci\u00f3n, el Prof. Bircher se refiri\u00f3 al pasaporte antial\u00e9rgico. &#8220;Aqu\u00ed no basta con escribir alergia. Es necesario un diagn\u00f3stico cl\u00ednico preciso, por ejemplo, exantema maculo-papular medicamentoso.<\/p>\n<p>Tambi\u00e9n puede ser \u00fatil indicar la localizaci\u00f3n&#8221;. Adem\u00e1s, debe mencionarse la fecha de la prueba y los al\u00e9rgenos de contacto probados, as\u00ed como una valoraci\u00f3n de la pertinencia. Dado que los pasaportes de alergia pueden perderse, tambi\u00e9n debe archivarse una copia en el historial m\u00e9dico.<\/p>\n<h2 id=\"verrugas-vulgares-curso-a-menudo-autolimitado\">Verrugas vulgares &#8211; curso a menudo autolimitado<\/h2>\n<p>La conferencia del Dr. med. Markus Streit, de Aarau, abord\u00f3 el quid de las verrugas vulgares. &#8220;Lo t\u00edpico de estas verrugas es una estructura fisurada circunscrita. Suelen sobresalir como c\u00fapulas y tener una superficie rugosa&#8221;, dijo el ponente. Sin embargo, la imagen tambi\u00e9n puede variar en funci\u00f3n de la localizaci\u00f3n en el cuerpo. Seg\u00fan cifras m\u00e1s antiguas del Reino Unido, las verrugas vulgares afectan al 3,9-4,9% de los ni\u00f1os y adolescentes [2]. La prevalencia en adultos (15-74 a\u00f1os) es del 3,28% [3].&nbsp;  Las verrugas suelen ser la expresi\u00f3n de una infecci\u00f3n por el virus del papiloma humano (VPH). &#8220;Como infecci\u00f3n v\u00edrica, las verrugas cut\u00e1neas tienen en realidad un curso autolimitado. As\u00ed, unos dos tercios se han curado al cabo de dos a\u00f1os&#8221;. No obstante, el tratamiento puede estar indicado en determinados casos, por ejemplo, si los cambios persisten durante m\u00e1s de dos a\u00f1os, en caso de dolor, limitaciones funcionales, r\u00e1pida propagaci\u00f3n o por razones est\u00e9ticas.<\/p>\n<h2 id=\"buenas-pruebas-para-el-acido-salicilico\">Buenas pruebas para el \u00e1cido salic\u00edlico<\/h2>\n<p>En principio, para tratar las verrugas vulgares pueden utilizarse m\u00e9todos que destruyan el tejido qu\u00edmica (por ejemplo, los queratol\u00edticos) o f\u00edsicamente (por ejemplo, la crioterapia) o que tengan un efecto inmunomodulador o antiv\u00edrico. Adem\u00e1s, siempre hay historias sobre diversos remedios caseros que pueden utilizarse para tratar eficazmente las verrugas.<\/p>\n<p>Se dispone de informaci\u00f3n cient\u00edficamente s\u00f3lida sobre la terapia de las verrugas vulgares en una revisi\u00f3n Cochrane publicada en 2012 [4]. Se incluyeron datos de 85 ensayos con un total de 8815 pacientes aleatorizados. La revisi\u00f3n encontr\u00f3 las mejores pruebas de un \u00e9xito terap\u00e9utico significativo para el \u00e1cido salic\u00edlico aplicado localmente frente al placebo. El efecto fue mejor en las manos que en los pies en los an\u00e1lisis de subgrupos. El Dr. Streit afirm\u00f3: &#8220;Sin embargo, resulta un tanto sorprendente que el \u00e1cido salic\u00edlico se utilizara a menudo en combinaci\u00f3n en los estudios, por ejemplo, con \u00e1cido l\u00e1ctico o \u00e1cido monocloroac\u00e9tico. Por tanto, los resultados deben tomarse con cautela. &#8220;No obstante, el \u00e1cido salic\u00edlico es sin duda lo que m\u00e1s necesitamos en la pr\u00e1ctica&#8221;.<\/p>\n<p>Entre las sustancias corrosivas utilizadas en la pr\u00e1ctica para la terapia local de las verrugas, mencion\u00f3 el \u00e1cido monocloroac\u00e9tico, <sup>el Solcoderm\u00ae<\/sup> (mezcla de \u00e1cidos org\u00e1nicos e inorg\u00e1nicos) y las barritas de nitrato de plata. En la pr\u00e1ctica, los f\u00e1rmacos citost\u00e1ticos utilizados son principalmente el 5-fluorouracilo y la bleomicina. &#8220;La eficacia del 5-fluorouracilo se declara en la revisi\u00f3n Cochrane como no evaluable porque los datos disponibles no eran comparables&#8221;. La revisi\u00f3n tambi\u00e9n encontr\u00f3 s\u00f3lo pruebas inconsistentes sobre la bleomicina. En los estudios, sin embargo, se aplic\u00f3 de forma diferente y en distintas concentraciones. Sin embargo, seg\u00fan la experiencia del Dr. Streit, la bleomicina ha demostrado ser una muy buena opci\u00f3n para las verrugas plantares resistentes a la terapia.<\/p>\n<h2 id=\"fisioterapia-de-las-verrugas\">Fisioterapia de las verrugas<\/h2>\n<p>Entre las opciones de fisioterapia para las verrugas, la crioterapia encabeza la lista. Sin embargo, la revisi\u00f3n Cochrane no encontr\u00f3 ninguna ventaja de este m\u00e9todo sobre el placebo [4]. Sin embargo, en uno de los estudios incluidos, la crioterapia para las verrugas de las manos demostr\u00f3 ser superior al placebo y tambi\u00e9n al \u00e1cido salic\u00edlico. El intervalo de aplicaci\u00f3n (2, 3 \u00f3 4 semanas) no influy\u00f3 en las tasas de curaci\u00f3n. &#8220;Adem\u00e1s, despu\u00e9s de cuatro ciclos de tratamiento, continuar con la terapia ya no parece tener mucho sentido&#8221;, a\u00f1adi\u00f3 el experto. Seg\u00fan la revisi\u00f3n, una crioterapia m\u00e1s agresiva (&gt;10 seg.) parece ser m\u00e1s eficaz que una suave, pero tambi\u00e9n se asocia a un mayor riesgo de efectos secundarios como dolor, ampollas y cicatrices.<\/p>\n<p>Por \u00faltimo, la inmunoterapia con dinitroclorobenceno demostr\u00f3 ser significativamente m\u00e1s eficaz que el placebo en dos estudios [4]. El Dr. Streit concluy\u00f3: &#8220;Es interesante que no existan ensayos aleatorios ni siquiera para algunos m\u00e9todos muy comunes, como el legrado o la escisi\u00f3n&#8221;.<\/p>\n<p><em>Fuente:<sup>3er<\/sup> D\u00eda Suizo del Derma, 30 de enero de 2014, Lucerna<\/em><\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Karlberg AT, et al.: Dermatitis al\u00e9rgica de contacto: formaci\u00f3n, requisitos estructurales y reactividad de los sensibilizadores cut\u00e1neos. Chem Res Toxicol 2008; 21: 53-69.<\/li>\n<li>Williams HC, et al: La epidemiolog\u00eda descriptiva de las verrugas en los escolares brit\u00e1nicos. Br J Dermatol 1993; 128: 504-511.<\/li>\n<li>Rea JN, et al: Enfermedades de la piel en Lambeth. Un estudio comunitario sobre la prevalencia y el uso de la atenci\u00f3n m\u00e9dica. Br J Prev Soc Med 1976; 30: 107-114.<\/li>\n<li>Kwok CS, et al: Tratamientos t\u00f3picos para las verrugas cut\u00e1neas. Cochrane Database Syst Rev 2012 Sep 12;9:CD001781.<\/li>\n<\/ol>\n<p><em>PR\u00c1CTICA DERMATOL\u00d3GICA 2014; 24(2): 42-45<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El D\u00eda Suizo del Derma de este a\u00f1o se centr\u00f3 en el tratamiento de las enfermedades infecciosas e inmunol\u00f3gicas de la piel. Entre otros muchos temas, se debatieron la indicaci\u00f3n&hellip;<\/p>\n","protected":false},"author":4,"featured_media":43098,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"3er D\u00eda Suizo del Derma","footnotes":""},"category":[11298,11310,11483,11552],"tags":[40248,52634,53806,52995,53812,53822,53818,53815,53809,32888],"powerkit_post_featured":[],"class_list":["post-345532","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-inmunologia-clinica","category-dermatologia-y-venereologia","category-el-congreso-informa","category-rx-es","tag-acido-salicilico-es","tag-alergeno-de-contacto","tag-derma-dia","tag-enfermedades-de-la-piel","tag-hapteno","tag-pasaporte-para-alergicos","tag-prehapteno","tag-prohapteno","tag-verruga-vulgar-es","tag-verrugas","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:34:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/345532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=345532"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/345532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/43098"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=345532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=345532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=345532"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=345532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}