{"id":345828,"date":"2014-03-06T00:00:00","date_gmt":"2014-03-05T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/es-posible-alcanzar-tasas-de-curacion-muy-elevadas-con-una-terapia-correcta\/"},"modified":"2023-01-18T23:57:22","modified_gmt":"2023-01-18T22:57:22","slug":"es-posible-alcanzar-tasas-de-curacion-muy-elevadas-con-una-terapia-correcta","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/es-posible-alcanzar-tasas-de-curacion-muy-elevadas-con-una-terapia-correcta\/","title":{"rendered":"Es posible alcanzar tasas de curaci\u00f3n muy elevadas con una terapia correcta"},"content":{"rendered":"<p><strong>El v\u00e9rtigo posicional benigno, o m\u00e1s correctamente v\u00e9rtigo posicional parox\u00edstico benigno (VPPB), es la causa m\u00e1s com\u00fan de mareo, representando el 20-30% de todos los pacientes que consultan al m\u00e9dico por mareos. Dado que puede tratarse bien en un alto porcentaje mediante sencillas maniobras de posicionamiento y es curable en muchos casos, casi todos los m\u00e9dicos deber\u00edan poder aliviar a sus pacientes de este cuadro cl\u00ednico tan desagradable. El siguiente art\u00edculo ofrece consejos sobre el diagn\u00f3stico y la terapia.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Seg\u00fan un estudio de Brevern et al. En 2007 [1], de 1003 pacientes encuestados, s\u00f3lo el 8% recibi\u00f3 una terapia eficaz para el v\u00e9rtigo posicional parox\u00edstico benigno (VPPB). Para un buen tratamiento, debe identificarse con precisi\u00f3n la arcada afectada para poder realizar la maniobra de liberaci\u00f3n \u00f3ptima para esta arcada. Adem\u00e1s, en caso de BPLS anamn\u00e9sicamente relativamente t\u00edpico, pero nistagmo ausente o at\u00edpico, tambi\u00e9n deben considerarse los posibles diagn\u00f3sticos diferenciales <strong>(Tab.&nbsp;1) <\/strong>. El BPLS nunca debe confundirse con otros trastornos vestibulares como la enfermedad de Meniere o la vestibulopat\u00eda aguda, porque la distinci\u00f3n es sencilla en principio.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3340\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679.jpg\" width=\"844\" height=\"336\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679.jpg 844w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679-800x318.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679-120x48.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679-90x36.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679-320x127.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Tab1_S16_HP3.jpg-0aff3b_1679-560x223.jpg 560w\" sizes=\"(max-width: 844px) 100vw, 844px\" \/><\/p>\n<h2 id=\"patologia-del-bpls\">Patolog\u00eda del BPLS<\/h2>\n<p>La BPLS es desencadenada por la otoconia, que son peque\u00f1os cuerpos (5-35&nbsp;\u03bcm) similares a cristales, predominantemente de carbonato c\u00e1lcico, que se asientan en la m\u00e1cula del utr\u00edculo, donde aumentan la percepci\u00f3n de la gravedad y la aceleraci\u00f3n lineal. Cuando estas part\u00edculas se desprenden, pueden caer en los arcos abiertos al utr\u00edculo. Afecta a una arcada vertical posterior en el 80-90% de los casos, a una arcada horizontal en alrededor del 10% y raramente a una arcada vertical anterior. En los arcos, siempre son arrastrados por la gravedad hasta el punto m\u00e1s bajo del arco y, al hundirse, desencadenan un movimiento fluido que desv\u00eda la c\u00fapula. Esto es interpretado por el cerebro como una irritaci\u00f3n de la arcada correspondiente y se experimenta como v\u00e9rtigo rotacional, ya que las arcadas miden los movimientos de rotaci\u00f3n de la cabeza. Este v\u00e9rtigo giratorio s\u00f3lo dura mientras las part\u00edculas desencadenan un flujo de fluido que desv\u00eda la c\u00fapula. El mareo giratorio, as\u00ed como el nistagmo observado, son por tanto de corta duraci\u00f3n. S\u00f3lo cuando las part\u00edculas se adhieren a una c\u00fapula, lo que ocurre raramente y hasta ahora s\u00f3lo se ha descrito para las arcadas horizontales, el v\u00e9rtigo y el nistagmo se prolongan. Dado que las part\u00edculas tambi\u00e9n tardan poco tiempo en desencadenar un flujo, muy a menudo se produce una latencia de unos segundos antes de que aparezcan el mareo y el nistagmo. A menudo se informa de que esta latencia es significativamente m\u00e1s corta o incluso inexistente para las arcadas horizontales, pero esto tambi\u00e9n puede ocurrir para las arcadas posteriores.<\/p>\n<h2 id=\"diagnostico\">Diagn\u00f3stico<\/h2>\n<p>Para el diagn\u00f3stico del BPLS, primero es importante realizar un historial m\u00e9dico detallado. La pregunta de si el mareo es constante o intermitente suele responderse incorrectamente, ya que muchos pacientes experimentan mareos cada vez que mueven la cabeza. Como realizan estos movimientos muy a menudo, describen el mareo como continuo. Aqu\u00ed, la cuesti\u00f3n del desencadenamiento por los cambios de posici\u00f3n de la cabeza es especialmente importante. Si se confirma, habr\u00e1 que hacer preguntas espec\u00edficas sobre el v\u00e9rtigo que se desencadena al tumbarse en la cama y girar la cabeza. Si s\u00f3lo se indica como desencadenante un giro de la cabeza hacia un lado, es probable que el arco posterior est\u00e9 afectado en el lado hacia el que se realiza el giro. Si se informa de v\u00e9rtigo al girar la cabeza hacia cualquier lado mientras se est\u00e1 tumbado, entonces debe sospecharse de una arcada horizontal, ya que la canalolitiasis de una arcada horizontal siempre da lugar a BPLS en ambas direcciones. Sin embargo, el v\u00e9rtigo suele ser m\u00e1s fuerte cuando se gira la cabeza hacia el lado afectado, porque en este caso los canalolitos gotean sobre la c\u00fapula, lo que corresponde a una estimulaci\u00f3n. Seg\u00fan la segunda ley de Ewald, esto siempre desencadena una respuesta m\u00e1s fuerte que la inhibici\u00f3n. Sin embargo, con la anamnesis s\u00f3lo se asegura la asunci\u00f3n del arco afectado. El examen cl\u00ednico es decisivo. Para ello, existe la maniobra Dix-Hallpike [2] para los arcos verticales y la &#8220;maniobra barbacoa&#8221; [3] para los arcos horizontales<strong> (Fig. 1 y 2<\/strong>).<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3341 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678.jpg\" width=\"1100\" height=\"822\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-800x598.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-320x240.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-300x225.jpg 300w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-120x90.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-90x68.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb1-2_HP3_s17.jpg-08f61a_1678-560x418.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/822;\" \/><\/p>\n<p><strong>Maniobra de Dix-Hallpike para el arco posterior izquierdo: <\/strong>Cuando el arco posterior est\u00e1 afectado, se produce un nistagmo predominantemente rotatorio en la maniobra de Hallpike, es decir, los ojos giran alrededor del eje visual, por lo que la direcci\u00f3n del movimiento del polo superior del ojo determina la direcci\u00f3n del nistagmo en la fase r\u00e1pida. As\u00ed, en la canalolitiasis del arco posterior izquierdo, el polo superior del ojo late hacia el o\u00eddo inferior.<\/p>\n<p><strong>Maniobra de barbacoa:<\/strong> la canalolitiasis de una arcada horizontal provoca un nistagmo batiente horizontal cuando se gira la cabeza hacia ambos lados. En la mayor\u00eda de los casos, \u00e9sta es geotr\u00f3pica, es decir, golpea hacia el suelo por ambos lados. Tambi\u00e9n cambia la direcci\u00f3n del golpe con la posici\u00f3n de la cabeza. El lado en el que el nistagmo late m\u00e1s fuerte y normalmente el mareo tambi\u00e9n es m\u00e1s fuerte es el lado afectado. Incluso con el paciente en dec\u00fabito supino con la cabeza recta, suele producirse un ligero nistagmo horizontal. Esto suele indicar ya el lado afectado. Al menos el lado al que late suele ser el afectado.<\/p>\n<p>Importante: el nistagmo casi puramente torsional habla por el arco posterior de la oreja inferior. Al enderezarse, este nistagmo de torsi\u00f3n cambia en sentido contrario. El nistagmo horizontal es indicativo de una arcada horizontal.<\/p>\n<p>En raras ocasiones, tambi\u00e9n se ven afectadas las arcadas posteriores y horizontales de ambos lados, lo que puede provocar un nistagmo mixto. Dependiendo del historial m\u00e9dico, siempre examinamos primero la arcada que probablemente est\u00e9 afectada. Si se confirma la canalolitiasis, la maniobra de diagn\u00f3stico va seguida inmediatamente de la maniobra de rescate. Si el nistagmo no es t\u00edpico de una canalolitiasis de la arcada correspondiente, a\u00fan se puede realizar la maniobra de liberaci\u00f3n, pero hay que pensar en los diagn\u00f3sticos diferenciales. Si los s\u00edntomas no mejoran tras maniobras de liberaci\u00f3n infructuosas, siempre deben tenerse en cuenta los diagn\u00f3sticos diferenciales <strong>(tab.&nbsp;1) <\/strong>y\/o remitir al paciente a un especialista adecuado.<\/p>\n<h2 id=\"tratamiento\">Tratamiento<\/h2>\n<p>Tras el diagn\u00f3stico del arco afectado:<\/p>\n<p><strong>Arco posterior: <\/strong>Existe la maniobra de Epley [4] y la maniobra de Semont [5] <strong>(Fig.&nbsp;3 y 4)<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3342 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682.jpg\" width=\"1100\" height=\"1361\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682-800x990.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682-120x148.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682-90x111.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682-320x396.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb3_HP3_s18.jpg-0f2223_1682-560x693.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1361;\" \/><\/p>\n<p>Ambos tienen tasas de curaci\u00f3n igual de buenas. La maniobra de Semont, sin embargo, requiere un almacenamiento r\u00e1pido de un lado a otro, mientras que la maniobra de Epley tambi\u00e9n puede realizarse lentamente. En los pa\u00edses franc\u00f3fonos se utiliza a menudo la maniobra de Semont, pero en los pa\u00edses de habla alemana e inglesa se recurre sobre todo a la maniobra de Epley. Adem\u00e1s, cuando el paciente repite la maniobra de posicionamiento, comete menos errores durante la maniobra de Epley.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3343 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681.jpg\" width=\"1100\" height=\"1004\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681-800x730.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681-120x110.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681-90x82.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681-320x292.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb4_HP3_s18.jpg-0e36be_1681-560x511.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1004;\" \/><\/p>\n<p>La maniobra de Epley tambi\u00e9n puede repetirla f\u00e1cilmente el paciente en casa por su cuenta si el tratamiento en el m\u00e9dico no le ayud\u00f3 de inmediato o en caso de recidiva, lo que ocurre m\u00e1s a menudo en las primeras semanas.<\/p>\n<p>Al posicionar seg\u00fan Semont, aseg\u00farese de que la posici\u00f3n de la cabeza sigue siendo la misma en todas las posiciones del cuerpo, es decir, en el caso de canalolitiasis del arco posterior izquierdo, siempre una cabeza girada 45\u00b0 a la derecha. Esto significa que en la primera posici\u00f3n lateral el paciente mira hacia arriba, en la segunda hacia abajo. Esto se hace muy a menudo de forma incorrecta cuando los pacientes repiten la maniobra de forma independiente, por lo que preferimos la maniobra de Epley.<\/p>\n<p>Se han descrito cambios o variaciones de las maniobras, pero a\u00fan no se han demostrado mejores \u00e9xitos que las maniobras originales. La vibraci\u00f3n de la mastoides durante el almacenamiento, que se supone que afloja las part\u00edculas a\u00fan adheridas a la pared, a\u00fan no ha dado lugar a ninguna ventaja demostrable. Ha habido varios estudios que han investigado una restricci\u00f3n posicional espec\u00edfica tras una maniobra de reducci\u00f3n con \u00e9xito, reduciendo as\u00ed la tasa de recidiva. No se encontr\u00f3 ning\u00fan \u00e9xito significativo en todos los estudios, pero en un nuevo an\u00e1lisis global de todos estos estudios, se encontr\u00f3 un efecto significativo de evitar ciertas posturas. En consecuencia, los pacientes deben dormir con la cabeza ligeramente elevada durante unos d\u00edas [6].<\/p>\n<p><strong>Arco horizontal: <\/strong>Tras el diagn\u00f3stico del arco afectado, se trata mediante la maniobra de reducci\u00f3n seg\u00fan Lempert [7] o mediante una maniobra de Guffoni [8]. En el nistagmo geotr\u00f3pico, se ve afectado el lado en el que el v\u00e9rtigo y\/o el nistagmo son m\u00e1s pronunciados. En caso de nistagmo apogeotr\u00f3pico, primero intente convertirlo en nistagmo geotr\u00f3pico girando repetidamente la cabeza de izquierda a derecha y viceversa, que luego tambi\u00e9n puede tratarse con la maniobra de Lempert<strong> (Fig.&nbsp;5)<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3344 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680.jpg\" width=\"844\" height=\"596\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680.jpg 844w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680-800x565.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680-120x85.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680-90x64.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680-320x226.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/03\/Abb5_HP3_s18.jpg-0cbd0c_1680-560x395.jpg 560w\" data-sizes=\"(max-width: 844px) 100vw, 844px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 844px; --smush-placeholder-aspect-ratio: 844\/596;\" \/><\/p>\n<p>Si la maniobra de Lempert no tiene \u00e9xito o es inicial, tambi\u00e9n se puede realizar la maniobra de Gufoni. Esto es aplicable tanto al nistagmo de posici\u00f3n horizontal geotr\u00f3pico como al apogeotr\u00f3pico. S\u00f3lo es importante prestar atenci\u00f3n a la posici\u00f3n en la que el nistagmo es m\u00e1s fuerte, es decir, cuando la cabeza se gira hacia la derecha o hacia la izquierda. En cualquier caso, la maniobra de Gufoni debe realizarse en el lado con el nistagmo posicional bajo. En el nistagmo posicional geotr\u00f3pico, el paciente se tumba primero sobre el lado sano y tras unos diez segundos gira la cabeza hacia abajo unos 45\u00b0. Permanece en esta posici\u00f3n unos 30 segundos y despu\u00e9s puede levantarse. Esta maniobra mostr\u00f3 una tasa de curaci\u00f3n del 67% en un estudio de Casani et al [9].<\/p>\n<p>En el nistagmo apogeotr\u00f3pico, el paciente se tumba sobre el lado afectado, que es tambi\u00e9n el lado con el nistagmo m\u00e1s d\u00e9bil. Tras 10-30 segundos, gira entonces la cabeza 45\u00b0 hacia arriba y permanece en esta posici\u00f3n unos dos minutos.<\/p>\n<p>Si la maniobra de Gufoni tampoco tiene \u00e9xito, se puede pedir al paciente que permanezca tumbado sobre la oreja sana el mayor tiempo posible, al menos tres horas en nuestra experiencia, aunque en la literatura se mencionan 12 horas, pero esto es dif\u00edcilmente sostenible. Este tratamiento se describe como una &#8220;posici\u00f3n prolongada forzada&#8221;. A menudo tiene \u00e9xito incluso despu\u00e9s de varias maniobras de almacenamiento infructuosas. Se describi\u00f3 una recuperaci\u00f3n superior al 90% en un estudio con 35 pacientes [10]. Aconsejamos a los pacientes que se duerman sobre su lado sano y que permanezcan sobre este lado si es posible. Por supuesto, tambi\u00e9n puede hacerse desde el principio, adem\u00e1s de las maniobras de posicionamiento.<\/p>\n<p><em><strong>PD Stefan Hegemann, MD<br \/>\nDra. Arianne Monge Naldi<\/strong><\/em><\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Von Brevern M, et al: Epidemiolog\u00eda del v\u00e9rtigo posicional parox\u00edstico benigno: un estudio basado en la poblaci\u00f3n. J Neurol Neurosurg Psychiatry 2007; 78: 710-715.<\/li>\n<li>Dix MR, Hallpike CS: La sintomatolog\u00eda patol\u00f3gica y el diagn\u00f3stico de ciertos trastornos comunes del sistema vestibular. Proc R Soc Med 1952; 45: 341-354.<\/li>\n<li>Baloh RW, Jacobson K, Honrubia V: Variante del canal semicircular horizontal del v\u00e9rtigo posicional benigno. Neurolog\u00eda 1993; 43: 2542-2549.<\/li>\n<li>Epley JM: El procedimiento de reposicionamiento canalicular: para el tratamiento del v\u00e9rtigo posicional parox\u00edstico benigno. Otolaryngol Head Neck Surg 1992; 107: 399-404.<\/li>\n<li>Semont A, Freyss G, Vitte E: Curar el VPPB con una maniobra liberadora. Otorrinolaringolog\u00eda avanzada 1988; 42: 290-293.<\/li>\n<li>Hunt WT, Zimmermann EF, Hilton MP: Modificaciones de la maniobra de Epley (reposicionamiento canalicular) para el v\u00e9rtigo posicional parox\u00edstico benigno del canal posterior (VPPB). Cochrane Database Syst Rev 2012; 18; 4:CD008675.<\/li>\n<li>Lempert T: V\u00e9rtigo posicional benigno horizontal. Neurolog\u00eda 1994 nov; 44: 2213-2214.<\/li>\n<li>Gufoni M, Mastrosimone L, Di Nasso F: Maniobra de reposicionamiento en el v\u00e9rtigo parox\u00edstico benigno del canal semicircular horizontal. Acta Otorhinolaryngol Ital 1998; 18: 363-367.<\/li>\n<li>Casani AP, et al: El tratamiento del v\u00e9rtigo posicional de canal horizontal: nuestra experiencia en 66 casos. Laringoscopio 2002; 112: 172-178.<\/li>\n<li>Vannucchi P, Giannoni B, Pagnini P: Tratamiento del v\u00e9rtigo posicional parox\u00edstico benigno del canal semicircular horizontal. J Vestib Res 1997; 7: 1-6.<\/li>\n<\/ol>\n<h4 id=\"conclusion-para-la-practica\">CONCLUSI\u00d3N PARA LA PR\u00c1CTICA<\/h4>\n<ul>\n<li>Un historial m\u00e9dico preciso es fundamental para el diagn\u00f3stico de la BPLS. El examen cl\u00ednico posterior debe confirmar la suposici\u00f3n de la arcada afectada (maniobra seg\u00fan Dix-Hallpike para las arquer\u00edas verticales, &#8220;maniobra de barbacoa&#8221; para las arquer\u00edas horizontales).<\/li>\n<li>Con las maniobras de posicionamiento descritas (Epley, Semont, Lempert, Gufoni), hay una tasa de recuperaci\u00f3n de &gt;90% de los afectados al cabo de unos tres d\u00edas.<\/li>\n<li>En caso de molestias persistentes, recomendamos remitirle a una consulta especializada.<\/li>\n<\/ul>\n<p>&nbsp;\n<\/p>\n<p><em>PR\u00c1CTICA GP 2014; 9(3): 16-20<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El v\u00e9rtigo posicional benigno, o m\u00e1s correctamente v\u00e9rtigo posicional parox\u00edstico benigno (VPPB), es la causa m\u00e1s com\u00fan de mareo, representando el 20-30% de todos los pacientes que consultan al m\u00e9dico&hellip;<\/p>\n","protected":false},"author":4,"featured_media":41709,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"V\u00e9rtigo posicional parox\u00edstico benigno (VPPB)","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11478,11393,11552],"tags":[54663,15076,54668,54669,19760,43798,54671,54672,54670,54673,54674,54675,54664,44718,54666,54667,54662,54665],"powerkit_post_featured":[],"class_list":["post-345828","post","type-post","status-publish","format-standard","has-post-thumbnail","category-formacion-continua","category-orl-es","category-rx-es","tag-arcade-es","tag-bpls-es","tag-cabeza","tag-cupula-es","tag-enfermedad-de-meniere","tag-macula-es","tag-maniobra-de-barbacoa-es","tag-maniobra-de-epley","tag-maniobra-dix-hallpike","tag-maniobra-gufoni","tag-maniobra-lempert","tag-nistagmo-apogeotropico-es","tag-nistagmo-atipico-es","tag-oido","tag-otokonien-es","tag-utriculus-es","tag-vertigo-posicional-paroxistico-benigno","tag-vestibulopatia-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 22:06:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/345828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=345828"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/345828\/revisions"}],"predecessor-version":[{"id":345845,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/345828\/revisions\/345845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/41709"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=345828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=345828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=345828"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=345828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}