{"id":346277,"date":"2014-02-12T00:00:00","date_gmt":"2014-02-11T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/eficacia-del-extracto-de-petasita-ze-339-repetidamente-probada\/"},"modified":"2014-02-12T00:00:00","modified_gmt":"2014-02-11T23:00:00","slug":"eficacia-del-extracto-de-petasita-ze-339-repetidamente-probada","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/eficacia-del-extracto-de-petasita-ze-339-repetidamente-probada\/","title":{"rendered":"Eficacia del extracto de petasita Ze 339 repetidamente probada"},"content":{"rendered":"<p><strong>Tambi\u00e9n en medicina la casualidad ayuda a veces: los empleados de una empresa farmac\u00e9utica tomaron uno de los preparados de petasita de su compa\u00f1\u00eda para el dolor de cabeza y de repente notaron como resultado muchos menos s\u00edntomas de fiebre del heno. Posteriormente, los cient\u00edficos de la empresa examinaron de nuevo el extracto y pudieron demostrar cient\u00edficamente la eficacia experimentada emp\u00edricamente contra la rinitis al\u00e9rgica estacional. El resultado fue el extracto de petasita Ze 339.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La rinoconjuntivitis al\u00e9rgica estacional, tambi\u00e9n conocida como fiebre del heno, es una afecci\u00f3n gen\u00e9tica con una prevalencia creciente en el hemisferio occidental. Los al\u00e9rgenos desencadenantes son el polen vegetal de \u00e1rboles, hierbas y gram\u00edneas. Hay pacientes que s\u00f3lo son al\u00e9rgicos a un tipo de polen, mientras que otros desarrollan una alergia a toda una gama de p\u00f3lenes y, por lo tanto, sufren los conocidos s\u00edntomas como secreci\u00f3n nasal, estornudos, enrojecimiento, lagrimeo y picor en varias cavidades corporales durante un periodo de tiempo significativamente m\u00e1s largo. La calidad de vida de los pacientes afectados se reduce considerablemente durante la estaci\u00f3n del polen. Esto se ve dificultado por el hecho de que, especialmente para el segundo grupo, evitar la exposici\u00f3n al polen es dif\u00edcilmente factible. Por lo tanto, la farmacoterapia, que consiste principalmente en el tratamiento con antihistam\u00ednicos, es la opci\u00f3n obvia.<\/p>\n<h2 id=\"petasita-petasites-hybridus\">Petasita, Petasites hybridus<\/h2>\n<p>La petasita <strong>(Fig. 1) <\/strong>ya se utilizaba como planta medicinal en la antig\u00fcedad; Diosc\u00f3rides la empleaba contra las \u00falceras. La planta recibi\u00f3 su nombre alem\u00e1n en la Edad Media, donde se utilizaba para tratar la peste. M\u00e1s tarde, los m\u00e9dicos prescribieron la petasita para la tos y el asma, y despu\u00e9s tambi\u00e9n para los c\u00f3licos y las migra\u00f1as.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-3140\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563.png\" width=\"701\" height=\"551\" srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563.png 701w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563-120x94.png 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563-90x71.png 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563-320x252.png 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Pestwurz_s7.png-eaf59c_1563-560x440.png 560w\" sizes=\"(max-width: 701px) 100vw, 701px\" \/><\/p>\n<p>Debido al efecto t\u00f3xico para el h\u00edgado de los alcaloides de pirrolizidina, la petasita cultivada de forma natural fue prohibida de la lista de plantas medicinales. Sin embargo, existe una variedad de petasita protegida por patente llamada <sup>Petzell\u00ae<\/sup> a partir de la cual se produce el extracto de petasita Ze 339 <strong>(Tab. 1)<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3141 lazyload\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562.jpg\" width=\"1100\" height=\"689\" data-srcset=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562.jpg 1100w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562-800x501.jpg 800w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562-120x75.jpg 120w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562-90x56.jpg 90w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562-320x200.jpg 320w, https:\/\/medizinonline.com\/wp-content\/uploads\/2014\/02\/Tab1_s7_Hp2.jpg-4a19d1_1562-560x351.jpg 560w\" data-sizes=\"(max-width: 1100px) 100vw, 1100px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/689;\" \/><\/p>\n<h2 id=\"eficacia-de-ze-339\">Eficacia de Ze 339<\/h2>\n<p>Farmacol\u00f3gicamente, se ha demostrado que el Ze 339 inhibe la bios\u00edntesis de leucotrienos y la eliminaci\u00f3n de iones de calcio en las c\u00e9lulas, y estabiliza los mastocitos, lo que detiene la liberaci\u00f3n de mediadores inflamatorios como la histamina [1].<\/p>\n<p>Ze 339 se revis\u00f3 por primera vez en un estudio abierto con s\u00f3lo seis sujetos con una dosis diaria de 3\u00d72 comprimidos [2], lo que corresponde a 48 mg de petasina. Aqu\u00ed se pudo demostrar una buena eficacia, los s\u00edntomas de las personas sometidas a la prueba y su calidad de vida mejoraron de forma decisiva.<\/p>\n<p>Mientras tanto, se han llevado a cabo otros estudios cl\u00ednicos en los que se ha probado la eficacia de Ze 339 frente a sustancias comparativas o frente a placebo.<\/p>\n<p><strong>Ze 339 frente a cetirizina:<\/strong> En un estudio aleatorizado, doble ciego, prospectivo, controlado y multic\u00e9ntrico de 131 pacientes, se compar\u00f3 la Ze 339 con la cetirizina [3]. El criterio de valoraci\u00f3n primario fue el cambio en la puntuaci\u00f3n del Cuestionario de Resultados M\u00e9dicos de Salud (SF-36). Los resultados mostraron que la Ze 339 no era inferior a la cetirizina.<\/p>\n<p><strong>Ze 339 frente a placebo: <\/strong>De nuevo, se trat\u00f3 de un ensayo multic\u00e9ntrico aleatorizado, doble ciego, prospectivo y controlado con placebo en el que se probaron dos dosis diferentes de Ze 339 frente a placebo [4]. Los sujetos del grupo verum recibieron un comprimido de Ze 339 dos o tres veces al d\u00eda. Ambas dosis de petasita fueron significativamente superiores en comparaci\u00f3n con el placebo. La dosis m\u00e1s fuerte de Ze-339 tambi\u00e9n fue significativamente superior a la m\u00e1s d\u00e9bil.<\/p>\n<p>Otros estudios [5] confirmaron los resultados encontrados, as\u00ed como la buena tolerabilidad [6]. Por el momento, la \u00faltima publicaci\u00f3n sobre el producto fue un estudio [7] de 2011 en el que se compar\u00f3 Ze 339 con el antihistam\u00ednico desloratadina. En este estudio de tres brazos, 18 pacientes fueron pretratados con Ze 339, desloratadina o placebo durante cinco d\u00edas antes de la exposici\u00f3n al polen de gram\u00edneas. En el grupo Ze-339, los s\u00edntomas se calmaron significativamente m\u00e1s r\u00e1pido tras la exposici\u00f3n que en el grupo placebo (p=0,027), pero tambi\u00e9n m\u00e1s r\u00e1pido que en el grupo desloratadina (p=0,030).<\/p>\n<h3 id=\"literatura\">Literatura:<\/h3>\n<ol>\n<li>Thomet OAR, et al: Papel de la petasina en la potencial actividad antiinflamatoria de un extracto vegetal de petasites hybridus. Bioqu\u00edmica Farmac\u00e9utica 2001; 61: 1041-1047.<\/li>\n<li>Thomet OAR, et al.: Actividad antiinflamatoria de un extracto de Petasites hybridus en la rinitis al\u00e9rgica. Inmunofarmacol Internacional 2002; 2: 997-1006.<\/li>\n<li>Schapowal A: En nombre del grupo de estudio Petasites: Ensayo controlado aleatorio de petasita y cetirizina para el tratamiento de la rinitis al\u00e9rgica estacional. BMJ 2002; 324: 144-146.<\/li>\n<li>Schapowal A: En nombre del grupo de estudio Petasites: Petasita Ze 339 para el tratamiento de la rinitis al\u00e9rgica (&#8220;fiebre del heno&#8221;): eficacia dependiente de la dosis en un estudio prospectivo, aleatorizado, doble ciego y controlado con placebo. Alergia 2003; 58 (Supl 74): 286-287.<\/li>\n<li>Schapowal A: En nombre del grupo de estudio Petasites: Treating intermittent allergic rhinitis: a prospective, randomized, placebo and antihistaminic-controlled study of Butterbur extract Ze 339, Phytother Res 2005(6); 19: 530-537.<\/li>\n<li>K\u00e4ufeler R: Eficacia y seguridad del extracto de hierbas de petasita Ze 339 en la rinitis al\u00e9rgica estacional: estudio de vigilancia postcomercializaci\u00f3n, Adv Ther 2006(2); 23: 373-384.<\/li>\n<li>Dumitr AF, et al: El complejo de butenoato de Petasol (Ze339) alivia la obstrucci\u00f3n nasal inducida por la rinitis al\u00e9rgica de forma m\u00e1s eficaz que la desloratadina, J Allergy Clin Immunol 2001 (6); 127: 1515-1521.<\/li>\n<\/ol>\n<p><em>PR\u00c1CTICA GP 2014; 9(2): 7<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tambi\u00e9n en medicina la casualidad ayuda a veces: los empleados de una empresa farmac\u00e9utica tomaron uno de los preparados de petasita de su compa\u00f1\u00eda para el dolor de cabeza y&hellip;<\/p>\n","protected":false},"author":4,"featured_media":40918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Fitoterapia contra la rinitis al\u00e9rgica","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11298,11408,74323,11412,11470,11552],"tags":[14466,57392,13384,12552,38947,57379,12522,39048,57388,57374,57384,38949],"powerkit_post_featured":[],"class_list":["post-346277","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alergologia-e-inmunologia-clinica","category-farmacologia-y-toxicologia","category-fitoterapia-es","category-medicina-farmaceutica","category-noticias","category-rx-es","tag-calidad-de-vida","tag-cetrizina-es","tag-fiebre-del-heno","tag-fitoterapia-es","tag-petasita","tag-petasites-hybridus-es","tag-picor","tag-polen-es","tag-pollvita-es","tag-rinoconjuntivitis-alergica","tag-tesalin-es","tag-ze-339-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:28:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/346277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=346277"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/346277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/40918"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=346277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=346277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=346277"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=346277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}