{"id":346518,"date":"2013-12-20T00:00:00","date_gmt":"2013-12-19T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/que-beneficios-ampliados-ofrecen-los-farmacos-utilizados-actualmente\/"},"modified":"2013-12-20T00:00:00","modified_gmt":"2013-12-19T23:00:00","slug":"que-beneficios-ampliados-ofrecen-los-farmacos-utilizados-actualmente","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/que-beneficios-ampliados-ofrecen-los-farmacos-utilizados-actualmente\/","title":{"rendered":"\u00bfQu\u00e9 beneficios ampliados ofrecen los f\u00e1rmacos utilizados actualmente?"},"content":{"rendered":"<p><strong>La artritis reumatoide (AR) es una enfermedad cr\u00f3nica que provoca inflamaci\u00f3n y, por tanto, restricci\u00f3n del movimiento y dolor en las articulaciones. Se da dos veces m\u00e1s en mujeres que en hombres y su incidencia es elevada en todo el mundo. Aunque la AR afecta principalmente a las articulaciones, la inflamaci\u00f3n tambi\u00e9n puede extenderse a otros \u00f3rganos. La gravedad de la enfermedad y la inflamaci\u00f3n se asocian a un mayor riesgo de cardiopat\u00eda coronaria en comparaci\u00f3n con la poblaci\u00f3n normal, por lo que el tratamiento eficaz de estos factores es fundamental. Los resultados de los nuevos estudios se debatieron en el Congreso del ACR en San Diego. Se trataba de un posible efecto de la terapia previa de AR para otras entidades patol\u00f3gicas.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><em>(ag) <\/em>Los inhibidores del factor de necrosis tumoral (TNF), como el infliximab, el adalimumab, el golimumab y el certolizumab pegol, y la prote\u00edna gen\u00e9ticamente modificada etanercept forman una clase de f\u00e1rmacos que se utilizan desde hace diez a\u00f1os. Se utiliza en todo el mundo para tratar enfermedades inflamatorias como la artritis reumatoide (AR), la artritis psori\u00e1sica (APs), la artritis juvenil, la enfermedad de Crohn, la espondilitis anquilosante (enfermedad de Bekhterev) y la psoriasis. Dado que las opciones de tratamiento actuales en la AR conducen a un buen control de la inflamaci\u00f3n articular, la cuesti\u00f3n es si esto tambi\u00e9n puede abordar ciertas comorbilidades.<\/p>\n<h2 id=\"pueden-los-inhibidores-del-tnf-reducir-el-riesgo-de-sca\">\u00bfPueden los inhibidores del TNF reducir el riesgo de SCA?<\/h2>\n<p>Un grupo de investigadores de Suecia ha investigado ahora si los inhibidores del TNF en el tratamiento de pacientes con AR reducen tambi\u00e9n el mayor riesgo de cardiopat\u00eda coronaria aguda (SCA). Los resultados fueron presentados por la doctora Lotta Ljung, de Ume\u00e5, en el Congreso del ACR de este a\u00f1o [1]. En concreto, se form\u00f3 una cohorte de 7704 pacientes del Registro Sueco de Biol\u00f3gicos que no ten\u00edan antecedentes de cardiopat\u00eda isqu\u00e9mica hasta ese momento y que iniciaron por primera vez su tratamiento&nbsp; con un inhibidor del TNF entre 2001 y 2010. Las cohortes de comparaci\u00f3n ponderadas incluyeron 23 112 pacientes con AR del registro nacional de pacientes que nunca hab\u00edan tomado un biol\u00f3gico y 38 520 personas del registro de poblaci\u00f3n general. Los pacientes se consideraron &#8220;activos&#8221; si tomaban inhibidores del TNF hasta el punto final definido y durante otros 90 d\u00edas.<\/p>\n<p>El SCA se defini\u00f3 como un diagn\u00f3stico de golpe primario de infarto de miocardio, angina inestable o infarto de miocardio con resultado de muerte. En la poblaci\u00f3n general, se produjeron a un ritmo de 3,3\/1000 personas al a\u00f1o, en comparaci\u00f3n con 5,7\/1000 en pacientes con AR que ten\u00edan un estado &#8220;activo&#8221; y 8,6\/1000 en pacientes con AR que nunca tomaron un biol\u00f3gico. Tras controlar otros factores influyentes, la probabilidad de sufrir un SCA era un 50% mayor en los pacientes con AR que tomaban &#8220;activamente&#8221; inhibidores del TNF, y el doble en los que nunca lo hac\u00edan, en comparaci\u00f3n con la poblaci\u00f3n general. En comparaci\u00f3n con los que se abstuvieron de tomar biol\u00f3gicos, el riesgo de los pacientes en estado &#8220;activo&#8221; fue, en consecuencia, un 27% menor. Este estudio demuestra que tomar inhibidores del TNF tambi\u00e9n influye en las comorbilidades cardiovasculares, pero no aclara si el menor riesgo se debe a los propios f\u00e1rmacos o a un mejor control de la inflamaci\u00f3n.<\/p>\n<h2 id=\"un-estudio-britanico-confirma-el-efecto\">Un estudio brit\u00e1nico confirma el efecto<\/h2>\n<p>Audrey Low, de Manchester, present\u00f3 los resultados de un estudio brit\u00e1nico que comparaba el riesgo y la gravedad del infarto de miocardio en pacientes con AR que tomaban inhibidores del TNF con los que tomaban f\u00e1rmacos antirreum\u00e1ticos modificadores de la enfermedad (DMARD) no biol\u00f3gicos [2]. Esto se bas\u00f3 en los datos del estudio prospectivo en curso BSRBR-RA, que estudia la seguridad de la terapia biol\u00f3gica en la AR, y en los del Proyecto Nacional de Auditor\u00eda de la Isquemia Mioc\u00e1rdica (MINAP), una recopilaci\u00f3n nacional de datos de hospitalizaciones por infarto de miocardio en Inglaterra y Gales.<\/p>\n<p>El an\u00e1lisis compar\u00f3 a los pacientes con AR reclutados entre 2001 y 2008 que iniciaron un tratamiento con inhibidores del TNF (etanercept, infliximab, adalimumab) y los tratados con FAME no biol\u00f3gicos. El resultado es similar al del estudio mencionado anteriormente: los pacientes tratados con inhibidores del TNF tuvieron un menor riesgo de infarto de miocardio en comparaci\u00f3n con el otro grupo. No obstante, la gravedad de los infartos que se produjeron fue la misma en ambos grupos.<\/p>\n<h2 id=\"mayor-eficacia-del-tratamiento-de-la-ar\">Mayor eficacia del tratamiento de la AR<\/h2>\n<p>El rituximab es un f\u00e1rmaco utilizado habitualmente para la AR, pero tambi\u00e9n para la granulomatosis con poliange\u00edtis y algunos c\u00e1nceres. En el congreso del ACR se debati\u00f3 la hip\u00f3tesis de que la v\u00eda terap\u00e9utica tambi\u00e9n es segura y eficaz para las enfermedades asociadas a la IgG4. El doctor John Stone, de Boston, present\u00f3 los resultados de un estudio [3] que investigaba exactamente esto.<\/p>\n<p>La enfermedad asociada a IgG4 (IgG4-RD) se descubri\u00f3 recientemente. Se trata de una afecci\u00f3n multiorg\u00e1nica que imita numerosas afecciones reumatol\u00f3gicas&nbsp;, entre otras. Puede afectar a casi todos los \u00f3rganos del cuerpo. Las imitaciones reumatol\u00f3gicas m\u00e1s comunes son el s\u00edndrome de Sj\u00f6gren, la granulomatosis con poliange\u00edtis, el lupus eritematoso sist\u00e9mico y la sarcoidosis. Adem\u00e1s, la IgG4-RD tambi\u00e9n imita infecciones y tumores malignos, especialmente linfomas, carcinomas pancre\u00e1ticos, renales o pulmonares. La IgG4-RD se define ahora como una entidad de enfermedad por derecho propio, agrupando m\u00e1s de una docena de afecciones que antes se consideraban entidades de un solo \u00f3rgano.<br \/>\nUn equipo de investigadores dirigido por Stone ha investigado ahora si el tratamiento cl\u00e1sico de la AR con rituximab tambi\u00e9n ayuda contra la IgG4-RD. &#8220;Se necesitan urgentemente nuevas estrategias terap\u00e9uticas para esta enfermedad&#8221;, afirma Stone. &#8220;Los pacientes de nuestro estudio ten\u00edan m\u00faltiples \u00f3rganos afectados (por ejemplo, gl\u00e1ndulas salivales, pulmones, ganglios linf\u00e1ticos, p\u00e1ncreas, ri\u00f1ones, pr\u00f3stata), su IgG4-RD se confirm\u00f3 patol\u00f3gicamente. Se les trat\u00f3 con 1000 mg de rituximab al principio y el d\u00eda 15, pero no con una dosis de mantenimiento despu\u00e9s del d\u00eda 15. Con cada dosis de rituximab, recibieron tambi\u00e9n 100 mg de metilprednisolona. S\u00f3lo dos pacientes fueron tratados con prednisona adem\u00e1s de rituximab&#8221;.<\/p>\n<p>Se evalu\u00f3 a los pacientes uno, tres, cinco, seis, ocho, diez y doce meses despu\u00e9s de la primera dosis de rituximab para tres puntos: Respuesta de la enfermedad al f\u00e1rmaco, reagudizaci\u00f3n de la enfermedad al sexto mes y necesidad de a\u00f1adir un esteroide entre el segundo y el sexto mes. Estos factores (respuesta, ausencia de reagudizaci\u00f3n, ausencia de necesidad de esteroides) constituyeron el criterio de valoraci\u00f3n primario.<\/p>\n<p>26 de los 28 pacientes seguidos durante al menos un mes y 22 de 24 seguidos durante tres meses lograron una reducci\u00f3n de la actividad de la enfermedad sin el uso de esteroides. Entre los 23 pacientes seguidos hasta los seis meses, 20 cumplieron las tres condiciones del criterio de valoraci\u00f3n primario. S\u00f3lo dos de los 28 participantes necesitaron un aumento de prednisona tras el primer mes del estudio. El equipo de Stone no pudo detectar ning\u00fan efecto secundario grave o inesperado con el rituximab.<br \/>\n&#8220;Este estudio representa un paso importante para los pacientes con IgG4-RD y abre interesantes perspectivas de investigaci\u00f3n. El rituximab parece representar una nueva e importante opci\u00f3n de tratamiento para ellos, que podr\u00eda sustituir a la terapia prolongada e incluso indefinida con esteroides, a menudo combinada con otros f\u00e1rmacos potencialmente t\u00f3xicos de valor incierto. Por supuesto, es necesario verificar los resultados en un gran ensayo aleatorizado y aclarar las v\u00edas del rituximab en el contexto de esta enfermedad&#8221;, concluy\u00f3 Stone.<\/p>\n<p><em>Fuente: Reuni\u00f3n anual ACR\/ARHP, 26-30 de octubre de 2013, San Diego<\/em><\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Ljung L, et al: Los inhibidores del factor de necrosis tumoral y el riesgo de s\u00edndrome coronario agudo en la artritis reumatoide: un estudio nacional de cohortes. Resumen del ACR n\u00ba 804.<\/li>\n<li>Low ASL, et al: Incidence and Severity Of Myocardial Infarction In Subjects Receiving Anti Tumour Necrosis Factor Drugs For Rheumatoid Arthritis: Results From Linking the British Society For Rheumatology Biologics Register For Rheumatoid Arthritis and Myocardial Ischaemia National Audit Project. Resumen del ACR n\u00ba 2760.<\/li>\n<li>Stone J, et al: Rituximab para el tratamiento de la enfermedad relacionada con IgG4: un ensayo cl\u00ednico prospectivo. Resumen n\u00ba 2649 del ACR.<\/li>\n<\/ol>\n<p><em>ESPECIAL DEL CONGRESO 2014; 6(1): 2-3<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La artritis reumatoide (AR) es una enfermedad cr\u00f3nica que provoca inflamaci\u00f3n y, por tanto, restricci\u00f3n del movimiento y dolor en las articulaciones. Se da dos veces m\u00e1s en mujeres que&hellip;<\/p>\n","protected":false},"author":4,"featured_media":39733,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Artritis reumatoide","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11324,11483,11316,11451,11552],"tags":[50985,38264,14323,41992,20277,17816,14975,43808,58925,58930,58957,58936,58952,58945,15715,13983,19988,17034,13556,39391,29806],"powerkit_post_featured":[],"class_list":["post-346518","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologia","category-el-congreso-informa","category-geriatria","category-reumatologia","category-rx-es","tag-acr-es","tag-acs-es","tag-artritis-reumatoide","tag-conjunta","tag-cronica-es","tag-dmard-es","tag-dolor-es","tag-dolor-articular","tag-enfermedad-coronaria-es-2","tag-espondilitis-anquilosante-es","tag-estudio-bsrbr-ra","tag-factor-de-necrosis-tumoral","tag-igg4-rd-es","tag-inhibidor","tag-psa-es","tag-psoriasis-es-2","tag-ra-es","tag-riesgo","tag-rituximab-es","tag-san-diego-es","tag-tnf-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:57:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/346518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=346518"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/346518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/39733"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=346518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=346518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=346518"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=346518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}