{"id":347184,"date":"2013-09-19T00:00:00","date_gmt":"2013-09-18T22:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/como-se-puede-hacer-frente-a-los-depositos\/"},"modified":"2013-09-19T00:00:00","modified_gmt":"2013-09-18T22:00:00","slug":"como-se-puede-hacer-frente-a-los-depositos","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/como-se-puede-hacer-frente-a-los-depositos\/","title":{"rendered":"\u00bfC\u00f3mo se puede hacer frente a los dep\u00f3sitos?"},"content":{"rendered":"<p><strong>En el congreso EULAR de este a\u00f1o, el Prof. Thomas Bardin, MD de Par\u00eds, profundiz\u00f3 en las diversas estrategias terap\u00e9uticas para la gota y otras enfermedades inducidas por cristales. En concreto, habl\u00f3 de las ventajas y desventajas de los distintos f\u00e1rmacos utilizados para la inflamaci\u00f3n aguda y cr\u00f3nica.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>El Prof. Dr. med. Thomas Bardin, de Par\u00eds, comenz\u00f3 su conferencia con una visi\u00f3n general de las posibles estrategias de gesti\u00f3n de los ataques agudos de gota. Por un lado, el enfriamiento y el reposo ya pueden ayudar; por otro, a menudo se utilizan en combinaci\u00f3n colchicinas y antiinflamatorios no esteroideos (AINE). Los glucocorticoides y los anti-IL-1 tambi\u00e9n son eficaces. &#8220;La regla general es que los f\u00e1rmacos funcionan mejor si se administran precozmente. Sin embargo, la gota no puede curarse con ellos en ning\u00fan caso&#8221;, afirma el Prof. Bardin.<\/p>\n<p>Las recomendaciones de la EULAR de 2006 afirman que las dosis altas de colchicina pueden provocar efectos secundarios, pero las dosis peque\u00f1as (por ejemplo, 3\u00d7 0,5&nbsp;mg\/d) ya son eficaces en algunos pacientes. As\u00ed lo confirma un estudio de Terkeltaub et al. (2010): La administraci\u00f3n de dosis bajas de colchicina (1,8 mg\/d\u00eda) se toler\u00f3 mejor (menos efectos secundarios como diarrea o v\u00f3mitos) y funcion\u00f3 con la misma eficacia que la dosis alta (4,8 mg\/d\u00eda) [1]. Las recomendaciones del ACR de 2012 para el uso de la colchicina en la gota aguda tambi\u00e9n consideran una dosis inicial de 1,2 mg m\u00e1s 0,6 mg una hora despu\u00e9s, seguida de 0,6 mg una o dos veces al d\u00eda hasta que el ataque de gota haya terminado.<\/p>\n<p>La comparaci\u00f3n entre un AINE (naproxeno) y un glucocorticoide sint\u00e9tico (prednisolona) fue realizada por Janssens et al. (2008) [2]. El resultado: La prednisolona y el naproxeno son igual de eficaces en el tratamiento inicial de la gota durante cuatro d\u00edas.<\/p>\n<p>Los inhibidores de la IL-1 se han estudiado sobre todo en el contexto de los ataques agudos de gota. Seg\u00fan el Prof. Bardin, pueden considerarse una opci\u00f3n de tratamiento para los pacientes dif\u00edciles de tratar. Sin embargo, todav\u00eda no se ha comercializado ning\u00fan inhibidor de la IL-1 con esta indicaci\u00f3n. Tambi\u00e9n preocupa el coste y la tolerancia de la inhibici\u00f3n de la IL-1 a largo plazo. Hay datos que muestran una buena eficacia de la anakinra, por ejemplo, aunque no de forma consistente. Especialmente en la gota aguda, este antagonista del receptor de la IL-1 parece ser eficaz, menos en la inflamaci\u00f3n cr\u00f3nica. El canakinumab es un anticuerpo anti-IL-1 de larga duraci\u00f3n. Schlesinger et al. demostr\u00f3 en 2012 que el canakinumab proporcionaba un alivio significativo del dolor y la inflamaci\u00f3n y reduc\u00eda el riesgo de nuevos ataques en pacientes con gota aguda [3].<\/p>\n<h2 id=\"inflamaciones-cpp-y-bcp\">Inflamaciones CPP y BCP<\/h2>\n<p>El enfriamiento, el reposo, la aspiraci\u00f3n articular o las inyecciones de esteroides pueden utilizarse para tratar la inflamaci\u00f3n aguda por pirofosfato c\u00e1lcico (PPC). Adem\u00e1s, tienen efecto las colchicinas, los AINE , los esteroides, las hormonas adrenocorticotr\u00f3picas (ACTH) y los bloqueantes de la IL1. En la forma cr\u00f3nica, adem\u00e1s de los esteroides sist\u00e9micos, pueden utilizarse colchicina, AINE, inyecciones articulares con esteroides, radiois\u00f3topos e hidroxicloroquina. Tambi\u00e9n pueden considerarse el metotrexato o los bloqueantes de IL-1.<br \/>\nLa inflamaci\u00f3n por fosfato b\u00e1sico de calcio (BCP) se puede tratar con AINE, esteroides, colquicina o anakinra, seg\u00fan el profesor Bardin.<\/p>\n<h2 id=\"evite-los-depositos\">Evite los dep\u00f3sitos<\/h2>\n<p>La parte m\u00e1s importante de la terapia de la gota es controlar los dep\u00f3sitos de urato monos\u00f3dico (MSU), subray\u00f3 el Prof. Bardin. La reducci\u00f3n de la uremia por debajo del nivel de saturaci\u00f3n de MSU permite la resoluci\u00f3n de los dep\u00f3sitos de cristales y, por tanto, de las caracter\u00edsticas de la gota. El objetivo en este caso, seg\u00fan las recomendaciones de la EULAR, ser\u00eda un valor de &lt;6&nbsp;mg\/dl (360 mmol\/l). En el caso de las formas de gota tofos, los valores objetivo se fijan posiblemente a\u00fan m\u00e1s bajos, lo que plantea la cuesti\u00f3n de si el valor se reduce demasiado con f\u00e1rmacos eficaces, nuevos o terapias combinadas, seg\u00fan el Prof. Bardin. &#8220;El \u00e1cido \u00farico es un antioxidante beneficioso para el cerebro. As\u00ed lo indican diversos estudios. Adem\u00e1s, parece existir una conexi\u00f3n entre los niveles extremos de \u00e1cido \u00farico y la mortalidad [4]&#8221;.<\/p>\n<p>Entonces, \u00bfc\u00f3mo se puede reducir el \u00e1cido \u00farico? La modificaci\u00f3n del estilo de vida, como la dieta y el ejercicio, s\u00f3lo tienen un efecto moderado sobre la uremia. Es importante interrumpir los f\u00e1rmacos inductores de hiperuricemia (diur\u00e9ticos, ciclosporina, tacrolimus) y utilizar aquellos que tengan un efecto reductor de la uratosis, como el alopurinol o el probenecid. En 2010, un estudio de Thanassoulis et al. muestran que la administraci\u00f3n de alopurinol puede ser especialmente \u00fatil para los pacientes de gota con defectos card\u00edacos [5]. &#8220;Sin embargo, varios puntos son tambi\u00e9n problem\u00e1ticos con el alopurinol. La mayor\u00eda de los m\u00e9dicos no superan una dosis m\u00e1xima de 300&nbsp;mg\/d\u00eda. Por ello, a menudo no alcanzan el objetivo de uremia de &lt;6 mg\/dl. Adem\u00e1s, el f\u00e1rmaco puede provocar reacciones cut\u00e1neas graves (Lyell, Steven-Johnson, DRESS)&#8221;, afirma el Prof. Bardin. &#8220;En general, la adherencia a los f\u00e1rmacos reductores del \u00e1cido \u00farico (DLU) en la gota es relativamente pobre en comparaci\u00f3n con otras enfermedades cr\u00f3nicas&#8221;. Por lo tanto, el paciente debe estar bien informado y participar intensamente en el proceso de toma de decisiones en todos los casos.&#8221;<\/p>\n<p><em>Fuente: &#8220;Gota y otras enfermedades cristalinas&#8221;, EULAR,&nbsp;12-15 junio 2013, Madrid<\/em><\/p>\n<p>Literatura:<\/p>\n<ol>\n<li>Terkeltaub RA, et al: Dosis alta frente a dosis baja de colchicina oral para el brote agudo precoz de gota: Resultado a las 24 horas del primer estudio multic\u00e9ntrico, aleatorizado, doble ciego, controlado con placebo, de grupos paralelos y de comparaci\u00f3n de dosis de colchicina. Arthritis Rheum 2010 abr; 62(4): 1060-1068. doi: 10.1002\/art.27327.<\/li>\n<li>Janssens HJ, et al: Uso de prednisolona oral o naproxeno para el tratamiento de la artritis gotosa: un ensayo de equivalencia aleatorizado y doble ciego. Lancet 2008 31 de mayo; 371(9627): 1854-1860. doi: 10.1016\/S0140-6736(08)60799-0.<\/li>\n<li>Schlesinger N, et al: Canakinumab para la artritis gotosa aguda en pacientes con opciones de tratamiento limitadas: resultados de dos ensayos aleatorizados, multic\u00e9ntricos, controlados activamente, doble ciego y sus ampliaciones iniciales. Ann Rheum Dis 2012; 71: 1839-1848. doi:10.1136\/annrheumdis-2011-200908.<\/li>\n<li>Kuo CF, et al: Importancia de los niveles s\u00e9ricos de \u00e1cido \u00farico en el riesgo de mortalidad por todas las causas y cardiovascular. Reumatolog\u00eda (Oxford) 2013; 52(1): 127-134.<\/li>\n<li>Thanassoulis G, et al: Gota, uso de alopurinol y resultados de la insuficiencia cardiaca. Arch Intern Med 2010; 170(15): 1358-1364. doi:10.1001\/archinternmed.2010.198.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>En el congreso EULAR de este a\u00f1o, el Prof. Thomas Bardin, MD de Par\u00eds, profundiz\u00f3 en las diversas estrategias terap\u00e9uticas para la gota y otras enfermedades inducidas por cristales. En&hellip;<\/p>\n","protected":false},"author":4,"featured_media":35174,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Gota","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11483,11316,11451,11552],"tags":[17486,26737,61426,20277,51609,41006,11940,40603,19223,45052,17170,51005,61450,61442,61435,11810],"powerkit_post_featured":[],"class_list":["post-347184","post","type-post","status-publish","format-standard","has-post-thumbnail","category-el-congreso-informa","category-geriatria","category-reumatologia","category-rx-es","tag-aine-es","tag-anakinra-es","tag-anti-il-1-es","tag-cronica-es","tag-depositos-es","tag-diureticos-es","tag-efectos-secundarios","tag-esteroides-es-3","tag-eular-es","tag-glucocorticoides-es","tag-gota-es","tag-inflamacion","tag-inflamacion-por-fosfato-basico-de-calcio-bcp","tag-inflamacion-por-pirofosfato-calcico-cpp","tag-recomendacion-del-acr","tag-terapia-es","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 17:49:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/347184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=347184"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/347184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/35174"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=347184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=347184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=347184"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=347184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}