{"id":393528,"date":"2025-02-13T00:01:00","date_gmt":"2025-02-12T23:01:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=393528"},"modified":"2025-02-12T22:12:18","modified_gmt":"2025-02-12T21:12:18","slug":"sindrome-de-wolfram","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/sindrome-de-wolfram\/","title":{"rendered":"S\u00edndrome de Wolfram"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El t\u00e9rmino s\u00edndrome &#8220;DIDMOAD&#8221; -un acr\u00f3nimo de los s\u00edntomas caracter\u00edsticos- sirve como nombre alternativo para esta enfermedad neurodegenerativa autos\u00f3mica recesiva, que se describi\u00f3 por primera vez en 1938: Diabetes Ins\u00edpida, Diabetes Mellitus, Atrofia \u00d3ptica y Sordera\/Sordera. En la mayor\u00eda de los pacientes pueden detectarse mutaciones en el gen WFS1. <\/strong><\/p>\n\n\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Fsindrome-de-wolfram%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El t\u00e9rmino s\u00edndrome &#8220;DIDMOAD&#8221; -un acr\u00f3nimo de los s\u00edntomas caracter\u00edsticos- sirve como nombre alternativo para esta enfermedad neurodegenerativa autos\u00f3mica recesiva, que se describi\u00f3 por primera vez en 1938: Diabetes Ins\u00edpida,&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Fsindrome-de-wolfram%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":393531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Enfermedades raras","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11552,11324,11352,11475,11478,11364,11288,11377,11328,11393,11435,11461],"tags":[11662,80729,26292,13094,80731,80733],"powerkit_post_featured":[],"class_list":["post-393528","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-es","category-cardiologia","category-endocrinologia-y-diabetologia","category-estudios","category-formacion-continua","category-genetica","category-medicina-interna-general","category-nefrologia","category-neurologia","category-orl-es","category-psiquiatria-y-psicoterapia","category-urologia","tag-diabetes-es","tag-didmoad-es","tag-enfermedades-raras-es","tag-mutaciones","tag-sindrome-de-wolfram","tag-wfs1-es","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:56:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/393528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=393528"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/393528\/revisions"}],"predecessor-version":[{"id":394895,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/393528\/revisions\/394895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/393531"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=393528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=393528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=393528"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=393528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}