{"id":410973,"date":"2025-12-02T00:30:00","date_gmt":"2025-12-01T23:30:00","guid":{"rendered":"https:\/\/medizinonline.com\/?p=410973"},"modified":"2025-12-02T09:04:58","modified_gmt":"2025-12-02T08:04:58","slug":"perdida-de-orientacion-en-el-cerebelo","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/perdida-de-orientacion-en-el-cerebelo\/","title":{"rendered":"P\u00e9rdida de orientaci\u00f3n en el cerebelo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Las ataxias espinocerebelosas representan un amplio grupo de enfermedades neurodegenerativas raras y progresivas que afectan al cerebelo y sus conexiones y se manifiestan predominantemente en un s\u00edndrome cerebeloso. Adem\u00e1s de la discapacidad motora progresiva, que se manifiesta en una marcha inestable, incoordinaci\u00f3n de las extremidades o disartria, la enfermedad suele ir acompa\u00f1ada de un s\u00edndrome cerebeloso cognitivo-afectivo. \u00c9ste abarca un espectro de d\u00e9ficits cognitivos y neuropsiqui\u00e1tricos, en los que las alteraciones de las funciones ejecutivas, ling\u00fc\u00edsticas y visuoespaciales ocupan un lugar central.  <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Fperdida-de-orientacion-en-el-cerebelo%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Las ataxias espinocerebelosas representan un amplio grupo de enfermedades neurodegenerativas raras y progresivas que afectan al cerebelo y sus conexiones y se manifiestan predominantemente en un s\u00edndrome cerebeloso. Adem\u00e1s de&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Fperdida-de-orientacion-en-el-cerebelo%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":410974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Ataxia de Friedreich","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11552,11475,11478,11328],"tags":[84945,85825],"powerkit_post_featured":[],"class_list":["post-410973","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-es","category-estudios","category-formacion-continua","category-neurologia","tag-ataxia-de-friedreich","tag-perdida-de-orientacion","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:17:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/410973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=410973"}],"version-history":[{"count":3,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/410973\/revisions"}],"predecessor-version":[{"id":450360,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/410973\/revisions\/450360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/410974"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=410973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=410973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=410973"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=410973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}