{"id":459790,"date":"2026-02-15T00:30:00","date_gmt":"2026-02-14T23:30:00","guid":{"rendered":"https:\/\/medizinonline.com\/los-glp-1ra-mostraron-un-valioso-doble-beneficio\/"},"modified":"2026-02-14T21:52:58","modified_gmt":"2026-02-14T20:52:58","slug":"los-glp-1ra-mostraron-un-valioso-doble-beneficio","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/es\/los-glp-1ra-mostraron-un-valioso-doble-beneficio\/","title":{"rendered":"Los GLP-1RA mostraron un valioso doble beneficio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Los GLP-1RA, incluidos la semaglutida y la liraglutida, se utilizan con frecuencia en la actualidad para el tratamiento de la diabetes de tipo 2 y la obesidad. Un estudio reciente investig\u00f3 si los pacientes con psoriasis diab\u00e9tica y\/o sobrepeso se benefician del tratamiento con GLP-1RAs y de qu\u00e9 manera. Los resultados iniciales se presentaron en el congreso de este a\u00f1o de la <em>Academia Europea de Dermatolog\u00eda y Venereolog\u00eda<\/em> (EADV).  <\/strong><\/p>\n\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Flos-glp-1ra-mostraron-un-valioso-doble-beneficio%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Los GLP-1RA, incluidos la semaglutida y la liraglutida, se utilizan con frecuencia en la actualidad para el tratamiento de la diabetes de tipo 2 y la obesidad. Un estudio reciente&#8230;&hellip;... <\/p>\n<div class=\"pmpro\"><div class=\"pmpro_card pmpro_content_message\"><div class=\"pmpro_card_content\">Dieser Inhalt ist nur f\u00fcr Benutzer der Gruppe: Medizinische Fachperson zug\u00e4nglich <br \/><a href=\"https:\/\/medizinonline.com\/es\/mi-cuenta\/paquetes\/\">Jetzt beitreten<\/a><\/div><div class=\"pmpro_card_actions pmpro_font-medium\">\u00bfYa eres miembro? <a href=\"https:\/\/medizinonline.com\/es\/conectarse\/?redirect_to=https%3A%2F%2Fmedizinonline.com%2Fes%2Flos-glp-1ra-mostraron-un-valioso-doble-beneficio%2F\">Accede aqu\u00ed<\/a><\/div><\/div><\/div>","protected":false},"author":7,"featured_media":459793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Psoriasis y comorbilidades metab\u00f3licas: datos de un nuevo estudio","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11552,11324,11310,11483,11352,11475,11408,11451],"tags":[87667,12033,16732,18646,12458,13983,17397,12456],"powerkit_post_featured":[],"class_list":["post-459790","post","type-post","status-publish","format-standard","has-post-thumbnail","category-rx-es","category-cardiologia","category-dermatologia-y-venereologia","category-el-congreso-informa","category-endocrinologia-y-diabetologia","category-estudios","category-farmacologia-y-toxicologia","category-reumatologia","tag-comorbilidades-metabolicas","tag-diabetes-tipo-2-es-2","tag-eadv-es","tag-liraglutida","tag-obesidad","tag-psoriasis-es-2","tag-semaglutida-es","tag-sobrepeso","pmpro-level-required","pmpro-level-1","pmpro-no-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 17:49:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"es_ES","wpml_translations":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/459790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/comments?post=459790"}],"version-history":[{"count":1,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/459790\/revisions"}],"predecessor-version":[{"id":459795,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts\/459790\/revisions\/459795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media\/459793"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/media?parent=459790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/category?post=459790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags?post=459790"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/powerkit_post_featured?post=459790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}