{"id":22110,"count":3,"description":"","link":"https:\/\/medizinonline.com\/es\/tag\/erenumab-es\/","name":"Erenumab","slug":"erenumab-es","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags\/22110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?tags=22110"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?tags=22110"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?tags=22110"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tribe_events?tags=22110"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=22110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}