{"id":24816,"count":1,"description":"","link":"https:\/\/medizinonline.com\/es\/tag\/hepatopatia-mediada-por-el-alcohol\/","name":"Hepatopat\u00eda mediada por el alcohol","slug":"hepatopatia-mediada-por-el-alcohol","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags\/24816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?tags=24816"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?tags=24816"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?tags=24816"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tribe_events?tags=24816"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=24816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}