{"id":44431,"count":1,"description":"","link":"https:\/\/medizinonline.com\/es\/tag\/terapia-con-celulas-t\/","name":"Terapia con c\u00e9lulas T","slug":"terapia-con-celulas-t","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags\/44431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?tags=44431"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?tags=44431"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?tags=44431"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tribe_events?tags=44431"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=44431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}