{"id":95714,"count":1,"description":"","link":"https:\/\/medizinonline.com\/es\/tag\/mrd-als-staerkster-praediktor\/","name":"MRD als st\u00e4rkster Pr\u00e4diktor","slug":"mrd-als-staerkster-praediktor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags\/95714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/posts?tags=95714"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/article_rx?tags=95714"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/post_dl?tags=95714"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tribe_events?tags=95714"},{"href":"https:\/\/medizinonline.com\/es\/wp-json\/wp\/v2\/tec_calendar_embed?tags=95714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}