{"id":324090,"date":"2022-11-23T12:11:38","date_gmt":"2022-11-23T11:11:38","guid":{"rendered":"https:\/\/medizinonline.com\/protection-cardiaque-et-renale-pour-un-large-eventail-de-patients\/"},"modified":"2022-11-23T12:11:38","modified_gmt":"2022-11-23T11:11:38","slug":"protection-cardiaque-et-renale-pour-un-large-eventail-de-patients","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/protection-cardiaque-et-renale-pour-un-large-eventail-de-patients\/","title":{"rendered":"Protection cardiaque et r\u00e9nale pour un large \u00e9ventail de patients"},"content":{"rendered":"<p><strong>Les donn\u00e9es de l&#8217;\u00e9tude EMPA-KIDNEY, lanc\u00e9e par le professeur Christoph Wanner de l&#8217;h\u00f4pital universitaire de W\u00fcrzburg en collaboration avec l&#8217;universit\u00e9 d&#8217;Oxford, \u00e9largissent le spectre de l&#8217;administration d&#8217;inhibiteurs de SGLT2 en cas de maladie r\u00e9nale chronique, ind\u00e9pendamment du statut du diab\u00e8te, de l&#8217;albuminurie ou de la fonction r\u00e9nale.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">La pr\u00e9sentation des r\u00e9sultats n&#8217;a certes pas \u00e9t\u00e9 un coup de tonnerre : en effet, l&#8217;utilit\u00e9 clinique des deux inhibiteurs du SGLT2, la dapagliflozine et la canagliflozine, dans le traitement des maladies r\u00e9nales chroniques a d\u00e9j\u00e0 \u00e9t\u00e9 prouv\u00e9e dans des \u00e9tudes ant\u00e9rieures. Les inhibiteurs de SGLT2 inhibent le transporteur r\u00e9nal de glucose d\u00e9pendant du sodium SGLT-2 (Sodium dependent glucose co-transporter 2) et entra\u00eenent une augmentation de l&#8217;excr\u00e9tion de sucre dans l&#8217;urine. Cela fait baisser le taux de glyc\u00e9mie et peut entra\u00eener une l\u00e9g\u00e8re diminution du poids et de la pression art\u00e9rielle. En m\u00eame temps, les reins et la circulation sanguine sont soulag\u00e9s. L&#8217;efficacit\u00e9 de la substance active empagliflozine a toutefois cr\u00e9\u00e9 la surprise, m\u00eame chez le professeur Dr Christoph Wanner. Le chef du service de n\u00e9phrologie de l&#8217;h\u00f4pital universitaire de W\u00fcrzburg a \u00e9t\u00e9 l&#8217;un des premiers \u00e0 publier le potentiel des inhibiteurs de SGLT2 dans le traitement du diab\u00e8te et des maladies cardiovasculaires et r\u00e9nales d\u00e8s 2015 dans l&#8217;\u00e9tude EMPA-REG OUTCOME. Il a eu l&#8217;id\u00e9e de l&#8217;\u00e9tude EMPA-KIDNEY, dont les r\u00e9sultats ont \u00e9t\u00e9 publi\u00e9s dans le New England Journal of Medicine parall\u00e8lement \u00e0 la Kidney Week de l&#8217;ASN.&nbsp;<\/span><\/p>\n<p><strong><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">R\u00e9duction du risque de 28% par rapport au placebo&nbsp;<\/span><\/strong><\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">L&#8217;\u00e9quipe de l&#8217;\u00e9tude, dirig\u00e9e par l&#8217;Universit\u00e9 d&#8217;Oxford en coop\u00e9ration avec la m\u00e9decine universitaire de W\u00fcrzburg, avait pr\u00e9vu au d\u00e9but des recherches une r\u00e9duction du risque de 18 pour cent. Le risque comprenait une combinaison des crit\u00e8res d&#8217;\u00e9valuation primaires que sont le d\u00e9c\u00e8s d\u00fb \u00e0 une maladie cardiaque et l&#8217;insuffisance r\u00e9nale, c&#8217;est-\u00e0-dire la n\u00e9cessit\u00e9 d&#8217;une dialyse ou d&#8217;une transplantation r\u00e9nale ou une baisse de la performance de la fonction r\u00e9nale, appel\u00e9e d\u00e9bit de filtration glom\u00e9rulaire (DFG) de 40 pour cent ou plus. &#8220;Mais le fait que l&#8217;administration d&#8217;empagliflozine permette d&#8217;obtenir une r\u00e9duction du risque de 28% par rapport \u00e0 un placebo, et ce dans une large population de patients souffrant d&#8217;une maladie r\u00e9nale chronique, est sensationnel&#8221;, commente Christoph Wanner. &#8220;Nous avons pu observer les effets positifs sur la protection cardiaque et r\u00e9nale ind\u00e9pendamment du statut du diab\u00e8te ou de la quantit\u00e9 d&#8217;albumine dans l&#8217;urine&#8221;.&nbsp;L&#8217;empagliflozine a \u00e9galement montr\u00e9 un r\u00e9sultat significatif en termes de taux d&#8217;hospitalisation. Le nombre d&#8217;hospitalisations a diminu\u00e9 de 14 %, quel que soit le motif d&#8217;hospitalisation. &#8220;J&#8217;ai \u00e9galement \u00e9t\u00e9 positivement surpris de constater que l&#8217;empagliflozine continue d&#8217;agir m\u00eame \u00e0 un d\u00e9bit de filtration glom\u00e9rulaire (DFG) de 20 millilitres par minute&#8221;.<\/span><\/p>\n<p><strong><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">L&#8217;empagliflozine adapt\u00e9e \u00e0 diff\u00e9rents profils de maladie<\/span><\/strong><\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">Cela signifie que l&#8217;empagfliflozine peut \u00eatre utilis\u00e9e en cas de maladie r\u00e9nale chronique sans diab\u00e8te et sans albuminurie, ou en cas d&#8217;insuffisance cardiaque concomitante et m\u00eame en cas de faible fonction r\u00e9nale. Selon Wanner, cela facilitera consid\u00e9rablement la pratique de prescription des m\u00e9decins lib\u00e9raux. Selon Wanner, il est toutefois important de poser un diagnostic et donc d&#8217;\u00e9valuer le risque de maladies cardiaques et r\u00e9nales, id\u00e9alement selon le sch\u00e9ma ABCDE : A signifie albuminurie, une excr\u00e9tion \u00e9lev\u00e9e d&#8217;albumine dans les urines indique tr\u00e8s t\u00f4t une atteinte r\u00e9nale, bien avant que les effets de l&#8217;insuffisance r\u00e9nale ne se fassent m\u00eame sentir. Chez une personne en bonne sant\u00e9, la concentration d&#8217;albumine dans l&#8217;urine est inf\u00e9rieure \u00e0 30 milligrammes. B correspond \u00e0 la pression art\u00e9rielle, C au cholest\u00e9rol, D au diab\u00e8te et E au statut eGFR. Le e signifie estimated, estim\u00e9 en anglais. Le taux de filtration glom\u00e9rulaire est estim\u00e9 en fonction de la cr\u00e9atinine s\u00e9rique, de l&#8217;\u00e2ge, du sexe et de la couleur de peau. La valeur normale de l&#8217;urine primaire filtr\u00e9e \u00e0 partir du sang est de 90 \u00e0 130 millilitres par minute.&nbsp;<\/span><\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\"><strong>Une m\u00e9ta-analyse confirme les r\u00e9sultats de l&#8217;\u00e9tude EMPA-KIDNEY<\/strong>&nbsp;<\/span><\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">Les r\u00e9sultats de l&#8217;\u00e9tude EMPA-KIDNEY ont \u00e9galement \u00e9t\u00e9 int\u00e9gr\u00e9s et confirm\u00e9s dans une m\u00e9ta-analyse de 13 \u00e9tudes SGLT2 portant sur un total de 90.309 personnes diab\u00e9tiques et 15.605 personnes non diab\u00e9tiques. Dans l&#8217;analyse qui vient d&#8217;\u00eatre publi\u00e9e dans la prestigieuse revue The Lancet&nbsp;, plusieurs responsables d&#8217;essais cliniques, appel\u00e9s investigateurs principaux, ont sp\u00e9cifiquement \u00e9tudi\u00e9 l&#8217;influence du diab\u00e8te en ce qui concerne l&#8217;effet des inhibiteurs de SGLT2 sur les valeurs r\u00e9nales et les maladies cardiovasculaires. Christoph Wanner, qui a particip\u00e9 \u00e0 la fois au comit\u00e9 d&#8217;\u00e9criture et au consortium dit SMART-c de la m\u00e9ta-analyse, r\u00e9sume : &#8220;Les donn\u00e9es soutiennent l&#8217;utilisation des inhibiteurs de SGLT2 pour r\u00e9duire le risque de progression des maladies r\u00e9nales et des l\u00e9sions r\u00e9nales aigu\u00ebs, ind\u00e9pendamment du risque de diab\u00e8te&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color:rgb(34, 34, 34); font-family:helvetica neue,helveticaneue,helvetica,arial,lucida grande,sans-serif\">Publication originale :<\/span><\/p>\n<p>Impact du diab\u00e8te sur les effets des inhibiteurs du co-transporteur 2 du glucose sodique sur les r\u00e9sultats r\u00e9naux : m\u00e9ta-analyse collaborative de grands essais contr\u00f4l\u00e9s par placebo. The Lancet, VOLUME 400, ISSUE 10365, P1788-1801, NOVEMBRE 19 ; DOI : https:\/\/doi.org\/10.1016\/S0140-6736(22)02074-8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les donn\u00e9es de l&#8217;\u00e9tude EMPA-KIDNEY, lanc\u00e9e par le professeur Christoph Wanner de l&#8217;h\u00f4pital universitaire de W\u00fcrzburg en collaboration avec l&#8217;universit\u00e9 d&#8217;Oxford, \u00e9largissent le spectre de l&#8217;administration d&#8217;inhibiteurs de SGLT2 en&hellip;<\/p>\n","protected":false},"author":16,"featured_media":126853,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Inhibiteur du SGLT-2 Empagliflozine","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11378,11404,11527,11549],"tags":[],"powerkit_post_featured":[],"class_list":["post-324090","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cardiologie","category-endocrinologie-et-diabetologie","category-etudes","category-rx-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:16:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":324096,"slug":"protezione-del-cuore-e-dei-reni-per-un-ampio-spettro-di-pazienti","post_title":"Protezione del cuore e dei reni per un ampio spettro di pazienti","href":"https:\/\/medizinonline.com\/it\/protezione-del-cuore-e-dei-reni-per-un-ampio-spettro-di-pazienti\/"},"pt_PT":{"locale":"pt_PT","id":324121,"slug":"proteccao-do-coracao-e-dos-rins-para-um-largo-espectro-de-doentes","post_title":"Protec\u00e7\u00e3o do cora\u00e7\u00e3o e dos rins para um largo espectro de doentes","href":"https:\/\/medizinonline.com\/pt-pt\/proteccao-do-coracao-e-dos-rins-para-um-largo-espectro-de-doentes\/"},"es_ES":{"locale":"es_ES","id":324123,"slug":"proteccion-cardiaca-y-renal-para-un-amplio-espectro-de-pacientes","post_title":"Protecci\u00f3n cardiaca y renal para un amplio espectro de pacientes","href":"https:\/\/medizinonline.com\/es\/proteccion-cardiaca-y-renal-para-un-amplio-espectro-de-pacientes\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/324090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=324090"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/324090\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=324090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=324090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=324090"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=324090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}