{"id":324494,"date":"2022-10-17T01:00:00","date_gmt":"2022-10-16T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/un-age-avance-une-dose-elevee\/"},"modified":"2022-10-17T01:00:00","modified_gmt":"2022-10-16T23:00:00","slug":"un-age-avance-une-dose-elevee","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/un-age-avance-une-dose-elevee\/","title":{"rendered":"Un \u00e2ge avanc\u00e9 &#8211; une dose \u00e9lev\u00e9e !"},"content":{"rendered":"<p><strong>La grippe est la maladie infectieuse \u00e0 pr\u00e9vention vaccinale la plus fr\u00e9quente. N\u00e9anmoins, elle est toujours en t\u00eate de la liste des maladies infectieuses en Europe, \u00e0 l&#8217;exception des deux derni\u00e8res saisons o\u00f9 la pand\u00e9mie de COVID-19 a fortement influenc\u00e9 le tableau. Mais quel a \u00e9t\u00e9 l&#8217;impact de la pand\u00e9mie sur l&#8217;immunit\u00e9 de la population contre la grippe et que peut-on en attendre pour les saisons post-pand\u00e9miques ?<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>L&#8217;infection en elle-m\u00eame est un des probl\u00e8mes de la grippe. L&#8217;autre est l&#8217;augmentation du risque de maladies secondaires telles que l&#8217;infarctus du myocarde (jusqu&#8217;\u00e0 10 fois plus \u00e9lev\u00e9) ou l&#8217;accident vasculaire c\u00e9r\u00e9bral (jusqu&#8217;\u00e0 8 fois plus \u00e9lev\u00e9), a rappel\u00e9 le professeur Susanne Herold, Clinique m\u00e9dicale V &#8211; M\u00e9decine interne, infectiologie et hygi\u00e8ne hospitali\u00e8re, H\u00f4pital universitaire de Giessen et Marburg (D) [1]. Lors de la derni\u00e8re forte saison grippale 2017\/2018, les deux tiers des cas \u00e9taient des infections \u00e0 la grippe B de la lign\u00e9e Yamagata. Le probl\u00e8me \u00e0 l&#8217;\u00e9poque \u00e9tait que le vaccin contre la grippe n&#8217;incluait pas cette lign\u00e9e. Depuis lors, le vaccin antigrippal quadrivalent (QIV) avec 2 lignes B et 2 lignes A est donc toujours recommand\u00e9.<\/p>\n<p>Le professeur Herold a soulign\u00e9 que la vaccination simultan\u00e9e contre la grippe et le COVID-19 \u00e9tait possible et qu&#8217;aucun intervalle de temps n&#8217;\u00e9tait requis, ce qui devrait sans aucun doute am\u00e9liorer l&#8217;observance chez les patients. En outre, et c&#8217;est une nouveaut\u00e9, les personnes \u00e2g\u00e9es (en Suisse, \u00e0 partir de 65 ans) peuvent \u00eatre vaccin\u00e9es avec un vaccin \u00e0 haute dose<span style=\"font-family:franklin gothic demi\"> (encadr\u00e9, tab.&nbsp;1),<\/span> qui contient une plus grande quantit\u00e9 d&#8217;antig\u00e8nes.<\/p>\n<p>Il est bien connu que les adultes \u00e2g\u00e9s souffrent beaucoup plus de la morbidit\u00e9 et de la mortalit\u00e9 associ\u00e9es \u00e0 la grippe. L&#8217;experte a pr\u00e9sent\u00e9 des donn\u00e9es provenant d&#8217;Allemagne, selon lesquelles la proportion d&#8217;hospitalisations de patients de plus de 60 ans \u00e9tait de 58% pour la saison 2017\/2018, la proportion de d\u00e9c\u00e8s li\u00e9s \u00e0 la grippe atteignant m\u00eame 86% dans ce groupe d&#8217;\u00e2ge. La raison en est l&#8217;immunos\u00e9nescence, qui entra\u00eene une moins bonne efficacit\u00e9 chez les personnes \u00e2g\u00e9es.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19832\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/10\/tab1_pa3_s34.png\" style=\"height:226px; width:600px\" width=\"1100\" height=\"414\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"meilleure-reponse-immunitaire-chez-les-personnes-agees\">Meilleure r\u00e9ponse immunitaire chez les personnes \u00e2g\u00e9es<\/h2>\n<p>En Allemagne, la <em>commission permanente sur les vaccinations<\/em> (STIKO) s&#8217;est pench\u00e9e sur le probl\u00e8me et a examin\u00e9 les nouveaux vaccins autoris\u00e9s dans ce contexte. Quatre approches diff\u00e9rentes ont \u00e9t\u00e9 \u00e9tudi\u00e9es : adjuvanter les vaccins contre la grippe, utiliser des doses plus \u00e9lev\u00e9es (h\u00e9magglutinine multipli\u00e9e par 4 par rapport au vaccin standard), examiner les vaccins bas\u00e9s sur la culture cellulaire et les vaccins recombinants, qui ont \u00e9galement \u00e9t\u00e9 consid\u00e9r\u00e9s comme produisant une meilleure r\u00e9ponse vaccinale que les vaccins \u00e0 base d&#8217;\u0153ufs [2]. &#8220;Cependant, le r\u00e9sultat \u00e9tait que seul le vaccin \u00e0 haute dose entra\u00eenait une meilleure r\u00e9ponse immunitaire chez les patients \u00e2g\u00e9s&#8221;, a r\u00e9sum\u00e9 le professeur Herold. Sur la base de ces r\u00e9sultats, les scientifiques allemands recommandent donc \u00e0 toutes les personnes \u00e2g\u00e9es de 60 ans et plus (65 ans et plus en Suisse) de se faire vacciner chaque ann\u00e9e en automne contre la grippe saisonni\u00e8re \u00e0 l&#8217;aide d&#8217;un vaccin grippal quadrivalent inactiv\u00e9 \u00e0 haute dose contenant la combinaison antig\u00e9nique actuelle recommand\u00e9e par l&#8217;OMS.<\/p>\n<p>L&#8217;\u00e9tude a \u00e9t\u00e9 bas\u00e9e sur une \u00e9tude multicentrique am\u00e9ricano-canadienne [3]. Dans leur analyse en intention de traiter (ITT), sur 32 000 participants, 1,4% ont contract\u00e9 la grippe avec le vaccin \u00e0 dose \u00e9lev\u00e9e, contre 1,9% avec la dose standard. &#8220;Cela ne semble pas si terrible&#8221;, a d\u00e9clar\u00e9 le professeur Herold, &#8220;mais l&#8217;activit\u00e9 relative du vaccin dans le groupe \u00e0 forte dose \u00e9tait 24,2% plus \u00e9lev\u00e9e et l&#8217;immunog\u00e9nicit\u00e9 \u00e9tait \u00e9galement significativement plus \u00e9lev\u00e9e&#8221;.<\/p>\n<h2 id=\"-4\">&nbsp;<\/h2>\n<table border=\"1\" cellpadding=\"4\" cellspacing=\"1\" style=\"width:624px\">\n<tbody>\n<tr>\n<td style=\"width:611px\">\n<p><strong>Recommandations de l&#8217;OFSP<\/strong><\/p>\n<p>L&#8217;Office f\u00e9d\u00e9ral de la sant\u00e9 publique (OFSP) recommande la vaccination contre la grippe aux personnes pr\u00e9sentant un risque accru de complications :<\/p>\n<ul>\n<li>Les personnes \u00e2g\u00e9es de 65 ans et plus,<\/li>\n<li>les femmes enceintes,<\/li>\n<li>les enfants pr\u00e9matur\u00e9s jusqu&#8217;\u00e0 deux ans, et<\/li>\n<li>les personnes souffrant de maladies chroniques.<\/li>\n<\/ul>\n<p>Pour mieux prot\u00e9ger ces personnes, elles devraient \u00eatre vaccin\u00e9es contre la grippe, mais aussi toutes les personnes qui sont en contact r\u00e9gulier et proche avec elles. Il s&#8217;agit notamment de la famille proche, des personnes s&#8217;occupant des nourrissons et des professionnels de la sant\u00e9.<\/p>\n<p>La p\u00e9riode recommand\u00e9e pour la vaccination s&#8217;\u00e9tend de la mi-octobre au d\u00e9but de l&#8217;\u00e9pid\u00e9mie de grippe.<\/p>\n<p>La vaccination contre la grippe peut \u00eatre effectu\u00e9e en m\u00eame temps, avant ou apr\u00e8s la vaccination contre le COVID-19. Il n&#8217;est pas recommand\u00e9 de respecter un intervalle minimum entre une vaccination ARNm et d&#8217;autres vaccinations [4].<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2 id=\"-5\">&nbsp;<\/h2>\n<h2 id=\"nouveaux-developpements-vaccins-a-base-darnm\">Nouveaux d\u00e9veloppements : vaccins \u00e0 base d&#8217;ARNm<\/h2>\n<p>Depuis COVID-19, on conna\u00eet les avantages d&#8217;un vaccin bas\u00e9 sur l&#8217;ARNm. Selon la fa\u00e7on dont l&#8217;ARNm est modifi\u00e9, il peut agir comme un adjuvant. Comme l&#8217;ARNm est reconnu par la cellule h\u00f4te comme un antig\u00e8ne viral, les voies de signalisation TLR ou interf\u00e9ron peuvent \u00eatre directement d\u00e9clench\u00e9es, ce qui am\u00e9liore la r\u00e9ponse immunitaire. Des \u00e9tudes de phase 1\/2 sont en cours pour \u00e9valuer la s\u00e9curit\u00e9 et la r\u00e9actog\u00e9nicit\u00e9 ainsi que l&#8217;immunog\u00e9nicit\u00e9 en termes de titres d&#8217;anticorps.<\/p>\n<p>Un autre objectif du d\u00e9veloppement de vaccins est la &#8220;vaccination universelle contre la grippe&#8221;. La raison pour laquelle la vaccination doit \u00eatre renouvel\u00e9e chaque ann\u00e9e est la d\u00e9rive antig\u00e9nique, c&#8217;est-\u00e0-dire des mutations dans la t\u00eate de l&#8217;h\u00e9magglutinine (HA) et de la neuraminidase (NA). Les structures cibles de l&#8217;approche sont donc des \u00e9pitopes hautement conserv\u00e9s tels que la souche HA. &#8220;Si vous pouvez obtenir des anticorps contre la souche, vous n&#8217;avez pas besoin de faire des ajustements r\u00e9p\u00e9t\u00e9s&#8221;, a expliqu\u00e9 le professeur Herold. La prot\u00e9ine de matrice M2e ou la neuraminidase seule pourraient \u00eatre adress\u00e9es de la m\u00eame mani\u00e8re, car on sait qu&#8217;elle conserve une r\u00e9activit\u00e9 crois\u00e9e relativement \u00e9lev\u00e9e au sein d&#8217;un sous-type et qu&#8217;elle peut par exemple agir contre le H5N1 si elle agit \u00e9galement contre le H1N1.<\/p>\n<p>Enfin, l&#8217;infectiologue a pr\u00e9sent\u00e9 de nouvelles m\u00e9thodes d&#8217;administration en am\u00e9liorant l&#8217;immunit\u00e9 muqueuse par d\u00e9p\u00f4t local. &#8220;C&#8217;est ce que nous faisons d\u00e9j\u00e0 chez les enfants avec le vaccin vivant att\u00e9nu\u00e9 et le spray nasal&#8221;. L&#8217;objectif est d&#8217;induire des cellules T et B \u00e0 m\u00e9moire locale, principalement dans le tissu lympho\u00efde associ\u00e9 au nasopharynx et dans le tissu lympho\u00efde associ\u00e9 aux bronches, dans les voies respiratoires sup\u00e9rieures et, si possible, inf\u00e9rieures, ainsi que d&#8217;induire des anticorps muqueux. &#8220;La muqueuse est la premi\u00e8re ligne de d\u00e9fense. Si vous combinez cette approche avec d&#8217;autres vaccins syst\u00e9miques, vous pouvez peut-\u00eatre obtenir une meilleure efficacit\u00e9&#8221;. Ainsi, le probl\u00e8me de la faible immunog\u00e9nicit\u00e9 pourrait \u00eatre r\u00e9solu \u00e0 l&#8217;avenir en ce qui concerne la pr\u00e9vention de la contagion et la baisse des titres d&#8217;Ac apr\u00e8s environ 6 mois.<\/p>\n<p>\n<em>62e Congr\u00e8s de la Soci\u00e9t\u00e9 allemande de pneumologie et de m\u00e9decine respiratoire \u00e0 Leipzig (D), du 25 au 28 mai 2022.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Herold S : Influenza. Symposium &#8220;Update &#8211; Vaccination in pneumological infections&#8221; dans le cadre du congr\u00e8s de la DGP, 26.05.2022.<\/li>\n<li>Michaelis K, et al : Epid Bull 2021 ; 1 : 3-25.<\/li>\n<li>DiazGranados CA, et al : N Engl J Med 2014 ; 371 : 635-645 ; doi : 10.1056\/NEJMoa1315727.<\/li>\n<li>Office f\u00e9d\u00e9ral de la sant\u00e9 publique ; www.bag.admin.ch\/bag\/de\/home\/krankheiten\/krankheiten-im-ueberblick\/grippe.html#-2084790127 (derni\u00e8re consultation : 24.08.2022).<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo PNEUMOLOGIE &amp; ALLERGOLOGIE 2022 ; 4(3) : 34-36<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La grippe est la maladie infectieuse \u00e0 pr\u00e9vention vaccinale la plus fr\u00e9quente. N\u00e9anmoins, elle est toujours en t\u00eate de la liste des maladies infectieuses en Europe, \u00e0 l&#8217;exception des deux&hellip;<\/p>\n","protected":false},"author":7,"featured_media":125171,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Vaccination contre la grippe","footnotes":""},"category":[11523,11527,11368,11428,11315,11482,11535,11549],"tags":[13581,13583,12049],"powerkit_post_featured":[],"class_list":["post-324494","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites","category-etudes","category-geriatrie-fr","category-infectiologie","category-medecine-interne-generale","category-prevention-et-soins-de-sante","category-rapports-de-congres","category-rx-fr","tag-grippe-fr","tag-grippe-fr-2","tag-vaccination-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:13:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":324502,"slug":"eta-elevata-dose-elevata","post_title":"Et\u00e0 elevata - dose elevata!","href":"https:\/\/medizinonline.com\/it\/eta-elevata-dose-elevata\/"},"pt_PT":{"locale":"pt_PT","id":324464,"slug":"idade-alta-dose-alta","post_title":"Idade alta - dose alta!","href":"https:\/\/medizinonline.com\/pt-pt\/idade-alta-dose-alta\/"},"es_ES":{"locale":"es_ES","id":324473,"slug":"edad-elevada-dosis-elevada","post_title":"Edad elevada - \u00a1dosis elevada!","href":"https:\/\/medizinonline.com\/es\/edad-elevada-dosis-elevada\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/324494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=324494"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/324494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/125171"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=324494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=324494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=324494"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=324494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}