{"id":325187,"date":"2022-07-22T14:00:00","date_gmt":"2022-07-22T12:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/le-developpement-de-la-therapie-de-remplacement-des-enzymes-offre-une-nouvelle-option-de-traitement\/"},"modified":"2022-07-22T14:00:00","modified_gmt":"2022-07-22T12:00:00","slug":"le-developpement-de-la-therapie-de-remplacement-des-enzymes-offre-une-nouvelle-option-de-traitement","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/le-developpement-de-la-therapie-de-remplacement-des-enzymes-offre-une-nouvelle-option-de-traitement\/","title":{"rendered":"Le d\u00e9veloppement de la th\u00e9rapie de remplacement des enzymes offre une nouvelle option de traitement"},"content":{"rendered":"<p><strong>De nouvelles donn\u00e9es de l&#8217;extension ouverte \u00e0 long terme de l&#8217;\u00e9tude randomis\u00e9e en double aveugle de phase 3 COMET montrent que les personnes atteintes de la maladie de Pompe au stade avanc\u00e9 (LOPD) ont conserv\u00e9 des am\u00e9liorations de la fonction respiratoire et de la mobilit\u00e9 apr\u00e8s un traitement de pr\u00e8s de deux ans avec l&#8217;avalglucosidase alfa. L&#8217;analyse a \u00e9t\u00e9 pr\u00e9sent\u00e9e lors du 18e symposium annuel WORLD.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>L&#8217;avalglucosidase alfa (AVA ; Nexviazyme\u00ae) est une \u00e9volution de l&#8217;enzymoth\u00e9rapie substitutive par l&#8217;alglucosidase alfa (AL ; Myozyme\u00ae), qui peut ralentir la progression de la maladie de Pompe. Les r\u00e9sultats de l&#8217;\u00e9tude comparative de phase 3 COMET montrent que l&#8217;enzyme recombinante AVA pr\u00e9sente une liaison qualitativement sup\u00e9rieure au r\u00e9cepteur du mannose-6-phosphate par rapport \u00e0 AL, ce qui se traduit par une meilleure absorption dans les cellules cibles.<\/p>\n<p>Les r\u00e9sultats d&#8217;efficacit\u00e9 et de s\u00e9curit\u00e9 \u00e0 long terme ont \u00e9t\u00e9 \u00e9tudi\u00e9s chez des patients ayant re\u00e7u un traitement continu par AVA (20&nbsp;mg\/kg). En outre, l&#8217;analyse a port\u00e9 sur les patients trait\u00e9s par AVA pendant au moins 48 semaines apr\u00e8s \u00eatre pass\u00e9s d&#8217;un traitement ant\u00e9rieur par AL (20&nbsp;mg\/kg). Au cours des 97 semaines, l&#8217;effet du traitement sous AVA s&#8217;est maintenu et s&#8217;est stabilis\u00e9 chez les patients pass\u00e9s de l&#8217;AL en termes de fonction respiratoire, mesur\u00e9e par la capacit\u00e9 vitale forc\u00e9e (CVF) en position verticale par rapport \u00e0 la valeur initiale, et de mobilit\u00e9, mesur\u00e9e par le test de marche de six minutes (6MWT) par rapport \u00e0 la valeur initiale.<\/p>\n<h2 id=\"resultats-de-letude-de-phase-3-comet-sur-la-prolongation-a-long-terme\">R\u00e9sultats de l&#8217;\u00e9tude de phase 3 COMET sur la prolongation \u00e0 long terme<\/h2>\n<p>Le traitement par AVA a entra\u00een\u00e9 une am\u00e9lioration du pourcentage de pronostic de la CVF de 2,65 (1,05) points par rapport \u00e0 la valeur initiale, \u00e0 la fois dans l&#8217;analyse primaire et dans la phase de prolongation. Chez les patients trait\u00e9s par AVA uniquement pendant la p\u00e9riode de prolongation, on a observ\u00e9 une am\u00e9lioration de 0,36 (1,12) point par rapport au score initial. Chez les patients trait\u00e9s par AVA \u00e0 la fois pendant l&#8217;analyse primaire et la p\u00e9riode de prolongation, la distance de marche mesur\u00e9e par le 6MWT a augment\u00e9 en moyenne de 18,6 (12,01) m\u00e8tres par rapport \u00e0 la distance initiale. Chez les patients trait\u00e9s par AVA uniquement pendant la p\u00e9riode de prolongation, la distance moyenne de marche a augment\u00e9 de 4,56 (12,44) m\u00e8tres par rapport \u00e0 la valeur initiale.<\/p>\n<p>Le profil de s\u00e9curit\u00e9 \u00e9tait comparable entre les deux bras de traitement pendant le traitement par AVA. Aucun nouveau signal de s\u00e9curit\u00e9 n&#8217;a \u00e9t\u00e9 observ\u00e9 chez les patients qui sont pass\u00e9s d&#8217;AL \u00e0 AVA pendant la p\u00e9riode de prolongation. Dans les deux groupes, cinq personnes ont arr\u00eat\u00e9 le traitement pendant la p\u00e9riode de prolongation en raison d&#8217;\u00e9v\u00e9nements ind\u00e9sirables tels que l&#8217;hyper\u00e9mie oculaire, l&#8217;\u00e9ryth\u00e8me, l&#8217;urticaire, la d\u00e9tresse respiratoire, l&#8217;infarctus aigu du myocarde ou l&#8217;ad\u00e9nocarcinome du pancr\u00e9as. Six participants ont pr\u00e9sent\u00e9 des effets secondaires graves li\u00e9s au traitement, qui pourraient \u00eatre associ\u00e9s au traitement.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-19355\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/07\/abb1-hp6_s45.jpg\" style=\"height:382px; width:400px\" width=\"914\" height=\"873\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"resultats-de-lextension-a-long-terme-de-letude-de-phase-2-mini-comet\">R\u00e9sultats de l&#8217;extension \u00e0 long terme de l&#8217;\u00e9tude de phase 2 Mini-COMET<\/h2>\n<p>Les r\u00e9sultats de la phase d&#8217;extension de l&#8217;\u00e9tude mini COMET de phase 2 ont \u00e9galement \u00e9t\u00e9 pr\u00e9sent\u00e9s lors du symposium WORLD. L&#8217;\u00e9tude ouverte \u00e0 doses croissantes et \u00e0 trois cohortes a \u00e9valu\u00e9 l&#8217;innocuit\u00e9 et l&#8217;efficacit\u00e9 de l&#8217;AVA chez des patients de moins de 18 ans atteints de la maladie de Pompe infantile (MIP) (une application toujours \u00e0 l&#8217;\u00e9tude aux \u00c9tats-Unis) qui avaient pr\u00e9c\u00e9demment re\u00e7u de l&#8217;AL pendant six mois ou plus et qui pr\u00e9sentaient soit une r\u00e9ponse sous-optimale, soit une d\u00e9t\u00e9rioration clinique.<\/p>\n<p>Les patients ont \u00e9t\u00e9 inclus dans l&#8217;une des trois cohortes suivantes : (1) 20&nbsp;mg\/kg AVA toutes les deux semaines (n=6), (2) 40&nbsp;mg\/kg d&#8217;AVA toutes les deux semaines (n=5), et (3) randomis\u00e9 \u00e0 AVA 40&nbsp;mg\/kg toutes les deux semaines (n=5) ou AL \u00e0 sa dose stable avant l&#8217;inclusion dans la cohorte (dans une fourchette de 20 mg\/kg toutes les deux semaines \u00e0 40&nbsp;mg\/kg par semaine n=6). En outre, les 22 participants ont particip\u00e9 \u00e0 une phase de prolongation et ont re\u00e7u jusqu&#8217;\u00e0 40&nbsp;mg\/kg d&#8217;AVA toutes les deux semaines.<\/p>\n<p>Les effets ind\u00e9sirables li\u00e9s au traitement les plus fr\u00e9quemment rapport\u00e9s \u00e9taient de gravit\u00e9 l\u00e9g\u00e8re \u00e0 mod\u00e9r\u00e9e et comprenaient des \u00e9ruptions cutan\u00e9es (8 participants), des chutes, une pneumonie, une pyrexie (7&nbsp;participants chacun), des maux de t\u00eate, des infections des voies respiratoires sup\u00e9rieures (6 participants chacun) et des vomissements (5 participants). Il n&#8217;y a pas eu d&#8217;effets secondaires graves ou s\u00e9rieux li\u00e9s au traitement, ni de d\u00e9c\u00e8s. Avec la dose plus \u00e9lev\u00e9e d&#8217;AVA (40&nbsp;mg\/kg toutes les deux semaines), aucune augmentation du risque de s\u00e9curit\u00e9 n&#8217;a \u00e9t\u00e9 observ\u00e9e chez les participants qui sont pass\u00e9s de l&#8217;AL \u00e0 l&#8217;AVA.<\/p>\n<p>\u00c0 la semaine 97, les r\u00e9sultats ont montr\u00e9 que les patients trait\u00e9s par AVA pr\u00e9sentaient une fonction motrice stable ou am\u00e9lior\u00e9e, mesur\u00e9e par la mesure de la fonction motrice (GMFM-88), le pourcentage du score total du Quick Motor Function Test (QMFT) et l&#8217;\u00e9chelle de comp\u00e9tences fonctionnelles Pompe-PEDI (Pediatric Evaluation of Disability Index). En outre, le Z-score du ventricule gauche (LVMZ) de tous les participants se situait dans la fourchette normale.<\/p>\n<p><em>Source : &#8220;Nexviazyme\u00ae (avalglucosidase alfa) montre des am\u00e9liorations soutenues de la fonction respiratoire et de la mobilit\u00e9 chez les patients atteints de la maladie de Pompe&#8221; 08.02.2022, Sanofi<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>PRATIQUE DU M\u00c9DECIN DE FAMILLE 2022 ; 17(6) : 45<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nouvelles donn\u00e9es de l&#8217;extension ouverte \u00e0 long terme de l&#8217;\u00e9tude randomis\u00e9e en double aveugle de phase 3 COMET montrent que les personnes atteintes de la maladie de Pompe au&hellip;<\/p>\n","protected":false},"author":7,"featured_media":123070,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Maladie de Pompe","footnotes":""},"category":[11404,11527,11545,11315,11535,11549],"tags":[14936,14931,14934],"powerkit_post_featured":[],"class_list":["post-325187","post","type-post","status-publish","format-standard","has-post-thumbnail","category-endocrinologie-et-diabetologie","category-etudes","category-marche-medecine","category-medecine-interne-generale","category-rapports-de-congres","category-rx-fr","tag-comet-fr","tag-maladie-de-pompe","tag-therapie-de-remplacement-des-enzymes","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:07:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":325194,"slug":"un-ulteriore-sviluppo-della-terapia-enzimatica-sostitutiva-fornisce-una-nuova-opzione-di-trattamento","post_title":"Un ulteriore sviluppo della terapia enzimatica sostitutiva fornisce una nuova opzione di trattamento","href":"https:\/\/medizinonline.com\/it\/un-ulteriore-sviluppo-della-terapia-enzimatica-sostitutiva-fornisce-una-nuova-opzione-di-trattamento\/"},"pt_PT":{"locale":"pt_PT","id":325200,"slug":"um-maior-desenvolvimento-da-terapia-de-substituicao-enzimatica-proporciona-uma-nova-opcao-de-tratamento","post_title":"Um maior desenvolvimento da terapia de substitui\u00e7\u00e3o enzim\u00e1tica proporciona uma nova op\u00e7\u00e3o de tratamento","href":"https:\/\/medizinonline.com\/pt-pt\/um-maior-desenvolvimento-da-terapia-de-substituicao-enzimatica-proporciona-uma-nova-opcao-de-tratamento\/"},"es_ES":{"locale":"es_ES","id":325207,"slug":"un-mayor-desarrollo-de-la-terapia-de-sustitucion-enzimatica-ofrece-una-nueva-opcion-de-tratamiento","post_title":"Un mayor desarrollo de la terapia de sustituci\u00f3n enzim\u00e1tica ofrece una nueva opci\u00f3n de tratamiento","href":"https:\/\/medizinonline.com\/es\/un-mayor-desarrollo-de-la-terapia-de-sustitucion-enzimatica-ofrece-una-nueva-opcion-de-tratamiento\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/325187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=325187"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/325187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media\/123070"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=325187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=325187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=325187"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=325187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}