{"id":325821,"date":"2022-05-15T01:00:00","date_gmt":"2022-05-14T23:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/des-soins-de-base-coherents-selon-le-principe-soak-and-seal\/"},"modified":"2022-05-15T01:00:00","modified_gmt":"2022-05-14T23:00:00","slug":"des-soins-de-base-coherents-selon-le-principe-soak-and-seal","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/des-soins-de-base-coherents-selon-le-principe-soak-and-seal\/","title":{"rendered":"Des soins de base coh\u00e9rents selon le principe &#8220;Soak and Seal&#8221;."},"content":{"rendered":"<p><strong>Des soins de base r\u00e9guliers sont une composante importante du traitement, quelle que soit la gravit\u00e9 de la dermatite atopique, conform\u00e9ment aux directives. Outre la r\u00e9g\u00e9n\u00e9ration de la fonction barri\u00e8re perturb\u00e9e de la peau, la x\u00e9rose cutan\u00e9e et les d\u00e9mangeaisons sont r\u00e9duites. Il faut veiller \u00e0 ce que le syst\u00e8me gal\u00e9nique de la pr\u00e9paration utilis\u00e9e soit adapt\u00e9 \u00e0 l&#8217;\u00e9tat de la peau.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>Les soins cutan\u00e9s topiques de base sont recommand\u00e9s dans les directives nationales et internationales pour tous les stades et degr\u00e9s de s\u00e9v\u00e9rit\u00e9 de la dermatite atopique [1\u20133]. &#8220;La base de toute th\u00e9rapie est un bon soin de base avec des \u00e9mollients&#8221;, explique le professeur Dr. h. c. Andreas Wollenberg. Clinique de l&#8217;Universit\u00e9 de Munich [4]. Dans l&#8217;ecz\u00e9ma atopique, l&#8217;absence ou l&#8217;affaiblissement g\u00e9n\u00e9tique de la r\u00e9ponse immunitaire \u00e0 certains antig\u00e8nes entra\u00eene une alt\u00e9ration de la fonction de barri\u00e8re \u00e9pidermique et facilite la p\u00e9n\u00e9tration de facteurs exog\u00e8nes tels que les allerg\u00e8nes et les toxines, ce qui affaiblit encore la barri\u00e8re cutan\u00e9e et provoque des pouss\u00e9es d&#8217;ecz\u00e9ma. Il convient de lutter contre ce cercle vicieux. Un traitement de base ad\u00e9quat permet de pr\u00e9venir le cycle d\u00e9mangeaisons-grattage et d&#8217;allonger ainsi l&#8217;intervalle sans r\u00e9cidive. Pour y parvenir, il est indispensable d&#8217;utiliser syst\u00e9matiquement des pr\u00e9parations topiques pour les soins de base.<\/p>\n<h2 id=\"soin-de-base-relipidant-et-hydratant-essentiel-pour-les-personnes-souffrant-de-dermatite-atopique\">Soin de base relipidant et hydratant : essentiel pour les personnes souffrant de dermatite atopique<\/h2>\n<p>L&#8217;application de traitements de base topiques juste apr\u00e8s la douche ou le bain (&#8220;soak-and-seal&#8221;) est une tr\u00e8s bonne id\u00e9e, souligne le professeur Wollenberg. L&#8217;objectif premier des soins de base est de rem\u00e9dier aux troubles de la barri\u00e8re cutan\u00e9e qui peuvent entra\u00eener une s\u00e9cheresse de la peau et, par cons\u00e9quent, des irritations, des d\u00e9mangeaisons et une propagation de l&#8217;agent pathog\u00e8ne <em>Staphylococcus aureus <\/em> [3,5,6]. La gal\u00e9nique du produit utilis\u00e9 doit toujours \u00eatre adapt\u00e9e \u00e0 l&#8217;\u00e9tat individuel de la peau, les formulations hydrophiles \u00e9tant plus recommand\u00e9es dans les phases aigu\u00ebs de l&#8217;ecz\u00e9ma, tandis que les formulations plus riches en lipides doivent \u00eatre utilis\u00e9es dans les phases intermittentes.<span style=\"font-family:franklin gothic demi\"> <\/span>[7] <span style=\"font-family:franklin gothic demi\">(Fig. 1).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18910\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/05\/abb1_dp2_s26.png\" style=\"height:290px; width:600px\" width=\"1100\" height=\"532\"><\/p>\n<p>&nbsp;<\/p>\n<p>Les pr\u00e9parations dans lesquelles des substances actives favorisant l&#8217;hydratation sont incorpor\u00e9es dans la base correspondante sont \u00e9galement appel\u00e9es &#8220;humectants&#8221;. Il s&#8217;agit de substances actives qui augmentent la capacit\u00e9 de la peau \u00e0 retenir l&#8217;eau, explique le professeur Wollenberg [8]. Outre une substance favorisant l&#8217;hydratation telle que l&#8217;ur\u00e9e, l&#8217;acide lactique ou la glyc\u00e9rine, un \u00e9mollient contient \u00e9galement un &#8220;occlusif&#8221; qui emp\u00eache la perte d&#8217;eau de la peau, comme la vaseline par exemple. Dans la litt\u00e9rature anglophone, les termes &#8220;Moisturizer&#8221; et &#8220;Emollient&#8221; sont souvent utilis\u00e9s dans le contexte des soins de base pour les maladies ecz\u00e9mateuses, sans d\u00e9finition uniforme, comme le montre une revue Cochrane [19].<\/p>\n<h2 id=\"externes-contenant-de-la-glycerine-bien-adaptes-aux-jeunes-enfants\">Externes contenant de la glyc\u00e9rine : bien adapt\u00e9s aux jeunes enfants<\/h2>\n<p>La glyc\u00e9rine (glycerol) ne provoquant aucune irritation cutan\u00e9e, le guide europ\u00e9en sur la dermatite atopique recommande \u00e9galement l&#8217;utilisation de produits de soins de base contenant de la glyc\u00e9rine chez les nourrissons et les jeunes enfants [3]. Des \u00e9tudes ont d\u00e9montr\u00e9 que chez les nourrissons pr\u00e9dispos\u00e9s, l&#8217;utilisation pr\u00e9coce de tels produits peut r\u00e9duire jusqu&#8217;\u00e0 50% la probabilit\u00e9 d&#8217;apparition d&#8217;une dermatite atopique [11,12]. Et une \u00e9tude en double aveugle contr\u00f4l\u00e9e par placebo chez des enfants de deux \u00e0 six ans a montr\u00e9 une am\u00e9lioration de la s\u00e9cheresse de la peau pendant plusieurs semaines apr\u00e8s seulement quatre semaines d&#8217;application d&#8217;une cr\u00e8me H\/E contenant 15% de glyc\u00e9rine [13]. D&#8217;autres \u00e9tudes sur l&#8217;effet hydratant des topiques contenant de la glyc\u00e9rine confirment cette constatation, tant pour l&#8217;utilisation chez les enfants que chez les adultes [14\u201316]. Il est \u00e9galement int\u00e9ressant de noter que des \u00e9tudes ont montr\u00e9 que les topiques contenant de la glyc\u00e9rine peuvent pr\u00e9venir les pouss\u00e9es d&#8217;ecz\u00e9ma et r\u00e9duire le besoin de glucocortico\u00efdes topiques dans la dermatite atopique [8,17,18].<\/p>\n<p>Outre les produits externes appel\u00e9s \u00e9mollients, qui ne contiennent pas ou plus d&#8217;agents pharmacologiquement actifs, le terme &#8220;\u00e9mollients plus&#8221; a \u00e9t\u00e9 red\u00e9fini dans les lignes directrices europ\u00e9ennes actuelles [9]. Les pr\u00e9parations contenant des extraits d&#8217;avoine jeune sans prot\u00e9ines et des lysats bact\u00e9riens d&#8217;<em>Aquaphilus dolomiae <\/em>ou <em>de Vitreoscilla filiformis<\/em> sont cit\u00e9es \u00e0 titre d&#8217;exemple.<\/p>\n<p>\n<em>Congr\u00e8s :&nbsp;Mise \u00e0 jour sur les maladies inflammatoires de la peau<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Eichenfield LF, et al : J Am Acad Dermatol 2014 ; 71 : 116-132.<\/li>\n<li>Werfel T, et al : JDDG 2016 ; 14 : 92-106.<\/li>\n<li>Wollenberg A, et al : J Eur Acad Dermatol Venereol 2018 ; 32 : 657-682.<\/li>\n<li>Wollenberg A : Mise \u00e0 jour sur l&#8217;ecz\u00e9ma atopique. 5e mise \u00e0 jour de L\u00fcbeck : maladies inflammatoires de la peau, 05.03.2022<\/li>\n<li>Werfel T, et al. : Ligne directrice sur la dermatite atopique [ecz\u00e9ma atopique ; dermatite atopique]. Mise \u00e0 jour : 31.03.2015. www.awmf.org, (derni\u00e8re consultation 08.03.2022)<\/li>\n<li>Augustin M, et al. : Prise de position &#8211; Diagnostic et traitement de la x\u00e9rose cutan\u00e9e. JDDG 2018 (16), Suppl 4, 3-35.<\/li>\n<li>Prise de position de la Soci\u00e9t\u00e9 de dermopharmacie (Gesellschaft f\u00fcr Dermopharmazie e. V.) Traitement de base topique de la dermatite atopique,<\/li>\n<li>www.gd-online.de (dernier appel 08.03.2022)<\/li>\n<li>Rossi AB, et al : Dermatol The(Heidelb) 2018 ; 8 : 217-228.<\/li>\n<li>Wollenberg A, et al : Consensus-based European guidelines for treatment of atopic eczema (atopic dermatitis) in adults and children : part I. J Eur Acad Dermatol Venereol 2018 ; 32 : 657-682.<\/li>\n<li>Wohlrab J, et al : Lignes directrices S2k sur l&#8217;utilisation des pr\u00e9parations pour application locale sur la peau (topiques). Mise \u00e0 jour : 01.11.2017. www.awmf.org<\/li>\n<li>Simpson EL, et al : J Allergy Clin Immunol 2014 ; 134 : 818-823.<\/li>\n<li>Horimukai K, et al : J Allergy Clin Immunol 2014 ; 134 : 824-830.<\/li>\n<li>Boralevi F, et al : J Eur Acad Dermatol Venereol 2014 ; 28 : 1456-1462.<\/li>\n<li>Blanchet-Bardon C, et al : J Eur Acad Dermatol Venereol 2012 ; 26 : 1014-1019.<\/li>\n<li>Lod\u00e9n M, et al : Acta Derm Venereol 2002 ; 82(14) : 45-47.<\/li>\n<li>Cristaudo A, et al : G Ital Dermatol Venereol 2015 ; 150 : 297-302.<\/li>\n<li>Tiplica GS, et al : Pediatr Dermatol 2017 ; 34 : 282-289.<\/li>\n<li>Tiplica GS, et al : J Eur Acad Dermatol Venereol 2018 ; 32 : 1180-1187.<\/li>\n<li>Van Zuuren EJ, et al : Cochrane Database of Systematic Reviews 2017 ; 2 : Art.No CD012110<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>DERMATOLOGIE PRATIQUE 2022 ; 32(2) : 26-27<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des soins de base r\u00e9guliers sont une composante importante du traitement, quelle que soit la gravit\u00e9 de la dermatite atopique, conform\u00e9ment aux directives. Outre la r\u00e9g\u00e9n\u00e9ration de la fonction barri\u00e8re&hellip;<\/p>\n","protected":false},"author":7,"featured_media":119890,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Ecz\u00e9ma atopique","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11349,11362,11527,11535,11549],"tags":[15868,15870,15873],"powerkit_post_featured":[],"class_list":["post-325821","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allergologie-et-immunologie-clinique","category-dermatologie-et-venerologie","category-etudes","category-rapports-de-congres","category-rx-fr","tag-eczema-atopique","tag-seal-fr","tag-soak-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 15:33:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":325834,"slug":"cura-di-base-coerente-secondo-il-principio-ammollo-e-sigillo","post_title":"Cura di base coerente secondo il principio \"ammollo e sigillo\".","href":"https:\/\/medizinonline.com\/it\/cura-di-base-coerente-secondo-il-principio-ammollo-e-sigillo\/"},"pt_PT":{"locale":"pt_PT","id":325794,"slug":"cuidados-basicos-consistentes-de-acordo-com-o-principio-de-encharcar-e-selar","post_title":"Cuidados b\u00e1sicos consistentes de acordo com o princ\u00edpio de encharcar e selar","href":"https:\/\/medizinonline.com\/pt-pt\/cuidados-basicos-consistentes-de-acordo-com-o-principio-de-encharcar-e-selar\/"},"es_ES":{"locale":"es_ES","id":325814,"slug":"cuidados-basicos-constantes-segun-el-principio-de-empapar-y-sellar","post_title":"Cuidados b\u00e1sicos constantes seg\u00fan el principio de empapar y sellar","href":"https:\/\/medizinonline.com\/es\/cuidados-basicos-constantes-segun-el-principio-de-empapar-y-sellar\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/325821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=325821"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/325821\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=325821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=325821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=325821"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=325821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}