{"id":326436,"date":"2022-03-06T01:00:00","date_gmt":"2022-03-06T00:00:00","guid":{"rendered":"https:\/\/medizinonline.com\/le-defi-du-diagnostic-differentiel\/"},"modified":"2022-03-06T01:00:00","modified_gmt":"2022-03-06T00:00:00","slug":"le-defi-du-diagnostic-differentiel","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/le-defi-du-diagnostic-differentiel\/","title":{"rendered":"Le d\u00e9fi du diagnostic diff\u00e9rentiel"},"content":{"rendered":"<p><strong>Le terme g\u00e9n\u00e9rique &#8220;hypertension pulmonaire (HTP)&#8221; englobe plusieurs types d&#8217;hypertension pulmonaire potentiellement mortels, dont les approches th\u00e9rapeutiques sont tr\u00e8s diff\u00e9rentes et tr\u00e8s complexes. Comme les sympt\u00f4mes sont souvent non sp\u00e9cifiques, l&#8217;\u00e9tablissement du diagnostic repr\u00e9sente d\u00e9j\u00e0 un grand d\u00e9fi.<\/strong><\/p>\n<p> <!--more--> <\/p>\n<p>La classification clinique de l&#8217;hypertension pulmonaire (HTP) se fait actuellement en cinq groupes, comme l&#8217;a rappel\u00e9 d&#8217;embl\u00e9e le professeur Horst Olschewski, chef du service clinique de pneumologie, clinique universitaire de m\u00e9decine interne, LKH-Universit\u00e4tsklinikum Graz :<\/p>\n<ul>\n<li>Le groupe 1 comprend l&#8217;hypertension art\u00e9rielle pulmonaire (HTAP), la forme la plus rare d&#8217;hypertension pulmonaire, qui n&#8217;est diagnostiqu\u00e9e qu&#8217;apr\u00e8s avoir exclu d&#8217;autres causes sous-jacentes.<\/li>\n<li>Le groupe 2, l&#8217;hypertension pulmonaire dans les cardiopathies gauches, est de loin la forme la plus fr\u00e9quente d&#8217;hypertension pulmonaire.<\/li>\n<li>Le groupe 3 comprend l&#8217;hypertension pulmonaire en cas de maladie pulmonaire et\/ou d&#8217;hypoxie. Cette forme est \u00e9galement beaucoup plus fr\u00e9quente que l&#8217;HTAP.<\/li>\n<li>Le groupe 4 comprend l&#8217;hypertension pulmonaire apr\u00e8s une embolie pulmonaire, qui concerne jusqu&#8217;\u00e0 4% des patients ayant subi une embolie pulmonaire aigu\u00eb.<\/li>\n<li>Le groupe 5 rassemble les formes rares d&#8217;hypertension pulmonaire qui ne peuvent \u00eatre clairement class\u00e9es dans aucun des groupes pr\u00e9c\u00e9dents, comme l&#8217;hypertension pulmonaire li\u00e9e \u00e0 une sarco\u00efdose ou \u00e0 une maladie r\u00e9nale chronique.<\/li>\n<\/ul>\n<p>Selon le professeur Olschewski, les groupes 2 et 3 repr\u00e9sentent ensemble 90% de toutes les hypertensions pulmonaires, ce qui pr\u00e9sente des dangers en termes de diagnostic diff\u00e9rentiel.<\/p>\n<h2 id=\"heterogeneite-de-lipah\">H\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 de l&#8217;IPAH<\/h2>\n<p>Pour une analyse en grappes, les patients r\u00e9pondant aux crit\u00e8res de l&#8217;hypertension art\u00e9rielle pulmonaire idiopathique (HAPI) ont \u00e9t\u00e9 identifi\u00e9s.<\/p>\n<p>Une analyse en cluster a par exemple permis d&#8217;identifier diff\u00e9rents ph\u00e9notypes qui se distinguent par leur pr\u00e9sentation clinique, leur r\u00e9ponse au traitement et leur taux de survie. Les groupes analys\u00e9s ont \u00e9t\u00e9 constitu\u00e9s \u00e0 partir du registre COMPERA [1], trois clusters ont \u00e9t\u00e9 d\u00e9finis : le cluster 1 (n=106 ; 12,6%) comprenait des patients dont l&#8217;\u00e2ge moyen \u00e9tait de 45 ans, 76% \u00e9taient des femmes, sans comorbidit\u00e9s, le plus souvent jamais fumeurs, DLCO \u226545% ; le cluster 2 (n=301 ; 35,8%) comprenait des patients dont l&#8217;\u00e2ge moyen \u00e9tait de 75 ans, 98% \u00e9taient des femmes, comorbidit\u00e9s fr\u00e9quentes, pas d&#8217;ant\u00e9c\u00e9dents de tabagisme, DLCO le plus souvent \u226545% ; cluster&nbsp;3 (n=434 ; 51,6%) \u00e9tait compos\u00e9 de sujets d&#8217;un \u00e2ge moyen de 72 ans, 72% \u00e9taient des hommes, comorbidit\u00e9s fr\u00e9quentes, ant\u00e9c\u00e9dents de tabagisme et DLCO en grande partie inf\u00e9rieure \u00e0 45%.<\/p>\n<p>Les patients du cluster 1 ont mieux r\u00e9pondu au traitement de l&#8217;HTAP que les patients des deux autres clusters. Le taux de survie \u00e0 cinq ans \u00e9tait de 84,6% dans le cluster&nbsp;1, 59,2% dans le cluster&nbsp;2 et 42,2% dans le cluster&nbsp;3 <span style=\"font-family:franklin gothic demi\">(Fig.&nbsp;1).<\/span> Selon l&#8217;expert, ces donn\u00e9es sugg\u00e8rent que des crit\u00e8res sont n\u00e9cessaires pour distinguer les patients IPAH atypiques des vrais patients IPAH.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-18577\" alt=\"\" src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb1_pa1_s20.png\" style=\"height:615px; width:600px\" width=\"1100\" height=\"1128\"><\/p>\n<p>&nbsp;<\/p>\n<h2 id=\"diagnostic-differentiel-parfois-difficile\">Diagnostic diff\u00e9rentiel parfois difficile<\/h2>\n<p>Comme les cons\u00e9quences th\u00e9rapeutiques d\u00e9pendent en grande partie de la cause de l&#8217;hypertension pulmonaire, il est important de terminer les proc\u00e9dures de diagnostic et de d\u00e9terminer la cause principale de l&#8217;HTP avant de prendre une d\u00e9cision sur les m\u00e9dicaments contre l&#8217;HTAP. Le <em>World Symposia on Pulmonary Hypertension<\/em> (WSPH) a \u00e9tabli des lignes directrices pour ces d\u00e9cisions importantes. Les PH du groupe&nbsp;2 ou les maladies complexes du d\u00e9veloppement avec une pression post-capillaire \u00e9lev\u00e9e sont relativement faciles \u00e0 identifier gr\u00e2ce \u00e0 des pressions de Wedge art\u00e9rielles pulmonaires \u00e9lev\u00e9es. L&#8217;HTP du groupe&nbsp;4 peut \u00eatre d\u00e9tect\u00e9e ou exclue par des scanners pulmonaires de perfusion combin\u00e9s \u00e0 un scanner thoracique. Les HTAP du groupe 1 et les HTP du groupe&nbsp;3 pr\u00e9sentent des profils de maladie assez diff\u00e9rents, mais peuvent parfois \u00eatre difficiles \u00e0 distinguer. La WSPH sugg\u00e8re qu&#8217;une hypertension pulmonaire s\u00e9v\u00e8re associ\u00e9e \u00e0 une l\u00e9g\u00e8re alt\u00e9ration de la fonction pulmonaire (VEMS &gt;60 et CVF &gt;60%), \u00e0 de l\u00e9g\u00e8res anomalies parenchymateuses au scanner thoracique haute r\u00e9solution et \u00e0 une restriction circulatoire \u00e0 l&#8217;\u00e9preuve d&#8217;effort cardiopulmonaire sont en faveur d&#8217;une HTAP du groupe&nbsp;1. Ces patients sont des candidats au traitement de l&#8217;HTAP. Si le patient souffre d&#8217;une HTP du groupe 3, la seule indication possible pour un traitement de l&#8217;HTAP est une hypertension pulmonaire s\u00e9v\u00e8re (mPAP \u226535&nbsp;mmHg ou mPAP entre 25 et 35&nbsp;mmHg associ\u00e9e \u00e0 un index cardiaque (IC) tr\u00e8s bas &lt;2,0&nbsp;L\/min\/m2), qui ne peut \u00eatre d\u00e9riv\u00e9e que de mani\u00e8re invasive, selon le professeur Olschewski.<\/p>\n<p>Une \u00e9tude s&#8217;est \u00e9galement pench\u00e9e sur la distinction entre les patients souffrant d&#8217;HTAP (groupe&nbsp;1) et ceux souffrant d&#8217;insuffisance cardiaque (groupe&nbsp;2) [2]. Bien que des pressions de remplissage \u00e9lev\u00e9es du c\u00f4t\u00e9 gauche et une insuffisance valvulaire mitrale fonctionnelle entra\u00eenent en premier lieu une HTP post-capillaire, les directives et les recommandations font la distinction entre l&#8217;HTP post-capillaire isol\u00e9e (IpcPH) et l&#8217;HTP post-capillaire et pr\u00e9capillaire combin\u00e9e (CpcPH). Cette derni\u00e8re est d\u00e9finie par une r\u00e9sistance vasculaire pulmonaire (RVP) \u00e9lev\u00e9e \u00e0 des unit\u00e9s de Wood (UB). Il est important de faire la diff\u00e9rence entre la d\u00e9finition g\u00e9n\u00e9rale de l&#8217;HTP (mPAP &gt;20&nbsp;mmHg) et la d\u00e9finition de l&#8217;HTP pr\u00e9capillaire, y compris l&#8217;HTAP, pour laquelle on exige en plus une pression art\u00e9rielle pulmonaire (PAWP) \u226415&nbsp;mmHg et une augmentation de la r\u00e9sistance vasculaire pulmonaire (PVR) \u00e0 \u22653 unit\u00e9s Wood. Selon ce document, le traitement m\u00e9dicamenteux cibl\u00e9 d&#8217;une HTAP est indiqu\u00e9 lorsque la PAWP est \u226415&nbsp;mmHg.<\/p>\n<p>Il n&#8217;est pas non plus facile de distinguer les patients souffrant d&#8217;HTAP et de BPCO (groupe 1) des patients souffrant d&#8217;HTP en raison d&#8217;une BPCO (groupe 3). La plupart des patients atteints de BPCO avec HTP appartiennent au groupe 3. Certains patients atteints de BPCO avec HTP et une pression de remplissage du ventricule gauche \u00e9lev\u00e9e (HTP post-capillaire), caus\u00e9e par des maladies cardiovasculaires concomitantes, sont class\u00e9s dans le groupe 2. Les maladies thromboemboliques chroniques peuvent \u00e9galement provoquer une HTP, en particulier parce que la BPCO est un facteur de risque de thromboembolie veineuse, ces patients atteints de BPCO sont g\u00e9n\u00e9ralement class\u00e9s dans le groupe 4. Chez les patients pr\u00e9sentant une obstruction tr\u00e8s l\u00e9g\u00e8re des voies respiratoires p\u00e9riph\u00e9riques et une HTP pr\u00e9capillaire s\u00e9v\u00e8re avec une r\u00e9sistance vasculaire pulmonaire (RVP) tr\u00e8s \u00e9lev\u00e9e et un faible d\u00e9bit cardiaque (CO), on suppose principalement que l&#8217;HTAP (groupe&nbsp;1) est associ\u00e9e \u00e0 une BPCO l\u00e9g\u00e8re. Dans la plupart des cas, l&#8217;HTP est relativement l\u00e9g\u00e8re chez les patients atteints de BPCO, a expliqu\u00e9 le pneumologue, mais dans un sous-groupe de patients atteints de BPCO, la pr\u00e9sence de certaines caract\u00e9ristiques cliniques est en faveur d&#8217;un &#8220;ph\u00e9notype vasculaire pulmonaire&#8221;. Un tel ph\u00e9notype serait caract\u00e9ris\u00e9 par une HTP pr\u00e9capillaire s\u00e9v\u00e8re avec une r\u00e9sistance vasculaire pulmonaire fortement accrue, une restriction mod\u00e9r\u00e9e du flux d&#8217;air, une capacit\u00e9 de diffusion du monoxyde de carbone fortement r\u00e9duite, une normo- ou une hypocapnie, une restriction de l&#8217;effort circulatoire et une insuffisance cardiaque droite progressive.<\/p>\n<p>Une autre \u00e9tude a tent\u00e9 de d\u00e9terminer des seuils h\u00e9modynamiques pronostiques pertinents pour l&#8217;HTP s\u00e9v\u00e8re dans la BPCO \u00e0 l&#8217;aide d&#8217;une approche non biais\u00e9e [3]. Dans ce contexte, un PVR &gt;5&nbsp;WU s&#8217;est av\u00e9r\u00e9 \u00eatre le plus fort pr\u00e9dicteur h\u00e9modynamique ind\u00e9pendant de la mortalit\u00e9 des patients atteints de BPCO. Ce seuil est le plus appropri\u00e9 pour identifier les patients BPCO souffrant d&#8217;une maladie vasculaire pulmonaire s\u00e9v\u00e8re.<\/p>\n<h2 id=\"progres-dans-la-therapie-medicamenteuse\">Progr\u00e8s dans la th\u00e9rapie m\u00e9dicamenteuse<\/h2>\n<p>Les progr\u00e8s r\u00e9cents dans le traitement m\u00e9dicamenteux de l&#8217;HTAP ne sont pas dus \u00e0 la d\u00e9couverte de nouvelles voies de signalisation, mais au d\u00e9veloppement de nouvelles strat\u00e9gies de th\u00e9rapie combin\u00e9e et \u00e0 l&#8217;escalade des traitements sur la base d&#8217;une \u00e9valuation syst\u00e9matique de la r\u00e9ponse clinique. La strat\u00e9gie de traitement est bas\u00e9e sur la s\u00e9v\u00e9rit\u00e9 du patient souffrant d&#8217;HTAP nouvellement diagnostiqu\u00e9, d\u00e9termin\u00e9e par une approche de stratification du risque multiparam\u00e9trique. Les param\u00e8tres cliniques, d&#8217;effort, de fonction ventriculaire droite et h\u00e9modynamiques sont combin\u00e9s pour d\u00e9finir un statut de risque faible, moyen ou \u00e9lev\u00e9 en fonction de la mortalit\u00e9 attendue \u00e0 1 an. L&#8217;algorithme de traitement actuel fournit la strat\u00e9gie initiale la plus appropri\u00e9e, y compris la monoth\u00e9rapie, la bith\u00e9rapie ou la trith\u00e9rapie. Une nouvelle escalade du traitement est n\u00e9cessaire si le statut de faible risque n&#8217;est pas atteint lors des examens de suivi pr\u00e9vus. Dans la plupart des cas avanc\u00e9s, une transplantation pulmonaire peut \u00eatre n\u00e9cessaire sous traitement m\u00e9dical maximal<span style=\"font-family:franklin gothic demi\"> (Fig.&nbsp;2).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-18578 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/abb2_pa1_s21.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/1674;height:913px; width:600px\" width=\"1100\" height=\"1674\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/p>\n<p>&nbsp;<\/p>\n<p>Les m\u00e9dicaments approuv\u00e9s pour le traitement oral comprennent les inhibiteurs de la phosphodiest\u00e9rase 5 (PDE5i) comme le sild\u00e9nafil et le tadalafil, les antagonistes des r\u00e9cepteurs de l&#8217;endoth\u00e9line (ERA) comme le bosentan, l&#8217;arbrisentan et le macitentan, les stimulateurs de la guanylate cyclase soluble (sGC) comme le riociguat et les agonistes des r\u00e9cepteurs de la prostacycline comme le s\u00e9lexipag. Il est \u00e9galement possible de traiter l&#8217;HTAP par inhalation ou par perfusion continue.<\/p>\n<h2 id=\"etudes-prospectives-sur-la-therapie\">\u00c9tudes prospectives sur la th\u00e9rapie<\/h2>\n<p>Par exemple, le riociguat et les inhibiteurs de la phosphodiest\u00e9rase 5 (PDE5i), qui sont autoris\u00e9s dans le traitement de l&#8217;hypertension art\u00e9rielle pulmonaire (HTAP), agissent par des m\u00e9canismes diff\u00e9rents et par la m\u00eame voie. L&#8217;\u00e9tude REPLACE a donc cherch\u00e9 \u00e0 d\u00e9terminer si le riociguat pouvait constituer une option alternative pour les patients atteints d&#8217;HTAP qui ne r\u00e9pondent pas suffisamment au traitement par PDE5i. L&#8217;objectif \u00e9tait d&#8217;\u00e9valuer l&#8217;impact du passage au riociguat d&#8217;un traitement par PDE5i \u00e0 un traitement continu par PDE5i chez des patients atteints d&#8217;HTAP pr\u00e9sentant un risque moyen de mortalit\u00e9 \u00e0 1 an. Les r\u00e9sultats montrent que le passage du traitement par PDE5i au riociguat, qui agissent tous deux via la voie de signalisation entre la guanylate cyclase soluble dans le monoxyde d&#8217;azote et la guanosine monophosphate cyclique, peut \u00eatre une option strat\u00e9gique pour l&#8217;escalade th\u00e9rapeutique chez les patients atteints d&#8217;HTAP pr\u00e9sentant un risque moyen de mortalit\u00e9 \u00e0 1 an [5].<\/p>\n<p>Le sotatercept, un nouvel antagoniste de l&#8217;activine, se lie aux activines et aux facteurs de diff\u00e9renciation de la croissance, tentant ainsi de r\u00e9tablir l&#8217;\u00e9quilibre entre les voies de signalisation favorisant et inhibant la croissance. Dans l&#8217;\u00e9tude PULSAR, un traitement de 24 semaines par le sotatercept chez des patients souffrant d&#8217;hypertension art\u00e9rielle pulmonaire et recevant un traitement de fond pour celle-ci a entra\u00een\u00e9 une diminution de la r\u00e9sistance vasculaire pulmonaire [6]. Les performances physiques (mesur\u00e9es par la distance de marche de 6 minutes) et les taux de NT-proBNP se sont \u00e9galement am\u00e9lior\u00e9s sous sotatercept, selon le professeur Olschewski.<\/p>\n<h2 id=\"sensation-des-etats-unis\">&#8220;Sensation&#8221; des \u00c9tats-Unis<\/h2>\n<p>Le professeur Olschewski a fait \u00e9tat d&#8217;une &#8220;sensation&#8221; aux \u00c9tats-Unis : Il n&#8217;y avait encore jamais eu de traitement autoris\u00e9 pour la PH dans les maladies pulmonaires (groupe 3). Cela a maintenant chang\u00e9 &#8211; du moins aux \u00c9tats-Unis. C&#8217;est la premi\u00e8re fois que le tr\u00e9prostinil inhal\u00e9 y est utilis\u00e9 pour ce groupe de patients. L&#8217;\u00e9tude INCREASE, contr\u00f4l\u00e9e par placebo et d&#8217;une dur\u00e9e de 16 semaines, a port\u00e9 sur des patients atteints de pneumopathie interstitielle et d&#8217;hypertension pulmonaire, auxquels on a administr\u00e9 du tr\u00e9prostinil par inhalation \u00e0 l&#8217;aide d&#8217;un n\u00e9buliseur \u00e0 ultrasons \u00e0 administration puls\u00e9e en 12 respirations maximum (72&nbsp;\u03bcg au total), quatre fois par jour. Compar\u00e9 au placebo, le tr\u00e9prostinil inhal\u00e9 a significativement am\u00e9lior\u00e9 les performances physiques des patients, \u00e9valu\u00e9es par un test de marche de 6 minutes [7]. La substance active a d\u00e9j\u00e0 \u00e9t\u00e9 approuv\u00e9e par la FDA aux \u00c9tats-Unis, mais on ne sait pas encore si le fabricant en fera rapidement la demande aupr\u00e8s de l&#8217;Agence europ\u00e9enne des m\u00e9dicaments (EMA) ou s&#8217;il attendra de nouvelles \u00e9tudes, comme l&#8217;a expliqu\u00e9 l&#8217;expert. &#8220;Quoi qu&#8217;il en soit, c&#8217;est une lueur d&#8217;espoir&#8221;.<\/p>\n<h2 id=\"\">&nbsp;<\/h2>\n<h2 id=\"-2\"><img decoding=\"async\" class=\"size-full wp-image-18579 lazyload\" alt=\"\" data-src=\"https:\/\/medizinonline.com\/wp-content\/uploads\/2022\/03\/takehome_kasten.png\" style=\"--smush-placeholder-width: 1100px; --smush-placeholder-aspect-ratio: 1100\/404;height:220px; width:600px\" width=\"1100\" height=\"404\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/h2>\n<h2 id=\"-3\">&nbsp;<\/h2>\n<h2 id=\"lentrainement-physique-standardise-est-etabli-avec-succes\">L&#8217;entra\u00eenement physique standardis\u00e9 est \u00e9tabli avec succ\u00e8s<\/h2>\n<p>L&#8217;\u00e9tude randomis\u00e9e contr\u00f4l\u00e9e EU-TRAIN sur l&#8217;entra\u00eenement \u00e0 l&#8217;exercice chez les patients atteints d&#8217;hypertension art\u00e9rielle pulmonaire (HTAP) et d&#8217;hypertension pulmonaire thromboembolique chronique (HTTPC), men\u00e9e dans 11 centres de 10 pays europ\u00e9ens sur une large population de patients, a permis de constater une am\u00e9lioration significative et cliniquement significative du crit\u00e8re d&#8217;\u00e9valuation principal 6MGT et des crit\u00e8res d&#8217;\u00e9valuation secondaires WHO-FC, QoL et consommation maximale d&#8217;oxyg\u00e8ne [8]. L&#8217;\u00e9tude a montr\u00e9 pour la premi\u00e8re fois qu&#8217;un programme d&#8217;entra\u00eenement s\u00fbr et efficace en compl\u00e9ment du traitement m\u00e9dicamenteux peut \u00eatre standardis\u00e9 et mis en \u0153uvre dans diff\u00e9rents pays avec des syst\u00e8mes de sant\u00e9 diff\u00e9rents.<\/p>\n<p><em>Source : Pneumo Update 2021 : Hypertension art\u00e9rielle pulmonaire, 12.11.2021<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Litt\u00e9rature :<\/p>\n<ol>\n<li>Hoeper, et al : ph\u00e9notypes d&#8217;hypertension art\u00e9rielle pulmonaire idiopathique d\u00e9termin\u00e9s par analyse en grappes \u00e0 partir du registre COMPERA. J Heart Lung Transplant 2020, doi : 10.1016\/j.healun.2020.09.011.<\/li>\n<li>Rosenkranz, et al. : Hypertension pulmonaire en HFpEF et HFrEF : Physiopathologie, diagnostic, approches th\u00e9rapeutiques. C\u0153ur 2019, doi : 10.1007\/s00059-019-4831-6.<\/li>\n<li>Zeder, et al : L&#8217;augmentation de la r\u00e9sistance vasculaire pulmonaire pr\u00e9dit la mortalit\u00e9 chez les patients atteints de BPCO. Eur Respir J 2021, doi : 10.1183\/13993003.00944-2021.<\/li>\n<li>Gali\u00e8, et al : Risk stratification and medical therapy of pulmonary arterial hypertension. European Respiratory Journal 2019,&nbsp;doi : 10.1183\/13993003.01889-2018.<\/li>\n<li>Hoeper, et al. : Switching to riociguat versus maintenance therapy with phosphodiesterase-5 inhibitors in patients with pulmonary arterial hypertension (REPLACE) : a multicentre, open-label, randomised controlled trial. Lancet Respir Med 2021, doi : 10.1016\/S2213-2600(20)30532-4.<\/li>\n<li>Humbert, et al : Sotatercept pour le traitement de l&#8217;hypertension art\u00e9rielle pulmonaire. N Engl J Med 2021, doi : 10.1056\/NEJMoa2024277.<\/li>\n<li>Waxman, et al : Treprostinil inhaled in Pulmonary Hypertension Due to Interstitial Lung Disease. N Engl J Med 2021, doi : 10.1056\/NEJMoa2008470.<\/li>\n<li>Gr\u00fcning, et al : L&#8217;exercice standardis\u00e9 est faisable, s\u00fbr et efficace dans l&#8217;hypertension art\u00e9rielle pulmonaire et l&#8217;hypertension pulmonaire thromboembolique chronique : r\u00e9sultats d&#8217;un grand essai europ\u00e9en multicentrique randomis\u00e9 et contr\u00f4l\u00e9. Eur Heart J 2021, doi : 10.1093\/eurheartj\/ehaa696.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><em>InFo PNEUMOLOGIE &amp; ALLEROLOGIE 2022 ; 4(1) : 20-22<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le terme g\u00e9n\u00e9rique &#8220;hypertension pulmonaire (HTP)&#8221; englobe plusieurs types d&#8217;hypertension pulmonaire potentiellement mortels, dont les approches th\u00e9rapeutiques sont tr\u00e8s diff\u00e9rentes et tr\u00e8s complexes. Comme les sympt\u00f4mes sont souvent non sp\u00e9cifiques,&hellip;<\/p>\n","protected":false},"author":7,"featured_media":117561,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Hypertension art\u00e9rielle pulmonaire","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11527,11477,11535,11549],"tags":[13456,16919,16930,16925],"powerkit_post_featured":[],"class_list":["post-326436","post","type-post","status-publish","format-standard","has-post-thumbnail","category-etudes","category-pneumologie-fr","category-rapports-de-congres","category-rx-fr","tag-diagnostic-differentiel","tag-hypertension-arterielle-pulmonaire","tag-hypertension-arterielle-pulmonaire-fr","tag-ph-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 20:41:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":326447,"slug":"la-sfida-della-diagnosi-differenziale","post_title":"La sfida della diagnosi differenziale","href":"https:\/\/medizinonline.com\/it\/la-sfida-della-diagnosi-differenziale\/"},"pt_PT":{"locale":"pt_PT","id":326412,"slug":"o-desafio-do-diagnostico-diferencial","post_title":"O desafio do diagn\u00f3stico diferencial","href":"https:\/\/medizinonline.com\/pt-pt\/o-desafio-do-diagnostico-diferencial\/"},"es_ES":{"locale":"es_ES","id":326425,"slug":"el-reto-del-diagnostico-diferencial","post_title":"El reto del diagn\u00f3stico diferencial","href":"https:\/\/medizinonline.com\/es\/el-reto-del-diagnostico-diferencial\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/326436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=326436"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/326436\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=326436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=326436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=326436"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=326436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}