{"id":330116,"date":"2021-01-22T13:07:02","date_gmt":"2021-01-22T12:07:02","guid":{"rendered":"https:\/\/medizinonline.com\/inhibiteurs-de-parp-dans-le-cadre-dune-recidive\/"},"modified":"2021-01-22T13:07:02","modified_gmt":"2021-01-22T12:07:02","slug":"inhibiteurs-de-parp-dans-le-cadre-dune-recidive","status":"publish","type":"post","link":"https:\/\/medizinonline.com\/fr\/inhibiteurs-de-parp-dans-le-cadre-dune-recidive\/","title":{"rendered":"Inhibiteurs de PARP dans le cadre d&#8217;une r\u00e9cidive"},"content":{"rendered":"<p>Le cancer de l&#8217;ovaire n&#8217;est souvent d\u00e9couvert qu&#8217;\u00e0 un stade avanc\u00e9 en raison de sympt\u00f4mes initiaux non sp\u00e9cifiques ou absents [1]. Par cons\u00e9quent, le pronostic est plut\u00f4t mauvais, notamment en raison du taux de rechute \u00e9lev\u00e9 [2]. L&#8217;autorisation de mise sur le march\u00e9 des inhibiteurs de PARP a toutefois permis d&#8217;am\u00e9liorer consid\u00e9rablement la situation des patientes, car un traitement d&#8217;entretien apr\u00e8s une chimioth\u00e9rapie \u00e0 base de platine peut prolonger la survie sans maladie et sans progression, sans affecter de mani\u00e8re significative la qualit\u00e9 de vie li\u00e9e \u00e0 la sant\u00e9 [2, 3].<\/p>\n<p><!--more--><\/p>\n<p>Chaque ann\u00e9e en Suisse, environ 600 femmes d\u00e9veloppent un cancer de l&#8217;ovaire [1]. Environ 75% des patientes subissent une r\u00e9cidive dans les 18 \u00e0 28 mois suivant la fin du traitement initial et le taux de survie \u00e0 5 ans n&#8217;est que de 30 \u00e0 50% [2]. Les options de traitement du cancer de l&#8217;ovaire en r\u00e9cidive ont \u00e9t\u00e9 consid\u00e9rablement \u00e9largies par l&#8217;introduction des inhibiteurs de la PARP. Avec le niraparib, les patientes atteintes d&#8217;un cancer de l&#8217;ovaire r\u00e9cidivant sensible au platine disposent d&#8217;un traitement d&#8217;entretien qui entra\u00eene une prolongation significative de la survie sans progression, ind\u00e9pendamment du statut mutationnel BRCA [4]. Le dosage de d\u00e9part individuel autoris\u00e9 en Suisse permet alors une meilleure tol\u00e9rance tout en conservant l&#8217;efficacit\u00e9 [2, 4, 5].<\/p>\n<p><strong>Le niraparib agit ind\u00e9pendamment du statut mutationnel BRCA<\/strong><\/p>\n<p>Le niraparib a \u00e9t\u00e9 le premier PARPi \u00e0 montrer une am\u00e9lioration significative de la survie sans progression (PFS) chez les patientes atteintes d&#8217;un cancer de l&#8217;ovaire sensible au platine en r\u00e9cidive, ind\u00e9pendamment du statut mutationnel BRCA, dans une \u00e9tude de phase III randomis\u00e9e et contr\u00f4l\u00e9e par placebo (ENGOT-OV16\/NOVA) [6]. Ainsi, chez les patientes pr\u00e9sentant une mutation germinale BRCA (gBRCA), la PFS a \u00e9t\u00e9 prolong\u00e9e de 15,5 mois (niraparib : 21,0 mois ; placebo : 5,5 mois ; HR 0,27 ; P&lt;0,001) et de 5,4 mois chez les patientes sans mutation germinale BRCA (non-gBRCA) (Niraparib : 9,3 mois ; placebo : 3,9 mois ; HR 0,45 ; P&lt;0.001) [6].<\/p>\n<p>Sur la base des r\u00e9sultats de ces \u00e9tudes, le niraparib est autoris\u00e9 en Suisse depuis octobre 2018 en tant que traitement d&#8217;entretien chez les patientes atteintes d&#8217;un carcinome \u00e9pith\u00e9lial s\u00e9reux primaire de haut grade de l&#8217;ovaire, des trompes ou du p\u00e9ritoine sensible au platine et r\u00e9cidivant, apr\u00e8s une r\u00e9ponse compl\u00e8te ou partielle \u00e0 une chimioth\u00e9rapie \u00e0 base de platine [4].<\/p>\n<p>L&#8217;autre PARPi autoris\u00e9 en Suisse, l&#8217;olaparib, a \u00e9galement montr\u00e9 des r\u00e9sultats positifs en termes de PFS dans l&#8217;\u00e9tude de phase III randomis\u00e9e et contr\u00f4l\u00e9e par placebo SOLO2\/ENGOT-Ov21, mais uniquement chez les patientes avec gBRCA [7].&nbsp;  Pour les non-BRCA, les donn\u00e9es de l&#8217;\u00e9tude de phase II 19 et de l&#8217;\u00e9tude de phase IIIb \u00e0 un bras OPINION sont disponibles [8, 9].<\/p>\n<p><strong>Une dose de d\u00e9part r\u00e9duite permet d&#8217;obtenir la m\u00eame efficacit\u00e9 avec moins d&#8217;effets secondaires<\/strong><\/p>\n<p>Outre l&#8217;efficacit\u00e9, la bonne tol\u00e9rance et le maintien de la qualit\u00e9 de vie li\u00e9e \u00e0 la sant\u00e9 sont des pr\u00e9occupations majeures des traitements d&#8217;entretien [10]. En g\u00e9n\u00e9ral, les effets secondaires du traitement par niraparib ont \u00e9t\u00e9 bien g\u00e9r\u00e9s [6]. Les effets ind\u00e9sirables graves les plus fr\u00e9quents (grade 3\/4) sous Niraparib comprenaient la thrombocytop\u00e9nie (33,8%), l&#8217;an\u00e9mie (25,3%) et la neutrop\u00e9nie (19,6%) et sont g\u00e9n\u00e9ralement survenus au cours des trois premiers cycles de traitement [6]. En revanche, apr\u00e8s des ajustements de dose individuels, la thrombocytop\u00e9nie, la neutrop\u00e9nie et la fatigue (grade 3\/4) ont \u00e9t\u00e9 moins fr\u00e9quemment observ\u00e9es lors des cycles ult\u00e9rieurs [6]. Les thrombocytop\u00e9nies \u00e9taient g\u00e9n\u00e9ralement transitoires et le nombre de plaquettes s&#8217;est stabilis\u00e9 \u00e0 partir du troisi\u00e8me cycle de traitement [6].<\/p>\n<p>Une analyse r\u00e9trospective des donn\u00e9es ENGOT-OV16\/NOVA a examin\u00e9 les liens entre la dose de niraparib et la survenue d&#8217;effets ind\u00e9sirables associ\u00e9s au traitement (TEAE) [5]. Il s&#8217;est av\u00e9r\u00e9 qu&#8217;une r\u00e9duction de la dose a \u00e9t\u00e9 effectu\u00e9e chez 68,9% des patientes en raison des TEAE, le plus souvent au cours des trois premiers mois de traitement. Le plus souvent, la dose de niraparib a \u00e9t\u00e9 r\u00e9duite de 300 mg \u00e0 200 mg, ce qui a permis d&#8217;augmenter le taux de TEAE de 3e\/4e g\u00e9n\u00e9ration. La r\u00e9duction de l&#8217;incidence de l&#8217;alcool sur la sant\u00e9 a \u00e9t\u00e9 tr\u00e8s importante. Un taux d&#8217;an\u00e9mie plus faible (grade 3\/4) n&#8217;a \u00e9t\u00e9 observ\u00e9 qu&#8217;avec une dose de niraparib de 100 mg [5]. De plus, une num\u00e9ration plaquettaire basse (&lt;150000\/\u00b5l) et un poids corporel &lt;77 kg ont \u00e9t\u00e9 identifi\u00e9s comme des facteurs de risque de d\u00e9velopper une thrombocytop\u00e9nie de grade 3\/4 dans les 30 premiers jours sous niraparib [5]. Aucune diff\u00e9rence d&#8217;efficacit\u00e9 n&#8217;a \u00e9t\u00e9 observ\u00e9e chez les patientes recevant une dose r\u00e9duite de niraparib (200 mg ou 100 mg) par rapport \u00e0 la dose plus \u00e9lev\u00e9e de 300 mg. Afin d&#8217;exclure tout biais en d\u00e9faveur de la dose de 300 mg, les donn\u00e9es de SSP n&#8217;ont \u00e9t\u00e9 prises en compte qu&#8217;\u00e0 partir du quatri\u00e8me mois de traitement, car la plupart des patientes avaient atteint une dose stable \u00e0 ce moment-l\u00e0 [5].<\/p>\n<p>Sur la base de ces r\u00e9sultats, le niraparib a \u00e9t\u00e9 autoris\u00e9 en Suisse avec une dose de d\u00e9part recommand\u00e9e de 200 mg [4]. Seules les patientes ayant un poids corporel<br \/>\n\u2265 77 kg et une num\u00e9ration plaquettaire normale (\u2265150&#8217;000\/\u00b5l), le traitement par niraparib continue d&#8217;\u00eatre initi\u00e9 \u00e0 la dose de 300 mg [4]. Le Niraparib ne doit \u00eatre pris qu&#8217;une fois par jour, ce qui simplifie le traitement et favorise ainsi l&#8217;adh\u00e9rence [4].<\/p>\n<p><strong>Bonne compatibilit\u00e9 dans le cadre du monde r\u00e9el<\/strong><\/p>\n<p>Dans des conditions r\u00e9elles, un traitement par 200 mg de niraparib est \u00e9galement associ\u00e9 \u00e0 une meilleure tol\u00e9rance [2]. C&#8217;est ce qui ressort d&#8217;une \u00e9tude du monde r\u00e9el qui a \u00e9valu\u00e9 les dossiers anonymes de 153 patientes ayant re\u00e7u du niraparib \u00e0 une dose initiale de 200 mg [2]. Les patientes avaient un \u00e2ge m\u00e9dian de 59 ans et un poids m\u00e9dian de 70 kg. Le d\u00e9lai entre la fin de la chimioth\u00e9rapie \u00e0 base de platine et le d\u00e9but du traitement d&#8217;entretien par 200 mg de niraparib \u00e9tait de 33 jours en moyenne [2]. Dans les \u00e9tudes cliniques, les naus\u00e9es, la thrombocytop\u00e9nie et la fatigue ont \u00e9t\u00e9 les effets ind\u00e9sirables les plus fr\u00e9quents sous niraparib. En situation r\u00e9elle, ces effets secondaires sont survenus chez 37% des patientes au cours des trois premiers mois, mais leur incidence a \u00e9t\u00e9 consid\u00e9rablement r\u00e9duite avec 200 mg de niraparib par rapport \u00e0 la dose initiale de 300 mg de niraparib dans l&#8217;\u00e9tude ENGOT-OV16\/NOVA (figure 1). Une r\u00e9duction de la dose de Niraparib de 200 mg \u00e0 100 mg a \u00e9t\u00e9 effectu\u00e9e chez 11% des patientes. Une interruption du traitement en raison d&#8217;effets secondaires a \u00e9t\u00e9 n\u00e9cessaire chez 4% des patientes et le traitement a d\u00fb \u00eatre interrompu dans les trois premiers mois chez seulement 2% d&#8217;entre elles [2].<\/p>\n<p><img decoding=\"async\" style=\"caret-color: #000000; color: #000000; width: 100%;\" data-src=\"https:\/\/assets.medizinonline.com\/sites\/default\/files\/field\/images\/abb1_2.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/p>\n<p><strong>Figure 1 :<\/strong>&nbsp;Survenue des trois effets ind\u00e9sirables de grade 3\/4 les plus fr\u00e9quents chez les patientes dans le cadre clinique du monde r\u00e9el (Niraparib dose de d\u00e9part 200 mg) par rapport aux patientes de l&#8217;\u00e9tude ENGOT-OV16\/NOVA (Niraparib dose de d\u00e9part 300 mg), modifi\u00e9 d&#8217;apr\u00e8s [2].<\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p>La Suisse est le premier pays \u00e0 avoir autoris\u00e9 le niraparib avec une dose initiale r\u00e9duite de 200 mg [4]. Cette r\u00e9duction de la dose permet de r\u00e9duire consid\u00e9rablement le taux d&#8217;effets secondaires par rapport \u00e0 la dose de 300 mg, sans pour autant compromettre l&#8217;efficacit\u00e9 du traitement d&#8217;entretien [5, 6]. Comme le montre une \u00e9tude du monde r\u00e9el, la dose r\u00e9duite est \u00e9galement associ\u00e9e \u00e0 une meilleure tol\u00e9rance dans la pratique clinique [2]. Les ajustements de dose individuels permettent une gestion optimale des effets secondaires et contribuent ainsi \u00e0 pr\u00e9server la qualit\u00e9 de vie des patientes sous traitement d&#8217;entretien [2].<\/p>\n<table style=\"width: 500px;\" border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td><strong><a href=\"https:\/\/medizinonline.com\/swiss-oncology-in-motion\/\">L&#8217;oncologie suisse en mouvement<\/a><img decoding=\"async\" style=\"float: right; height: 150px; width: 150px;\" data-src=\"https:\/\/assets.medizinonline.com\/sites\/default\/files\/styles\/partner_teaser\/public\/swisnonco_motion.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/strong><\/p>\n<p>Swiss Oncology in Motion est une formation continue accr\u00e9dit\u00e9e en ligne pour les oncologues m\u00e9dicaux, les h\u00e9matologues et les sp\u00e9cialistes en oncologie, disponible gratuitement sur medizinonline.ch. Des modules vid\u00e9o d&#8217;une heure abordent des th\u00e8mes oncologiques pertinents par le biais de trois expos\u00e9s de 15 minutes chacun, pr\u00e9sent\u00e9s par des sp\u00e9cialistes et suivis de r\u00e9ponses aux questions. Les modules sont anim\u00e9s par le Prof. em. Dr. med. Richard Herrmann.<\/p>\n<p>Dans le module sur le cancer de l&#8217;ovaire, le Dr Anita Wolfer (ancien m\u00e9decin-chef du CHUV) pr\u00e9sente dans la premi\u00e8re partie des chiffres et des faits scientifiques pertinents sur la maladie. Dans la deuxi\u00e8me partie, le professeur Andreas G\u00fcnthert (directeur du gyn-zentrum de Lucerne) fera un expos\u00e9 sur la situation des soins et du traitement en Suisse. Marcus Vetter (m\u00e9decin-chef en oncologie m\u00e9dicale, H\u00f4pital universitaire de B\u00e2le) pr\u00e9sente et discute les options actuelles en mati\u00e8re de traitement d&#8217;entretien. Cliquez sur ce <a href=\"https:\/\/www.medizinonline.com\/soim\/video-ovarialkarzinom-33\" target=\"_blank\" rel=\"noopener\">lien<\/a> pour acc\u00e9der directement \u00e0 la vid\u00e9o.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Le contenu de cet article est sous la responsabilit\u00e9 et le financement de GlaxoSmithKline AG, Talstrasse 3 &#8211; 5, 3053 M\u00fcnchenbuchsee. Les marques d\u00e9pos\u00e9es sont la propri\u00e9t\u00e9 de leurs propri\u00e9taires respectifs. 2020 GSK group of companies ou son licenci\u00e9.<\/p>\n<p>Zejula est indiqu\u00e9 dans le traitement d&#8217;entretien des patientes adultes atteintes d&#8217;un carcinome \u00e9pith\u00e9lial primaire s\u00e9reux de haut grade (hautement d\u00e9diff\u00e9renci\u00e9) de l&#8217;ovaire, des trompes ou du p\u00e9ritoine, sensible au platine et r\u00e9cidivant. La patiente doit avoir r\u00e9pondu compl\u00e8tement ou partiellement \u00e0 une chimioth\u00e9rapie \u00e0 base de platine [4].<\/p>\n<p><a href=\"https:\/\/assets.medizinonline.com\/sites\/default\/files\/link_page\/190716_zejula_kurz-fi_d_0719.pdf\">Zejula information sp\u00e9cialis\u00e9e courte<\/a><\/p>\n<p>Dr. sc. nat. Jenny Thom<\/p>\n<p>PM-CH-NRP-ADVR-210008-01\/2021<\/p>\n<p><strong>Litt\u00e9rature<\/strong><\/p>\n<div><span style=\"font-size: 12px;\">1. cancer de l&#8217;ovaire (carcinome ovarien) <a href=\"https:\/\/www.krebsliga.ch\/ueber-krebs\/krebsarten\/eierstockkrebs-ovarialkarzinom\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.krebsliga.ch\/ueber-krebs\/krebsarten\/eierstockkrebs-ovarialkarzinom\/.<\/a> Dernier acc\u00e8s 15.07.2020.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">2.&nbsp;<\/span><span style=\"font-size: 12px;\">Gallagher, J.R., et al., Real-world adverse events with niraparib 200 mg\/day maintenance therapy in ovarian cancer : a retrospective study. Future Oncol, 2019. 15(36) : p. 4197-4206.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">3.&nbsp;<\/span><span style=\"font-size: 12px;\">Madariaga, A., et al, Manage wisely : poly (ADP-ribose) polymerase inhibitor (PARPi) treatment and adverse events. Int J Gynecol Cancer, 2020.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">4.&nbsp;<\/span><span style=\"font-size: 12px;\">Information sur le produit Zejula (Niraparib). <\/span><a style=\"font-size: 12px;\" href=\"http:\/\/www.swissmedicinfo.ch\" target=\"_blank\" rel=\"noopener\">www.swissmedicinfo.ch<\/a><span style=\"font-size: 12px;\">. Dernier acc\u00e8s 27.10.2020.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">5.&nbsp;<\/span><span style=\"font-size: 12px;\">Berek, J.S., et al., Safety and dose modification for patients receiving niraparib. Ann Oncol, 2018. 29(8) : p. 1784-1792.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">6.&nbsp;<\/span><span style=\"font-size: 12px;\">Mirza, M.R., et al., Niraparib Maintenance Therapy in Platinum-Sensitive, Recurrent Ovarian Cancer. N Engl J Med, 2016. 375(22) : p. 2154-2164.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">7.&nbsp;<\/span><span style=\"font-size: 12px;\">Pujade-Lauraine, E., et al., Olaparib tablets as maintenance therapy in patients with platinum-sensitive, relapsed ovarian cancer and a BRCA1\/2 mutation (SOLO2\/ENGOT-Ov21) : a double-blind, randomised, placebo-controlled, phase 3 trial. Lancet Oncol, 2017. 18(9) : p. 1274-1284.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">8.&nbsp;<\/span><span style=\"font-size: 12px;\">Ledermann, J., et al., Olaparib maintenance therapy in platinum-sensitive relapsed ovarian cancer. N Engl J Med, 2012. 366(15) : p. 1382-92.<\/span><\/div>\n<div><span style=\"font-size: 12px;\">9.&nbsp;<\/span><span style=\"font-size: 12px;\">Poveda, A., et al., Olaparib maintenance monotherapy for non-germline BRCA1\/2-mutated (non-gBRCAm) platinum-sensitive relapsed ovarian cancer (PSR OC) patients (pts) : Phase IIIb OPINION interim analysis. J Clin Oncol, 2020. 38(suppl ; abstract 6057).<\/span><\/div>\n<div><span style=\"font-size: 12px;\">10.&nbsp;<\/span><span style=\"font-size: 12px;\">DiSilvestro, P. and A. Alvarez Secord, Maintenance treatment of recurrent ovarian cancer : Is it ready for prime time ? Cancer Treat Rev, 2018. 69 : p. 53-65.<\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le cancer de l&#8217;ovaire n&#8217;est souvent d\u00e9couvert qu&#8217;\u00e0 un stade avanc\u00e9 en raison de sympt\u00f4mes initiaux non sp\u00e9cifiques ou absents [1]. Par cons\u00e9quent, le pronostic est plut\u00f4t mauvais, notamment en&hellip;<\/p>\n","protected":false},"author":12,"featured_media":103294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","cat_1_feature_home_top":false,"cat_2_editor_pick":false,"csco_eyebrow_text":"Cancer de l'ovaire sensible au platine","footnotes":"","_members_access_role":[],"_members_access_error":""},"category":[11389,11549],"tags":[],"powerkit_post_featured":[],"class_list":["post-330116","post","type-post","status-publish","format-standard","has-post-thumbnail","category-oncologie","category-rx-fr","pmpro-has-access"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:33:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"wpml_current_locale":"fr_FR","wpml_translations":{"it_IT":{"locale":"it_IT","id":330260,"slug":"gli-inibitori-parp-nel-contesto-di-recidiva","post_title":"Gli inibitori PARP nel contesto di recidiva","href":"https:\/\/medizinonline.com\/it\/gli-inibitori-parp-nel-contesto-di-recidiva\/"},"pt_PT":{"locale":"pt_PT","id":330263,"slug":"inibidores-parp-no-cenario-de-recaida","post_title":"Inibidores PARP no cen\u00e1rio de reca\u00edda","href":"https:\/\/medizinonline.com\/pt-pt\/inibidores-parp-no-cenario-de-recaida\/"},"es_ES":{"locale":"es_ES","id":330266,"slug":"inhibidores-de-parp-en-el-contexto-de-recaida","post_title":"Inhibidores de PARP en el contexto de reca\u00edda","href":"https:\/\/medizinonline.com\/es\/inhibidores-de-parp-en-el-contexto-de-recaida\/"}},"_links":{"self":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/330116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/comments?post=330116"}],"version-history":[{"count":0,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/posts\/330116\/revisions"}],"wp:attachment":[{"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/media?parent=330116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/category?post=330116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/tags?post=330116"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/medizinonline.com\/fr\/wp-json\/wp\/v2\/powerkit_post_featured?post=330116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}